{"id":88797,"date":"2015-06-15T10:23:35","date_gmt":"2015-06-15T13:23:35","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=88797"},"modified":"2020-05-29T13:23:00","modified_gmt":"2020-05-29T16:23:00","slug":"para-quem-tem-mais-de-65-anos","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/","title":{"rendered":"Para quem tem mais de 65 anos"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2015\/06\/idosos.jpg\" alt=\"idosos\" width=\"750\" height=\"400\" \/><\/p>\n<p><strong>Ivone Boechat<\/strong><\/p>\n<p><strong>1 &#8211;<\/strong> Tome posse da maturidade. A longevidade \u00e9 uma b\u00ean\u00e7\u00e3o! Comemore! Ser maduro \u00e9 um privil\u00e9gio; \u00e9 a \u00faltima etapa da sua vida e se voc\u00ea acha que n\u00e3o soube viver as outras, n\u00e3o perca tempo, viva muito bem esta. N\u00e3o fique falando toda hora: \u201cestou velho\u201d. Velho \u00e9 coisa engui\u00e7ada. Idade n\u00e3o \u00e9 pretexto para ningu\u00e9m ficar velho. Engane a voc\u00ea mesmo sobre a sua idade, porque os psic\u00f3logos dizem que se vive de acordo com a idade declarada!<\/p>\n<p><strong>2 &#8211;<\/strong> Perdoe a voc\u00ea antes de perdoar os outros. Se voc\u00ea falhou, pediu perd\u00e3o? Deus j\u00e1 o perdoou e n\u00e3o se lembra mais. Mas voc\u00ea fica remoendo o passado&#8230; N\u00e3o se importe com o julgamento dos outros. S\u00f3 h\u00e1 dois times no Universo: o do Salvador e o do acusador. Neste \u00faltimo voc\u00ea sabe quem \u00e9 goleiro. Continue no time do Salvador.<\/p>\n<p><strong>3<\/strong> &#8211; Viva com intelig\u00eancia todo o seu tempo. Viva a sua vida, n\u00e3o a do seu marido, dos filhos, dos netos, dos parentes, dos vizinhos&#8230; Nem viva s\u00f3 pra eles, viva pra voc\u00ea tamb\u00e9m. Isto se chama amor pr\u00f3prio, aquilo que voc\u00ea sacrificou sempre! Nunca viva em fun\u00e7\u00e3o dos outros. Fa\u00e7a o seu projeto de vida!<\/p>\n<p><strong>4<\/strong> &#8211; Coma muito menos; durma o suficiente; n\u00e3o fique o dia inteiro, dormindo, dando desculpa de velhice. Tenha disciplina. Fale com muita sabedoria. Discipline sua voz: nem met\u00e1lica, nem baixinha; seja agrad\u00e1vel!<\/p>\n<p><strong>5<\/strong> &#8211; Poupe seus familiares e amigos das mem\u00f3rias do passado. Valorize o que foi bom. Experi\u00eancias ca\u00f3ticas, traumas, fobias, neuroses, devem ser tratadas com o psicoterapeuta. N\u00e3o transforme poltrona em div\u00e3, ouvido em descarga.<\/p>\n<p><strong>6<\/strong> &#8211; N\u00e3o aborre\u00e7a ningu\u00e9m com o relat\u00f3rio das suas viagens. Elas s\u00e3o interessantes s\u00f3 pra quem viaja. Ningu\u00e9m aguenta ouvir os relat\u00f3rios e ver fotografias horas e horas. Comente apenas o destino e a dura\u00e7\u00e3o da viagem, se algu\u00e9m perguntar. Aprenda a fazer uma s\u00edntese de tudo, a n\u00e3o ser que seus amigos pe\u00e7am mais detalhes. Se algu\u00e9m perguntar mais alguma coisa, seja breve.<\/p>\n<p><strong>7<\/strong> &#8211; Escolha bons m\u00e9dicos. N\u00e3o se automedique. N\u00e3o h\u00e1 nada mais irritante do que um idoso metido a receitar rem\u00e9dio pra tudo o que o outro sente. Fa\u00e7a uma faxina na sua farm\u00e1cia dom\u00e9stica.<\/p>\n<p><strong>8<\/strong> &#8211; N\u00e3o arrisque cirurgias pl\u00e1sticas rejuvenescedoras. Elas t\u00eam prazo curto de dura\u00e7\u00e3o. A chance de voc\u00ea ficar mais feio \u00e9 alt\u00edssima e a de ficar mais jovem \u00e9 fugaz. Fa\u00e7a exerc\u00edcios faciais. Socorra os m\u00fasculos da sua face. Tome no m\u00ednimo oito copos de \u00e1gua por dia e o sol da manh\u00e3 \u00e9 indispens\u00e1vel. O crime n\u00e3o compensa, mas o creme compensa!<\/p>\n<p><strong>9<\/strong> &#8211; Use seu dinheiro com crit\u00e9rio. Gaste em coisas importantes e evite economizar tanto com voc\u00ea. Tudo o que se economizar com voc\u00ea ser\u00e1 para quem? No dia em que voc\u00ea morrer, vai ser uma feira de Caruaru na sua casa. V\u00e3o carregar tudo. N\u00e3o dar\u00e3o valor a nada daquilo que voc\u00ea valorizou tanto: enfeites, penduricalhos, livros antigos, roupas usadas, bijuterias cafonas, ouro velho&#8230; prataria preta, trof\u00e9us encardidos, placas de homenagens. Por que n\u00e3o doar as roupas, abrir um brech\u00f3 ou vender todas as suas bugigangas, apurar um bom dinheiro e viajar?<\/p>\n<p><strong>10<\/strong> &#8211; A maturidade n\u00e3o lhe d\u00e1 o direito de ser mal educado. Nada de encher o prato na casa dos outros ou no self-service (com os outros pagando); falar de boca cheia, ou palitar os dentes na mesa de refei\u00e7\u00f5es (insuport\u00e1vel).<\/p>\n<p><strong>11<\/strong> &#8211; S\u00f3 masque chiclete sem testemunhas. N\u00e3o corra o risco de acharem que voc\u00ea j\u00e1 est\u00e1 ruminando ou falando sozinho.<\/p>\n<p><strong>12<\/strong> &#8211; Aposentadoria n\u00e3o significa ociosidade. Voc\u00ea deve arranjar alguma ocupa\u00e7\u00e3o interessante e que lhe d\u00ea prazer. Trabalhar traz muitas vantagens para a sa\u00fade mental, al\u00e9m do dinheiro extra para gastar, tamb\u00e9m com voc\u00ea.<\/p>\n<p><strong>13<\/strong> &#8211; Cuidado com a nostalgia e o otimismo. Pessoas amargas e tristes s\u00e3o chat\u00edssimas, as alegres demais, tamb\u00e9m. Elogie os amigos, n\u00e3o fique exigindo explica\u00e7\u00f5es de tudo. Amigo \u00e9 amigo.<\/p>\n<p><strong>14<\/strong> &#8211; Leia. Ainda h\u00e1 tempo para gostar de aprender. A maturidade pode lhe trazer sabedoria. Coloque-se no grupo sempre pronto para aprender. N\u00e3o se apresente em lugar nenhum dizendo: sou muito experiente!<\/p>\n<p><strong>15<\/strong> &#8211; N\u00e3o acredite nas pessoas que dizem que n\u00e3o tem nada demais o idoso usar roupas de jovens, cuidado. Vista-se bem, mas com discri\u00e7\u00e3o. Cuidado com a maquiagem, se for pesada, voc\u00ea vai ficar horr\u00edvel.<\/p>\n<p><strong>16<\/strong> &#8211; Seja av\u00f3 do seus netos, n\u00e3o a m\u00e3e nem a bab\u00e1. Por isso nem pense em educ\u00e1-los ou comprometer todo o seu tempo com as tarefas chatas de ir buscar na escola, levar a festinhas, nata\u00e7\u00e3o, ingl\u00eas, v\u00f4lei&#8230; S\u00f3 nas emerg\u00eancias. Cuidado com aquela disponibilidade que torna os outros irrespons\u00e1veis.<\/p>\n<p><strong>17<\/strong> &#8211; Se algu\u00e9m perguntar como v\u00e3o seus netos, n\u00e3o precisa contar tuuuuuuuudo! Evite discorrer sobre a beleza rara e a intelig\u00eancia excepcional deles. Cuidado com a idolatria de neto e o abandono dos filhos casados&#8230;<\/p>\n<p><strong>18<\/strong> &#8211; N\u00e3o seja uma sogra chata. Nunca pe\u00e7a relat\u00f3rio de nada. Seu filho tem a fam\u00edlia dele. Voc\u00ea agora \u00e9 parente! Nunca, nunca, nunca mesmo, visite seus filhos sem que seja convidado. Se o filho ligar pra voc\u00ea, n\u00e3o diga: ah! lembrou finalmente da sua m\u00e3e? \u00c9 melhor dizer: Deus o aben\u00e7oe meu filho.<\/p>\n<p><strong>19<\/strong> &#8211; Cuidado em atender ao telefone: se a pessoa perguntar como voc\u00ea vai e voc\u00ea responder \u201cestou levando a vida como Deus quer\u201d; \u201ca vida \u00e9 dura\u201d; \u201cestou preparando a partida\u201d; \u201cestou vencendo a dureza\u201d; voc\u00ea vai ver que as liga\u00e7\u00f5es dos amigos e dos parentes v\u00e3o rarear, cada vez mais.<\/p>\n<p><strong>20<\/strong> &#8211; A maturidade \u00e9 o auge da vida, porque voc\u00ea tem idade, ju\u00edzo, experi\u00eancia, tempo e capacidade para se relacionar melhor com as pessoas. Ent\u00e3o delete do seu computador mental o v\u00edrus da inveja, do orgulho, da vaidade, promiscuidades, cobran\u00e7as, coisas pequenas e frustrantes para tomar posse de tudo o que voc\u00ea sempre sonhou: a felicidade.<\/p>\n<p><strong>Ivone Boechat<\/strong> <em>\u00e9 Consultora em educa\u00e7\u00e3o, PhD Psicologia da Educa\u00e7\u00e3o, Mestre em Educa\u00e7\u00e3o, possui 17 livros publicados e \u00e9 membro da Academia Duquecaxiense de Letras e Artes-RJ. Seu blog: www.ivoneboechat.blogspot.com.br<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Ivone Boechat<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Para quem tem mais de 65 anos - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para quem tem mais de 65 anos - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Ivone Boechat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-15T13:23:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-29T16:23:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2015\/06\/idosos.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/\",\"name\":\"Para quem tem mais de 65 anos - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2015-06-15T13:23:35+00:00\",\"dateModified\":\"2020-05-29T16:23:00+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para quem tem mais de 65 anos\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Para quem tem mais de 65 anos - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"Para quem tem mais de 65 anos - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Ivone Boechat","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2015-06-15T13:23:35+00:00","article_modified_time":"2020-05-29T16:23:00+00:00","og_image":[{"url":"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2015\/06\/idosos.jpg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/","name":"Para quem tem mais de 65 anos - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2015-06-15T13:23:35+00:00","dateModified":"2020-05-29T16:23:00+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/para-quem-tem-mais-de-65-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"Para quem tem mais de 65 anos"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/88797"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=88797"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/88797\/revisions"}],"predecessor-version":[{"id":185134,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/88797\/revisions\/185134"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=88797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=88797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=88797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}