{"id":81766,"date":"2015-03-20T08:31:18","date_gmt":"2015-03-20T11:31:18","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=81766"},"modified":"2020-06-03T09:56:47","modified_gmt":"2020-06-03T12:56:47","slug":"retiro-espiritual-o-que-e","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/","title":{"rendered":"Retiro espiritual: o que \u00e9?"},"content":{"rendered":"<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2015\/03\/eremo_g.jpg\" alt=\"eremo_g\" width=\"820\" height=\"355\" \/><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><strong><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Frei Alberto Beckh\u00e4user, OFM<\/span><\/strong><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">\u00a0<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Entre os exerc\u00edcios da espiritualidade crist\u00e3 encontra-se o<span class=\"apple-converted-space\">\u00a0<\/span><i>Retiro espiritual<\/i><span class=\"apple-converted-space\">\u00a0<\/span>ou simplesmente o<span class=\"apple-converted-space\">\u00a0<\/span><i>Retiro<\/i>, que pode ser de um dia, de uma semana, de um m\u00eas ou, mesmo, mensal ou anual.<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">\u00a0<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Antes do Conc\u00edlio Vaticano II o<span class=\"apple-converted-space\">\u00a0<\/span><i>Retiro espiritual<\/i><span class=\"apple-converted-space\">\u00a0<\/span>era muito praticado pelo clero, pelos religiosos, pelas religiosas e Associa\u00e7\u00f5es de fi\u00e9is leigos. Infelizmente, nos anos ap\u00f3s o Conc\u00edlio, esta pr\u00e1tica foi em grande parte abandonada pelos fi\u00e9is leigos, tanto na forma de<span class=\"apple-converted-space\">\u00a0<\/span><i>Exerc\u00edcios espirituais<\/i><span class=\"apple-converted-space\">\u00a0<\/span>segundo a tradi\u00e7\u00e3o de Santo In\u00e1cio de Loyola, como na forma de<span class=\"apple-converted-space\">\u00a0<\/span><i>Retiro<\/i>, seja individual, seja coletivo. Nos dias atuais, a pr\u00e1tica, aos poucos, vem ressurgindo. Vemos, sobretudo, grupos de jovens se reunindo em retiro espiritual.<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">O Instituto Teol\u00f3gico Francisco elaborou um Projeto no sentido de oferecer a oportunidade do<span class=\"apple-converted-space\">\u00a0<\/span><i>Retiro espiritual<\/i><span class=\"apple-converted-space\">\u00a0<\/span>para fi\u00e9is leigos em geral e para todos os que sinceramente buscam a Deus. No ano de 2014 foram oferecidos dois Retiros orientados por frades professores do Instituto. Neste ano de 2015 s\u00e3o oferecidas tr\u00eas oportunidades de Retiro, no ambiente silencioso e convidativo do Instituto, \u00e0 Rua Coronel Veiga 550.<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">\u00a0<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">O primeiro ser\u00e1 em prepara\u00e7\u00e3o \u00e0 celebra\u00e7\u00e3o da P\u00e1scoa:<span class=\"apple-converted-space\">\u00a0<\/span><i>Viver \u00e0 luz da P\u00e1scoa do Senhor<\/i>. Ser\u00e1 no dia 21 de mar\u00e7o, s\u00e1bado, de 8 \u00e0s 18h. Objetivo:<span class=\"apple-converted-space\">\u00a0<\/span><i>Predispor o entendimento e o cora\u00e7\u00e3o para a celebra\u00e7\u00e3o da solenidade da P\u00e1scoa de Jesus Cristo.<\/i><span class=\"apple-converted-space\">\u00a0<\/span>O segundo acontecer\u00e1 por ocasi\u00e3o da solenidade de S\u00e3o Francisco de Assis, no dia 26 de setembro, tamb\u00e9m de 8 \u00e0s 18h. O lema \u00e9:<span class=\"apple-converted-space\">\u00a0<\/span><i>Pai nosso, venha teu reino!<\/i><span class=\"apple-converted-space\">\u00a0<\/span>Objetivo: <i>Cultivar a ora\u00e7\u00e3o e a contempla\u00e7\u00e3o com S\u00e3o Francisco de Assis.<span class=\"apple-converted-space\">\u00a0<\/span><\/i>O terceiro ser\u00e1 no Advento em prepara\u00e7\u00e3o da celebra\u00e7\u00e3o do Natal do Senhor, dia 12 de dezembro de 2015, com o lema:<span class=\"apple-converted-space\">\u00a0<\/span><i>Deus, vem a meu encontro!<\/i>Objetivo:<span class=\"apple-converted-space\">\u00a0<\/span><i>preparar a mente e o cora\u00e7\u00e3o para a celebra\u00e7\u00e3o da fraternidade natalina.<\/i><\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">\u00a0<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Mas, afinal, o que \u00e9 um<span class=\"apple-converted-space\">\u00a0<\/span><i>Retiro espiritual?<span class=\"apple-converted-space\">\u00a0<\/span><\/i>Sua pr\u00e1tica atualmente est\u00e1 bastante distante da consci\u00eancia e da pr\u00e1tica dos crist\u00e3os. Por isso, nas linhas que se seguem, proponho-me a introduzir de maneira simples as pessoas na compreens\u00e3o do<span class=\"apple-converted-space\">\u00a0<\/span><i>Retiro espiritual<\/i>, real\u00e7ando, assim, a sua import\u00e2ncia.<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">\u00a0<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><b><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Modalidades deste exerc\u00edcio de espiritualidade<\/span><\/b><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">: No decorrer da hist\u00f3ria da Igreja sobressaem dois tipos de cultivo intenso da vida espiritual em sua express\u00e3o individual. Temos os<span class=\"apple-converted-space\">\u00a0<\/span><i>Exerc\u00edcios espirituais<\/i><span class=\"apple-converted-space\">\u00a0<\/span>na tradi\u00e7\u00e3o de Santo In\u00e1cio de Loyola, promovidos e orientados tamb\u00e9m hoje, sobretudo, pelos Padres Jesu\u00edtas. Costumam durar 30 dias. Trata-se de um tempo forte de medita\u00e7\u00e3o, de discernimento, de ora\u00e7\u00e3o, de convers\u00e3o, enfim, de renova\u00e7\u00e3o espiritual. Acentua-se a caminhada; existe um pregador e um diretor espiritual. D\u00e1-se grande import\u00e2ncia ao m\u00e9todo. O segundo tipo vai na linha do<span class=\"apple-converted-space\">\u00a0<\/span><i>Retiro<\/i>, tendo como modelo S\u00e3o Francisco de Assis.<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">\u00a0<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Aqui gostar\u00edamos de abordar o chamado<span class=\"apple-converted-space\">\u00a0<\/span><i>Retiro<\/i><span class=\"apple-converted-space\">\u00a0<\/span>ou<span class=\"apple-converted-space\">\u00a0<\/span><i>Retiro espiritual<\/i><span class=\"apple-converted-space\">\u00a0<\/span>muito praticado por S\u00e3o Francisco de Assis. O<span class=\"apple-converted-space\">\u00a0<\/span><i>Retiro<\/i><span class=\"apple-converted-space\">\u00a0<\/span>pode ser feito em comum, em geral com algum sacerdote orientador ou pregador. O orientador n\u00e3o precisa necessariamente ser sacerdote. Ele pode ser feito tamb\u00e9m individualmente, a exemplo do pr\u00f3prio Cristo e de S\u00e3o Francisco de Assis.<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">\u00a0<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><b><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">A pr\u00e1tica de Jesus:<span class=\"apple-converted-space\">\u00a0<\/span><\/span><\/b><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Antes de momentos importantes de sua miss\u00e3o messi\u00e2nica, Jesus se retirava para rezar. Pensemos na ora\u00e7\u00e3o por ocasi\u00e3o de seu batismo no rio Jord\u00e3o, nos 40 dias no deserto. A ora\u00e7\u00e3o antes de chamar os ap\u00f3stolos, antes de ensinar os ap\u00f3stolos a rezar, antes de sua Paix\u00e3o no Monte das Oliveiras. Retirava-se tamb\u00e9m do meio das \u201cmultid\u00f5es\u201d e dos disc\u00edpulos para p\u00f4r-se em ora\u00e7\u00e3o, para cultivar o col\u00f3quio com o Pai, para estar com o Pai.<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">\u00a0<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><b><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">A pr\u00e1tica de Francisco<\/span><\/b><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">: Se os Evangelhos apresentam Jesus Cristo retirando-se para a ora\u00e7\u00e3o, para a contempla\u00e7\u00e3o no ermo, no deserto, nas montanhas, na solid\u00e3o, Francisco queria fazer o mesmo. Em sua vida constatamos longos retiros, at\u00e9 quatro retiros de quarenta dias no mesmo ano. Ele se retirava geralmente paras as montanhas junto aos vales e l\u00e1 nas montanhas, como os \u201cCarceri\u201d no Vale de Espoleto, Greccio, Fonte Colombo, La Foresta e Poggio Bustone, no Vale de Rieti, e o monte Alverne no Vale Caselino, entre outras, ele se refugiava nas grutas ou nas cavernas. Para ele, toda esta topografia tinha um significado. Basta pensar no sentido simb\u00f3lico dos vales, das montanhas e das grutas ou cavernas. Para Francisco, o vale simboliza a sociedade, o mundo, o s\u00e9culo; a montanha, os ideais, o lugar de Deus, o pr\u00f3prio Deus; a gruta ou caverna, o encontro consigo mesmo. De fato, o homem s\u00f3 se encontra consigo mesmo na montanha, onde se entra na caverna. Encontra-se consigo mesmo somente em Deus. \u00c9 significativo que a moradia mais permanente de Francisco e de seus companheiros tenha sido Nossa Senhora dos Anjos da Porci\u00fancula, situada na plan\u00edcie de Assis. Francisco, com seus irm\u00e3os, era chamado a realizar o apostolado do testemunho fraterno, de reconcilia\u00e7\u00e3o e de paz, a ser o irm\u00e3o universal, irm\u00e3o de todo irm\u00e3o, irm\u00e3o de toda irm\u00e3. Mas, da\u00ed ele se retirava sempre de novo para as montanhas, onde se recolhia nas cavernas em intensa ora\u00e7\u00e3o.<\/span><\/p>\n<p style=\"line-height: 14.7pt; background: whitesmoke; margin: 11.25pt 0cm 11.25pt 0cm;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Assim tamb\u00e9m o crist\u00e3o em geral, embora viva na plan\u00edcie, entre os homens, sempre de novo ter\u00e1 que retirar-se para o seu quarto, onde se dedicar\u00e1 \u00e0 ora\u00e7\u00e3o, a fim de que possa iluminar o mundo e ser sal da terra e fermento na massa. Na escola franciscana de espiritualidade, o Retiro tem algo de erem\u00edtico. Apela fortemente para o indiv\u00edduo, mesmo quando feito em grupo. Praticamente \u00e9 destitu\u00eddo de m\u00e9todo.<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><b><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Elementos do retiro espiritual:<span class=\"apple-converted-space\">\u00a0<\/span><\/span><\/b><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Existem alguns elementos que s\u00e3o pr\u00f3prios das v\u00e1rias formas de Retiro ou de Exerc\u00edcios espirituais. Eles se distinguem de cursos, de encontros, de estudos em grupos. Sua finalidade n\u00e3o \u00e9, em primeiro lugar, a de adquirir mais conhecimentos para saber mais, mas amar mais intensamente a Deus como filhos e filhas, ao pr\u00f3ximo como irm\u00e3os e irm\u00e3s, e ao mundo como senhores e senhoras da cria\u00e7\u00e3o. Trata-se de deixar-se libertar de todas as amarras para, na liberdade dos filhos de Deus, viver sempre mais intensamente o amor a Deus e ao pr\u00f3ximo, em a\u00e7\u00e3o de gra\u00e7as, abra\u00e7ando toda a realidade criada.<\/span><\/p>\n<p style=\"line-height: 14.7pt; background: whitesmoke; margin: 11.25pt 0cm 11.25pt 0cm;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Os Retiros e os Exerc\u00edcios espirituais caracterizam-se pelo ermo, pela solid\u00e3o, pelo sair do ambiente do cotidiano da vida. Trata-se de deixar as agita\u00e7\u00f5es do dia-a-dia, os ru\u00eddos que entram atrav\u00e9s de todos os sentidos e acabam ocupando nossa mente e nosso cora\u00e7\u00e3o. Procura-se fazer o jejum das palavras para dar lugar \u00e0 Palavra, o Verbo de Deus, Jesus Cristo. Diria que o recolhimento e o sil\u00eancio s\u00e3o condi\u00e7\u00f5es indispens\u00e1veis para um retiro frutuoso.<\/span><\/p>\n<p style=\"line-height: 14.7pt; background: whitesmoke; margin: 11.25pt 0cm 11.25pt 0cm;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Neste ambiente de sil\u00eancio e de recolhimento podem-se realizar os exerc\u00edcios pr\u00f3prios do Retiro ou dos Exerc\u00edcios espirituais. Ser\u00e3o de grande utilidade as confer\u00eancias, sobretudo, quando o Retiro \u00e9 realizado em grupo. Tais confer\u00eancias s\u00e3o, antes de tudo, medita\u00e7\u00f5es que querem levar \u00e0 contempla\u00e7\u00e3o dos mist\u00e9rios de Deus, de Jesus Cristo, da Igreja; contemplar\u00e3o a voca\u00e7\u00e3o e a miss\u00e3o do ser humano neste mundo, sua origem e seu destino, o mist\u00e9rio do mal, o pecado. Ajudam a provocar o confronto com Deus, com o pr\u00f3ximo, consigo mesmo e com todo o criado, donde brotar\u00e1 uma resposta de reconcilia\u00e7\u00e3o, de a\u00e7\u00e3o de gra\u00e7as, de amor. Este confronto poder\u00e1 ser provocado tamb\u00e9m pela leitura de trechos da Sagrada Escritura ou de outros livros apropriados.<\/span><\/p>\n<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 14.7pt; background: whitesmoke;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Sobretudo nos Retiros individuais, este confronto pode ser suscitado pela contempla\u00e7\u00e3o da natureza, pela reflex\u00e3o, pela medita\u00e7\u00e3o. Trata-se de dar uma resposta concreta \u00e0quela pergunta que fazia S\u00e3o Francisco: <i>\u201cSenhor, quem sois v\u00f3s e quem sou eu? V\u00f3s o alt\u00edssimo Senhor do c\u00e9u e da terra, e eu, um miser\u00e1vel vermezinho, vosso \u00ednfimo servo\u201d.<\/i><\/span><\/p>\n<p style=\"line-height: 14.7pt; background: whitesmoke; margin: 11.25pt 0cm 11.25pt 0cm;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">O retiro \u00e9 um tempo de cultivo intenso de Deus pela medita\u00e7\u00e3o, pela ora\u00e7\u00e3o e a contempla\u00e7\u00e3o. Ser\u00e1 uma experi\u00eancia de reconcilia\u00e7\u00e3o com Deus, com o pr\u00f3ximo, consigo mesmo e com toda a natureza criada.<\/span><\/p>\n<p style=\"line-height: 14.7pt; background: whitesmoke; margin: 11.25pt 0cm 11.25pt 0cm;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">A din\u00e2mica interna do retiro parece ser sempre: a escuta de Deus, a medita\u00e7\u00e3o que leva ao confronto; a medita\u00e7\u00e3o que leva \u00e0 resposta orante; a medita\u00e7\u00e3o que leva \u00e0 contempla\u00e7\u00e3o. Surgir\u00e3o, assim, como consequ\u00eancia, os prop\u00f3sitos de convers\u00e3o, de resposta ao Deus de bondade e de miseric\u00f3rdia.<\/span><\/p>\n<p style=\"line-height: 14.7pt; background: whitesmoke; margin: 11.25pt 0cm 11.25pt 0cm;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Ouvi algu\u00e9m dizer: \u201c\u00c9 importante que n\u00f3s religiosos reservemos para o cultivo expresso, intenso e exclusivo de nossa vida espiritual uma semana por ano, um dia por m\u00eas e uma hora por dia. Claro que estamos diante de um ideal. Os religiosos, as religiosas e os sacerdotes assumem este compromisso como fazendo parte de sua forma de vida. Oxal\u00e1 tamb\u00e9m os fi\u00e9is leigos consigam realizar algo desse ideal. Seu retiro anual em geral se restringir\u00e1 a um fim de semana. E a hora por dia? Ser\u00e1 uma breve medita\u00e7\u00e3o, seguida de um momento de ora\u00e7\u00e3o. Lembro que em muitas de nossas casas de fam\u00edlia havia um orat\u00f3rio. Nem sempre ser\u00e1 poss\u00edvel recolher-se. Mas, quem sabe, pela manh\u00e3, ou \u00e0 noite, a pessoa poder\u00e1 reservar-se uns 10 minutos, se n\u00e3o 15 ou meia hora, para a medita\u00e7\u00e3o a partir da leitura da Palavra de Deus do dia ou de outro subs\u00eddio v\u00e1lido.<\/span><\/p>\n<p style=\"line-height: 14.7pt; background: whitesmoke; margin: 11.25pt 0cm 11.25pt 0cm;\"><span style=\"font-size: 10.5pt; font-family: 'Arial','sans-serif'; color: #333333;\">Tudo parte do amor! Quem ama faz um esfor\u00e7o especial para estar com o amado. Importa dar uma resposta de amor ao Amor que nos amou primeiro.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Frei Alberto Beckh\u00e4user, OFM<\/p>\n","protected":false},"author":1,"featured_media":184892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Retiro espiritual: o que \u00e9? - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retiro espiritual: o que \u00e9? - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Frei Alberto Beckh\u00e4user, OFM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-20T11:31:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-03T12:56:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2015\/03\/eremo_g.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/\",\"name\":\"Retiro espiritual: o que \u00e9? - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2015-03-20T11:31:18+00:00\",\"dateModified\":\"2020-06-03T12:56:47+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retiro espiritual: o que \u00e9?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retiro espiritual: o que \u00e9? - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/","og_locale":"pt_BR","og_type":"article","og_title":"Retiro espiritual: o que \u00e9? - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Frei Alberto Beckh\u00e4user, OFM","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2015-03-20T11:31:18+00:00","article_modified_time":"2020-06-03T12:56:47+00:00","og_image":[{"width":800,"height":599,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2015\/03\/eremo_g.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/","name":"Retiro espiritual: o que \u00e9? - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2015-03-20T11:31:18+00:00","dateModified":"2020-06-03T12:56:47+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/retiro-espiritual-o-que-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"Retiro espiritual: o que \u00e9?"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/81766"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=81766"}],"version-history":[{"count":3,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/81766\/revisions"}],"predecessor-version":[{"id":185235,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/81766\/revisions\/185235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/184892"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=81766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=81766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=81766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}