{"id":25270,"date":"2010-09-28T09:56:33","date_gmt":"2010-09-28T12:56:33","guid":{"rendered":"http:\/\/new.franciscanos.org.br\/?p=25270"},"modified":"2020-05-26T08:38:20","modified_gmt":"2020-05-26T11:38:20","slug":"o-bem-da-paz","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/","title":{"rendered":"O bem da paz"},"content":{"rendered":"<p><strong><img decoding=\"async\" loading=\"lazy\" class=\"alignright size-full wp-image-25271\" title=\"3549_290912\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2012\/09\/3549_290912.jpg\" alt=\"\" width=\"300\" height=\"300\" \/>Frei Vit\u00f3rio Mazzuco Filho<\/strong><\/p>\n<p>A cidade de Assis, na regi\u00e3o italiana da \u00dambria, \u00e9 terra de S\u00e3o Francisco e um lugar s\u00edmbolo da sonhada fraternidade universal. Entre os anos 1181-82, Mestre Rufino, Bispo de Assis, escreveu um tratado chamado &#8220;De Bono Pacis&#8221;. E um dos mais antigos textos escritos sobre o tema da paz. Sintetizo aqui algumas id\u00e9ias de &#8220;O Bem da Paz&#8221; para refletirmos como este texto medieval reveste-se de uma imensa atualidade.<\/p>\n<p>O que \u00e9 a Paz? \u00c9 a quietude de uma coisa natural, a serenidade existencial, a tranquilidade e conc\u00f3rdia entre seres diferentes, um comportamento novo para o Amor.<\/p>\n<p>A Paz \u00e9 um grande encontro entre a vontade do Divino e a obedi\u00eancia Humana; um acordo perfeito entre esp\u00edrito, sentidos, intelig\u00eancia e vontade.<\/p>\n<p>O que \u00e9 o Bem? \u00c9 acender a capacidade de amar com boas obras. \u00c9 acreditar que, para satisfazer as necessidades fundamentais da vida, \u00e9 necess\u00e1rio a coopera\u00e7\u00e3o de todos; por isso a solidariedade e o m\u00fatuo socorro geram seguran\u00e7a e diminuem os conflitos. Se a vida \u00e9 sempre depend\u00eancia formal e expl\u00edcita de algo ou algu\u00e9m, \u00e9 natural que se estabele\u00e7am relacionamentos de conviv\u00eancia e troca rec\u00edproca.<\/p>\n<p>O tratado lembra que &#8220;\u00e9 preciso trocar m\u00e1rmore por madeira, metal com cereal, perfume com produtos da terra. O soldado depende do agricultor, o agricultor lhe d\u00e1 o alimento, o superior protege o s\u00fadito e o s\u00fadito lhe d\u00e1 em troca o servi\u00e7o&#8221;. Administrar bem uma troca de bens e de dons conserva a Paz.<\/p>\n<p>O Bem \u00e9 a certeza de que a harmonia se restabelece na pr\u00e1tica do Amor, isto \u00e9, na caridade e n\u00e3o no \u00f3dio e na intelig\u00eancia. Paz \u00e9 dar e receber, \u00e9 conviver bem com tudo o que existe. Diz o tratado de Mestre Rufino: &#8220;Como \u00e9 belo o piso desta casa, ou seja, a superf\u00edcie da terra, revestida de flores brancas, purp\u00fareas, douradas, amarelas e de mil outras cores! Como \u00e9 bel\u00edssima a cobertura, isto \u00e9, a ab\u00f3bada celeste, resplendente dos coros de estrelas como um teto adornado de pedras preciosas! Quantos dep\u00f3sitos de alimentos e bebidas existem nas \u00e1rvores e fontes desta casa! Quantas perfumarias de odorosas ess\u00eancias tiradas das mesmas flores e das ervas! Nesta casa, como l\u00e2mpada para a noite, existe o esplendor da lua e durante o dia temos o calor do sol em lugar do aparelho para aquecer, isto \u00e9, a caldeira, que no inverno costuma lan\u00e7ar vapor por meio de ofegantes chamas. Nesta casa, em lugar de camas, estendem-se leitos de ervas e, em vez da obedi\u00eancia das escravas, os elementos oferecem um servi\u00e7o espont\u00e2neo&#8221;. N\u00e3o seria esta a Paz e o Bem que sonhamos e que o mundo hoje tem sede?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Frei Vitorio Mazzuco<\/p>\n","protected":false},"author":1,"featured_media":184704,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[203],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O bem da paz - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O bem da paz - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Frei Vitorio Mazzuco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-28T12:56:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-26T11:38:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2010\/09\/3549_290912.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/\",\"name\":\"O bem da paz - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2010-09-28T12:56:33+00:00\",\"dateModified\":\"2020-05-26T11:38:20+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O bem da paz\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O bem da paz - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/","og_locale":"pt_BR","og_type":"article","og_title":"O bem da paz - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Frei Vitorio Mazzuco","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2010-09-28T12:56:33+00:00","article_modified_time":"2020-05-26T11:38:20+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2010\/09\/3549_290912.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/","name":"O bem da paz - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2010-09-28T12:56:33+00:00","dateModified":"2020-05-26T11:38:20+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/o-bem-da-paz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"O bem da paz"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/25270"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=25270"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/25270\/revisions"}],"predecessor-version":[{"id":181017,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/25270\/revisions\/181017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/184704"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=25270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=25270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=25270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}