{"id":23852,"date":"2007-09-10T12:24:52","date_gmt":"2007-09-10T15:24:52","guid":{"rendered":"http:\/\/new.franciscanos.org.br\/?p=23852"},"modified":"2020-05-26T08:40:39","modified_gmt":"2020-05-26T11:40:39","slug":"quando-a-eucaristia-se-torna-vida","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/","title":{"rendered":"Quando a Eucaristia se torna Vida!"},"content":{"rendered":"<p><strong><img decoding=\"async\" loading=\"lazy\" class=\"alignright size-full wp-image-23853\" title=\"3277_120912\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2012\/09\/3277_120912.jpg\" alt=\"\" width=\"400\" height=\"576\" \/>Frei Sinivaldo S. Tavares, OFM<\/strong><\/p>\n<p>Observando algumas atitudes que t\u00eam caracterizado a rela\u00e7\u00e3o das nossas comunidades de f\u00e9 com a Eucaristia, entre perplexos e desapontados, constatamos o retorno de atitudes esclerosadas, filhas de um passado que acredit\u00e1vamos enfim superado: a insist\u00eancia em conceber a participa\u00e7\u00e3o do ministro ordenado na celebra\u00e7\u00e3o da Eucaristia em termos de um poder aut\u00f4nomo e auto-suficiente, meio m\u00e1gico at\u00e9, de consagrar o p\u00e3o e o vinho; a tend\u00eancia a considerar as palavras da consagra\u00e7\u00e3o em si mesmas e, portanto, desvinculadas de seu natural contexto: a ora\u00e7\u00e3o eucar\u00edstica e, por extens\u00e3o, a inteira celebra\u00e7\u00e3o eucar\u00edstica; a presen\u00e7a real entendida, numa perspectiva objetivista (coisificada), como presen\u00e7a f\u00edsica, som\u00e1tica; a import\u00e2ncia exagerada que se tem dado \u00e0 adora\u00e7\u00e3o em detrimento da celebra\u00e7\u00e3o eucar\u00edstica. Nestes casos, ao se julgar conferir grande import\u00e2ncia \u00e0 Eucaristia, acaba-se ofuscando seu sentido mais origin\u00e1rio.<\/p>\n<p>Apesar de n\u00e3o ter elaborado um tratado sistem\u00e1tico e exaustivo acerca do Sacramento do Corpo e do Sangue do Senhor, Francisco revela possuir uma concep\u00e7\u00e3o deveras rica e integral deste mist\u00e9rio crist\u00e3o. Sua peculiaridade, de resto, reside propriamente no ter abra\u00e7ado com tamanha intensidade o evangelho e os mist\u00e9rios de Jesus Cristo de modo a sorv\u00ea-los at\u00e9 sua \u00faltima gota. Talvez seja esta a raz\u00e3o pela qual, Francisco atinja o \u00e2mago de tais mist\u00e9rios com uma invej\u00e1vel profundidade e evid\u00eancia. N\u00e3o deixa de suscitar admira\u00e7\u00e3o o fato que Francisco, no tocante ao Sacramento do Corpo e do Sangue do Senhor, tenha alcan\u00e7ado experiment\u00e1-lo na sua mais genu\u00edna radicalidade, n\u00e3o obstante toda aquela situa\u00e7\u00e3o de degrado que caracterizava tanto a devo\u00e7\u00e3o quanto as querelas teol\u00f3gicas de seu tempo.<\/p>\n<p>Para evitar abusos e especula\u00e7\u00f5es ligados \u00e0 pr\u00e1tica da simonia atrav\u00e9s da multiplica\u00e7\u00e3o indevida de Missas, como era costume em muitos mosteiros e par\u00f3quias de ent\u00e3o, e para dar maior visibilidade e efic\u00e1cia sacramental \u00e0 comunh\u00e3o eucar\u00edstica, Francisco recomenda insistentemente que os frades, em suas fraternidades, concelebrem a eucaristia. Na Carta enviada a toda a Ordem, ele escreve: \u201cPor isso, admoesto e exorto no Senhor a que, nos lugares onde moram os irm\u00e3os, seja celebrada apenas uma missa por dia, segundo a forma da santa Igreja. Se, por\u00e9m, houver muitos sacerdotes no lugar, por amor da caridade, contente-se um em ouvir a celebra\u00e7\u00e3o do outro sacerdote; porque o Senhor Jesus Cristo sacia os presentes e ausentes que s\u00e3o dignos dele. Ele, embora pare\u00e7a estar em muitos lugares, permanece, contudo, indivis\u00edvel e n\u00e3o conhece qualquer tipo de detrimento, mas, em todo lugar, como lhe agrada, opera em unidade com o Senhor Deus Pai e com o Esp\u00edrito Santo Par\u00e1clito pelos s\u00e9culos dos s\u00e9culos. Am\u00e9m (cf. Ap 1,6)\u201d (Ord 30-33).<\/p>\n<p>Embora n\u00e3o concordasse plenamente com as reivindica\u00e7\u00f5es dos movimentos her\u00e9ticos da \u00e9poca, Francisco parece ter aprendido algo com os C\u00e1taros. \u00c9 o que ele deixa transparecer ao assumir como pr\u00f3pria uma de suas principais reivindica\u00e7\u00f5es: que os sacerdotes celebrem de maneira digna o sacramento do Corpo e do Sangue do Senhor. Na Carta enviada a toda a Ordem, ele escreve: \u201cRogo tamb\u00e9m no Senhor a todos os meus irm\u00e3os sacerdotes \u2013 os que s\u00e3o, os que ser\u00e3o e os que desejam ser sacerdotes do Alt\u00edssimo \u2013 que, todas as vezes que quiserem celebrar a missa, puros e de maneira pura, ofere\u00e7am com rever\u00eancia o verdadeiro sacrif\u00edcio do sant\u00edssimo corpo e sangue de Nosso Senhor Jesus Cristo com santa e pura inten\u00e7\u00e3o, n\u00e3o em vista de alguma coisa terrena nem por temor ou amor a qualquer pessoa, como que agradando aos homens (cf. Ef 6,6; Cl 3,22). Mas toda a vossa vontade \u2013 \u00e0 medida que a gra\u00e7a [vos] ajudar \u2013 esteja dirigida a Deus, desejando assim agradar unicamente ao mesmo Senhor alt\u00edssimo, porque a\u00ed s\u00f3 ele opera como lhe apraz; pois \u2013 como ele mesmo diz: Fazei isto em mem\u00f3ria de mim (Lc 22,19); 1Cor 11,24) \u2013, se algu\u00e9m o fizer de modo diferente, torna-se Judas traidor e r\u00e9u do corpo e do sangue do Senhor (cf. 1Cor 11,27). [&#8230;] Considerai a vossa dignidade, irm\u00e3os (cf. 1Cor 1,26) sacerdotes, e sede santos, porque ele \u00e9 santo (cf. Lv 19,2). E assim como o Senhor Deus vos honrou acima de todos por causa deste minist\u00e9rio, de igual modo tamb\u00e9m v\u00f3s amai-o, reverenciai-o e honrai-o acima de todos. Grande mis\u00e9ria e fraqueza digna de comisera\u00e7\u00e3o, quando o tendes assim presente e vos preocupeis com qualquer outra coisa em todo o mundo\u201d (Ord 14-16. 23-25).<\/p>\n<p>Ao manifestar sua particular devo\u00e7\u00e3o ao sacramento do Corpo e do Sangue do Senhor, Francisco n\u00e3o reduz este sacramento \u00fanica e exclusivamente ao momento da consagra\u00e7\u00e3o. Nem se deixa sucumbir face \u00e0s tend\u00eancias em voga naquele tempo de valorizar mais a \u201ccomunh\u00e3o ocular\u201d do que propriamente a \u201ccomunh\u00e3o sacramental\u201d, salientando sobremaneira o rito da eleva\u00e7\u00e3o da h\u00f3stia e do c\u00e1lice com vinho, ap\u00f3s a consagra\u00e7\u00e3o. Naqueles idos, valorizava-se tanto a contempla\u00e7\u00e3o das esp\u00e9cies consagradas em detrimento da comunh\u00e3o propriamente dita que o Conc\u00edlio Lateranense IV chegou a prescrever que todo crist\u00e3o deveria comungar ao menos uma vez no ano, por ocasi\u00e3o da festa da P\u00e1scoa da Ressurrei\u00e7\u00e3o. Francisco, ao contr\u00e1rio, insiste na manduca\u00e7\u00e3o do Corpo e do Sangue do Senhor como express\u00e3o de sua aut\u00eantica recep\u00e7\u00e3o e da plena participa\u00e7\u00e3o do sacramento do Altar.<\/p>\n<p>A \u00edntima rela\u00e7\u00e3o entre comunh\u00e3o no Corpo e no Sangue de Jesus Cristo a produ\u00e7\u00e3o de dignos frutos de penit\u00eancia constitui nota caracter\u00edstica da concep\u00e7\u00e3o e devo\u00e7\u00e3o eucar\u00edsticas de Francisco. Neste sentido, ele n\u00e3o perde uma ocasi\u00e3o sequer para trazer-nos \u00e0 mem\u00f3ria a estreita rela\u00e7\u00e3o entre a participa\u00e7\u00e3o ao sacramento do Altar e a convers\u00e3o evang\u00e9lica. E o fundamento \u00faltimo desta preocupa\u00e7\u00e3o \u00e9 a estreita rela\u00e7\u00e3o entre Sacramento e Palavra t\u00e3o salientada pelo poverello de Assis. Na Carta enviada a toda a Ordem, ele afirma: \u201cE, porque quem prov\u00e9m de Deus ouve as palavras de Deus (cf. Jo 8,47), devemos n\u00f3s, por conseguinte, que mais especialmente fomos encarregados dos of\u00edcios divinos, n\u00e3o s\u00f3 ouvir e fazer o que o Senhor diz, mas tamb\u00e9m, para compenetrar-nos da grandeza do nosso Criador e da nossa submiss\u00e3o a ele, guardar os vasos e demais objetos do of\u00edcio, os quais cont\u00eam suas santas palavras. Por isso, admoesto e conforto todos os meus irm\u00e3os em Cristo a que, onde encontrarem as palavras divinas escritas, da maneira como puderem, as venerem e, no que lhes compete, se elas n\u00e3o estiverem bem colocadas ou se em algum lugar estiverem dispersas sem a devida honra, recolham-nas e guardem-nas, honrando o Senhor nas palavras que ele falou (1Rs 2,4). Pois muitas coisas s\u00e3o santificadas pelas palavras de Deus (cf. 1Tm 4,5), e \u00e9 em virtude das palavras de Cristo que se realiza o sacramento do altar\u201d (Ord 34-37).<\/p>\n<p>A efic\u00e1cia das palavras de Cristo \u00e9 recuperada mediante a peculiar virtude do Esp\u00edrito Santo. Por esta raz\u00e3o \u00e9 que o encontro com Cristo, que se d\u00e1 mediante a busca sincera de seguir seus passos, s\u00f3 \u00e9 poss\u00edvel na medida em que nos deixamos conduzir por este mesmo Esp\u00edrito que foi derramado em nossos cora\u00e7\u00f5es e que habita no seio da comunidade de f\u00e9 e no cora\u00e7\u00e3o da hist\u00f3ria e do cosmos. Neste sentido, a participa\u00e7\u00e3o plena no sacramento do Corpo e do Sangue do Senhor s\u00f3 se d\u00e1 naquele horizonte maior propiciado e mantido pelo Esp\u00edrito do Senhor. Este horizonte maior \u00e9 caracterizado pela singular experi\u00eancia de contemporaneidade entre Cristo e n\u00f3s. Esta contemporaneidade \u00e9 que cria uma situa\u00e7\u00e3o de peculiar empatia entre n\u00f3s e Cristo, experi\u00eancia esta que se encontra na raiz de toda e qualquer aut\u00eantica experi\u00eancia de encontro e de comunh\u00e3o. Francisco se mostra particularmente sens\u00edvel a esta leg\u00edtima e intr\u00ednseca dimens\u00e3o pneumatol\u00f3gica da eucaristia.<br \/>\nNada melhor, para conclus\u00e3o destas fragment\u00e1rias reflex\u00f5es, do que deixar o pr\u00f3prio Francisco falar. Qui\u00e7\u00e1 nos deixemos contagiar pela profundidade de suas palavras que revelam a singularidade de sua experi\u00eancia. Aqui fala o m\u00edstico que, como ningu\u00e9m, experimenta a estreiteza e o limite das palavras quando se trata de exprimir experi\u00eancias profundas. Da\u00ed a abund\u00e2ncia dos superlativos e o cont\u00ednuo jogo de palavras que caracterizam sobremaneira a linguagem e o estilo do poverello de Assis:<\/p>\n<p>\u201cPasme o homem todo, estreme\u00e7a o mundo inteiro, e exulte o c\u00e9u, quando sobre o altar, nas m\u00e3os do sacerdote, est\u00e1 o Cristo, o Filho de Deus vivo (Jo 11, 27)! \u00d3 admir\u00e1vel grandeza e estupenda dignidade! \u00d3 sublime humildade! \u00d3 humilde sublimidade: o Senhor do universo, Deus e Filho de Deus, tanto se humilha a ponto de esconder-se, pela nossa salva\u00e7\u00e3o, sob a m\u00f3dica forma de p\u00e3o! Vede, irm\u00e3os, a humildade de Deus e derramai diante dele os vossos cora\u00e7\u00f5es (Sl 61,9); humilhai-vos tamb\u00e9m v\u00f3s, para serdes exaltados (cf. 1Pd 5,6; Tg 4,10) por ele. Portanto, nada de v\u00f3s retenhais para v\u00f3s, a fim de que totalmente vos receba aquele que totalmente se vos oferece\u201d (Ord 26-29).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Frei Sinivaldo S. Tavares<\/p>\n","protected":false},"author":1,"featured_media":184706,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[49],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quando a Eucaristia se torna Vida! - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quando a Eucaristia se torna Vida! - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Frei Sinivaldo S. Tavares\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2007-09-10T15:24:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-26T11:40:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2007\/09\/3277_120912.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/\",\"name\":\"Quando a Eucaristia se torna Vida! - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2007-09-10T15:24:52+00:00\",\"dateModified\":\"2020-05-26T11:40:39+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quando a Eucaristia se torna Vida!\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quando a Eucaristia se torna Vida! - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/","og_locale":"pt_BR","og_type":"article","og_title":"Quando a Eucaristia se torna Vida! - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Frei Sinivaldo S. Tavares","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2007-09-10T15:24:52+00:00","article_modified_time":"2020-05-26T11:40:39+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2007\/09\/3277_120912.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/","name":"Quando a Eucaristia se torna Vida! - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2007-09-10T15:24:52+00:00","dateModified":"2020-05-26T11:40:39+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/quando-a-eucaristia-se-torna-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"Quando a Eucaristia se torna Vida!"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/23852"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=23852"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/23852\/revisions"}],"predecessor-version":[{"id":180952,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/23852\/revisions\/180952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/184706"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=23852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=23852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=23852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}