{"id":196033,"date":"2025-06-18T14:53:40","date_gmt":"2025-06-18T17:53:40","guid":{"rendered":"https:\/\/franciscanos.org.br\/vidacrista\/?p=196033"},"modified":"2025-06-18T14:53:40","modified_gmt":"2025-06-18T17:53:40","slug":"irma-lua-e-as-estrelas","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/","title":{"rendered":"Irm\u00e3 Lua e as Estrelas"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-196035 size-full\" src=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2025\/06\/materia.png\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2025\/06\/materia.png 1280w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2025\/06\/materia-450x253.png 450w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2025\/06\/materia-1024x576.png 1024w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2025\/06\/materia-768x432.png 768w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2025\/06\/materia-150x84.png 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p style=\"text-align: center;\">\u201cLouvado sejas, meu Senhor,<\/p>\n<p style=\"text-align: center;\">pela irm\u00e3 lua e pelas estrelas, no c\u00e9u<\/p>\n<p style=\"text-align: center;\">\u00a0as formaste claras e preciosas e belas\u201d<\/p>\n<p>Com essa estrofe do C\u00e2ntico das Criaturas somos convidados a refletir sobre virtudes e valores fundamentais sob tr\u00eas aspectos: transpar\u00eancia nas rela\u00e7\u00f5es, autoestima e o reconhecimento da dignidade do outro.<\/p>\n<p>O tema proposto \u00e9 inspirador, mas apresenta um desafio consider\u00e1vel para um redator inexperiente. Antecipadamente, \u00e9 bom dizer que o leitor precisa soltar a imagina\u00e7\u00e3o para ir al\u00e9m dos rudimentos que abaixo seguem.<\/p>\n<h3><strong>A motiva\u00e7\u00e3o de S\u00e3o Francisco<\/strong><\/h3>\n<p>Para compreender a profunda motiva\u00e7\u00e3o de S\u00e3o Francisco ao louvar o Criador por meio de suas criaturas, \u00e9 interessante considerar as qualidades que ele atribui \u00e0 irm\u00e3 Lua e \u00e0s Estrelas, descrevendo-as como \u201cclaras, preciosas e belas\u201d. As qualidades v\u00eam de uma quest\u00e3o anterior que precisa ser compreendida. \u00c9 preciso voltar um pouco atr\u00e1s, meio ao estilo do que disse certa vez um antigo professor de filosofia: \u201cPara fazer um salto de dist\u00e2ncia, o atleta n\u00e3o vai logo para frente, mas para tr\u00e1s, a fim de fazer uma corrida e pegar impulso\u201d. Voltar a outros textos de S\u00e3o Francisco, anteriores ao C\u00e2ntico das Criaturas, ajuda-nos a compreender as motiva\u00e7\u00f5es dele ao compor o C\u00e2ntico.\u00a0 Uma das qualidades motivacionais que levaram S\u00e3o Francisco a prorromper num c\u00e2ntico de louvor das criaturas pode ser encontrada na Carta enviada a toda a Ordem: \u201cOnipotente, eterno, justo e misericordioso Deus, dai-nos a n\u00f3s, m\u00edseros, por causa de v\u00f3s fazer o que sabemos que quereis e sempre querer o que vos agrada, para que, interiormente purificados, interiormente iluminados e abrasados pelo fogo do Esp\u00edrito Santo, possamos seguir os passos de vosso dileto Filho, Nosso Senhor Jesus Cristo\u201d (Ord 50-51). Essa percep\u00e7\u00e3o iluminada e abrasada pelo Esp\u00edrito Santo pode ser entendida como um reflexo de sua experi\u00eancia de Deus, na qual e, a partir da qual, ele percebe reflexos do Criador na beleza das criaturas.<\/p>\n<h3><strong>Transpar\u00eancia nas rela\u00e7\u00f5es<\/strong><\/h3>\n<p>\u201c(&#8230;) seu guardi\u00e3o, que tamb\u00e9m era seu companheiro, adquirindo uma pele de raposa e levando-a at\u00e9 ele, disse: \u2018Pai, padeces a enfermidade do ba\u00e7o e do est\u00f4mago. Suplico a tua caridade no Senhor que debaixo da t\u00fanica permitas que seja costurada esta pele. Se n\u00e3o a queres toda, pelo menos permite que se aplique sobre o est\u00f4mago\u2019. Respondeu-lhe o bem-aventurado Francisco: \u2018Se queres que eu permita isso sob minha t\u00fanica, manda que me seja aplicado exteriormente um remendo da mesma medida, o qual, costurado por fora, indique aos homens a pele escondida interiormente\u2019\u201d (2Cel 130).<\/p>\n<p>Uma das virtudes de Francisco que brotam da experi\u00eancia da grandeza e bondade do Criador \u00e9 a transpar\u00eancia nas rela\u00e7\u00f5es com os irm\u00e3os. Transpar\u00eancia no sentido de fidelidade \u00e0 verdade fundamentada nos valores do Evangelho. Mas, a verdade revestida de caridade, porque ele \u00e9 cort\u00eas e reverencial. Vejamos o que ele diz numa de suas admoesta\u00e7\u00f5es: \u201cBem-aventurado o servo que tanto ama e respeita seu irm\u00e3o quando [este] estiver longe dele como quando estiver com ele; e n\u00e3o disser por tr\u00e1s dele aquilo que, com caridade, n\u00e3o pode dizer diante dele\u201d (Ad 25). Essa transpar\u00eancia \u00e9 respeitosa e quando diz alguma coisa \u00e9 com caridade, porque vem de uma rela\u00e7\u00e3o que deve ser amorosa. As criaturas t\u00eam tra\u00e7os do Criador e por isso Francisco \u00e9 reverencial na rela\u00e7\u00e3o com elas. Depois que ele fez a sua experi\u00eancia de Deus como \u201cSumo Bem\u201d (LD) se tornou uma nova criatura e isso qualificou o seu relacionamento com os irm\u00e3os e com todas as criaturas.<\/p>\n<p>Na Regra Bulada ele institui, como norma, os mais finos modos de relacionamento, instruindo os irm\u00e3os a serem af\u00e1veis entre si, a manifestarem confiantemente as suas necessidades e a cultivarem um amor diligente maior que o de uma m\u00e3e:<\/p>\n<p>\u201cE onde quer que estiverem e se encontrarem os irm\u00e3os, mostrem-se af\u00e1veis entre si. E, com confian\u00e7a, manifeste um ao outro as suas necessidades, porque,\u00a0 se uma m\u00e3e ama e nutre seu filho carnal (cf. 1Ts 2,7), com quanto maior dilig\u00eancia n\u00e3o deve cada um amar e nutrir a seu irm\u00e3o espiritual?\u201d (RB 6,7-9). Este amor e dedica\u00e7\u00e3o, at\u00e9 maior que o de uma m\u00e3e, vem do fato de ser um irm\u00e3o espiritual, ou seja, um irm\u00e3o que est\u00e1 na dimens\u00e3o do esp\u00edrito do Senhor (Ad 12). Caso o irm\u00e3o n\u00e3o esteja nesta dimens\u00e3o, Francisco tamb\u00e9m \u00e9 transparente em manifestar o que pensa, e convoca o irm\u00e3o \u00e0 convers\u00e3o. Isso transparece na Carta enviada a toda a Ordem: \u201cAqueles irm\u00e3os, por\u00e9m, que n\u00e3o quiserem observar estas coisas (a Regra e os ensinamentos da Carta a toda a Ordem), n\u00e3o os tenho como cat\u00f3licos nem como meus irm\u00e3os; tamb\u00e9m n\u00e3o quero v\u00ea-los ou falar-lhes, enquanto n\u00e3o fizerem penit\u00eancia\u201d (Ord 44). Cabe ao irm\u00e3o, ou irm\u00e3os, fazer penit\u00eancia \u2013 entrar no processo de mudan\u00e7a de vida que o leva a ser um irm\u00e3o espiritual (RB 6,9). Na Carta aos Fi\u00e9is, Francisco esclarece sobre a quest\u00e3o de fazer penit\u00eancia, dizendo que \u201ctodos os que amam o Senhor de todo o cora\u00e7\u00e3o (&#8230;) (Mc 12,30) e amam seu pr\u00f3ximo como a si mesmos (cf. Mt 22,39), e odeiam seus corpos com os v\u00edcios e pecados, recebem o corpo e o sangue de Nosso Senhor Jesus Cristo, e produzem dignos frutos de penit\u00eancia: Qu\u00e3o bem aventurados e benditos s\u00e3o aqueles e aquelas ao fazerem tais coisas e nelas perseverarem, porque pousar\u00e1\u00a0sobre eles o Esp\u00edrito do Senhor (cf. Is 11,2) e far\u00e1 neles habita\u00e7\u00e3o e um lugar de repouso (cf. Jo 14,23)\u201d (cf. 1Fi 1-2). Para Francisco a rela\u00e7\u00e3o dos irm\u00e3os \u00e9 uma rela\u00e7\u00e3o que eleva a dignidade da pessoa, porque a coloca em rela\u00e7\u00e3o com o esp\u00edrito do Senhor \u201cque \u00e9 beleza, mansid\u00e3o, seguran\u00e7a, quietude, regozijo, esperan\u00e7a, alegria, justi\u00e7a, temperan\u00e7a e toda nossa riqueza at\u00e9 a saciedade\u201d (cf. LD).<\/p>\n<p>No cuidado dos irm\u00e3os que erram, ele tamb\u00e9m indica mais um modo de proceder: \u201cE cuidem todos os irm\u00e3os, tanto os ministros e servos como os demais, para n\u00e3o se perturbarem ou se irritarem por causa do pecado ou do mal do outro, porque o dem\u00f4nio quer, por causa do pecado de um s\u00f3, corromper a muitos; mas ajudem espiritualmente, como melhor puderem, aquele que pecou, porque n\u00e3o s\u00e3o os sadios que precisam de m\u00e9dico, mas os enfermos (cf. Mt 9,12; Mc 2,17)\u201d (RnB 5,7-8). Percebe-se que a inten\u00e7\u00e3o dele \u00e9 sempre a de recuperar o irm\u00e3o com esp\u00edrito de caridade.<\/p>\n<h3><strong>Autoestima<\/strong><\/h3>\n<p>\u201cMuito eloquente, tinha o rosto alegre e o aspecto bondoso\u201d (1Cel 83).<\/p>\n<p>Alegre e eloquente, Francisco vibra com as maravilhas do Senhor manifestadas nas suas criaturas. O C\u00e2ntico das Criaturas revela a sua conex\u00e3o amorosa e relacional com todo o universo, porque \u00e9 procedente das m\u00e3os d\u2019Aquele que \u00e9 o \u201cSumo Bem\u201d (LD). Ele mesmo \u00e9 parte desse universo e est\u00e1 embevecido do amor do Criador. Se a autoestima \u00e9 a percep\u00e7\u00e3o e avalia\u00e7\u00e3o que uma pessoa tem de si mesma, e tem a ver com o valor da pr\u00f3pria vida, algo que at\u00e9 o Evangelho faz alus\u00e3o quando fala de amar ao pr\u00f3ximo como a si mesmo (cf. Mt 22,39), ent\u00e3o, Francisco \u00e9 um exemplo de autoestima saud\u00e1vel, porque ele n\u00e3o busca a valida\u00e7\u00e3o da pr\u00f3pria vida em padr\u00f5es externos ou compara\u00e7\u00f5es, mas no reconhecimento da interconex\u00e3o com o mundo, no qual ele de rosto alegre e eloquente louva o Criador. Da\u00ed a sua recomenda\u00e7\u00e3o: \u201cE cuidem [os irm\u00e3os] para n\u00e3o se mostrar exteriormente tristes e sombriamente hip\u00f3critas; mas mostrem-se alegres no Senhor, sorridentes e convenientemente simp\u00e1ticos\u201d (RnB 7,16). Tom\u00e1s de Celano diz que ele \u201cviu uma vez um companheiro seu que apresentava um rosto desanimado e triste e, sentindo-se incomodado, disse-lhe: \u2018N\u00e3o conv\u00e9m que o servo de Deus (cf. Dn 6,20) se mostre triste e carrancudo (cf. Is 42,4) aos homens, mas se mostre sempre gracioso. Dissipa tuas ofensas em teu quarto (cf. Ecl 10,20), chora e geme diante de teu Deus (cf. Gn 6,8). Quando voltas para junto dos irm\u00e3os, tendo deposto a tristeza, conforma-te aos outros\u2019\u201d(2Cel 128).<\/p>\n<p>Francisco exulta em Deus de forma experiencial. Isso ele deixa transparecer nas express\u00f5es que usa no Bilhete a Frei Le\u00e3o: \u201cV\u00f3s sois amor, caridade; v\u00f3s sois sabedoria, v\u00f3s sois humildade, v\u00f3s sois paci\u00eancia (Sl 70,5), v\u00f3s sois beleza, v\u00f3s sois mansid\u00e3o, v\u00f3s sois seguran\u00e7a, v\u00f3s sois quietude, v\u00f3s sois regozijo, v\u00f3s sois nossa esperan\u00e7a e alegria, v\u00f3s sois justi\u00e7a, v\u00f3s sois temperan\u00e7a, v\u00f3s sois toda nossa riqueza at\u00e9 a saciedade\u201d (LD). Essas grandezas de Deus plenificam a sua vida at\u00e9 o fim de sua de sua trajet\u00f3ria terrestre, quando ele, \u00e0 semelhan\u00e7a do velho Sime\u00e3o, que n\u00e3o teme morrer (cf. Lc 2, 29), diz: \u201cLouvado sejas, meu Senhor, por nossa irm\u00e3, a morte corporal\u201d (Cnt 12). Ele tem confian\u00e7a de que vai descansar em paz em comunh\u00e3o com Aquele que \u00e9 o \u201cSumo Bem\u201d(LD).<\/p>\n<p>Clara, que se denomina de \u201cplantinha do bem-aventurado pai Francisco\u201d (RSC 1,3), tamb\u00e9m tem uma express\u00e3o m\u00e1xima de autoestima, quando diz no \u00faltimo instante de sua vida: \u201cBendito sejais V\u00f3s, Senhor, que me criastes!\u201d (LSC 46,5).<\/p>\n<p>Francisco e Clara s\u00e3o pessoas que souberam louvar e agradecer a Deus pelo dom da vida. Souberam, tamb\u00e9m, viver e transmitir uma cordial experi\u00eancia de amor aos irm\u00e3os e a todas as criaturas. O exemplo de vida deles nos leva a pensar que o carisma franciscano deveria ser uma li\u00e7\u00e3o de vida para as pessoas carentes de uma saud\u00e1vel autoestima no mundo de hoje.<\/p>\n<h3><strong>Reconhecimento da dignidade do outro\u00a0 \u2013\u00a0 Contempla\u00e7\u00e3o do Criador nas criaturas<\/strong><\/h3>\n<p>\u201cReconhece nas coisas belas aquele que \u00e9 o mais Belo; todas as coisas boas (cf. Gn 1,31) lhe clamam: \u2018Quem nos fez (cf. Sl 99, 3) \u00e9 o Melhor\u2019\u201d (2Cel 165).<\/p>\n<p>Como passar da contempla\u00e7\u00e3o da beleza e bondade do Criador \u00e0 percep\u00e7\u00e3o de que as criaturas t\u00eam tra\u00e7os dessa beleza e bondade, e consequentemente, t\u00eam a sua dignidade?<\/p>\n<p>Alguns dos escritos de Francisco nos ajudam a perceber que ele reconhecia a dignidade do outro por uma motiva\u00e7\u00e3o muito profunda. Veja-se, por exemplo, o que ele diz, na Regra Bulada, a respeito do relacionamento dos irm\u00e3os entre si: \u201c(&#8230;) se uma M\u00e3e ama e nutre seu filho carnal (cf. 1Ts 2,7), com quanto maior dilig\u00eancia n\u00e3o deve cada um amar e nutrir a seu irm\u00e3o espiritual? (RB 6,9). Para Francisco a compreens\u00e3o do irm\u00e3o espiritual \u00e9 a dignidade mais elevada de uma criatura, porque ela \u00e9 participante da filia\u00e7\u00e3o divina, do Deus que \u00e9 esp\u00edrito e s\u00f3 em esp\u00edrito pode ser visto (cf. Ad 1,4-6).\u00a0 Surge, assim, uma postura reverencial. A partir dessa compreens\u00e3o o irm\u00e3o espiritual, deve ser tratado com maior dilig\u00eancia. Essa \u201cdilig\u00eancia\u201d, entendida como: interesse, cuidado ou dedica\u00e7\u00e3o pelo irm\u00e3o, vem expressa em alguns de seus escritos:<\/p>\n<p>\u201cOnde quer que se encontrem os irm\u00e3os, mostrem-se familiares entre si\u201d (RB 6,8);<\/p>\n<p>\u201cE, se algum deles cair doente, os outros irm\u00e3os o devem servir, como gostariam de ser servidos\u201d(cf. Mt 7,12)(RB 6,10);<\/p>\n<p>(Aos irm\u00e3os que pecam) \u201cOs ministros, com miseric\u00f3rdia lhes imponham a penit\u00eancia\u201d (RB 7,3);<\/p>\n<p>\u201cE cuidem todos os irm\u00e3os, tanto os ministros e servos como os demais, para n\u00e3o se perturbarem por causa do pecado ou do mal do outro, porque o dem\u00f4nio quer, por causa do pecado e um s\u00f3, corromper a muitos; mas ajudem espiritualmente, como melhor puderem, aquele que pecou, porque n\u00e3o s\u00e3o os sadios que precisam de m\u00e9dico, mas os enfermos (cf. Mt 9,12; Mc 2,17)\u201d (RnB 5,7-8);<\/p>\n<p>\u201cNenhum irm\u00e3o fa\u00e7a mal a outro ou diga mal dele; muito pelo contr\u00e1rio, atrav\u00e9s da caridade do esp\u00edrito, sirvam e obede\u00e7am uns aos outros (Gl 5,13) de boa vontade\u201d (RnB 5,13).<\/p>\n<p>\u00c9 importante observar que Francisco, na sua atitude reverencial, v\u00ea com um olhar de grandeza todas as criaturas sens\u00edveis e insens\u00edveis (2Cel 165); desde a \u00e1rvore que serve para\u00a0 lenha, a vegeta\u00e7\u00e3o da horta, a pedra, o verde das ervas, a beleza das flores, at\u00e9 os vermezinhos (cf. 2Cel 165). A todos e a tudo ele acolhia e tratava bem. Tom\u00e1s de Celano diz que a bondade fontal (Deus) era a origem\u00a0 a partir da qual ele via a grandeza e a dignidade de todas as coisas: \u201cNa verdade, toda aquela bondade fontal, que h\u00e1 de ser tudo em todos (cf. 1Cor 12,6), j\u00e1 se manifestava a este santo como tudo em todos (cf. 1Cor 12,6)\u201d (2Cel 165).<\/p>\n<p>Francisco nos ajuda a perceber que no lado secreto ou manifesto de todas as criaturas e, por excel\u00eancia, do ser humano, h\u00e1 uma gota de virtude ou dignidade que pode manifestar-se, nem que seja como aquela do ladr\u00e3o no \u00faltimo momento de sua vida (cf. Lc 23,42).<\/p>\n<hr \/>\n<p><em>Frei Valdir Laurentino<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frei Valdir Laurentino<\/p>\n","protected":false},"author":10,"featured_media":196034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[407,410],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Irm\u00e3 Lua e as Estrelas - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Irm\u00e3 Lua e as Estrelas - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Frei Valdir Laurentino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-18T17:53:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2025\/06\/chamada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Adriana Rabelo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adriana Rabelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/\",\"name\":\"Irm\u00e3 Lua e as Estrelas - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2025-06-18T17:53:40+00:00\",\"dateModified\":\"2025-06-18T17:53:40+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/a0cbb2edfc0aecf8ac498802d1cb57b5\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Irm\u00e3 Lua e as Estrelas\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/a0cbb2edfc0aecf8ac498802d1cb57b5\",\"name\":\"Adriana Rabelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0a937b7500cd7df77540cfb8bede877d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0a937b7500cd7df77540cfb8bede877d?s=96&d=mm&r=g\",\"caption\":\"Adriana Rabelo\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/adrianarabelo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Irm\u00e3 Lua e as Estrelas - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/","og_locale":"pt_BR","og_type":"article","og_title":"Irm\u00e3 Lua e as Estrelas - Vida Crist\u00e3 - Franciscanos","og_description":"Frei Valdir Laurentino","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2025-06-18T17:53:40+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2025\/06\/chamada.png","type":"image\/png"}],"author":"Adriana Rabelo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Adriana Rabelo","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/","name":"Irm\u00e3 Lua e as Estrelas - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2025-06-18T17:53:40+00:00","dateModified":"2025-06-18T17:53:40+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/a0cbb2edfc0aecf8ac498802d1cb57b5"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/irma-lua-e-as-estrelas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"Irm\u00e3 Lua e as Estrelas"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/a0cbb2edfc0aecf8ac498802d1cb57b5","name":"Adriana Rabelo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0a937b7500cd7df77540cfb8bede877d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a937b7500cd7df77540cfb8bede877d?s=96&d=mm&r=g","caption":"Adriana Rabelo"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/adrianarabelo\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/196033"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=196033"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/196033\/revisions"}],"predecessor-version":[{"id":196036,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/196033\/revisions\/196036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/196034"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=196033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=196033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=196033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}