{"id":193673,"date":"2023-08-02T15:36:30","date_gmt":"2023-08-02T18:36:30","guid":{"rendered":"https:\/\/franciscanos.org.br\/vidacrista\/?p=193673"},"modified":"2023-08-02T15:36:30","modified_gmt":"2023-08-02T18:36:30","slug":"a-partir-da-pequena-porcao-chamada-porciuncula","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/","title":{"rendered":"A partir da pequena por\u00e7\u00e3o chamada Porci\u00fancula"},"content":{"rendered":"<h3><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-193674 size-full\" src=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2023\/08\/PORCIUNCULA_02.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2023\/08\/PORCIUNCULA_02.jpg 1280w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2023\/08\/PORCIUNCULA_02-450x253.jpg 450w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2023\/08\/PORCIUNCULA_02-1024x576.jpg 1024w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2023\/08\/PORCIUNCULA_02-768x432.jpg 768w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2023\/08\/PORCIUNCULA_02-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/h3>\n<h3>A partir da pequena por\u00e7\u00e3o &#8211;\u00a0GENEROSIDADE<\/h3>\n<p><em>\u00a0<\/em><em>\u201cQueridos irm\u00e3os e filhinhos meus, vejo que o Senhor quer nos multiplicar; por isso acho coisa boa e religiosa adquirir do bispo ou dos c\u00f4negos de S\u00e3o Rufino, ou do abade do mosteiro de S\u00e3o Bento, alguma igreja pequena e pobrezinha onde os frades possam dizer suas Horas, e ter, junto dela, s\u00f3 alguma casa pequena e pobrezinha, constru\u00edda de barro e ramos, onde os frades possam descansar e cuidar de trabalhos conforme as suas necessidades. (&#8230;) O abade ficou com pena, fez uma reuni\u00e3o sobre o assunto com seus irm\u00e3os e, como foi da vontade de Deus, concederam ao bem-aventurado Francisco e aos seus frades a igreja de Santa Maria da Porci\u00fancula, a mais pobre que tinham. Tamb\u00e9m era a mais pobrezinha do que qualquer outra que havia nos arredores de Assis; o que fazia tempo que o bem-aventurado Francisco desejava. (&#8230;) O bem-aventurado Francisco ficou muito contente com o lugar concedido aos irm\u00e3os e principalmente porque a igreja tinha o nome da M\u00e3e de Cristo, era uma igreja t\u00e3o pobrezinha, e tamb\u00e9m pelo apelido que tinha, Porci\u00fancula (&#8230;) E embora o abade e os monges tivessem concedido livremente ao bem-aventurado Francisco e a seus frades aquela igreja sem nenhuma exig\u00eancia ou pagamento anual, todavia o bem-aventurado Francisco, como um bom e experimentado mestre que quis edificar sua casa sobre a pedra firme, isto \u00e9, a sua congrega\u00e7\u00e3o sobre a grande pobreza, mandava todos os anos ele mesmo um cestinho cheio de peixinhos chamados lascas como sinal da maior humildade e pobreza\u201d<\/em> (cf. Compila\u00e7\u00e3o de Assis 56).<\/p>\n<p>As Fontes Franciscanas conservaram a mem\u00f3ria agradecida da primitiva Fraternidade Franciscana que, anualmente, levava um cesto de peixes aos monges beneditinos como forma de retribuir sua generosidade, cuidado e confian\u00e7a traduzidas na cess\u00e3o de um local para que os frades pudessem, como diz a legenda, \u201cdescansar e cuidar dos trabalhos\u201d. A oferta do cesto de peixes foi revivida no \u00faltimo dia 11 de julho, Festa Lit\u00fargica da Mem\u00f3ria de S\u00e3o Bento, na cidade do Rio de Janeiro. Irm\u00e3os da fraternidade do Convento Santo Ant\u00f4nio se dirigiram ao Mosteiro de S\u00e3o Bento, o terceiro a ser constru\u00eddo no Brasil pela fam\u00edlia beneditina no ano de 1592, depois de Salvador (1582) e de Olinda (1586).<\/p>\n<p>Os frades foram acolhidos com fraterna amizade e l\u00e1 ouviram do Abade a promessa de que no pr\u00f3ximo dia de S\u00e3o Francisco (04\/10) ser\u00e1 a vez dos monges retribu\u00edrem a visita e levarem, como o estabelecido costume, um pouco de azeite para a Fraternidade do Largo da Carioca. O mesmo movimento se d\u00e1 a partir da Fraternidade do Convento S\u00e3o Francisco, na cidade de S\u00e3o Paulo. Na fren\u00e9tica capital dos paulistas, os frades deixam o Convento do Largo S\u00e3o Francisco e descem at\u00e9 o Mosteiro de S\u00e3o Bento e repetem o gesto da entrega dos peixes, sinal de reconhecimento e gratid\u00e3o.<\/p>\n<p>A recorda\u00e7\u00e3o deste singelo compromisso, proporciona o reencontro com um dos momentos mais significativos da hist\u00f3ria do Movimento Franciscano. Antes de se reportar ao Abade beneditino, Francisco havia pedido aux\u00edlio ao Bispo e aos C\u00f4negos de S\u00e3o Rufino; ambos n\u00e3o atenderam ao pleito do <em>Poverello<\/em>. O Abade, por sua vez, compadeceu-se e fez um pedido a Francisco: \u201cIrm\u00e3os, n\u00f3s atendemos o que pediste; mas queremos que, se vossa congrega\u00e7\u00e3o se multiplicar, este lugar seja a cabe\u00e7a de todos v\u00f3s\u201d. O Movimento Franciscano se robusteceu e a Porci\u00fancula passou a ser o lugar de refer\u00eancia para todos os que buscam fazer da sua vida a tradu\u00e7\u00e3o eloquente do Evangelho de Nosso Senhor, conforme a inspira\u00e7\u00e3o de S\u00e3o Francisco de Assis.<\/p>\n<h3>A partir da pequena por\u00e7\u00e3o &#8211; FECUNDIDADE<\/h3>\n<p>Al\u00e9m de acolher os primeiros irm\u00e3os, nessa mesma porci\u00fancula, Clara, depois daquele Domingo de Ramos, foi acolhida pelos frades e, ao ter seus cabelos cortados, iniciou seu vigoroso itiner\u00e1rio de consagra\u00e7\u00e3o e aderiu ao modo de vida evang\u00e9lica ali iniciado. Tamb\u00e9m se diz que os primeiros leigos a seguirem a voca\u00e7\u00e3o franciscana secular, o casal Luqu\u00e9sio e sua esposa Buonadona, partiram da Porci\u00fancula para anunciar a todos a Paz e o Bem. Por isso, deste lugar se diz \u201c\u00e9 o fecundo ber\u00e7o da Ordem Franciscana\u201d.<\/p>\n<p>Ser o nascedouro do Movimento Franciscano j\u00e1 faria da celebrada igreja um lugar de destaque. Mas a hist\u00f3ria reservou a ela muito mais. Antes de ser casa dos franciscanos, j\u00e1 era casa da M\u00e3e de Deus, a Senhora dos Anjos.\u00a0 Ningu\u00e9m sabe ao certo como a igreja foi constru\u00edda. Diz-se que foi erguida por peregrinos que voltavam da Terra Santa e haviam trazido de l\u00e1 algumas pedras da casa de Nossa Senhora, e tais pedras teriam sido usadas na constru\u00e7\u00e3o. Outros tantos afirmam que, nalguns momentos, anjos podiam ser vistos por ali; eles vinham do c\u00e9u e se juntavam aos louvores e preces que a partir daquele lugar sagrado clamavam a intercess\u00e3o de Nossa Senhora.<\/p>\n<p>Os anjos s\u00e3o a comunica\u00e7\u00e3o do pr\u00f3prio Deus. Os anjos, em coros, tamb\u00e9m indicam os mais elevados louvores \u00e0 divindade. Foi um anjo que ouviu o sim de Maria, quando ela recebeu o convite para ser a M\u00e3e do Salvador.\u00a0 Foram os anjos que, com alegria e festa, acolheram Maria no c\u00e9u de corpo e alma, depois de tanta fidelidade vivida aqui na terra. A m\u00e3e pobre, do Cristo pobre sempre teve a companhia dos anjos. O jeito do c\u00e9u e seus anjos cuidarem da vida da M\u00e3e do Salvador evidencia a predile\u00e7\u00e3o de Deus pelos pequeninos e por aqueles que, com liberdade, fazem a sua vontade. A postura obediente de Maria, a Virgem do Sim, e a pobreza por ela experimentada, encantavam a S\u00e3o Francisco. Por isso, o santo de Assis, que n\u00e3o queria ter nesta terra propriedade qualquer, n\u00e3o se aborreceu por sua Fraternidade ter feito morada na casa de Santa Maria dos Anjos. A legenda registrou seu contentamento: \u201cO bem-aventurado Francisco ficou muito contente com o lugar concedido aos irm\u00e3os e principalmente porque a igreja tinha o nome da M\u00e3e de Cristo, era uma igreja t\u00e3o pobrezinha, e tamb\u00e9m pelo apelido que tinha\u201d. Ainda mais, afirmava \u201co Senhor a\u00ed mostrou e lhe foi revelado nesse lugar, que a Bem-aventurada Virgem ama esta igreja mais do que todas as outras igrejas desde mundo que ela ama\u201d (cf. CA 56).<\/p>\n<p>Por ter em conta que Santa Maria dos Anjos era \u201cforma e exemplo de toda a religi\u00e3o\u201d, Francisco dizia que os irm\u00e3os nunca deveriam abandonar a Porci\u00fancula e, se um dia, fossem expulsos pela porta, deveriam retornar pelas janelas. Ordenar aos frades para n\u00e3o arredarem o p\u00e9 de Santa Maria dos Anjos \u00e9 afirmar que para n\u00e3o esquecer onde se quer chegar, \u00e9 mister ter sempre presente o ponto de partida. N\u00e3o abandonar Santa Maria \u00e9 ter, constantemente, diante dos olhos o exemplo de pobreza e fidelidade da M\u00e3e do Senhor, e confiar na sua materna intercess\u00e3o. Estar na Porci\u00fancula \u00e9 regar com dilig\u00eancia a flor que desabrochou no cora\u00e7\u00e3o dos que desejam viver o Evangelho de Nosso Senhor.<\/p>\n<p>Santa Maria dos Anjos \u00e9 lugar original. Santa Maria dos Anjos \u00e9 fonte revigorante. Por isso, num momento de ora\u00e7\u00e3o nesta igrejinha, S\u00e3o Francisco de Assis foi inspirado a pedir que Santa Maria dos Anjos fosse tamb\u00e9m lugar do perd\u00e3o: ent\u00e3o ele disse \u201cpe\u00e7o que a todos quantos arrependidos e confessados, venham visitar esta igreja, lhes seja concedido amplo e generoso perd\u00e3o, com uma completa remiss\u00e3o de todas as culpas\u201d. O perd\u00e3o reconstitui os la\u00e7os que nos unem a Deus. O perd\u00e3o tem o dom de nos devolver a integridade original. O perd\u00e3o tem o cond\u00e3o de esvaziar nosso cora\u00e7\u00e3o da inveja, da gan\u00e2ncia, da intoler\u00e2ncia, da viol\u00eancia, do des\u00e2nimo, do medo, da mentira e da morte. O perd\u00e3o \u00e9 dom que revigora em n\u00f3s a capacidade de recome\u00e7ar sempre de novo.<\/p>\n<h3>A partir da pequena por\u00e7\u00e3o &#8211; RECOME\u00c7O<\/h3>\n<p>A integridade genu\u00edna, o esvaziamento e a capacidade de retomar a caminho n\u00e3o se constituem como faces daquela convoca\u00e7\u00e3o apresentada por Francisco em seu Testamento: \u201cComecemos, irm\u00e3os, pois at\u00e9 agora pouco ou nada fizemos\u201d? A vida da pobreza vivenciada e proposta pelo Movimento Franciscano \u00e9 a via do perd\u00e3o. Destarte, muito oportunamente, a celebra\u00e7\u00e3o da Porci\u00fancula, que fala das origens franciscanas, se associa \u00e0 celebra\u00e7\u00e3o do Perd\u00e3o de Assis. Ao pedir ao Santo Padre que a Porci\u00fancula pudesse ser lugar dispensador das mesmas indulg\u00eancias auferidas seja em Roma, seja na Terra Santa que, por dist\u00e2ncia e inseguran\u00e7a do caminho impediam os pobres de alcan\u00e7\u00e1-las, Francisco descortina novo horizonte de compreens\u00e3o e viv\u00eancia da rela\u00e7\u00e3o pobreza e perd\u00e3o.<\/p>\n<p>A escolha pela pobreza deveria luzir com intensidade em todos os \u00e2mbitos da vida da Fraternidade. A forma de vestir, o jeito de trabalhar, e at\u00e9 as habita\u00e7\u00f5es deveriam falar da escolha fundamental pelo seguimento do Cristo pobre. Por isso, ao se estabelecer em Santa Maria, o grupo dos frades p\u00f4de ver contemplado aquilo que desde sempre pretendeu: \u201cTamb\u00e9m era a mais pobrezinha do que qualquer outra que havia nos arredores de Assis; o que fazia tempo que o bem-aventurado Francisco desejava\u201d.<\/p>\n<p>A partir da Porci\u00fancula os irm\u00e3os foram tecendo relacionamentos que deram corpo \u00e0 sua forma de vida. A partir da igreja que tinha o nome da M\u00e3e de Cristo, aquela igreja t\u00e3o pobrezinha conhecida pelo apelido de Porci\u00fancula, a primitiva comunidade passou a constituir-se como Ordem, como os verdadeiros \u201cCavaleiros da Dama Pobreza\u201d, arautos do perd\u00e3o e da reconcilia\u00e7\u00e3o.<\/p>\n<h3>A partir da pequena por\u00e7\u00e3o &#8211; SEM NADA DE PR\u00d3PRIO<\/h3>\n<p>\u201cA Regra e vida dos Frades Menores \u00e9 esta, a saber: observar o santo Evangelho de nosso Senhor Jesus Cristo vivendo em obedi\u00eancia, sem nada de pr\u00f3prio e em castidade\u201d. A primeira frase da forma de vida proposta por S\u00e3o Francisco de Assis explicita o fundamento e a identidade da Ordem que nascia. Os conselhos evang\u00e9licos presentes em todas as demais fam\u00edlias religiosas j\u00e1 existentes ganha conota\u00e7\u00e3o original, especialmente o voto de pobreza apresentado por Francisco como o modo de viver \u201csem nada de pr\u00f3prio\u201d. Assim, a autenticidade da vida consagrada a partir do matiz franciscano sup\u00f5e radicalidade evang\u00e9lica, escuta atenta da vontade de Deus, pureza de cora\u00e7\u00e3o e uma vida \u201csem nada de pr\u00f3prio\u201d.<\/p>\n<p>O empreendimento para conseguir desposar a Pobreza, ideal experimentado pela Fraternidade primitiva, envolveu os irm\u00e3os num redobrado esfor\u00e7o por alcan\u00e7ar o cume da montanha onde se encontrava encarcerada a dama de grad\u00edssima beleza.\u00a0 O conto cavaleiresco relatado pelo \u201c<em>Sacrum Commercium<\/em>\u201d oferece a dimens\u00e3o da import\u00e2ncia da pobreza na vida franciscana. A orienta\u00e7\u00e3o para que os irm\u00e3os escolhessem estar entre os menores do seu tempo e sentissem satisfa\u00e7\u00e3o por esta aproxima\u00e7\u00e3o tamb\u00e9m atesta a maneira de olhar a pobreza como medida da realiza\u00e7\u00e3o do projeto da fraternidade: \u201cE devem alegrar-se quando convivem com pessoas vis e desprezadas, com pobres e fracos e doentes e leprosos e os que mendigam \u00e0 beira da estrada\u201d (RnB 9,2). Diversos textos das Fontes Franciscanas atestam que Francisco se envergonhava quando encontrava algu\u00e9m mais pobre do que ele: \u201cA mis\u00e9ria desse homem \u00e9 uma grande vergonha para n\u00f3s, e repreende muito a nossa pobreza. O companheiro respondeu: Por que, irm\u00e3o? E o santo, com voz de lamento: Escolhi a pobreza como minha senhora e toda minha riqueza, e ela est\u00e1 brilhando muito mais nesse homem. Ou n\u00e3o sabes que por todo o mundo correu nossa fama de pobres por amor de Cristo? Pois esse pobre est\u00e1 provando que isso n\u00e3o \u00e9 verdade\u201d (2Cel 84). O sentimento de vergonha, mesmo que inicialmente possa abater o \u00e2nimo, pode tamb\u00e9m servir como medida a ser alcan\u00e7ada por todos os que almejam a perfei\u00e7\u00e3o evang\u00e9lica; perfei\u00e7\u00e3o alcan\u00e7ada quanto mais dedica\u00e7\u00e3o houver por amor a Cristo.<\/p>\n<p>Embora tenha nutrido infinito amor por ela e a tenha buscado com todas as suas for\u00e7as, S\u00e3o Francisco de Assis n\u00e3o inventou o conceito de pobreza. Ali\u00e1s, tal conceito est\u00e1 enraizado nas origens do Cristianismo e pode ser considerado um dos principais elementos que identificam e sustentam a vida consagrada. A austeridade e r\u00edgida disciplina, marcas da heran\u00e7a deixada pelo eremitismo dalguns Pais e M\u00e3es da Igreja, apontam para a escolha da pobreza como um sinal da op\u00e7\u00e3o pelo Reino. Na mesma esteira, a vida cenob\u00edtica que, diferentemente da escolha pela solid\u00e3o do ermo \u00e9 experimentada em comunidade, exigia o esfor\u00e7o de todos os membros para garantir a sobriedade no modo de vida e a fidelidade \u00e0 pobreza. Tanto o eremitismo, como o cenobitismo, que marcaram a expans\u00e3o do Cristianismo florescente nos primeiros s\u00e9culos, passaram por graves crises e, entre idas e vindas, foram revisitados na Idade M\u00e9dia, especialmente pelos movimentos pauper\u00edsticos que imprimiam um caminho de retorno ao Evangelho.<\/p>\n<p>O dinamismo de retomada da radicalidade evang\u00e9lica foi experimentado por Francisco e a comunidade franciscana primitiva. A resist\u00eancia a tais movimentos com flagrante teor reformador e que eram, inclusive, acusados de flertar com heresias, ganhou corpo na Igreja. Diante disso, a aprova\u00e7\u00e3o da Regra Franciscana (1223), bem como a confirma\u00e7\u00e3o do privil\u00e9gio da pobreza conferido \u00e0s Damas Pobres (1228), toma um vulto de import\u00e2ncia destacada para o florescimento do Movimento Franciscano. Inapel\u00e1vel virtude para Francisco e seus irm\u00e3os, o tema da Pobreza gerou muitas controv\u00e9rsias. Para manter viva a intui\u00e7\u00e3o do Movimento Franciscano de testemunhar o Evangelho atrav\u00e9s de uma aut\u00eantica vida de pobreza \u00e9 necess\u00e1rio um renovado e criativo empenho para deixar transparecer, cada vez com maior nitidez, que a disposi\u00e7\u00e3o para uma \u201cvida sem nada de pr\u00f3prio\u201d, uma vida a partir da fraternidade e da minoridade, s\u00e3o os sinais mais l\u00facidos da identidade franciscana.<\/p>\n<h3>A partir da pequena por\u00e7\u00e3o &#8211; TESTEMUNHO E MISS\u00c3O<\/h3>\n<p>\u00c0 pobreza como ideal de vida para os irm\u00e3os e irm\u00e3s de S\u00e3o Francisco de Assis, se contrap\u00f5e o empobrecimento que desumaniza e ofende de morte o planeta Terra, nossa Irm\u00e3 e M\u00e3e. Milh\u00f5es de pessoas no mundo inteiro s\u00e3o empurradas, involuntariamente, para abaixo da linha que define as condi\u00e7\u00f5es m\u00ednimas necess\u00e1rias para a vida conservar dignidade. Diante desta tormentosa realidade, o Papa Francisco, em uma missa para encerrar o 27\u00ba Congresso Eucar\u00edstico Nacional da It\u00e1lia (Setembro 2022), alertou: \u201cAs injusti\u00e7as, as disparidades, os recursos da terra distribu\u00eddos de forma desigual, os abusos dos poderosos contra os fracos, a indiferen\u00e7a ao clamor dos pobres, o abismo que cavamos todos os dias, gerando marginaliza\u00e7\u00e3o, todas estas coisas n\u00e3o nos podem deixar indiferentes\u201d. E complementou: \u201cDeus pede ent\u00e3o uma convers\u00e3o eficaz: da indiferen\u00e7a \u00e0 compaix\u00e3o, do desperd\u00edcio \u00e0 partilha, do ego\u00edsmo ao amor, do individualismo \u00e0 fraternidade\u201d.<\/p>\n<p>N\u00e3o \u00e9 preciso recorrer a planilhas e estat\u00edsticas oficiais para perceber o escandaloso crescimento do empobrecimento em diversos pa\u00edses, especialmente aqueles do \u201cSul Global\u201d. A opini\u00e3o p\u00fablica mundial e o senso comum j\u00e1 acostumados a assistir, anestesiados, ao ignominioso desfile de corpos fam\u00e9licos em campos de refugiados nos pa\u00edses africanos ou na \u00c1sia, ultimamente passaram a ser incomodados com o alarmante avan\u00e7o da pobreza em regi\u00f5es outrora pr\u00f3speras. Sistemas econ\u00f4micos transnacionais t\u00eam promovido grande concentra\u00e7\u00e3o de riquezas e explora\u00e7\u00e3o dos recursos naturais, \u00e0 custa da globaliza\u00e7\u00e3o do empobrecimento. A promo\u00e7\u00e3o de conflitos armados e o intencional desprezo por busca de apaziguamento t\u00eam servido para o fortalecimento de comportamentos privatistas e a manuten\u00e7\u00e3o de estruturas que legitimam a supremacia de povos e pa\u00edses, de grupos e organiza\u00e7\u00f5es.<\/p>\n<p>Nas an\u00e1lises dos relacionamentos sociais tem sido bastante recorrente a utiliza\u00e7\u00e3o do termo \u201cAporofobia\u201d; sua etimologia promove a jun\u00e7\u00e3o de termos gregos que remetem a duas palavras em portugu\u00eas: pobre e avers\u00e3o. O comportamento que este neologismo identifica cont\u00e9m uma agressividade sem par, afinal, ele n\u00e3o apenas se contrap\u00f5e ao sentimento de solidariedade e cuidado que poderia nascer no relacionamento com os pobres, mas \u00e9 sustentado pela rejei\u00e7\u00e3o que n\u00e3o permite perceber que a pessoa em situa\u00e7\u00e3o de pobreza n\u00e3o representa perigo, e tamb\u00e9m pelo sentimento de \u00f3dio que aponta para comportamentos violentos com vistas a eliminar aquele que, simplesmente por existir, se faz uma amea\u00e7a.<\/p>\n<p>A globaliza\u00e7\u00e3o do empobrecimento e a Aporofobia s\u00e3o apenas dois dos muitos sinais de que vivemos uma sociedade doente. A lucidez do pontificado inaugurado pela elei\u00e7\u00e3o do Papa Francisco reconstitui a relev\u00e2ncia do papel da Igreja Cat\u00f3lica nas discuss\u00f5es e na participa\u00e7\u00e3o de organismos que podem assumir a tarefa de encontrar, antes que seja tarde, medicina e cura para esta doen\u00e7a que dizima os povos e o planeta como um todo. Ao escolher o nome de Francisco, o papa trouxe \u00e0 baila a dimens\u00e3o e o poder revolucion\u00e1rio do Movimento Franciscano. O vigor transformador da experi\u00eancia de S\u00e3o Francisco de Assis e seus primeiros companheiros e companheiras permitiu o reflorescimento da Igreja. A evidente inspira\u00e7\u00e3o franciscana dos escritos papais, com destaque \u00e0s Enc\u00edclicas <em>Laudato si\u2019<\/em> (2015) e <em>Fratelli Tutti<\/em> (2020), emprestam a voz aos pobres e pessoas de boa vontade que ousam sonhar uma \u201cTerra sem Males\u201d.<\/p>\n<p>O tempo \u00e9 agora. A realidade imp\u00f5e aos irm\u00e3os e irm\u00e3s de S\u00e3o Francisco de Assis a corajosa decis\u00e3o de voltar a Santa Maria dos Anjos. O anseio por revisitar a hist\u00f3ria revigora os passos vindouros e, certamente, nos levar\u00e1 a perceber a import\u00e2ncia de voltar a ter em grande conta a preciosidade do tesouro escondido no campo, pelo qual vale a pena deixar tudo para adquirir aquele campo. O compromisso renovado com o Evangelho deixar\u00e1 mais iluminadas as escolhas das institui\u00e7\u00f5es que est\u00e3o postas para promover o carisma franciscano. O reencontro com a identidade original dar\u00e1 a todos a leveza e a coragem para que, desapegados de tudo, possamos galgar a montanha onde habita a Senhora Pobreza.<\/p>\n<hr \/>\n<p><strong>FREI PAULO ROBERTO PEREIRA, OFM<\/strong><\/p>\n<p><strong><em>MINISTRO PROVINCIAL<\/em><\/strong><br \/>\nProv\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Frei Paulo Roberto Pereira<\/p>\n","protected":false},"author":3,"featured_media":193674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[380],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A partir da pequena por\u00e7\u00e3o chamada Porci\u00fancula - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A partir da pequena por\u00e7\u00e3o chamada Porci\u00fancula - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Frei Paulo Roberto Pereira\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-02T18:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2023\/08\/PORCIUNCULA_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/\",\"name\":\"A partir da pequena por\u00e7\u00e3o chamada Porci\u00fancula - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2023-08-02T18:36:30+00:00\",\"dateModified\":\"2023-08-02T18:36:30+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A partir da pequena por\u00e7\u00e3o chamada Porci\u00fancula\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A partir da pequena por\u00e7\u00e3o chamada Porci\u00fancula - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/","og_locale":"pt_BR","og_type":"article","og_title":"A partir da pequena por\u00e7\u00e3o chamada Porci\u00fancula - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Frei Paulo Roberto Pereira","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2023-08-02T18:36:30+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2023\/08\/PORCIUNCULA_02.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/","name":"A partir da pequena por\u00e7\u00e3o chamada Porci\u00fancula - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2023-08-02T18:36:30+00:00","dateModified":"2023-08-02T18:36:30+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-partir-da-pequena-porcao-chamada-porciuncula\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"A partir da pequena por\u00e7\u00e3o chamada Porci\u00fancula"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/193673"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=193673"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/193673\/revisions"}],"predecessor-version":[{"id":193675,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/193673\/revisions\/193675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/193674"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=193673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=193673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=193673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}