{"id":189517,"date":"2021-05-17T00:51:15","date_gmt":"2021-05-17T03:51:15","guid":{"rendered":"https:\/\/franciscanos.org.br\/vidacrista\/?p=189517"},"modified":"2021-05-17T06:29:21","modified_gmt":"2021-05-17T09:29:21","slug":"cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/","title":{"rendered":"Cinco anos da exorta\u00e7\u00e3o Amoris Laetitia: Quantos caminhamos?"},"content":{"rendered":"<div style=\"width: 850px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2021\/05\/artigo-840.jpg\" alt=\"\" width=\"840\" height=\"450\" \/><p class=\"wp-caption-text\"><em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Imagem ilustrativa (fonte: Catholic Pictures)<\/em><\/p><\/div>\n<p><strong>Frei Oton J\u00fanior, ofm<\/strong><\/p>\n<p>A celebra\u00e7\u00e3o de cinco anos da Exorta\u00e7\u00e3o Apost\u00f3lica P\u00f3s-sinodal <em>Amoris Laetitia<\/em> deve servir para uma breve revis\u00e3o de sua recep\u00e7\u00e3o nas comunidades. Se o desenrolar do S\u00ednodo ocasionou debates acalorados, no arco do tempo percebemos certo arrefecimento das reflex\u00f5es da Exorta\u00e7\u00e3o Apost\u00f3lica.<\/p>\n<p>Para al\u00e9m de uma pastoral baseada na miseric\u00f3rdia, no discernimento, na valoriza\u00e7\u00e3o da consci\u00eancia dos fi\u00e9is e na integra\u00e7\u00e3o das fam\u00edlias, o texto de Francisco traz passagens de verdadeira beleza espiritual que podem iluminar muito o caminho de f\u00e9 de nossas fam\u00edlias e de nossa a\u00e7\u00e3o pastoral.<\/p>\n<p>A presente reflex\u00e3o busca refazer o caminho sinodal, desde sua convoca\u00e7\u00e3o at\u00e9 a publica\u00e7\u00e3o da Exorta\u00e7\u00e3o Apost\u00f3lica, finalizando com sua recep\u00e7\u00e3o; e convida a um aprofundamento das propostas de Francisco a respeito das fam\u00edlias.<\/p>\n<h3><strong>A fase preparat\u00f3ria<\/strong><\/h3>\n<p>No dia 19 de mar\u00e7o, dia de S\u00e3o Jos\u00e9, comemoramos cinco anos da publica\u00e7\u00e3o da Exorta\u00e7\u00e3o Apost\u00f3lica p\u00f3s-sinodal <em>Amoris Laetitia<\/em>, cujo s\u00ednodo teve como motiva\u00e7\u00e3o: \u201cA voca\u00e7\u00e3o e a miss\u00e3o da fam\u00edlia na Igreja e no mundo contempor\u00e2neo\u201d. A \u00faltima exorta\u00e7\u00e3o sobre a fam\u00edlia tinha sido <em>Familiaris Consortio<\/em>, publicada em 1981, no pontificado de Jo\u00e3o Paulo II. Tr\u00eas d\u00e9cadas depois, Francisco convidou a Igreja a refletir novamente sobre este tema, levando em conta as novas realidades familiares, bem como a maneira de a Igreja lidar com esses novos contextos.<\/p>\n<p>O Conc\u00edlio Vaticano II inaugurara propriamente uma teologia da fam\u00edlia, em sentido amplo, uma vez que as perspectivas anteriores se fixavam na rela\u00e7\u00e3o do casal. Com o S\u00ednodo convocado por Francisco, \u201cdecididamente j\u00e1 n\u00e3o nos encontramos em uma simples pastoral voltada para casais e para fam\u00edlias, mas em uma pastoral verdadeiramente familiar, que busca integrar justamente aquelas ovelhas que parecem estar fora do rebanho\u201d (MOSER, 2016, p. 303).<\/p>\n<p>A expectativa pelo S\u00ednodo foi enorme. Os debates foram acalorados e a cada dia algu\u00e9m levantava um aspecto novo a ser considerado. Ainda nas fases iniciais j\u00e1 se podia notar duas frentes bem distintas: os que desejavam que a Igreja revisse toda a sua pr\u00e1xis de acompanhamento das fam\u00edlias, e aqueles que temiam que, de agora em diante, todo o patrim\u00f4nio eclesial sobre as fam\u00edlias se desfigurasse com novas propostas. Francisco, no in\u00edcio da Exorta\u00e7\u00e3o, destaca essas tens\u00f5es, \u201cdesde o desejo desenfreado de mudar tudo sem suficiente reflex\u00e3o ou fundamenta\u00e7\u00e3o, at\u00e9 \u00e0 atitude que pretende resolver tudo atrav\u00e9s da aplica\u00e7\u00e3o de normas gerais ou deduzindo conclus\u00f5es excessivas de algumas reflex\u00f5es teol\u00f3gicas\u201d (<em>Amoris Laetitia<\/em>, n. 2)<\/p>\n<p>Francisco ent\u00e3o pontua: \u201cCompreendo aqueles que preferem uma pastoral mais r\u00edgida, que n\u00e3o d\u00ea lugar a confus\u00e3o alguma; mas creio sinceramente que Jesus Cristo quer uma Igreja atenta ao bem que o Esp\u00edrito derrama no meio da fragilidade: uma M\u00e3e que, ao mesmo tempo que expressa claramente a sua doutrina objetiva, n\u00e3o renuncia ao bem poss\u00edvel, ainda que corra o risco de sujar-se com a lama da estrada\u201d (AL, n. 308). Dessa forma, Francisco ressalta um aspecto moral n\u00e3o muito comum nos documentos do magist\u00e9rio: n\u00e3o se fixa no dado objetivo da normatividade, mas valoriza o bem poss\u00edvel a ser alcan\u00e7ado pelos fi\u00e9is.<\/p>\n<p>Dois temas se impregnaram nas discuss\u00f5es sinodais, a ponto de Francisco ter de alertar que se tratava de uma reflex\u00e3o ampla sobre a fam\u00edlia e n\u00e3o s\u00f3 sobre estas, a saber: a comunh\u00e3o de recasados e o casamento de pessoas homoafetivas. Sobre os primeiros, diz a nota de rodap\u00e9 351: \u201cEm certos casos, poderia haver tamb\u00e9m a ajuda dos sacramentos. Por isso, aos sacerdotes, lembro que o confession\u00e1rio n\u00e3o deve ser uma c\u00e2mara de tortura, mas o lugar da miseric\u00f3rdia do Senhor. E de igual modo assinalo que a Eucaristia n\u00e3o \u00e9 um pr\u00eamio para os perfeitos, mas um rem\u00e9dio generoso e um alimento para os fracos\u201d.<\/p>\n<p>Sobre as uni\u00f5es homoafetivas, <em>Amoris Laetitia<\/em> retoma a reflex\u00e3o dos padres sinodais, os quais \u201canotaram, quanto aos projetos de equipara\u00e7\u00e3o ao matrim\u00f4nio das uni\u00f5es entre pessoas homossexuais, que n\u00e3o existe fundamento algum para assimilar ou estabelecer analogias, nem sequer remotas, entre as uni\u00f5es homossexuais e o des\u00edgnio de Deus sobre o matrim\u00f3nio e a fam\u00edlia\u201d (AL, n. 251). No n\u00famero anterior, diz Francisco: \u201ccada pessoa, independentemente da pr\u00f3pria orienta\u00e7\u00e3o sexual, deve ser respeitada na sua dignidade e acolhida com respeito, procurando evitar qualquer sinal de discrimina\u00e7\u00e3o injusta\u00a0e particularmente toda a forma de agress\u00e3o e viol\u00eancia. \u00c0s fam\u00edlias, por sua vez, deve-se assegurar um respeitoso acompanhamento, para que quantos manifestam a tend\u00eancia homossexual possam dispor dos aux\u00edlios necess\u00e1rios para compreender e realizar plenamente a vontade de Deus na sua vida\u201d (AL, n. 250).<\/p>\n<p>O processo sinodal teve in\u00edcio com um question\u00e1rio enviado \u00e0s confer\u00eancias episcopais do mundo todo a fim de colher as primeiras indica\u00e7\u00f5es por onde as reflex\u00f5es deveriam passar. As 38 perguntas basicamente se preocupavam em saber at\u00e9 que ponto a doutrina da Igreja sobre a fam\u00edlia era conhecida e vivida no contexto familiar. Aqui, j\u00e1 \u00e9 poss\u00edvel identificar a primeira lacuna: quantas pessoas tiveram acesso a esse question\u00e1rio e quantos de n\u00f3s o respondeu?<\/p>\n<h3><strong>As reflex\u00f5es do S\u00ednodo<\/strong><\/h3>\n<p>O pontificado de Francisco vem buscando resgatar a sinodalidade na Igreja. De modo direto, podemos dizer: Francisco deseja uma \u201croda de conversa\u201d, dando voz a todas as pessoas envolvidas nas discuss\u00f5es. O contr\u00e1rio disso seria legislar \u201cde cima para baixo\u201d, desconsiderando as realidades. Ali\u00e1s, esse tamb\u00e9m foi o m\u00e9todo adotado pelo Conc\u00edlio Vaticano II, igualmente abra\u00e7ado pelas Confer\u00eancias do CELAM, no chamado m\u00e9todo indutivo (popularizado como ver, julgar e agir): parte-se primeiro da realidade concreta, a qual ser\u00e1 iluminada pela Palavra de Deus e os ensinamentos da Igreja para, enfim, retornar \u00e0 realidade, inspirando-a \u00e0 transforma\u00e7\u00e3o.<\/p>\n<p>Na <em>Evangelii Gaudium<\/em>, Francisco j\u00e1 apresentava seu ponto de vista a este respeito: \u201cN\u00e3o se deve esperar do magist\u00e9rio papal uma palavra definitiva ou completa sobre todas as quest\u00f5es que dizem respeito \u00e0 Igreja e ao mundo. N\u00e3o conv\u00e9m que o Papa substitua os episcopados locais no discernimento de todas as problem\u00e1ticas que sobressaem nos seus territ\u00f3rios. Neste sentido, sinto a necessidade de proceder a uma salutar \u2019descentraliza\u00e7\u00e3o\u2019\u201d(n.16).<\/p>\n<p>Baseando-se no postulado de Jo\u00e3o Cris\u00f3stomo, Francisco insiste que \u201c\u2018Igreja e S\u00ednodo s\u00e3o sin\u00f4nimos\u2019, pois, a Igreja nada mais \u00e9 do que este \u2018caminhar juntos\u2019 (&#8230;). Dentro dela ningu\u00e9m pode ser \u2018elevado\u2019 acima dos outros. Pelo contr\u00e1rio, na Igreja, \u00e9 necess\u00e1rio que algu\u00e9m se abaixe pondo-se a servi\u00e7o dos irm\u00e3os ao longo do caminho\u201d (FRANCISCO, 17.10.15). No pontificado de Francisco, podemos lembrar ainda do S\u00ednodo da Juventude (2018) &#8211; filho do S\u00ednodo da fam\u00edlia &#8211; e da Amaz\u00f4nia (2019) \u2013 filho da <em>Laudato Si<\/em>\u2019 &#8211; os quais tamb\u00e9m se propuseram a escutar acuradamente as realidades em quest\u00e3o.<\/p>\n<p>No caso do S\u00ednodo da Fam\u00edlia, temos de recordar que ele foi celebrado em duas assembleias sinodais, em outubro de 2014 e outubro de 2015. Ao fim da primeira sess\u00e3o, foi publicado a <em>Relatio Synodi<\/em>, a qual indicou que a a\u00e7\u00e3o pastoral da Igreja deveria se pautar pelo acolhimento e pela miseric\u00f3rdia. Disse o documento: \u201c\u00c9 necess\u00e1rio acolher as pessoas com a sua exist\u00eancia concreta, saber fomentar a sua busca, encorajar o seu desejo de Deus e a sua vontade de se sentir plenamente parte da Igreja, at\u00e9 mesmo em quantos experimentaram a fal\u00eancia ou vivem as situa\u00e7\u00f5es mais diferentes. A mensagem crist\u00e3 cont\u00e9m sempre em si mesma a realidade e a din\u00e2mica da miseric\u00f3rdia e da verdade, que convergem em Cristo\u201d (<em>Relatio Synodi<\/em>, 2014, n. 11).<\/p>\n<p>Ao fim do processo sinodal, o documento final ressaltou a miseric\u00f3rdia como grande ilumina\u00e7\u00e3o do agir da Igreja para com as fam\u00edlias: \u201cCom o cora\u00e7\u00e3o misericordioso de Jesus, a Igreja deve acompanhar os seus filhos mais fr\u00e1geis, marcados pelo amor ferido e confuso, restituindo confian\u00e7a e esperan\u00e7a, como a luz do farol de um porto ou de uma tocha levada ao meio do povo para iluminar aqueles que perderam a rota ou que se encontram no meio da tempestade\u201d (Documento final, 2015, n. 55).<\/p>\n<h3><strong>A Exorta\u00e7\u00e3o Apost\u00f3lica e sua recep\u00e7\u00e3o<\/strong><\/h3>\n<p>O documento final do s\u00ednodo \u00e9 datado de 24 de outubro de 2015 e a Exorta\u00e7\u00e3o Apost\u00f3lica foi publicada em mar\u00e7o do ano seguinte, como j\u00e1 mencionado.<\/p>\n<p><em>Amoris Laetitia<\/em> cont\u00e9m nove cap\u00edtulos, os quais abordam desde as perspectivas b\u00edblicas, magisteriais, a realidade das fam\u00edlias e as dimens\u00f5es pastorais. Rapidamente, \u00e9 bom termos em vista a divis\u00e3o dos cap\u00edtulos:<\/p>\n<p style=\"padding-left: 40px;\"><strong>Cap\u00edtulo I<\/strong> &#8211; \u00c0 luz da Palavra<br \/>\n<strong>Cap\u00edtulo II<\/strong> &#8211; A realidade e os desafios das fam\u00edlias<br \/>\n<strong>Cap\u00edtulo III<\/strong> &#8211; O olhar fixo em Jesus: a voca\u00e7\u00e3o da fam\u00edlia<br \/>\n<strong>Cap\u00edtulo IV<\/strong> &#8211; O amor no matrim\u00f4nio<br \/>\n<strong>Cap\u00edtulo V<\/strong> &#8211; O amor que se torna fecundo<br \/>\n<strong>Cap\u00edtulo VI<\/strong> &#8211; Algumas perspectivas pastorais<br \/>\n<strong>Cap\u00edtulo VII<\/strong> &#8211; Refor\u00e7ar a educa\u00e7\u00e3o dos filhos<br \/>\n<strong>Cap\u00edtulo VIII<\/strong> &#8211; Acompanhar, discernir e integrar a fragilidade<br \/>\n<strong>Cap\u00edtulo IX<\/strong> &#8211; Espiritualidade conjugal e familiar<\/p>\n<p>O pr\u00f3prio Papa Francisco diz que a maneira de ler o documento n\u00e3o precisa ser linear. De acordo com as atividades de cada grupo (fi\u00e9is leigos, pastorais, minist\u00e9rios ordenados&#8230;) podem haver ordens e prioridades diferentes em torno do mesmo texto. \u201c\u00c9 prov\u00e1vel, por exemplo, que os esposos se identifiquem mais com o quarto e quinto cap\u00edtulos, que os agentes pastorais tenham especial interesse pelo cap\u00edtulo sexto, e que todos se sintam muito interpelados pelo oitavo\u201d (AL, n. 7).<\/p>\n<p>Quando o texto da Exorta\u00e7\u00e3o P\u00f3s-Sinodal veio a p\u00fablico, os sentimentos novamente se distinguiram: houve os que comemoraram a maneira pastoral e de acolhida misericordiosa com que Francisco apresentava a realidade da fam\u00edlia, e quem a interpretasse como uma proposi\u00e7\u00e3o \u2018her\u00e9tica\u2019, por apresentar uma reflex\u00e3o diferente do modelo vigente (lembremos das chamadas Dubia, apresentadas pelos cardeais Walter Brandm\u00fcller e Joachim Meisner; o norte-americano Raymond Burke; e o italiano Carlo Caffarra). Ainda na esteira cr\u00edtica, o fato de que a Enc\u00edclica n\u00e3o esteja endere\u00e7ada primeiramente \u00e0s fam\u00edlias, mas aos bispos, presb\u00edteros e di\u00e1conos tamb\u00e9m causou desconforto: \u201cIsto significa que os pobres que quiserem entender alguma coisa do texto n\u00e3o poder\u00e3o faz\u00ea-lo em forma direta, mas sempre atrav\u00e9s da media\u00e7\u00e3o interpretativa de bispos, presb\u00edteros, di\u00e1conos, etc\u201d (GEBARA, 2016, p. 35).<\/p>\n<p>H\u00e1 v\u00e1rias partes do documento que valem a pena ser retomadas, seja pela beleza com que foram escritas, seja pela vis\u00e3o pastoral que apresentam. Particularmente, as intui\u00e7\u00f5es do cap\u00edtulo IV ao refletir sobre o conhecido hino de Paulo sobre o Amor (1Cor\u00a013, 4-7) s\u00e3o uma preciosidade a serem lidas com calma. Dada a limita\u00e7\u00e3o dessa proposta, \u00e9 bom destacar a import\u00e2ncia do cap\u00edtulo VIII, em que o papa apresenta um modelo de acompanhamento dos casais, prev\u00ea a acolhida misericordiosa destes e busca formas de integr\u00e1-los na comunidade de f\u00e9.<\/p>\n<p><em>Amoris Laetitia<\/em> insiste que o matrim\u00f4nio n\u00e3o \u00e9 uma realidade acabada, mas a ser constru\u00edda gradualmente. Nem mesmo a imagem t\u00e3o frequentemente utilizada da uni\u00e3o entre Cristo e a Igreja (Ef 5, 21-33) deve ser considerada como uma realidade impositiva, mas como ideal inspirador: \u201cN\u00e3o se deve atirar para cima de duas pessoas limitadas o peso tremendo de ter que reproduzir perfeitamente a uni\u00e3o que existe entre Cristo e a sua Igreja, porque o matrim\u00f4nio como sinal, implica um processo din\u00e2mico, que avan\u00e7a gradualmente com a progressiva integra\u00e7\u00e3o dos dons de Deus\u201d (AL, n. 122). Consideremos bem as express\u00f5es aqui utilizadas: \u201cprocesso din\u00e2mico\u2019, \u201cque avan\u00e7a\u201d, \u201cgradualmente\u201d, \u201cprogressiva integra\u00e7\u00e3o\u201d.<\/p>\n<p><em>Amoris Laetitia<\/em> n\u00e3o idealiza as fam\u00edlias, n\u00e3o prescreve um ideal perfeito, inalcan\u00e7\u00e1vel, n\u00e3o condena os modelos \u201cirregulares\u201d (Francisco escreve a palavra com as aspas). Ao contr\u00e1rio, faz quest\u00e3o de dizer que \u201cn\u00e3o existem as fam\u00edlias perfeitas que a publicidade falaciosa e consumista nos prop\u00f5e\u201d (AL, n.135). O Papa convida a todos ao empenho necess\u00e1rio para rela\u00e7\u00f5es amorosas, na valoriza\u00e7\u00e3o de cada membro da fam\u00edlia, \u00e0 escuta atenta do Senhor.<\/p>\n<p>Francisco enfatiza o processo de discernimento, indicando assim que as atitudes nunca dever\u00e3o ser tomadas do dia para a noite, ou consideradas prontas e acabadas de uma vez para sempre. Vejamos tr\u00eas exemplos:<\/p>\n<p style=\"padding-left: 40px;\">1) \u201cTemos dificuldade em apresentar o matrim\u00f4nio mais como um caminho din\u00e2mico de crescimento e realiza\u00e7\u00e3o do que como um fardo a carregar a vida inteira. Tamb\u00e9m nos custa deixar espa\u00e7o \u00e0 consci\u00eancia dos fi\u00e9is, que muitas vezes respondem o melhor que podem ao Evangelho no meio dos seus limites e s\u00e3o capazes de realizar o seu pr\u00f3prio discernimento perante situa\u00e7\u00f5es onde se rompem todos os esquemas. Somos chamados a formar as consci\u00eancias, n\u00e3o a pretender substitu\u00ed-las\u201d (AL, n. 37);<\/p>\n<p style=\"padding-left: 40px;\">2) \u201cSaibam os pastores que, por amor \u00e0 verdade, est\u00e3o obrigados a discernir bem as situa\u00e7\u00f5es. O grau de responsabilidade n\u00e3o \u00e9 igual em todos os casos, e podem existir fatores que limitem a capacidade de decis\u00e3o. Por isso, ao mesmo tempo que se exprime com clareza a doutrina, h\u00e1 que evitar ju\u00edzos que n\u00e3o tenham em conta a complexidade das diferentes situa\u00e7\u00f5es, e \u00e9 preciso estar atentos ao modo como as pessoas vivem e sofrem por causa da sua condi\u00e7\u00e3o\u201d (AL, n. 79);<\/p>\n<p style=\"padding-left: 40px;\">3) \u201cOs divorciados que vivem numa nova uni\u00e3o, por exemplo, podem encontrar-se em situa\u00e7\u00f5es muito diferentes, que n\u00e3o devem ser catalogadas ou encerradas em afirma\u00e7\u00f5es demasiado r\u00edgidas, sem deixar espa\u00e7o para um adequado discernimento pessoal e pastoral\u201d (AL, n. 298);<\/p>\n<p>Seria ing\u00eanuo e falacioso imaginar que o discernimento e a escuta da consci\u00eancia se d\u00e3o num ambiente calmo e esterilizado. Pelo contr\u00e1rio, as decis\u00f5es s\u00e3o tomadas frequentemente em meio aos terremotos e conflitos da vida. Para al\u00e9m das quest\u00f5es internas da fam\u00edlia, h\u00e1 todo o drama do contexto sociocultural, afinal, o desemprego, a habita\u00e7\u00e3o, o alimento dos filhos, o cuidado dos idosos n\u00e3o s\u00e3o situa\u00e7\u00f5es que possam ser ignoradas (cf. AL, n.25 e 44).<\/p>\n<p>Mas devemos admitir que<em> Amoris Laetitia<\/em> n\u00e3o fez tanto \u2018sucesso\u2019 como<em> Evangelii Gaudium<\/em> (citada exaustivamente nas celebra\u00e7\u00f5es e encontros) e <em>Laudato Si<\/em>\u2019 (que foi mais bem recebida fora da Igreja do que nas comunidades, salvo exce\u00e7\u00f5es que confirmam a regra). A preocupa\u00e7\u00e3o pela recep\u00e7\u00e3o dos documentos da Igreja por parte da comunidade crist\u00e3 n\u00e3o \u00e9 algo novo, uma vez que n\u00e3o basta publicar o documento, deve-se cuidar para que seja conhecido, devidamente interpretado e posto em pr\u00e1tica, de forma madura e as circunst\u00e2ncias assim o permitirem.<\/p>\n<p>Mais que dar respostas sobre o porqu\u00ea da dificuldade na recep\u00e7\u00e3o do documento, devemos nos perguntar: <em>Amoris Laetitia<\/em> foi apresentada \u00e0s comunidades? Seu texto foi refletido, suas ideias foram assimiladas? Sabemos que uma forma bastante conhecida por muitos na Igreja, &#8211; numa postura t\u00edpica do clericalismo &#8211; \u00e9 a reten\u00e7\u00e3o do conhecimento, como se os fi\u00e9is leigos n\u00e3o tivessem o direito, ou n\u00e3o fossem capazes de interpretar os textos. Sim, os textos eclesiais muitas vezes utilizam uma linguagem t\u00e3o cifrada que impossibilitam um acesso imediato a quem faltem os pressupostos filos\u00f3ficos e teol\u00f3gicos, de prefer\u00eancia com bom entendimento de latim ou grego.<\/p>\n<p>Mas o problema do acesso aos documentos n\u00e3o est\u00e1 localizado s\u00f3 entre os leigos, como se n\u00e3o quisessem ou n\u00e3o pudessem conhecer os documentos, mas tamb\u00e9m os ministros ordenados nem sempre apresentam o gosto pelo estudo, pelo aprofundamento, pela atualiza\u00e7\u00e3o. Em n\u00e3o raros casos, vale aquilo que sempre valeu, numa pregui\u00e7osa postura de \u201cl\u00e1 vem mais um documento!\u201d.<\/p>\n<p>Para a recep\u00e7\u00e3o de um documento da Igreja, devemos considerar que uma coisa \u00e9 quem escreve, outra \u00e9 quem interpreta, quem o recebe, quem vai coloc\u00e1-lo em pr\u00e1tica, enfim. \u201cN\u00e3o h\u00e1 automatismo nem imediatismo. N\u00e3o h\u00e1 um sentido fixo e nem uma acolhida \u00fanica. Diferentemente das leis que s\u00e3o colocadas em pr\u00e1tica pela via da coer\u00e7\u00e3o, as normas de cunho \u00e9tico-pedag\u00f3gico exigem constru\u00e7\u00e3o de consensos desde as suas publica\u00e7\u00f5es at\u00e9 as suas \u00faltimas aplica\u00e7\u00f5es. A recep\u00e7\u00e3o pressup\u00f5e abertura, decis\u00e3o e esfor\u00e7o na busca do sentido comum, do caminho comum e da meta comum. Exige, em \u00faltima inst\u00e2ncia, convers\u00e3o, diria o Papa Francisco\u201d (PASSOS, 2017, p. 15).<\/p>\n<h3><strong>Perspectivas pastorais<\/strong><\/h3>\n<p><em>Amoris Laetitia<\/em> lan\u00e7a o desafio de acompanhar as pessoas e as fam\u00edlias em seu discernimento crist\u00e3o. Resta saber se estamos dispostos a isto, ou continua mais f\u00e1cil partir de um princ\u00edpio geral que valha para todos. Uma moral de \u2018pode e n\u00e3o pode\u2019 certamente nos pouparia tempo em ter de nos debru\u00e7ar sobre cada situa\u00e7\u00e3o. Quanto a isso, nos alerta<em> Amoris Laetitia<\/em>, recordando o princ\u00edpio medieval: \u201cEmbora nos princ\u00edpios gerais tenhamos o car\u00e1ter necess\u00e1rio, todavia \u00e0 medida que se abordam os casos particulares, aumenta a indetermina\u00e7\u00e3o\u201d (AL, n. 304).<\/p>\n<p>Nesse ponto, \u00e9 bom que se diga: o autor n\u00e3o trabalha diretamente com casais, n\u00e3o atua em par\u00f3quia, n\u00e3o est\u00e1 \u2018com a m\u00e3o na massa\u2019 com as fam\u00edlias. Desse modo, est\u00e1 longe de poder dizer o que os agentes pastorais deveriam, ou n\u00e3o, fazer! Mas um dado \u00e9 bastante curioso: com certa frequ\u00eancia, sou chamado a realizar estudos de documentos da Igreja com pastorais, par\u00f3quias, congrega\u00e7\u00f5es e dioceses. Ultimamente, por exemplo, os cinco anos da <em>Laudato Si<\/em>\u2019 e a publica\u00e7\u00e3o da Fratelli Tutti me exigiram diversas reflex\u00f5es. No caso da <em>Amoris Laetitia<\/em>, tudo se estacionou nos meses subsequentes \u00e0 sua publica\u00e7\u00e3o. Depois disso, ao longo desses cinco anos, nunca mais fui chamado a refletir o documento, a n\u00e3o ser em sala de aula, por dever de of\u00edcio.<\/p>\n<p>Passados cinco anos de sua publica\u00e7\u00e3o, toda aquela ebuli\u00e7\u00e3o nos debates, todas as expectativas parecem ter perdido f\u00f4lego. Se outros documentos de Francisco continuam a ser citados, serviram de refer\u00eancia para outras discuss\u00f5es, parece n\u00e3o ter sido o caso de <em>Amoris Laetitia<\/em>. Valeria a pena interrogar-nos do porqu\u00ea desse apagamento. Suas proposi\u00e7\u00f5es foram acatadas? A maneira de acolher e acompanhar as fam\u00edlias, sobretudo as mais fragilizadas, mudou? Talvez tenha raz\u00e3o quem interpretou a Exorta\u00e7\u00e3o n\u00e3o como um ponto final, mas \u201ccom a for\u00e7a de um \u2018in\u00edcio\u2019, ou, melhor, do in\u00edcio de um in\u00edcio\u201d. (GRILLO, 2016, p. 41).<\/p>\n<p>O anivers\u00e1rio de cinco anos desta Exorta\u00e7\u00e3o deve ressaltar mais uma vez seus grandes objetivos: apreciar os dons do matrim\u00f4nio e da fam\u00edlia e manter um amor forte e cheio de valores como a generosidade, o compromisso, a fidelidade e a paci\u00eancia; e encorajar todos a serem sinais de miseric\u00f3rdia e proximidade para a vida familiar (cf. AL, n.5).<\/p>\n<hr \/>\n<p style=\"padding-left: 40px;\"><strong>Frei Oton da Silva Ara\u00fajo J\u00fanior, ofm<\/strong> &#8211; <em>Frade Franciscano da Prov\u00edncia Santa Cruz, \u00e9 professor do Instituto Santo Tom\u00e1s de Aquino (BH) e Faculdade Jesu\u00edta (BH). Possui doutorado em Teologia Moral, com tese que analisa a import\u00e2ncia de Frei Bernardino Leers para a renova\u00e7\u00e3o da Teologia Moral no Brasil. Assessor de movimentos populares na \u00e1rea de \u00e9tica teol\u00f3gica. Foi membro da coordena\u00e7\u00e3o da Confer\u00eancia dos Religiosos do Brasil (CRB), regional de Minas Gerais. Membro da equipe interdisciplinar da CRB nacional. Diretor Pastoral do Col\u00e9gio Santo Ant\u00f4nio, BH.<\/em><\/p>\n<p style=\"padding-left: 40px;\"><strong>Refer\u00eancias<\/strong><\/p>\n<h6 style=\"padding-left: 40px;\">FRANCISCO, Discurso de comemora\u00e7\u00e3o do cinquenten\u00e1rio da institui\u00e7\u00e3o do S\u00ednodo dos Bispos, 17 de outubro de 2015.<br \/>\nGEBARA, Ivone, A Igreja solteira, masculina e hier\u00e1rquica que fala \u00e0 fam\u00edlia, Revista IHU n\u00ba 483, Ano XVI, 2016, p. 35-39.<br \/>\nGRILLO, Andrea, Amoris Laetitia e a supera\u00e7\u00e3o de contraposi\u00e7\u00f5es est\u00e9reis, Revista IHU n\u00ba 483, Ano XVI, 2016, p. 40-43.<br \/>\nMOSER, Antonio, A import\u00e2ncia da pastoral familiar: Ecos do S\u00ednodo dos Bispos de 2015. REB, Petr\u00f3polis, volume 76, n\u00famero 302, Abr\/Jun 2016, p. 280-303.<br \/>\nPASSOS, Jo\u00e3o D\u00e9cio, A recep\u00e7\u00e3o da Exorta\u00e7\u00e3o Apost\u00f3lica p\u00f3s-sinodal Amoris Laetitia: desafios e tarefas eclesiais. S\u00e3o Paulo: Espa\u00e7os, 25\/1 e 2, 2017. p. 13-22.<br \/>\nS\u00cdNODO DOS BISPOS, Relatio Synodi, 18 de outubro de 2014.<br \/>\nS\u00cdNODO DOS BISPOS, Relat\u00f3rio final do S\u00ednodo dos Bispos ao Santo Padre Francisco, 24 de outubro de 2015.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Frei Oton J\u00fanior, ofm<\/p>\n","protected":false},"author":6,"featured_media":189518,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cinco anos da exorta\u00e7\u00e3o Amoris Laetitia: Quantos caminhamos? - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinco anos da exorta\u00e7\u00e3o Amoris Laetitia: Quantos caminhamos? - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Frei Oton J\u00fanior, ofm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-17T03:51:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-17T09:29:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2021\/05\/artigo-800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jovenal Pereira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jovenal Pereira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/\",\"name\":\"Cinco anos da exorta\u00e7\u00e3o Amoris Laetitia: Quantos caminhamos? - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2021-05-17T03:51:15+00:00\",\"dateModified\":\"2021-05-17T09:29:21+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/c052c0d9165fa75af6e14f595d2333a0\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cinco anos da exorta\u00e7\u00e3o Amoris Laetitia: Quantos caminhamos?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/c052c0d9165fa75af6e14f595d2333a0\",\"name\":\"Jovenal Pereira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e94509f531086e2eaf97e72f29ea00f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e94509f531086e2eaf97e72f29ea00f9?s=96&d=mm&r=g\",\"caption\":\"Jovenal Pereira\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/jovenal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinco anos da exorta\u00e7\u00e3o Amoris Laetitia: Quantos caminhamos? - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/","og_locale":"pt_BR","og_type":"article","og_title":"Cinco anos da exorta\u00e7\u00e3o Amoris Laetitia: Quantos caminhamos? - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Frei Oton J\u00fanior, ofm","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2021-05-17T03:51:15+00:00","article_modified_time":"2021-05-17T09:29:21+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2021\/05\/artigo-800.jpg","type":"image\/jpeg"}],"author":"Jovenal Pereira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jovenal Pereira","Est. tempo de leitura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/","name":"Cinco anos da exorta\u00e7\u00e3o Amoris Laetitia: Quantos caminhamos? - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2021-05-17T03:51:15+00:00","dateModified":"2021-05-17T09:29:21+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/c052c0d9165fa75af6e14f595d2333a0"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/cinco-anos-da-exortacao-amoris-laetitia-quantos-caminhamos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"Cinco anos da exorta\u00e7\u00e3o Amoris Laetitia: Quantos caminhamos?"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/c052c0d9165fa75af6e14f595d2333a0","name":"Jovenal Pereira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e94509f531086e2eaf97e72f29ea00f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e94509f531086e2eaf97e72f29ea00f9?s=96&d=mm&r=g","caption":"Jovenal Pereira"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/jovenal\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/189517"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=189517"}],"version-history":[{"count":8,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/189517\/revisions"}],"predecessor-version":[{"id":189612,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/189517\/revisions\/189612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/189518"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=189517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=189517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=189517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}