{"id":188777,"date":"2021-01-11T08:21:02","date_gmt":"2021-01-11T11:21:02","guid":{"rendered":"https:\/\/franciscanos.org.br\/vidacrista\/?p=188777"},"modified":"2021-01-11T08:21:02","modified_gmt":"2021-01-11T11:21:02","slug":"a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/","title":{"rendered":"A democracia americana entre a sinodalidade e a Regra franciscana"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-188778 size-full\" src=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2021\/01\/artigo_1101.jpg\" alt=\"\" width=\"840\" height=\"450\" srcset=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2021\/01\/artigo_1101.jpg 840w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2021\/01\/artigo_1101-450x241.jpg 450w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2021\/01\/artigo_1101-768x411.jpg 768w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2021\/01\/artigo_1101-150x80.jpg 150w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/p>\n<p><strong>Pietro Messa<\/strong><\/p>\n<p>Os democratas venceram as elei\u00e7\u00f5es presidenciais norte-americanas de 2020; em 14 de dezembro, o eleitorado escolheu Joe Biden como presidente dos EUA; em 6 de janeiro, na sess\u00e3o do Congresso dos Estados Unidos, proclamou-se sua elei\u00e7\u00e3o, enquanto em 20 de janeiro de 2021 come\u00e7a oficialmente o mandato.<\/p>\n<p>Alguns apoiadores do presidente cessante, Donald Trump, manifestaram-se no Capit\u00f3lio e invadiram-no causando confrontos com at\u00e9 alguns mortos. Uma ferida que n\u00e3o \u00e9 pequena para a democracia dos Estados Unidos, frequentemente alardeada como um modelo para outros pa\u00edses; um fato n\u00e3o extempor\u00e2neo e que, portanto, exigir\u00e1 um trabalho paciente por parte dos republicanos e dos democratas, isto \u00e9, de todas as partes &#8211; das quais deriva o termo &#8220;partido&#8221; &#8211; da sociedade.<\/p>\n<p>A este respeito vem \u00e0 mente o documento &#8220;Sinodalidade na vida e na miss\u00e3o da Igreja&#8221; (http:\/\/www.vatican.va\/roman_curia\/congregations\/cfaith\/cti_documents\/rc_cti_20180302_sinodalita_it.html), publicado pela Comiss\u00e3o Teol\u00f3gica Internacional em mar\u00e7o de 2018 depois de receber o parecer favor\u00e1vel do Papa Francisco. Com efeito, o n\u00famero 119 indica a sinodalidade n\u00e3o s\u00f3 como caminho eclesial, mas tamb\u00e9m como diaconia, ou servi\u00e7o social: \u00abA vida sinodal da Igreja oferece-se, em particular, como diaconia na promo\u00e7\u00e3o da vida social, econ\u00f4mica e pol\u00edtica dos povos em sinal da justi\u00e7a, da solidariedade e da paz. Deus, em Cristo, resgata n\u00e3o s\u00f3 a pessoa individual, mas tamb\u00e9m as rela\u00e7\u00f5es sociais entre os homens. A pr\u00e1tica do di\u00e1logo e a busca de solu\u00e7\u00f5es partilhadas e eficazes em que \u00abcompromete-se a construir a paz e a justi\u00e7a como prioridade absoluta numa situa\u00e7\u00e3o de crise estrutural dos processos de participa\u00e7\u00e3o democr\u00e1tica e de desconfian\u00e7a nos seus princ\u00edpios e valores inspiradores, com o perigo de derivas autorit\u00e1rias e tecnocr\u00e1ticas\u00bb.<\/p>\n<p>Em termos pol\u00edticos, poder\u00edamos dizer que uma vis\u00e3o sinodal \u00e9 a capacidade de vencer sem oprimir, ou seja, deixar \u00e0s minorias a oportunidade de dar a sua contribui\u00e7\u00e3o. Em n\u00edvel eclesial podemos recordar as diferentes sensibilidades do Papa Jo\u00e3o XXIII e do Cardeal Alfredo Ottaviani, secret\u00e1rio do ent\u00e3o Santo Of\u00edcio, que tamb\u00e9m resultaram em verdadeiras tens\u00f5es; ainda assim, ele n\u00e3o foi removido por Roncalli, o papa que estabeleceu o Conselho Pontif\u00edcio para a Promo\u00e7\u00e3o da Unidade dos Crist\u00e3os e criou seu primeiro presidente, o cardeal jesu\u00edta Augustin Bea. A escolha de Jo\u00e3o XXIII poderia ser considerada uma estrat\u00e9gia da pol\u00edtica eclesi\u00e1stica, mas se se leem suas anota\u00e7\u00f5es, se entende que sob essas escolhas havia uma vis\u00e3o teol\u00f3gica da Igreja que \u00e9 um \u00fanico Corpo com muitos membros no qual se \u00e9 chamado a viver a unidade na diferen\u00e7a.<\/p>\n<p>Neste processo sinodal, cuja beleza \u00e9 &#8220;a harmonia das partes excelentemente coloridas&#8221; (S\u00e3o Boaventura de Bagnoregio), ao qual a Igreja, mas tamb\u00e9m a sociedade e a pol\u00edtica, \u00e9 chamada, encontra neste 2021 um novo est\u00edmulo a partir do oitavo centen\u00e1rio da reda\u00e7\u00e3o da &#8220;Regra n\u00e3o Bulada&#8221; dos Frades Menores. Na verdade, este texto &#8211; que ap\u00f3s nova reda\u00e7\u00e3o ser\u00e1 definitivamente aprovado em 1223 pelo Papa Hon\u00f3rio III &#8211; \u00e9 o resultado do encontro, troca, e at\u00e9 confronto entre os frades reunidos em cap\u00edtulo na Porci\u00fancula, que \u00e9 a pequena capela de Santa Maria dos Anjos na plan\u00edcie de Assis. Ali pode-se ver a contribui\u00e7\u00e3o do Frei Francisco de Assis, mas tamb\u00e9m a integra\u00e7\u00e3o b\u00edblica de Frei Ces\u00e1rio da Spira; h\u00e1 extens\u00f5es, mas tamb\u00e9m inser\u00e7\u00f5es negativas com proibi\u00e7\u00f5es de comportamentos n\u00e3o adequados \u00e0 escolha evang\u00e9lica.<\/p>\n<p>Conforme destacado h\u00e1 alguns anos pelos estudos coordenados por Gert Melville sobre as institui\u00e7\u00f5es religiosas medievais da Universidade de Dresden, o estudo e a compara\u00e7\u00e3o com as regras religiosas podem revelar nelas elementos \u00fateis para enfrentar os desafios e as ocasi\u00f5es do momento presente.<\/p>\n<p>Sem presun\u00e7\u00e3o, pode-se dizer que a situa\u00e7\u00e3o pol\u00edtica atual nos Estados Unidos, mas n\u00e3o s\u00f3, pode encontrar impulsos e solicita\u00e7\u00f5es por uma vida democr\u00e1tica mais madura precisamente na Regra franciscana, cujo oitavo centen\u00e1rio se celebra neste 2021.<\/p>\n<hr \/>\n<p><strong>Pietro Messa,<\/strong><em>\u00a0fadre da Prov\u00edncia de Assis (It\u00e1lia), \u00e9 professor de Teologia e Hist\u00f3ria do Franciscanismo na Pontif\u00edcia Universidade Antonianum, em Roma, com diversas publica\u00e7\u00f5es na \u00e1rea.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Frei Pietro Messa<\/p>\n","protected":false},"author":3,"featured_media":188779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[323],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A democracia americana entre a sinodalidade e a Regra franciscana - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A democracia americana entre a sinodalidade e a Regra franciscana - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Frei Pietro Messa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-11T11:21:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2021\/01\/artigo_1101d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/\",\"name\":\"A democracia americana entre a sinodalidade e a Regra franciscana - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2021-01-11T11:21:02+00:00\",\"dateModified\":\"2021-01-11T11:21:02+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A democracia americana entre a sinodalidade e a Regra franciscana\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A democracia americana entre a sinodalidade e a Regra franciscana - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/","og_locale":"pt_BR","og_type":"article","og_title":"A democracia americana entre a sinodalidade e a Regra franciscana - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Frei Pietro Messa","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2021-01-11T11:21:02+00:00","og_image":[{"width":800,"height":601,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2021\/01\/artigo_1101d.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/","name":"A democracia americana entre a sinodalidade e a Regra franciscana - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2021-01-11T11:21:02+00:00","dateModified":"2021-01-11T11:21:02+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-democracia-americana-entre-a-sinodalidade-e-a-regra-franciscana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"A democracia americana entre a sinodalidade e a Regra franciscana"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/188777"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=188777"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/188777\/revisions"}],"predecessor-version":[{"id":188780,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/188777\/revisions\/188780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/188779"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=188777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=188777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=188777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}