{"id":185381,"date":"2020-06-11T08:00:25","date_gmt":"2020-06-11T11:00:25","guid":{"rendered":"https:\/\/franciscanos.org.br\/vidacrista\/?p=185381"},"modified":"2020-07-23T13:53:23","modified_gmt":"2020-07-23T16:53:23","slug":"sobre-os-profetas-de-baal-de-nossos-dias","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/","title":{"rendered":"Sobre os profetas de Baal de nossos dias"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_186847\" style=\"width: 850px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-186847\" decoding=\"async\" loading=\"lazy\" class=\"wp-image-186847 size-full\" src=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/artigo_2307_1.jpg\" alt=\"\" width=\"840\" height=\"450\" srcset=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/artigo_2307_1.jpg 840w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/artigo_2307_1-450x241.jpg 450w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/artigo_2307_1-768x411.jpg 768w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/artigo_2307_1-150x80.jpg 150w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><p id=\"caption-attachment-186847\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<em> \u00a0Imagem ilustrativa: (Icon ortodoxo)<\/em><\/p><\/div>\n<p><strong>Pe. Ademir Guedes Azevedo, cp<\/strong><\/p>\n<p>Mais uma vez estamos acompanhando o profeta Elias. Agora, em 1 Rs 18, ele se confronta com os profetas de Baal. A primeira constata\u00e7\u00e3o: Elias est\u00e1 sozinho, foi o \u00fanico profeta do Senhor que restou, enquanto os profetas de Baal s\u00e3o a maioria, 450. Por\u00e9m, o \u00fanico que tem a palavra significativa \u00e9 Elias. Os outros profetas demonstram a inefic\u00e1cia da f\u00e9, aquela f\u00e9 de espet\u00e1culo e de ritos inf\u00e9rteis, pois gritam, gesticulam, dan\u00e7am, saltam, se flagelam e a sua divindade n\u00e3o os responde, permanece indiferente, sem relacionar-se. Os profetas de Baal partem deles mesmo para chegar a deus, ou seja, s\u00e3o autorreferenciais. O fracasso desta idolatria, t\u00e3o presente em nossos tempos, \u00e9 representada no texto pelo pr\u00f3prio sangue dos profetas que os recobre, depois de se retalharem. Quando uma f\u00e9 \u00e9 autorreferencial ela se destr\u00f3i por meio das pr\u00f3prias m\u00e3os de seus praticantes.<\/p>\n<p>Elias, ao contr\u00e1rio, n\u00e3o confia em si mesmo, ele simplesmente suplica humildemente ao verdadeiro Deus. Sabe que sem o Deus de Israel n\u00e3o \u00e9 nada e n\u00e3o pode fazer nada. Como ele usa a palavra significativa e n\u00e3o os gritos que encenam uma f\u00e9 de espet\u00e1culo, prepara o altar com doze pedras, ou seja, roga a Deus que n\u00e3o se esque\u00e7a de Israel, representado nas doze pedras. As doze pedras que sustentam o altar preparado pelo profeta, sinalizam um Deus que fez hist\u00f3ria com as tribos de Israel, que se revela s\u00f3 quando se envolve, que \u00e9 rela\u00e7\u00e3o, \u00e9 Emanuel, um Deus para n\u00f3s, diferente da divindade de Baal que apenas exige e n\u00e3o se relaciona.<\/p>\n<p>Incr\u00edvel! Neste tempo de pandemia n\u00e3o faltaram manifesta\u00e7\u00f5es religiosas semelhantes a estas dos profetas de Baal. Basta ver o excesso de<em> lives<\/em> que fizeram barganha com Deus. Foram in\u00fameras multiplica\u00e7\u00f5es de rituais e ora\u00e7\u00f5es que pediam a Deus que ele aplacasse a pandemia e, o mais terr\u00edvel: em troca a gente promete retornar \u00e0s Igrejas assim que tudo passar, pois est\u00e3o pregando por a\u00ed que depois de tudo isso o ser humano ser\u00e1 mais temente. Duvido que Deus, para nos atrair, mandaria uma pandemia para castigar a humanidade. Deus \u00e9 amor e \u00e9 a sua miseric\u00f3rdia que nos atrai e fascina. Deus n\u00e3o pode ser um terrorista que nos imp\u00f5e medo.<\/p>\n<p>Infelizmente, os profetas de Baal existir\u00e3o at\u00e9 que perdurem em nossos dias os representantes de uma &#8220;teologia do caga\u00e7o&#8221;, que imp\u00f5em o medo nas consci\u00eancias mais fr\u00e1geis das nossas comunidades. Vejamos o caso de algumas igrejas neopentecostais que encenam falsas curas e prometem o que n\u00e3o podem cumprir. S\u00f3 a fidelidade ao Deus de Jesus que se revela na gratuidade de nosso cotidiano nos poder\u00e1 salvar das armadilhas dos profetas de Baal de nossos dias! E o que dizer dos nossos irm\u00e3os padres que fazem espet\u00e1culos com o Sant\u00edssimo Sacramento em nossas comunidades, como se estivessem com um amuleto m\u00e1gico nas m\u00e3os? Que toda a honra e adora\u00e7\u00e3o sejam dadas a Deus na Santa Eucaristia e na carne de nossos irm\u00e3os sofredores que prolongam a paix\u00e3o no mundo, mas longe de qualquer liturgismo selvagem.<\/p>\n<p>Elias \u00e9 um profeta revolucion\u00e1rio. Ele nos ensina a usarmos a palavra certa na hora certa. Sua trajet\u00f3ria \u00e9 um prel\u00fadio do que far\u00e1 o pr\u00f3prio Jesus quando usa a verdade para desmascarar a idolatria de uma religi\u00e3o corrompida com os privil\u00e9gios de C\u00e9sar: \u201cDai a Deus o que \u00e9 de Deus e a C\u00e9sar o que \u00e9 de C\u00e9sar\u201d (Mt 22, 21).<\/p>\n<p>Elias inspira a vida crist\u00e3 a rezar com confian\u00e7a, mas sem modismos e sinais espetaculares. A ora\u00e7\u00e3o crist\u00e3 n\u00e3o desafia a divindade do Pai, for\u00e7ando-o a nutrir as miragens do nosso deserto existencial. Abandonemo-nos, mais do que nunca, ao Pai como Jesus fez em sua cruz. Libertemos Deus de nossas gaiolas religiosas e s\u00f3 assim haver\u00e1 um novo c\u00e9u e uma nova terra, onde Deus ser\u00e1 tudo em todos. Assim seja!<\/p>\n<hr \/>\n<p><strong>Pe. Ademir Guedes Azevedo<\/strong>,\u00a0<em>cp, \u00e9 mission\u00e1rio passionista e mestre em Teologia Fundamental na Pontif\u00edcia Universidade Gregoriana. Atualmente reside em Camaragibe \u2013 PE, no Semin\u00e1rio para a etapa do Postulantado dos Passionistas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Pe. Ademir Guedes Azevedo, cp<\/p>\n","protected":false},"author":3,"featured_media":186849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[188],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sobre os profetas de Baal de nossos dias - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sobre os profetas de Baal de nossos dias - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Pe. Ademir Guedes Azevedo, cp\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-11T11:00:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-23T16:53:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/artigo_2307_1d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/\",\"name\":\"Sobre os profetas de Baal de nossos dias - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2020-06-11T11:00:25+00:00\",\"dateModified\":\"2020-07-23T16:53:23+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre os profetas de Baal de nossos dias\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sobre os profetas de Baal de nossos dias - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/","og_locale":"pt_BR","og_type":"article","og_title":"Sobre os profetas de Baal de nossos dias - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Pe. Ademir Guedes Azevedo, cp","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2020-06-11T11:00:25+00:00","article_modified_time":"2020-07-23T16:53:23+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/artigo_2307_1d.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/","name":"Sobre os profetas de Baal de nossos dias - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2020-06-11T11:00:25+00:00","dateModified":"2020-07-23T16:53:23+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/sobre-os-profetas-de-baal-de-nossos-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"Sobre os profetas de Baal de nossos dias"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/185381"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=185381"}],"version-history":[{"count":6,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/185381\/revisions"}],"predecessor-version":[{"id":186905,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/185381\/revisions\/186905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/186849"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=185381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=185381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=185381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}