{"id":185325,"date":"2020-06-06T14:49:30","date_gmt":"2020-06-06T17:49:30","guid":{"rendered":"https:\/\/franciscanos.org.br\/vidacrista\/?p=185325"},"modified":"2020-07-24T12:39:05","modified_gmt":"2020-07-24T15:39:05","slug":"a-trindade-e-a-sociedade","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/","title":{"rendered":"A Trindade e a sociedade"},"content":{"rendered":"<div id=\"attachment_185326\" style=\"width: 970px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-185326\" decoding=\"async\" loading=\"lazy\" class=\"wp-image-185326 size-full\" src=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/trindade.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/trindade.jpg 960w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/trindade-450x253.jpg 450w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/trindade-768x432.jpg 768w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/trindade-150x84.jpg 150w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><p id=\"caption-attachment-185326\" class=\"wp-caption-text\"><em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Imagem ilustrativa (fonte: Canva)<\/em><\/p><\/div>\n<p><strong>Pe. Ademir Guedes Azevedo, cp<\/strong><\/p>\n<p>Este \u00e9 um assunto importante, n\u00e3o s\u00f3 para os crist\u00e3os, mas para todos aqueles que est\u00e3o em busca de novos tempos onde podemos desenvolver a nossa exist\u00eancia a partir de uma fraternidade mais parecida com o Evangelho de Jesus. Quando dizemos fraternidade, pensamos em comunidade, n\u00e3o como pessoas que est\u00e3o aglomeradas, ou que vivem umas paralelas \u00e0s outras. Fraternidade, para a tradi\u00e7\u00e3o crist\u00e3, \u00e9 algo que assenta as suas ra\u00edzes no seio da Trindade. A Trindade, para usarmos uma express\u00e3o de Leonardo Boff, \u00e9 a melhor comunidade. Mas isso n\u00e3o \u00e9 slogan ou grito de guerra. Isso \u00e9 o evangelho!<\/p>\n<p>Viver em comunidade, \u00e9 colocar-se um de frente ao rosto do outro. \u00c9 reconhecimento e venera\u00e7\u00e3o absoluta \u00e0 alteridade, ou seja, \u00e0 dimens\u00e3o do sagrado que cada um possui. Na Trindade, o Pai ama o Filho e o Filho oferece a humanidade o mesmo amor que recebeu do Pai. O Esp\u00edrito Santo \u00e9 o pr\u00f3prio amor. Ent\u00e3o, as tr\u00eas divinas pessoas n\u00e3o sabem fazer outra coisa sen\u00e3o amar. \u00c9 neste sentido que a Trindade \u00e9 e ser\u00e1 sempre a melhor comunidade.<\/p>\n<p>Por\u00e9m, temos que nos perguntar se as organiza\u00e7\u00f5es pol\u00edticas de nosso tempo ou se o modo social de encararmos a vida refletem de alguma forma a vida trinit\u00e1ria como estamos falando. Infelizmente, a hist\u00f3ria plasmou muitos imp\u00e9rios autorit\u00e1rios que ofuscaram a vida da comunidade. Basta citarmos as grandes duas \u00faltimas guerras mundiais que causaram danos irrepar\u00e1veis \u00e0 vida. Tudo come\u00e7a com os discursos populistas que prometem solucionar os problemas em nome da seguran\u00e7a nacional. Esses s\u00e3o os messias de ontem e de hoje que levantam a bandeira da p\u00e1tria para amea\u00e7ar o estrangeiro, ou para assegurar os direitos da classe burguesa que tem medo de perder o monop\u00f3lio e os seus privil\u00e9gios.<\/p>\n<p>Mas n\u00e3o vamos t\u00e3o longe na hist\u00f3ria, lembremo-nos dos tempos da ditadura onde o chumbo e a censura falavam mais alto com a pretens\u00e3o de calar a democracia e os direitos humanos. Como falar de comunidade se os poderosos deste mundo trabalham contra o amor trinit\u00e1rio? Como pensar numa sociedade de irm\u00e3os e irm\u00e3s, quando o direito e a igualdade s\u00e3o amea\u00e7ados pelo autoritarismo de nossos governantes que se auto-intitulam messias salvadores da p\u00e1tria? N\u00e3o! Estes modelos de organiza\u00e7\u00e3o pol\u00edtica trabalham contra a Boa Nova do Evangelho. Eles s\u00e3o, para usar uma express\u00e3o de Plat\u00e3o, a personifica\u00e7\u00e3o da tirania. E quem \u00e9 o tirano? \u00c9 aquele governante que se alimenta das v\u00edsceras humanas em nome do poder e da falsa ordem.<\/p>\n<p>Contudo, a l\u00f3gica de viver em comunidade, segundo o sonho da Trindade, n\u00e3o \u00e9 uma fantasia. Pode ser realidade! Para tanto, precisamos mudar, sobretudo, o nosso modo de educar as novas gera\u00e7\u00f5es. Mudar \u00e9 um processo \u00e1rduo e lento, mas poss\u00edvel. O pr\u00f3prio Jesus nos dir\u00e1 que no princ\u00edpio as coisas n\u00e3o eram assim, ou seja, o mundo era regido na l\u00f3gica do amor. Mas a sede e a corrida pelo poder nos corromperam.<\/p>\n<p>Organizar a sociedade a partir da l\u00f3gica da Trindade \u00e9 uma miss\u00e3o dif\u00edcil, pois requer o princ\u00edpio da gratuidade, t\u00e3o esquecido e banalizado em nossas rela\u00e7\u00f5es. Tudo seria feito sem interesses e sem a pretens\u00e3o de tirarmos sempre proveito sobre os outros. A gratuidade \u00e9 irm\u00e3 g\u00eamea do cuidado, ou seja, daquele outro princ\u00edpio que se recusa a ceifar a vida dos mais fr\u00e1geis, ou para usar uma express\u00e3o que se encontra no evangelho de S\u00e3o Mateus: \u201cN\u00e3o esmagar\u00e1 a cana rachada, nem apagar\u00e1 o pavio que fumega, at\u00e9 que fa\u00e7a vencer a justi\u00e7a\u201d.<\/p>\n<p>Sim, a Trindade \u00e9 a melhor comunidade. Mas viver na sociedade a partir desta l\u00f3gica \u00e9 necess\u00e1rio construir a cada dia uma via alternativa, ou seja, n\u00e3o se contentar com o <em>status quo<\/em> deste mundo. A comunidade que Jesus viveu e quis para a humanidade n\u00e3o se trata de assumir formas totalit\u00e1rias que excluem os que sofrem. Jesus n\u00e3o compactua com o sistema pol\u00edtico romano nem com o sistema pol\u00edtico do Templo de Jerusal\u00e9m. Podemos dizer que a Constitui\u00e7\u00e3o, ou seja, a Carta Magna que rege a sociedade sonhada por Jesus s\u00e3o as Bem-aventuran\u00e7as que sinalizam a chegada do Reino de Deus. E este Reino n\u00e3o \u00e9 um lugar, mas uma a\u00e7\u00e3o de vida e de liberta\u00e7\u00e3o integral da pessoa. A ideia de desenvolvimento e progresso, n\u00e3o \u00e9 para suprir apenas as necessidades biol\u00f3gicas do ser humano, apesar disso tamb\u00e9m ser importante, mas Jesus pretende restituir o todo da nossa vida, ele n\u00e3o nos d\u00e1 migalhas, nos redime por completo.<\/p>\n<p>Este \u00e9 o sonho de Deus para n\u00f3s que vivemos em sociedade: \u201cEu vim para que todos tenham a vida e vida em abund\u00e2ncia\u201d (Jo 10,10).<\/p>\n<p>Pensemos nisso, sobretudo neste tempo confuso e dif\u00edcil de pandemia. Reflita que voc\u00ea \u00e9 um cidad\u00e3o para construir pontes e ser protagonista do amor que une e que n\u00e3o levanta as bandeiras da divis\u00e3o.<\/p>\n<hr \/>\n<p><strong>Pe. Ademir Guedes Azevedo<\/strong>,\u00a0<em>cp, \u00e9 mission\u00e1rio passionista e mestre em Teologia Fundamental na Pontif\u00edcia Universidade Gregoriana. Atualmente reside em Camaragibe \u2013 PE, no Semin\u00e1rio para a etapa do Postulantado dos Passionistas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo do Pe. Ademir Guedes Azevedo, cp<\/p>\n","protected":false},"author":3,"featured_media":185327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[188],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Trindade e a sociedade - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Trindade e a sociedade - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo do Pe. Ademir Guedes Azevedo, cp\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-06T17:49:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-24T15:39:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/trindade_d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/\",\"name\":\"A Trindade e a sociedade - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2020-06-06T17:49:30+00:00\",\"dateModified\":\"2020-07-24T15:39:05+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Trindade e a sociedade\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Trindade e a sociedade - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/","og_locale":"pt_BR","og_type":"article","og_title":"A Trindade e a sociedade - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo do Pe. Ademir Guedes Azevedo, cp","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2020-06-06T17:49:30+00:00","article_modified_time":"2020-07-24T15:39:05+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/06\/trindade_d.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/","name":"A Trindade e a sociedade - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2020-06-06T17:49:30+00:00","dateModified":"2020-07-24T15:39:05+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-trindade-e-a-sociedade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"A Trindade e a sociedade"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/185325"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=185325"}],"version-history":[{"count":3,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/185325\/revisions"}],"predecessor-version":[{"id":186932,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/185325\/revisions\/186932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/185327"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=185325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=185325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=185325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}