{"id":183806,"date":"2020-03-20T07:43:39","date_gmt":"2020-03-20T10:43:39","guid":{"rendered":"https:\/\/franciscanos.org.br\/vidacrista\/?p=183806"},"modified":"2020-07-27T12:32:01","modified_gmt":"2020-07-27T15:32:01","slug":"uma-espiritualidade-crista-em-tempos-de-coronavirus","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/","title":{"rendered":"Uma espiritualidade crist\u00e3 em tempos de coronav\u00edrus"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_186999\" style=\"width: 850px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-186999\" decoding=\"async\" loading=\"lazy\" class=\"wp-image-186999 size-full\" src=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/03\/artigo_2707_5.png\" alt=\"\" width=\"840\" height=\"450\" srcset=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/03\/artigo_2707_5.png 840w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/03\/artigo_2707_5-450x241.png 450w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/03\/artigo_2707_5-768x411.png 768w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/03\/artigo_2707_5-150x80.png 150w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><p id=\"caption-attachment-186999\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<em> \u00a0 \u00a0 \u00a0 \u00a0 Imagem ilustrativa (fonte: Canva)<\/em><\/p><\/div>\n<p><strong>Pe. Ademir Guedes Azevedo<\/strong><\/p>\n<p>Sem d\u00favida estamos vivendo dias dif\u00edceis. O p\u00e2nico p\u00f5e em risco o autocontrole das emo\u00e7\u00f5es. Aos poucos renasce, com novas interfaces, o instinto de sobreviv\u00eancia darwiniano onde o mais forte e com capacidade de adapta\u00e7\u00e3o toma o primeiro lugar. Consequentemente, os idosos e os pobres correm o risco de serem descartados.<\/p>\n<p>Por outro lado, antigas imagens de Deus renascem ao interno da comunidade crist\u00e3. Para entend\u00ea-las temos que recordar os momentos tristes da hist\u00f3ria. Na segunda metade do sec. XIV explodiu a Peste Negra (peste bub\u00f4nica), dizimando um ter\u00e7o da popula\u00e7\u00e3o europeia. Como toda sociedade teoc\u00eantrica, acreditava-se que Deus estava revoltado, pregou-se demasiado a ira divina. Para aplacar tal f\u00faria buscaram-se os bodes expiat\u00f3rios: judeus foram perseguidos e bruxas queimadas. Dizia-se que tudo estava acontecendo porque a gravidade de nossos pecados desagradava a Deus.<\/p>\n<p>Em plena Segunda Guerra Mundial, o ilustre te\u00f3logo Dietrich Bonhoeffer deu-se conta que, diante da dor e morte dos inocentes, temos que falar de Deus a partir de uma linguagem n\u00e3o religiosa. Para ele, o vocabul\u00e1rio religioso que insiste numa imagem metafisica de um Deus todo poderoso j\u00e1 n\u00e3o consegue justificar a for\u00e7a do mal na humanidade. Al\u00e9m disso, Bonhoeffer denuncia profeticamente o comportamento de buscar o divino apenas quando tudo vai mal, transformando Deus em um tapa-buraco.<\/p>\n<p>Notemos que a recente epidemia do coronav\u00edrus fez explodir uma s\u00e9rie de rea\u00e7\u00f5es religiosas e psicol\u00f3gicas deturpadoras do essencial. Dizia-se que a grande doen\u00e7a do sec. XXI seria a depress\u00e3o, entendida como a exausta\u00e7\u00e3o do pr\u00f3prio eu &#8211; o cansa\u00e7o de si mesmo \u2013 ou o infarto ps\u00edquico da pr\u00f3pria imagem, causado pela corrida fren\u00e9tica de sucesso e bem-estar pessoal. Diante da explos\u00e3o da epidemia estamos testemunhando, infelizmente, um comportamento de medo em rela\u00e7\u00e3o ao pr\u00f3ximo. Se com a depress\u00e3o o grande inimigo do homem era a sua pr\u00f3pria imagem (o eu), agora com o coronav\u00edrus alguns insistem em dizer que o outro \u00e9 o novo inimigo que devemos evitar. Esse tipo de rea\u00e7\u00e3o amea\u00e7a o valor sagrado da alteridade. No entanto, para sairmos deste labirinto temos que ouvir as autoridades e, sobretudo, as recomenda\u00e7\u00f5es da OMS que prop\u00f5e o tempo de quarentena, dando-nos assim a oportunidade de estarmos mais unidos e nutrirmos mais ainda o respeito pela vida do pr\u00f3ximo. Aqui reside a verdadeira alteridade.<\/p>\n<p>Do ponto de vista religioso, a situa\u00e7\u00e3o \u00e9 ainda mais delicada. Muitos grupos e comunidades intensificam ora\u00e7\u00f5es, adora\u00e7\u00f5es e multiplicam missas. Quero acreditar que tudo isso \u00e9 realmente para evitar aglomera\u00e7\u00f5es, nos apoiarmos mutuamente e aprendermos acerca da solidariedade e da compaix\u00e3o com o pr\u00f3ximo, e n\u00e3o para fazer barganha com Deus. Se jogarmos a culpa em Deus com coment\u00e1rios do tipo: Por que Ele est\u00e1 permitindo isso? Retornaremos aos tempos da peste bub\u00f4nica e entraremos em campo com a multiplica\u00e7\u00e3o de ora\u00e7\u00f5es para tentarmos aplacar a ira dele. \u00c9 Justamente isso que devemos refletir a partir de uma \u00f3tica que retoma o Evangelho e n\u00e3o a partir de uma tradi\u00e7\u00e3o medieval.<\/p>\n<p>J. B. Metz, ao ser v\u00edtima das barb\u00e1ries do campo de concentra\u00e7\u00e3o nazista, levantou a seguinte pergunta: \u201cAinda \u00e9 poss\u00edvel crer em Deus depois de Auschwitz?\u201d Para atualizarmos a sua provoca\u00e7\u00e3o, nestes dias podemos dizer assim: \u201cComo crer em Deus em tempos de coronav\u00edrus?\u201d<\/p>\n<p>Pois bem, um antigo rabino, certa vez, afirmou: \u201c\u00c9 verdade que Deus fala, mas nem sempre Ele responde\u201d. \u00c0s vezes, a nossa forma de rezar pretende obrigar a Deus a dar-nos respostas e sinais. Tomados pelo desespero do coronav\u00edrus podemos cair na pior de todas as tenta\u00e7\u00f5es, aquela que tenta a divindade do Pai, ou seja, a exig\u00eancia da demonstra\u00e7\u00e3o de seu poder. No deserto, Jesus tamb\u00e9m foi exposto a isso quando o dem\u00f4nio lhe pedia para transformar as pedras em p\u00e3es.<\/p>\n<p>Por\u00e9m, o pr\u00f3prio Jesus nos ensina outra rela\u00e7\u00e3o com o Pai, a partir de sua f\u00e9 e obedi\u00eancia absoluta, sobretudo diante das consequ\u00eancias de sua fidelidade ao Reino de Deus. S\u00f3 o grito de Jesus na cruz pode nos ensinar uma nova espiritualidade libertadora para os nossos dias. O Filho grita e reclama ao Pai de seu abandono. Por\u00e9m, Deus silencia. No entanto, mesmo que pare\u00e7a que o Pai abandona o Filho, este por sua vez n\u00e3o abandona jamais ao Pai. Eis aqui a verdadeira f\u00e9!<\/p>\n<p>Uma espiritualidade crist\u00e3 em tempos de coronav\u00edrus n\u00e3o exige de Deus nenhum sinal ou a sua prote\u00e7\u00e3o, isso para n\u00e3o o tentarmos. O que dever\u00edamos aprender \u00e9 a fidelidade incondicional a Ele, sobretudo neste momento sombrio de nossa hist\u00f3ria, como o pr\u00f3prio Jesus que soube perseverar com a sua cruz. Quem se lan\u00e7a nas \u00e1guas profundas da perseveran\u00e7a aprende que, \u201cquanto mais escura for a noite, mais clara ser\u00e1 a madrugada\u201d (<em>Dom Helder C\u00e2mara)<\/em>. Que assim seja!<\/p>\n<hr \/>\n<p><strong>Pe. Ademir Guedes Azevedo<\/strong>,\u00a0<em>cp, \u00e9 mission\u00e1rio passionista e mestre em Teologia Fundamental na Pontif\u00edcia Universidade Gregoriana. Atualmente reside em Camaragibe \u2013 PE, novo Semin\u00e1rio para a etapa do Postulantado dos Passionistas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Pe. Ademir Guedes Azevedo<\/p>\n","protected":false},"author":3,"featured_media":187000,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[188],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Uma espiritualidade crist\u00e3 em tempos de coronav\u00edrus - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uma espiritualidade crist\u00e3 em tempos de coronav\u00edrus - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Pe. Ademir Guedes Azevedo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T10:43:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-27T15:32:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/03\/artigo_2707_5d.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/\",\"name\":\"Uma espiritualidade crist\u00e3 em tempos de coronav\u00edrus - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2020-03-20T10:43:39+00:00\",\"dateModified\":\"2020-07-27T15:32:01+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uma espiritualidade crist\u00e3 em tempos de coronav\u00edrus\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uma espiritualidade crist\u00e3 em tempos de coronav\u00edrus - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/","og_locale":"pt_BR","og_type":"article","og_title":"Uma espiritualidade crist\u00e3 em tempos de coronav\u00edrus - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Pe. Ademir Guedes Azevedo","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2020-03-20T10:43:39+00:00","article_modified_time":"2020-07-27T15:32:01+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2020\/03\/artigo_2707_5d.png","type":"image\/png"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/","name":"Uma espiritualidade crist\u00e3 em tempos de coronav\u00edrus - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2020-03-20T10:43:39+00:00","dateModified":"2020-07-27T15:32:01+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/uma-espiritualidade-crista-em-tempos-de-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"Uma espiritualidade crist\u00e3 em tempos de coronav\u00edrus"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/183806"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=183806"}],"version-history":[{"count":3,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/183806\/revisions"}],"predecessor-version":[{"id":187001,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/183806\/revisions\/187001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/187000"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=183806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=183806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=183806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}