{"id":182586,"date":"2019-11-21T14:06:08","date_gmt":"2019-11-21T17:06:08","guid":{"rendered":"https:\/\/franciscanos.org.br\/vidacrista\/?p=182586"},"modified":"2020-07-30T12:10:03","modified_gmt":"2020-07-30T15:10:03","slug":"jesus-e-o-reino-um-projeto-de-secularizacao","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/","title":{"rendered":"Jesus e o Reino: um projeto de seculariza\u00e7\u00e3o"},"content":{"rendered":"<div id=\"attachment_187207\" style=\"width: 850px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-187207\" decoding=\"async\" loading=\"lazy\" class=\"wp-image-187207 size-full\" src=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/11\/joao_3007.jpg\" alt=\"\" width=\"840\" height=\"450\" srcset=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/11\/joao_3007.jpg 840w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/11\/joao_3007-450x241.jpg 450w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/11\/joao_3007-768x411.jpg 768w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/11\/joao_3007-150x80.jpg 150w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><p id=\"caption-attachment-187207\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<em>Imagem ilustrativa (Annibale Carracci -1560\u20131609)<\/em><\/p><\/div>\n<p>&nbsp;<\/p>\n<p><strong>Pe. Ademir Guedes Azevedo, cp<\/strong><\/p>\n<p>No debate sobre seculariza\u00e7\u00e3o e cristianismo, a categoria de Reino de Deus \u00e9 fundamental para entrarmos no n\u00facleo da quest\u00e3o. Al\u00e9m do estilo de Jesus que refaz a imagem de Deus a partir de uma transcend\u00eancia que caminha dentro da hist\u00f3ria (encarna\u00e7\u00e3o), tudo o que Ele disse e fez foi para preparar uma vida nova, diferente daquela pregada pela religi\u00e3o de sua \u00e9poca. Tudo isso \u00e9 compendiado na ideia de Reino de Deus. Quem colabora com esta reflex\u00e3o \u00e9 o te\u00f3logo uruguaio Juan Luis em seu livro \u201c<strong>Ese Reino<\/strong> \u2013 <em>desgrabaci\u00f3n de 6 charlas sobre el Reino de Dios\u201d<\/em>. Pessoalmente, busco identificar a ideia de Reino com aquela de seculariza\u00e7\u00e3o, que para mim se cruzam de tal modo a serem vistas como irm\u00e3s g\u00eameas.<\/p>\n<p>A coisa mais importante em todo o minist\u00e9rio secularizado de Jesus foi: \u201cCumpriu-se o tempo e est\u00e1 chegando o Reino de Deus; arrependei-vos e crede no Evangelho\u201d (Mc 1,15). Por que se encontra no in\u00edcio do Evangelho esta not\u00edcia? A quest\u00e3o se esclarece s\u00f3 quando compararmos o modo de ser de Jesus com aquele de Jo\u00e3o Batista. Para este \u00faltimo, o Reino \u00e9 algo j\u00e1 pronto, enquanto para Jesus se trata de um projeto que se deve preparar. Jo\u00e3o entende o Reino como um an\u00fancio, Jesus como uma boa not\u00edcia. Para Jo\u00e3o, o Reino \u00e9 iminente, por isso est\u00e1 pr\u00f3ximo o ju\u00edzo de Deus: \u201cO machado j\u00e1 est\u00e1 posto \u00e0 raiz das \u00e1rvores, e toda \u00e1rvore que n\u00e3o der bom fruto ser\u00e1 cortada e jogada ao fogo\u201d. (Lc 3,9). Ele vai chegar para julgar e s\u00f3 aqueles que fazem penit\u00eancia ser\u00e3o livres do ju\u00edzo terr\u00edvel de Deus. Jesus, ao contr\u00e1rio, sonha o Reino como liberta\u00e7\u00e3o total do homem e isso se faz s\u00f3 a longo prazo, necessita ser constru\u00eddo nas rela\u00e7\u00f5es pessoais. Trata-se de uma din\u00e2mica paciente por meio da qual n\u00e3o podemos estabelecer um tempo definitivo. Tudo depende do cora\u00e7\u00e3o do homem e da sua abertura para acolher a boa not\u00edcia. Por isso, o Reino para Jesus \u00e9 um projeto secularizado, visto que vai acontecendo dentro das coisas concretas da vida e acompanha o processo de maturidade da liberdade humana.<\/p>\n<p>Enquanto Jo\u00e3o Batista est\u00e1 fortemente ligado \u00e0 ideia de ju\u00edzo, como aquele dia tremendo, Jesus se p\u00f5e fora desta tradi\u00e7\u00e3o religiosa, pois vai al\u00e9m dos preceitos religiosos que coagem e sufocam a liberdade humana. Jesus caminha na esteira do tempo, do cotidiano. Para Ele, a liberta\u00e7\u00e3o de Deus acontece de modo lento, n\u00e3o pode gerar medo. Deve restabelecer toda a dignidade da pessoa. A prop\u00f3sito, este vocabul\u00e1rio que surge da pr\u00e1tica de Jesus (vida, verdade, liberta\u00e7\u00e3o, mansid\u00e3o, cura etc.) n\u00e3o ser\u00e3o as grandes linhas mestras das revolu\u00e7\u00f5es modernas e atuais que sonham e lutam pela paz na sociedade? N\u00e3o s\u00e3o estes ideais que constituem a energia er\u00f3tica de tantos movimentos populares que resistem pacificamente contra as pol\u00edticas desumanas que insistem em retomar as formas totalit\u00e1rias de governar? Eis porque o Reino ser\u00e1 sempre a a\u00e7\u00e3o mais aut\u00eantica de construir rela\u00e7\u00f5es verdadeiras e s\u00f3lidas em todos os tempos. \u00c9 realmente um projeto a ser constru\u00eddo!<\/p>\n<p>Como Jo\u00e3o Batista concebe o Reino em perspectiva de an\u00fancio (linguagem t\u00edpica da religi\u00e3o de normas e preceitos), o estilo de vida que nasce daqui \u00e9 aquele isolado e r\u00edgido. Ele vive no deserto e se alimenta de mel silvestre. Trata-se de uma penit\u00eancia onde n\u00e3o tem espa\u00e7o a alegria. Essa forma de penit\u00eancia funda-se a partir de uma imagem de Deus como juiz castigador, o qual recompensar\u00e1 apenas aqueles que se penitenciam. No entanto, como Jesus concebe o Reino em perspectiva de projeto, seu estilo de vida \u00e9 vivaz e alegre. Ele \u00e9 soci\u00e1vel, senta-se \u00e0 mesa, come e bebe. Este estilo secularizado n\u00e3o se esconde no deserto e n\u00e3o julga o mundo como n\u00e3o ortodoxo, pelo contr\u00e1rio, vive a integridade do amor dentro das rela\u00e7\u00f5es, como pessoas que est\u00e3o sempre em busca, construindo a liberta\u00e7\u00e3o, mas sem refugiar-se em formas de vida obsoletas e autorit\u00e1rias.<\/p>\n<p>H\u00e1 ainda uma outra caracter\u00edstica que emerge do argumento do Reino de Deus em perspectiva de seculariza\u00e7\u00e3o: trata-se do desmascaramento da ideologia. E qual \u00e9 essa ideologia? Mais uma vez esta nasce do excesso de religi\u00e3o separada da hist\u00f3ria. A ideologia que Jesus teve que combater foi aquela que diz que os pobres s\u00e3o o que s\u00e3o pelo fato de serem pecadores, ou seja, a condi\u00e7\u00e3o de ser pobre \u00e9 ligada a condi\u00e7\u00e3o de ser pecador. Por isso, os pobres n\u00e3o merecem participar da vida do templo, sustenta a ideologia da religi\u00e3o vigente, s\u00e3o etiquetados como malvistos e suspeitos, indignos de confian\u00e7a. Devem ainda aceitar a maldi\u00e7\u00e3o da lepra, conviver com a ideia de serem malditos e n\u00e3o amados por Deus. \u00c9 neste cen\u00e1rio que Jesus revela o conte\u00fado do Reino, como desmascaramento da ideologia: As Bem-aventuran\u00e7as. Aqui, Ele oferece a boa not\u00edcia do seu projeto: os pobres s\u00e3o felizes, porque deles \u00e9 o Reino; os que choram ter\u00e3o as l\u00e1grimas enxugadas; todos os que carregam o fardo pesado, criado pela ideologia que associa o pobre com o pecado, Deus ter\u00e1 prefer\u00eancia por eles.<\/p>\n<p>Esta liberta\u00e7\u00e3o realizada por Jesus leva os pobres a descobrirem a primeira gra\u00e7a que reside no poder da conscientiza\u00e7\u00e3o, a qual n\u00e3o aceita a ideologia da religi\u00e3o que separa puros e impuros. Um dos pilares que inauguraram a seculariza\u00e7\u00e3o na modernidade foi a conquista da autonomia humana, ou seja, o homem descobre que pode pensar por si mesmo, que n\u00e3o necessita viver sob o jugo da falsa religi\u00e3o que escraviza. E \u00e9 incr\u00edvel como Jesus, quando falava do Reino, j\u00e1 havia proposto tudo isso!<\/p>\n<hr \/>\n<p><strong>Pe. Ademir Guedes Azevedo, cp<\/strong>,\u00a0<em>\u00e9 mission\u00e1rio passionista e mestre\u00a0 em Teologia Fundamental na Pontif\u00edcia Universidade Gregoriana. Atualmente colabora com a miss\u00e3o passionista de Montevid\u00e9u, no Uruguai.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Pe. Ademir Guedes Azevedo<\/p>\n","protected":false},"author":3,"featured_media":187208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[188],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jesus e o Reino: um projeto de seculariza\u00e7\u00e3o - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jesus e o Reino: um projeto de seculariza\u00e7\u00e3o - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Pe. Ademir Guedes Azevedo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-21T17:06:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-30T15:10:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/11\/joao_3007d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/\",\"name\":\"Jesus e o Reino: um projeto de seculariza\u00e7\u00e3o - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2019-11-21T17:06:08+00:00\",\"dateModified\":\"2020-07-30T15:10:03+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jesus e o Reino: um projeto de seculariza\u00e7\u00e3o\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jesus e o Reino: um projeto de seculariza\u00e7\u00e3o - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Jesus e o Reino: um projeto de seculariza\u00e7\u00e3o - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Pe. Ademir Guedes Azevedo","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2019-11-21T17:06:08+00:00","article_modified_time":"2020-07-30T15:10:03+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/11\/joao_3007d.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/","name":"Jesus e o Reino: um projeto de seculariza\u00e7\u00e3o - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2019-11-21T17:06:08+00:00","dateModified":"2020-07-30T15:10:03+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/jesus-e-o-reino-um-projeto-de-secularizacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"Jesus e o Reino: um projeto de seculariza\u00e7\u00e3o"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/182586"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=182586"}],"version-history":[{"count":5,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/182586\/revisions"}],"predecessor-version":[{"id":187209,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/182586\/revisions\/187209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/187208"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=182586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=182586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=182586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}