{"id":180797,"date":"2019-08-05T11:10:41","date_gmt":"2019-08-05T14:10:41","guid":{"rendered":"https:\/\/franciscanos.org.br\/vidacrista\/?p=180797"},"modified":"2021-08-26T17:01:32","modified_gmt":"2021-08-26T20:01:32","slug":"carta-do-papa-francisco-aos-presbiteros","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/","title":{"rendered":"Carta do Papa Francisco aos presb\u00edteros"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_190248\" style=\"width: 850px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-190248\" decoding=\"async\" loading=\"lazy\" class=\"wp-image-190248 size-full\" src=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/08\/mensagem_presbiterio.jpg\" alt=\"\" width=\"840\" height=\"473\" srcset=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/08\/mensagem_presbiterio.jpg 840w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/08\/mensagem_presbiterio-450x253.jpg 450w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/08\/mensagem_presbiterio-768x432.jpg 768w, https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/08\/mensagem_presbiterio-150x84.jpg 150w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><p id=\"caption-attachment-190248\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <em>\u00a0 \u00a0 \u00a0 Imagem: Vatican Media (12.05.19)<\/em><\/p><\/div>\n<p>Meus queridos irm\u00e3os!<\/p>\n<p>Estamos a comemorar cento e sessenta anos da morte do Santo Cura d&#8217;Ars, que Pio XI prop\u00f4s como patrono de todos os p\u00e1rocos do mundo.[1] Quero, na sua mem\u00f3ria lit\u00fargica, dirigir esta Carta n\u00e3o s\u00f3 aos p\u00e1rocos, mas a todos v\u00f3s, irm\u00e3os presb\u00edteros, que sem fazer alarde \u00abdeixais tudo\u00bb para vos empenhar na vida quotidiana das vossas comunidades; a v\u00f3s que, como o Cura d\u2019Ars, labutais na \u00abtrincheira\u00bb, aguentais o peso do dia e do calor (cf.\u00a0<i>Mt<\/i>\u00a020, 12) e, sujeitos a uma infinidade de situa\u00e7\u00f5es, as enfrentais diariamente e sem vos dar ares de import\u00e2ncia para que o povo de Deus seja cuidado e acompanhado. Dirijo-me a cada um de v\u00f3s que tantas vezes, de forma impercept\u00edvel e sacrificada, no cansa\u00e7o ou na fadiga, na doen\u00e7a ou na desola\u00e7\u00e3o, assumis a miss\u00e3o como um servi\u00e7o a Deus e ao seu povo e, mesmo com todas as dificuldades do caminho, escreveis as p\u00e1ginas mais belas da vida sacerdotal.<\/p>\n<p>H\u00e1 algum tempo, manifestava aos bispos italianos a preocupa\u00e7\u00e3o pelos nossos sacerdotes que, em v\u00e1rias regi\u00f5es, se sentem achincalhados e \u00abculpabilizados\u00bb por causa de crimes que n\u00e3o cometeram; dizia-lhes que eles precisam de encontrar no seu bispo a figura do irm\u00e3o mais velho e o pai que os encoraje nestes tempos dif\u00edceis, os estimule e apoie no caminho.[2]<\/p>\n<p>Como irm\u00e3o mais velho e pai, tamb\u00e9m eu quero estar perto, em primeiro lugar para vos\u00a0<i>agradecer<\/i>\u00a0em nome do santo Povo fiel de Deus tudo o que ele recebe de v\u00f3s e, por minha vez,\u00a0<i>encorajar-vos<\/i>\u00a0a relembrar as palavras que o Senhor pronunciou com tanta ternura no dia da nossa Ordena\u00e7\u00e3o e que constituem a fonte da nossa alegria: \u00abJ\u00e1 n\u00e3o vos chamo servos, (&#8230;) a v\u00f3s chamei-vos amigos\u00bb (<i>Jo<\/i>\u00a015, 15).[3]<\/p>\n<h3>TRIBULA\u00c7\u00c3O<\/h3>\n<p>\u00abVi a opress\u00e3o do meu povo\u00bb (<i>Ex<\/i>\u00a03, 7)<\/p>\n<p>Nos \u00faltimos tempos, pudemos ouvir mais claramente o clamor \u2013 muitas vezes silencioso e silenciado \u2013 de irm\u00e3os nossos, v\u00edtimas de abusos de poder, de consci\u00eancia e sexuais por parte de ministros ordenados. Sem d\u00favida, \u00e9 um per\u00edodo de sofrimento na vida das v\u00edtimas, que padeceram diferentes formas de abuso, e tamb\u00e9m para as suas fam\u00edlias e para todo o Povo de Deus.<\/p>\n<p>Como sabeis, estamos firmemente empenhados na atua\u00e7\u00e3o das reformas necess\u00e1rias para promover, a partir da raiz, uma cultura baseada no cuidado pastoral, de tal forma que a cultura do abuso n\u00e3o consiga encontrar espa\u00e7o para desenvolver-se e, menos ainda, perpetuar-se. N\u00e3o \u00e9 tarefa f\u00e1cil nem de curto prazo; requer o empenho de todos. Se, no passado, a omiss\u00e3o p\u00f4de transformar-se numa forma de resposta, hoje queremos que a convers\u00e3o, a transpar\u00eancia, a sinceridade e a solidariedade com as v\u00edtimas se tornem na nossa maneira de fazer a hist\u00f3ria e nos ajudem a estar mais atentos a todos os sofrimentos humanos.[4]<\/p>\n<p>E esta tribula\u00e7\u00e3o n\u00e3o deixa indiferentes os presb\u00edteros. Pude constat\u00e1-lo nas v\u00e1rias visitas pastorais, tanto na minha diocese como noutras onde tive oportunidade de encontrar e falar pessoalmente com os sacerdotes. Muitos deles manifestaram a pr\u00f3pria indigna\u00e7\u00e3o pelo que aconteceu e tamb\u00e9m uma esp\u00e9cie de impot\u00eancia, j\u00e1 que, al\u00e9m do \u00abdesgaste pela entrega, experimentaram o dano que provoca a suspeita e a contesta\u00e7\u00e3o, que pode ter insinuado \u2013 em alguns ou muitos \u2013 a d\u00favida, o medo e a difid\u00eancia\u00bb.[5] S\u00e3o numerosas as cartas de sacerdotes que partilham este sentimento. Por outro lado, consola encontrar pastores que, ao constatar e conhecer o sofrimento das v\u00edtimas e do Povo de Deus, se mobilizam, procuram palavras e percursos de esperan\u00e7a.<\/p>\n<p>Sem negar nem ignorar o dano causado por alguns dos nossos irm\u00e3os, seria injusto n\u00e3o reconhecer que tantos sacerdotes, de maneira constante e \u00edntegra, oferecem tudo o que s\u00e3o e t\u00eam pelo bem dos outros (cf.\u00a0<i>2 Cor<\/i>\u00a012, 15) e vivem uma paternidade espiritual capaz de chorar com os que choram; h\u00e1 in\u00fameros padres que fazem da sua vida uma obra de miseric\u00f3rdia em regi\u00f5es ou situa\u00e7\u00f5es frequentemente in\u00f3spitas, remotas ou abandonadas, mesmo a risco da pr\u00f3pria vida. Reconhe\u00e7o e agrade\u00e7o o vosso exemplo corajoso e constante que, em momentos de turbul\u00eancia, vergonha e sofrimento, nos mostra que v\u00f3s continuais a entregar-vos com alegria pelo Evangelho.[6]<\/p>\n<p>Estou convencido de que, na medida em que formos fi\u00e9is \u00e0 vontade de Deus, os tempos da purifica\u00e7\u00e3o eclesial que estamos a viver nos tornar\u00e3o mais alegres e simples e, num futuro n\u00e3o muito distante, ser\u00e3o muito fecundos. \u00abN\u00e3o desanimemos! O Senhor est\u00e1 a purificar a sua Esposa e, a todos, nos est\u00e1 convertendo a Ele. Permite-nos experimentar a prova, para compreendermos que, sem Ele, somos p\u00f3. Est\u00e1-nos a salvar da hipocrisia e da espiritualidade das apar\u00eancias. Est\u00e1 a soprar o seu Esp\u00edrito, para restaurar a beleza da sua Esposa surpreendida em flagrante adult\u00e9rio. Hoje far-nos-\u00e1 bem ler o cap\u00edtulo 16 de Ezequiel. Aquela \u00e9 a hist\u00f3ria da Igreja. Aquela \u2013 poder\u00e1 dizer cada um de n\u00f3s \u2013 \u00e9 a minha hist\u00f3ria. E no final, atrav\u00e9s da tua vergonha, continuar\u00e1s a ser um pastor. O nosso arrependimento humilde, que permanece em sil\u00eancio, em l\u00e1grimas perante a monstruosidade do pecado e a insond\u00e1vel grandeza do perd\u00e3o de Deus, \u00e9 o in\u00edcio renovado da nossa santidade\u00bb.[7]<\/p>\n<h3>GRATID\u00c3O<\/h3>\n<p>\u00abN\u00e3o cesso de dar gra\u00e7as a Deus por v\u00f3s\u00bb (<i>Ef<\/i>\u00a01, 16)<\/p>\n<p>Mais do que uma escolha nossa, a voca\u00e7\u00e3o \u00e9 resposta a uma chamada gratuita do Senhor. \u00c9 bom voltar uma vez e outra \u00e0quelas passagens evang\u00e9licas, onde vemos Jesus orar, escolher e chamar \u00abpara estarem com Ele e para os enviar a pregar\u00bb (<i>Mc<\/i>\u00a03,14; cf.\u00a0<i>Lc<\/i>\u00a06, 12-13).<\/p>\n<p>Gostaria de lembrar aqui um grande mestre de vida sacerdotal do meu pa\u00eds natal, o padre L\u00facio Gera, que, dirigindo-se a um grupo de sacerdotes em tempos de muitas prova\u00e7\u00f5es na Am\u00e9rica Latina, lhes dizia: \u00abSempre, mas sobretudo nas prova\u00e7\u00f5es, devemos voltar \u00e0queles momentos luminosos em que experimentamos a chamada do Senhor para consagrar toda a nossa vida ao seu servi\u00e7o\u00bb. A isto, apraz-me chamar-lhe \u00aba mem\u00f3ria deuteron\u00f4mica da voca\u00e7\u00e3o\u00bb, que nos permite retornar \u00ab\u00e0quele ponto incandescente em que a gra\u00e7a de Deus me tocou no in\u00edcio do caminho e com aquela centelha posso acender o fogo para o dia de hoje, para cada dia, e levar calor e luz aos meus irm\u00e3os e \u00e0s minhas irm\u00e3s. Daquela centelha, acende-se uma alegria humilde, uma alegria que n\u00e3o ofende o sofrimento e o desespero, uma alegria boa e serena\u00bb.[8]<\/p>\n<p>Um dia pronunciamos um \u00absim\u00bb que nasceu e cresceu no seio duma comunidade crist\u00e3 pela m\u00e3o daqueles santos \u00abao p\u00e9 da porta\u00bb[9] que nos mostraram, com f\u00e9 simples, como valia a pena dar tudo pelo Senhor e o seu Reino. Um \u00absim\u00bb, cujo alcance teve e ter\u00e1 uma transcend\u00eancia insuspeitada, n\u00e3o conseguindo muitas vezes imaginar todo o bem que foi e \u00e9 capaz de gerar. Como \u00e9 belo ver um padre idoso rodeado e visitado por aqueles pequeninos \u2013 hoje adultos \u2013 que ele batizou em seus in\u00edcios e que v\u00eam, com gratid\u00e3o, apresentar-lhe a fam\u00edlia! Ent\u00e3o descobrimos que fomos ungidos para ungir, e a un\u00e7\u00e3o de Deus nunca dececiona e faz-me dizer com o Ap\u00f3stolo: \u00abN\u00e3o cesso de dar gra\u00e7as a Deus por v\u00f3s\u00bb (<i>Ef<\/i>\u00a01, 16) e por todo o bem que fizestes.<\/p>\n<p>Em momentos de dificuldade, fragilidade, bem como de fraqueza e manifesta\u00e7\u00e3o dos nossos limites, quando a pior de todas as tenta\u00e7\u00f5es \u00e9 ficar a ruminar a desola\u00e7\u00e3o,[10] fragmentando o olhar, o ju\u00edzo e o cora\u00e7\u00e3o, nesses momentos \u00e9 importante \u2013 atrever-me-ia a dizer crucial \u2013 n\u00e3o s\u00f3 n\u00e3o perder a mem\u00f3ria agradecida da passagem do Senhor pela nossa vida, a mem\u00f3ria do seu olhar misericordioso que nos convidou a apostar n\u2019Ele e no seu Povo, mas tamb\u00e9m animar-se a p\u00f4-la em pr\u00e1tica e, com o salmista, poder compor o nosso pr\u00f3prio c\u00e2ntico de louvor porque \u00ab\u00e9 eterna a sua miseric\u00f3rdia\u00bb (<i>Sal<\/i>\u00a0136\/135).<\/p>\n<p>A gratid\u00e3o \u00e9 sempre uma \u00abarma poderosa\u00bb. S\u00f3 se formos capazes de contemplar e agradecer concretamente todos os gestos de amor, generosidade, solidariedade e confian\u00e7a, bem como de perd\u00e3o, paci\u00eancia, suporta\u00e7\u00e3o e compaix\u00e3o com que fomos tratados, \u00e9 que deixaremos o Esp\u00edrito obsequiar-nos com aquele ar puro capaz de renovar (e n\u00e3o empachar) a nossa vida e miss\u00e3o. Deixemos que a constata\u00e7\u00e3o de tanto bem recebido fa\u00e7a, \u00e0 semelhan\u00e7a de Pedro na manh\u00e3 da \u00abpesca milagrosa\u00bb, despertar em n\u00f3s a capacidade de deslumbramento e gratid\u00e3o que nos leve a dizer: \u00abAfasta-Te de mim, Senhor, porque sou um homem pecador\u00bb (<i>Lc<\/i>\u00a05, 8) e, mais uma vez, ou\u00e7amos da boca do Senhor a sua chamada: \u00abN\u00e3o tenhas receio; de futuro, ser\u00e1s pescador de homens\u00bb (<i>Lc<\/i>\u00a05, 10); porque \u00ab\u00e9 eterna a sua miseric\u00f3rdia\u00bb.<\/p>\n<p>Irm\u00e3os, obrigado pela vossa fidelidade aos compromissos assumidos. Numa sociedade e numa cultura que transformou o \u00abgasoso\u00bb em valor, \u00e9 verdadeiramente significativa a exist\u00eancia de pessoas que apostem e procurem assumir compromissos que exigem toda a vida. Substancialmente, estamos a dizer que continuamos a acreditar em Deus que nunca quebrou a sua alian\u00e7a, mesmo quando n\u00f3s a quebramos vezes sem conta. Isto convida-nos a celebrar a fidelidade de Deus que, apesar dos nossos limites e pecados, n\u00e3o deixa de confiar, crer e apostar em n\u00f3s, e convida-nos a fazer o mesmo. Cientes de trazer um tesouro em vasos de barro (cf.\u00a0<i>2 Cor<\/i>\u00a04, 7), sabemos que o Senhor Se manifesta vencedor na fraqueza (cf.\u00a0<i>2 Cor<\/i>\u00a012, 9), n\u00e3o deixa de nos sustentar e chamar, dando-nos cem por um (cf.\u00a0<i>Mc<\/i>\u00a010, 29-30), porque \u00ab\u00e9 eterna a sua miseric\u00f3rdia\u00bb.<\/p>\n<p>Obrigado pela alegria com que soubestes entregar a vossa vida, mostrando um cora\u00e7\u00e3o que, ao longo dos anos, lutou e luta para n\u00e3o se tornar mesquinho e amargo, mas ao inv\u00e9s deixar-se ampliar, diariamente, pelo amor de Deus e do seu povo; um cora\u00e7\u00e3o que o tempo, como sucede com o bom vinho, n\u00e3o azedou, mas dotou-o duma qualidade sempre mais requintada; porque \u00ab\u00e9 eterna a sua miseric\u00f3rdia\u00bb.<\/p>\n<p>Obrigado por procurardes refor\u00e7ar os v\u00ednculos de fraternidade e amizade no presbit\u00e9rio e com o vosso bispo, apoiando-vos mutuamente, cuidando de quem est\u00e1 doente, procurando aquele que se isola, encorajando e aprendendo a sabedoria do idoso, partilhando os bens, sabendo rir e chorar juntos\u2026 Como s\u00e3o necess\u00e1rios estes espa\u00e7os! E inclusivamente sendo constantes e perseverantes quando tivestes de assumir alguma miss\u00e3o \u00e1spera ou levar algum irm\u00e3o a assumir as suas responsabilidades; porque \u00ab\u00e9 eterna a sua miseric\u00f3rdia\u00bb.<\/p>\n<p>Obrigado pelo testemunho de perseveran\u00e7a e suporta\u00e7\u00e3o (<i>hypomon\u00e9<\/i>) na dedica\u00e7\u00e3o pastoral, que frequentemente, movidos pela ousadia (<i>parres\u00eda<\/i>) do pastor,[11] nos leva a lutar com o Senhor na ora\u00e7\u00e3o, como Mois\u00e9s naquela corajosa e at\u00e9 arriscada intercess\u00e3o pelo povo (cf.\u00a0<i>Nm<\/i>14, 13-19;\u00a0<i>Ex<\/i>\u00a032, 30-32;\u00a0<i>Dt<\/i>\u00a09, 18-21); porque \u00ab\u00e9 eterna a sua miseric\u00f3rdia\u00bb.<\/p>\n<p>Obrigado por celebrar diariamente a Eucaristia e apascentar com miseric\u00f3rdia no sacramento da Reconcilia\u00e7\u00e3o, sem rigorismos nem laxismos, ocupando-se das pessoas e acompanhando-as no caminho da convers\u00e3o \u00e0 vida nova que o Senhor nos d\u00e1 a todos. Sabemos que, atrav\u00e9s dos degraus da miseric\u00f3rdia, podemos descer at\u00e9 ao ponto mais baixo da nossa condi\u00e7\u00e3o humana \u2013 fragilidade e pecados inclu\u00eddos \u2013 e subir at\u00e9 ao ponto mais alto da perfei\u00e7\u00e3o divina: \u00abSede misericordiosos como o Pai \u00e9 misericordioso\u00bb.[12] E assim ser \u00abcapazes de aquecer o cora\u00e7\u00e3o das pessoas, caminhar com elas na noite, saber dialogar e inclusive adentrar-se na sua noite e obscuridade sem se perder\u00bb;[13] porque \u00ab\u00e9 eterna a sua miseric\u00f3rdia\u00bb.<\/p>\n<p>Obrigado por ungir e anunciar a todos, com ardor, \u00abem tempo prop\u00edcio e fora dele\u00bb (<i>2 Tm<\/i>\u00a04, 2), o Evangelho de Jesus Cristo, sondando o cora\u00e7\u00e3o da pr\u00f3pria comunidade \u00abpara identificar onde est\u00e1 vivo e ardente o desejo de Deus e tamb\u00e9m onde \u00e9 que este di\u00e1logo de amor foi sufocado ou n\u00e3o p\u00f4de dar fruto\u00bb;[14] porque \u00ab\u00e9 eterna a sua miseric\u00f3rdia\u00bb.<\/p>\n<p>Obrigado pelas vezes em que, deixando-vos entranhadamente comover, acolhestes os ca\u00eddos, curastes as feridas, dando calor aos seus cora\u00e7\u00f5es, mostrando ternura e compaix\u00e3o como o samaritano da par\u00e1bola (cf.\u00a0<i>Lc<\/i>\u00a010, 25-37). Nada \u00e9 mais urgente do que isto: proximidade, vizinhan\u00e7a, abeirar-se da carne do irm\u00e3o que sofre. Quanto bem faz o exemplo dum sacerdote que n\u00e3o evita, mas se aproxima das feridas dos seus irm\u00e3os![15] \u00c9 reflexo do cora\u00e7\u00e3o do pastor que aprendeu o gosto espiritual de se sentir um s\u00f3 com o seu povo;[16] que n\u00e3o se esquece que saiu dele e que, s\u00f3 no seu servi\u00e7o, encontrar\u00e1 e poder\u00e1 desenvolver a sua identidade mais pura e plena, que lhe faz cultivar um estilo de vida austero e simples, sem aceitar privil\u00e9gios que n\u00e3o t\u00eam o sabor do Evangelho; porque \u00ab\u00e9 eterna a sua miseric\u00f3rdia\u00bb.<\/p>\n<p>Demos gra\u00e7as tamb\u00e9m pela santidade do Povo fiel de Deus, que somos convidados a apascentar e atrav\u00e9s do qual tamb\u00e9m o Senhor nos apascenta e cuida de n\u00f3s com o dom de poder contemplar este povo \u00abnos pais que criam os seus filhos com tanto amor, nos homens e mulheres que trabalham a fim de trazer o p\u00e3o para casa, nos doentes, nas consagradas idosas que continuam a sorrir. Nesta const\u00e2ncia de continuar a caminhar dia ap\u00f3s dia, vejo a santidade da Igreja militante\u00bb.[17] Agrade\u00e7amos por cada um deles e deixemo-nos ajudar e estimular pelo seu testemunho; porque \u00ab\u00e9 eterna a sua miseric\u00f3rdia\u00bb.<\/p>\n<h3>ARDOR<\/h3>\n<p>\u00abTenham \u00e2nimo nos seus cora\u00e7\u00f5es\u00bb (<i>Col<\/i>\u00a02, 2)<\/p>\n<p>Um segundo grande desejo meu, inspirando-me nas palavras de S\u00e3o Paulo, \u00e9 fazer-vos companhia na renova\u00e7\u00e3o do nosso ardor sacerdotal, fruto sobretudo da a\u00e7\u00e3o do Esp\u00edrito Santo em nossas vidas. Perante experi\u00eancias dolorosas, todos n\u00f3s precisamos de conforto e encorajamento. A miss\u00e3o a que fomos chamados n\u00e3o comporta ser imunes ao sofrimento, \u00e0 dor e at\u00e9 \u00e0 incompreens\u00e3o;[18] pelo contr\u00e1rio, pede-nos para os enfrentar e assumir a fim de deixar que o Senhor os transforme e nos configure mais a Ele. \u00abNo fundo, a falta dum reconhecimento sincero, pesaroso e orante dos nossos limites \u00e9 que impede a gra\u00e7a de atuar melhor em n\u00f3s, pois n\u00e3o lhe deixa espa\u00e7o para provocar aquele bem poss\u00edvel que se integra num caminho sincero e real de crescimento\u00bb.[19]<\/p>\n<p>Um bom \u00abteste\u00bb para saber como est\u00e1 o nosso cora\u00e7\u00e3o de pastor \u00e9 perguntar-se como enfrentamos a dor. Muitas vezes pode acontecer de comportar-se como o levita ou o sacerdote da par\u00e1bola que passam do lado oposto e ignoram o homem que jaz por terra (cf.\u00a0<i>Lc<\/i>10, 31-32). Outros aproximam-se de forma errada, ou seja, intelectualizam o caso refugiando-se em frases comuns tais como \u00aba vida \u00e9 assim\u00bb, \u00abn\u00e3o se pode fazer nada\u00bb, dando lugar ao fatalismo e ao desalento; ou aproximam-se com um leque de prefer\u00eancias seletivas cujo \u00fanico resultado \u00e9 isolamento e exclus\u00e3o. \u00ab\u00c0 semelhan\u00e7a do profeta Jonas, sempre permanece latente em n\u00f3s a tenta\u00e7\u00e3o de fugir para um lugar seguro, que pode ter muitos nomes: individualismo, espiritualismo, confinamento em mundos pequenos\u00bb,[20] os quais, longe de fazer com que as nossas entranhas se comovam, acabam por nos afastar das feridas pr\u00f3prias, das dos outros e, consequentemente, das feridas de Jesus.[21]<\/p>\n<p>Nesta mesma linha, quero assinalar outra postura subtil e perigosa que, como gostava de dizer Bernanos, \u00e9 \u00abo mais precioso dos elixires do dem\u00f3nio\u00bb[22] e a mais nociva para quem deseja servir o Senhor, porque semeia des\u00e2nimo, orfandade e leva ao desespero.[23] Desiludidos com a realidade, com a Igreja ou connosco mesmos, podemos cair na tenta\u00e7\u00e3o de nos apegarmos a uma\u00a0<i>tristeza adocicada<\/i>\u00a0que os padres do Oriente chamavam de ac\u00e9dia. O cardeal Tom\u00e1s Spidlik dizia: \u00abSe nos assalta a tristeza pelo que a vida \u00e9, pela companhia dos outros, porque estamos sozinhos (&#8230;), ent\u00e3o \u00e9 porque temos falta de f\u00e9 na Provid\u00eancia de Deus e na sua obra (&#8230;). A tristeza paralisa o ardor de continuar com o trabalho e com a ora\u00e7\u00e3o, torna-nos antip\u00e1ticos aqueles que vivem ao nosso lado. (&#8230;) Os monges, que dedicam uma longa descri\u00e7\u00e3o a este v\u00edcio, chamam-no o pior inimigo da vida espiritual\u00bb.[24]<\/p>\n<p>Conhecemos esta tristeza que leva \u00e0 habitua\u00e7\u00e3o e pouco a pouco faz-nos ver como natural o mal e a injusti\u00e7a, sussurrando tenuemente \u00absempre se fez assim\u00bb. Tristeza, que torna est\u00e9ril todas as tentativas de transforma\u00e7\u00e3o e convers\u00e3o, espalhando ressentimento e avers\u00e3o. \u00abEsta n\u00e3o \u00e9 a escolha duma vida digna e plena, este n\u00e3o \u00e9 o des\u00edgnio que Deus tem para n\u00f3s, esta n\u00e3o \u00e9 a vida no Esp\u00edrito que jorra do cora\u00e7\u00e3o de Cristo ressuscitado\u00bb[25] e para a qual fomos chamados. Irm\u00e3os, quando esta\u00a0<i>tristeza adocicada<\/i>\u00a0amea\u00e7a tomar conta da nossa vida ou da nossa comunidade, sem nos assustar nem preocupar mas com determina\u00e7\u00e3o, pe\u00e7amos e fa\u00e7amos pedir ao Esp\u00edrito que \u00abvenha despertar-nos, dar-nos um aban\u00e3o na nossa sonol\u00eancia, libertar-nos da in\u00e9rcia. Desafiemos a habitua\u00e7\u00e3o, abramos bem os olhos, os ouvidos e sobretudo o cora\u00e7\u00e3o, para nos deixarmos mover pelo que acontece ao nosso redor e pelo clamor da Palavra viva e eficaz do Ressuscitado\u00bb.[26]<\/p>\n<p>Deixai que vo-lo repita: todos precisamos do conforto e da for\u00e7a de Deus e dos irm\u00e3os em tempos dif\u00edceis. A todos n\u00f3s, s\u00e3o de proveito estas sentidas palavras de S\u00e3o Paulo \u00e0s suas comunidades: \u00abPe\u00e7o-vos que n\u00e3o desanimeis com as tribula\u00e7\u00f5es\u00bb (<i>Ef<\/i>\u00a03,13); \u00abtenham \u00e2nimo nos seus cora\u00e7\u00f5es\u00bb (<i>Col<\/i>\u00a02, 2). Assim, poderemos cumprir a miss\u00e3o que o Senhor nos d\u00e1 cada manh\u00e3: transmitir uma boa nova, \u00abuma grande alegria, que o ser\u00e1 para todo o povo\u00bb (<i>Lc<\/i>\u00a02,10). Mas, aten\u00e7\u00e3o! N\u00e3o como teoria, como conhecimento intelectual ou moral do que deveria ser, mas como homens que, no meio da tribula\u00e7\u00e3o, foram transformados e transfigurados pelo Senhor e, como Job, chegam a exclamar: \u00abOs meus ouvidos tinham ouvido falar de Ti, mas agora veem-Te os meus pr\u00f3prios olhos\u00bb (42, 5). Sem esta experi\u00eancia fundadora, todos os nossos esfor\u00e7os nos levar\u00e3o pelo caminho da frustra\u00e7\u00e3o e do desencanto.<\/p>\n<p>Ao longo da nossa vida, pudemos contemplar como, \u00abcom Jesus Cristo, renasce sem cessar a alegria\u00bb.[27] Embora existam diferentes etapas nesta viv\u00eancia, sabemos que Deus, independentemente das nossas fragilidades e pecados, sempre \u00abnos permite levantar a cabe\u00e7a e recome\u00e7ar, com uma ternura que nunca nos defrauda e sempre nos pode restituir a alegria\u00bb.[28] Esta alegria n\u00e3o nasce dos nossos esfor\u00e7os voluntariosos ou intelectualistas, mas da confian\u00e7a de saber que continuam eficazes as palavras de Jesus a Pedro: no momento em que fores joeirado, n\u00e3o te esque\u00e7as de que \u00abEu roguei por ti, para que a tua f\u00e9 n\u00e3o desfale\u00e7a\u00bb (<i>Lc<\/i>22, 32). O Senhor \u00e9 o primeiro a rezar e lutar por ti e por mim. E convida-nos a entrar plenamente na sua ora\u00e7\u00e3o. Pode at\u00e9 haver momentos em que tenhamos de mergulhar na \u00abora\u00e7\u00e3o do Gets\u00e9mani, a mais humana e mais dram\u00e1tica das ora\u00e7\u00f5es de Jesus (&#8230;). H\u00e1 s\u00faplica, tristeza, ang\u00fastia, quase um desnorteamento (<i>Mc<\/i>\u00a014, 33-42)\u00bb.[29]<\/p>\n<p>Sabemos que n\u00e3o \u00e9 f\u00e1cil permanecer diante do Senhor, deixando que o seu olhar percorra a nossa vida, cure o nosso cora\u00e7\u00e3o ferido e lave os nossos p\u00e9s impregnados pela mundanidade que se lhes aderiu ao longo do caminho e nos impede de caminhar. Na ora\u00e7\u00e3o, experimentamos aquela nossa bendita precariedade que nos lembra que somos disc\u00edpulos carecidos do aux\u00edlio do Senhor e nos liberta da tend\u00eancia prometeuca \u00abde quem, no fundo, s\u00f3 confia nas suas pr\u00f3prias for\u00e7as e se sente superior aos outros por cumprir determinadas normas\u00bb.[30]<\/p>\n<p>Irm\u00e3os, Jesus \u2013 melhor do que ningu\u00e9m \u2013 conhece os nossos esfor\u00e7os e resultados, bem como os fracassos e desvios. \u00c9 o primeiro a dizer-nos: \u00abVinde a Mim, todos os que estais cansados e oprimidos, que Eu hei de aliviar-vos. Tomai sobre v\u00f3s o meu jugo e aprendei de Mim, porque sou manso e humilde de cora\u00e7\u00e3o, e encontrareis descanso para o vosso esp\u00edrito\u00bb (<i>Mt<\/i>\u00a011, 28-29).<\/p>\n<p>Numa ora\u00e7\u00e3o como esta, sabemos que nunca estamos sozinhos. A ora\u00e7\u00e3o do pastor \u00e9 uma ora\u00e7\u00e3o habitada tanto pelo Esp\u00edrito \u00abque clama: \u201cAbb\u00e1! \u2013 Pai!\u201d\u00bb (<i>Gal<\/i>\u00a04, 6) como pelo povo que lhe foi confiado. A nossa miss\u00e3o e identidade compreendem-se a partir desta dupla liga\u00e7\u00e3o.<\/p>\n<p>A ora\u00e7\u00e3o do pastor nutre-se e encarna-se no cora\u00e7\u00e3o do Povo de Deus. Traz as marcas das feridas e alegrias do seu povo, apresentando-as em ora\u00e7\u00e3o silenciosa ao Senhor para que as unja com o dom do Esp\u00edrito Santo. \u00c9 a esperan\u00e7a do pastor que confia e luta para que o Senhor cure a nossa fragilidade, tanto a pessoal como a das nossas comunidades. Mas n\u00e3o percamos de vista que \u00e9 precisamente na ora\u00e7\u00e3o do Povo de Deus que o cora\u00e7\u00e3o do pastor se encarna e encontra o seu lugar. Isto preserva-nos a todos de procurar ou querer respostas f\u00e1ceis, r\u00e1pidas e pr\u00e9-fabricadas, permitindo ao Senhor ser Ele \u2013 e n\u00e3o as nossas receitas e prioridades \u2013 a mostrar-nos um caminho de esperan\u00e7a. N\u00e3o percamos de vista que, nos momentos mais dif\u00edceis da comunidade primitiva (como se l\u00ea no livro dos Atos dos Ap\u00f3stolos), a ora\u00e7\u00e3o tornou-se a verdadeira protagonista.<\/p>\n<p>Irm\u00e3os, reconhe\u00e7amos a nossa fragilidade, sim; mas deixemos que Jesus a transforme e nos projete sempre de novo para a miss\u00e3o. N\u00e3o percamos a alegria de nos sentir \u00abovelhas\u00bb, de saber que Ele \u00e9 o nosso Senhor e Pastor.<\/p>\n<p>Para manter o cora\u00e7\u00e3o animado, \u00e9 necess\u00e1rio n\u00e3o negligenciar estas duas liga\u00e7\u00f5es constitutivas da nossa identidade: com Jesus e com o nosso povo. A primeira liga\u00e7\u00e3o: sempre que nos desligamos de Jesus ou negligenciamos a nossa rela\u00e7\u00e3o com Ele, pouco a pouco a nossa dedica\u00e7\u00e3o vai-se estiolando e as nossas l\u00e2mpadas ficam sem o azeite capaz de iluminar a vida (cf.\u00a0<i>Mt<\/i>\u00a025, 1-13): \u00abTal como o ramo n\u00e3o pode dar fruto por si mesmo, mas s\u00f3 permanecendo na videira, assim tamb\u00e9m acontecer\u00e1 convosco, se n\u00e3o permanecerdes em Mim. (\u2026) Quem permanece em Mim e Eu nele, esse d\u00e1 muito fruto, pois, sem Mim, nada podeis fazer\u00bb (<i>Jo<\/i>\u00a015, 4-5). Neste sentido, gostaria de vos encorajar a que n\u00e3o negligenci\u00e1sseis o acompanhamento espiritual, tendo um irm\u00e3o com quem falar, confrontar-se, debater e discernir, com plena confian\u00e7a e transpar\u00eancia, a prop\u00f3sito do pr\u00f3prio caminho; um irm\u00e3o s\u00e1bio, com quem fazer a experi\u00eancia de se saber disc\u00edpulo. Procurai-o, encontrai-o e gozai a alegria de vos deixardes cuidar, acompanhar e aconselhar. \u00c9 uma ajuda insubstitu\u00edvel para poder viver o minist\u00e9rio, fazendo a vontade do Pai (cf.\u00a0<i>Heb<\/i>\u00a010, 9) e deixar o cora\u00e7\u00e3o palpitar com \u00abos mesmos sentimentos, que est\u00e3o em Cristo Jesus\u00bb (<i>Flp<\/i>\u00a02, 5). Fazem-nos bem estas palavras de Qoh\u00e9let: \u00ab\u00c9 melhor dois do que um s\u00f3 (\u2026). Se ca\u00edrem, um ergue o seu companheiro. Mas ai do solit\u00e1rio que cai: n\u00e3o tem outro para o levantar\u00bb (4, 9-10).<\/p>\n<p>Quanto \u00e0 outra liga\u00e7\u00e3o constitutiva, robustecei e nutri o v\u00ednculo com o vosso povo. N\u00e3o vos isoleis do vosso povo nem dos presbit\u00e9rios ou das comunidades. E menos ainda\u2026 encerrar-vos em grupos fechados e elitistas. Isto, no fim, asfixia e envenena o esp\u00edrito. Um ministro ardoroso \u00e9 um ministro sempre em sa\u00edda; e \u00abestar em sa\u00edda\u00bb leva-nos a caminhar \u00abpor vezes \u00e0 frente, por vezes no meio e outras atr\u00e1s: \u00e0 frente, para guiar a comunidade; no meio, para melhor a compreender, animar e sustentar; atr\u00e1s, para a manter unida, a fim de que ningu\u00e9m se atrase demais, (\u2026) e tamb\u00e9m por outro motivo, ou seja, porque o povo tem intuito! Tem intuito para encontrar novas sendas para o caminho, tem o\u00a0<i>sensus fidei<\/i>\u00a0(cf.\u00a0<i>LG<\/i>\u00a012). Poder\u00e1 existir algo de mais bonito?\u00bb[31] O pr\u00f3prio Jesus \u00e9 modelo desta op\u00e7\u00e3o evangelizadora, que nos introduz no cora\u00e7\u00e3o do povo. Faz-nos bem v\u00ea-Lo perto de todos. A entrega de Jesus na cruz \u00e9 apenas o ponto culminante deste estilo evangelizador que marcou toda a sua exist\u00eancia.<\/p>\n<p>Irm\u00e3os, o sofrimento de tantas v\u00edtimas, o sofrimento do Povo de Deus e nosso tamb\u00e9m, n\u00e3o pode ser em v\u00e3o. \u00c9 o pr\u00f3prio Jesus que carrega todo este peso na sua cruz e nos convida a renovar a nossa miss\u00e3o de estar perto dos que sofrem, de estar sem vergonha perto das mis\u00e9rias humanas e \u2013 por que n\u00e3o? &#8211; viv\u00ea-las como se fossem pr\u00f3prias para as tornar eucaristia.[32] O nosso tempo, marcado por velhas e novas feridas, precisa que sejamos artes\u00e3os de rela\u00e7\u00e3o e comunh\u00e3o, abertos, confiados e esperan\u00e7osos da novidade que o Reino de Deus quer suscitar hoje; um Reino de pecadores perdoados, convidados a testemunhar a compaix\u00e3o sempre viva e ativa do Senhor; \u00abporque \u00e9 eterna a sua miseric\u00f3rdia\u00bb.<\/p>\n<h3>LOUVOR<\/h3>\n<p>\u00abA minha alma glorifica o Senhor\u00bb (<i>Lc<\/i>\u00a01, 46)<\/p>\n<p>\u00c9 imposs\u00edvel falar de gratid\u00e3o e encorajamento sem contemplar Maria. Ela, mulher do cora\u00e7\u00e3o trespassado (cf.\u00a0<i>Lc<\/i>\u00a02, 35), ensina-nos o louvor capaz de abrir o olhar para o futuro e devolver a esperan\u00e7a ao presente. Toda a sua vida ficou condensada no seu c\u00e2ntico de louvor (cf.\u00a0<i>Lc<\/i>\u00a01, 46-55), que somos convidados, tamb\u00e9m n\u00f3s, a entoar como promessa de plenitude.<\/p>\n<p>Sempre que vou a um santu\u00e1rio mariano, gosto de \u00abganhar tempo\u00bb contemplando e deixando-me contemplar pela M\u00e3e, pedindo a confian\u00e7a da crian\u00e7a, do pobre e da pessoa simples que sabe que ali est\u00e1 a sua M\u00e3e e pode mendigar um lugar no seu rega\u00e7o. E enquanto A contemplo, apraz-me ouvir mais uma vez como o \u00edndio Jo\u00e3o Diego: \u00abQue tens, meu filho, o mais pequenino? O que \u00e9 que entristece o teu cora\u00e7\u00e3o? Porventura n\u00e3o estou aqui Eu, que tenho a honra de ser tua m\u00e3e?\u00bb[33]<\/p>\n<p>Contemplar Maria \u00e9 voltar \u00aba acreditar na for\u00e7a revolucion\u00e1ria da ternura e do afeto. N\u2019Ela, vemos que a humildade e a ternura n\u00e3o s\u00e3o virtudes dos fracos, mas dos fortes, que n\u00e3o precisam de maltratar os outros para se sentir importantes\u00bb.[34]<\/p>\n<p>Se alguma vez o olhar come\u00e7ar a insensibilizar-se ou sentirmos que a for\u00e7a sedutora da apatia ou da desola\u00e7\u00e3o quer criar ra\u00edzes e apoderar-se do cora\u00e7\u00e3o; se o gosto de nos sentirmos parte viva e integrante do Povo de Deus come\u00e7a a incomodar-nos dando-nos conta de ser impelidos para uma atitude elitista, n\u00e3o tenhamos medo de contemplar Maria e entoar o seu c\u00e2ntico de louvor.<\/p>\n<p>Se alguma vez nos sentirmos tentados a isolar-nos e fechar-nos em n\u00f3s mesmos e nos nossos projetos protegendo-nos dos caminhos sempre poeirentos da hist\u00f3ria, ou se o lamento, a queixa, a cr\u00edtica ou a ironia tomam conta das nossas a\u00e7\u00f5es sem querer lutar, esperar e amar, olhemos para Maria a fim de que limpe os nossos olhos de toda a \u00abpalheira\u00bb que nos possa impedir de estarmos atentos e despertos para contemplar e celebrar a Cristo que vive no meio do seu Povo. E se virmos que n\u00e3o conseguimos caminhar direito, que nos custa manter os prop\u00f3sitos de convers\u00e3o, digamos-Lhe como A suplicava, quase com cumplicidade, aquele grande p\u00e1roco \u2013 poeta tamb\u00e9m \u2013 da minha diocese anterior: \u00abEsta tarde, Senhora, a promessa \u00e9 sincera. Mas, pelo sim e pelo n\u00e3o, n\u00e3o Te esque\u00e7as de deixar a chave por fora\u00bb.[35] Ela \u00ab\u00e9 a amiga sempre sol\u00edcita para que n\u00e3o falte o vinho na nossa vida. \u00c9 Aquela que tem o cora\u00e7\u00e3o trespassado pela espada, que compreende todas as penas. Como M\u00e3e de todos, \u00e9 sinal de esperan\u00e7a para os povos que sofrem as dores do parto at\u00e9 que germine a justi\u00e7a (&#8230;). Como uma verdadeira m\u00e3e, caminha connosco, luta connosco e aproxima-nos incessantemente do amor de Deus\u00bb.[36]<\/p>\n<p>Irm\u00e3os, mais uma vez vos digo que \u00abn\u00e3o cesso de dar gra\u00e7as a Deus por v\u00f3s\u00bb (<i>Ef<\/i>\u00a01, 16), pela vossa dedica\u00e7\u00e3o e miss\u00e3o, com a certeza de que \u00abDeus remove as pedras mais duras, contra as quais v\u00e3o embater esperan\u00e7as e expetativas: a morte, o pecado, o medo, a mundanidade. A hist\u00f3ria humana n\u00e3o acaba frente a uma pedra sepulcral, j\u00e1 que hoje mesmo descobre a \u201cpedra viva\u201d (cf.\u00a0<i>1 Ped<\/i>\u00a02, 4): Jesus ressuscitado. Como Igreja, estamos fundados sobre Ele e, mesmo quando desfalecemos, mesmo quando somos tentados a julgar tudo a partir dos nossos fracassos, Ele vem fazer novas todas as coisas\u00bb.[37]<\/p>\n<p>Deixemos que seja a gratid\u00e3o a suscitar o louvor e nos encoraje mais uma vez na miss\u00e3o de ungir os nossos irm\u00e3os na esperan\u00e7a; nos encoraje a ser homens que testemunhem com a sua vida a compaix\u00e3o e miseric\u00f3rdia que s\u00f3 Jesus nos pode dar.<\/p>\n<p>Que o Senhor Jesus vos aben\u00e7oe e a Virgem Sant\u00edssima vos guarde. E pe\u00e7o-vos, por favor, que n\u00e3o vos esque\u00e7ais de rezar por mim.<\/p>\n<p>Fraternamente,<\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<i>Francisco<\/i><\/strong><\/p>\n<p><em>Roma, em S\u00e3o Jo\u00e3o de Latr\u00e3o, na Mem\u00f3ria lit\u00fargica do Santo Cura d\u2019Ars, 4 de agosto de 2019.<\/em><\/p>\n<hr \/>\n<p style=\"padding-left: 40px;\">[1] Cf. Carta ap.\u00a0<i>Anno iubilari<\/i>\u00a0(23 de abril de 1929):\u00a0<i>AAS<\/i>\u00a021 (1929), 312-313.<br \/>\n[2] Cf.\u00a0<i>Discurso \u00e0 Confer\u00eancia Episcopal Italiana<\/i>, 20 de maio de 2019. A paternidade espiritual que impele o Bispo a n\u00e3o deixar \u00f3rf\u00e3os os seus presb\u00edteros, pode-se \u00abtocar\u00bb n\u00e3o apenas na capacidade de manter as portas abertas para todos os seus padres, mas tamb\u00e9m em ir procur\u00e1-los para cuidar deles e acompanh\u00e1-los.<br \/>\n[3] Cf. S\u00e3o Jo\u00e3o XXIII, Carta enc.\u00a0<i>Sacerdotii nostri primordia<\/i>, no I centen\u00e1rio do pio tr\u00e2nsito do Santo Cura d\u2019Ars (1 de agosto de 1959):\u00a0<i>AAS<\/i>\u00a051 (1959), 548.<br \/>\n[4] Cf.\u00a0<i>Carta ao Povo de Deus<\/i>\u00a0(20 de agosto de 2018).<br \/>\n[5]\u00a0<i>Encontro com os sacerdotes, religiosos e religiosas, consagrados e seminaristas,\u00a0<\/i>Santiago do Chile, 16 de janeiro de 2018.<br \/>\n[6] Cf.\u00a0<i>Carta ao Povo de Deus que peregrina no Chile<\/i>, 31 de maio de 2018.<br \/>\n[7]\u00a0<i>Encontro com o clero de Roma<\/i>, 7 de mar\u00e7o de 2019.<br \/>\n[8]\u00a0<i>Homilia na Vig\u00edlia Pascal<\/i>, 19 de abril de 2014.<br \/>\n[9] Exort. ap.\u00a0<i>Gaudete et exsultate<\/i>, 7.<br \/>\n[10] Cf. J. M. Bergoglio,\u00a0<i>Cartas da tribula\u00e7\u00e3o<\/i>, Mil\u00e3o, p. 18.<br \/>\n[11] Cf.\u00a0<i>Discurso aos p\u00e1rocos de Roma<\/i>, 6 de mar\u00e7o de 2014.<br \/>\n[12]\u00a0<i>Retiro por ocasi\u00e3o do Jubileu dos Sacerdotes: Primeira Medita\u00e7\u00e3o<\/i>, 2 de junho de 2016.<br \/>\n[13] A. Spadaro, \u00abEntrevista a Papa Francisco\u00bb,\u00a0<i>La Civilt\u00e0 Cattolica<\/i>, n. 3918 (19 de setembro de 2013), p. 462.<br \/>\n[14] Exort. ap.\u00a0<i>Evangelii gaudium<\/i>, 137.<br \/>\n[15] Cf.\u00a0<i>Discurso aos p\u00e1rocos de Roma<\/i>, 6 de mar\u00e7o de 2014.<br \/>\n[16] Cf. Exort. ap.\u00a0<i>Evangelii gaudium<\/i>, 268.<br \/>\n[17] Exort. ap.\u00a0<i>Gaudete et exsultate<\/i>, 7.<br \/>\n[18] Cf. Carta ap.\u00a0<i>Misericordia et misera<\/i>, 13.<br \/>\n[19] Exort. ap.\u00a0<i>Gaudete et exsultate<\/i>, 50.<br \/>\n[20]\u00a0<i>Ibid,<\/i>, 134.<br \/>\n[21] Cf. J. M. Bergoglio,\u00a0<i>Reflex\u00f5es em esperan\u00e7a<\/i>, Cidade do Vaticano, p. 14.<br \/>\n[22]\u00a0<i>Di\u00e1rio dum p\u00e1roco de aldeia<\/i>, Paris 1974, 135; cf. Exort. ap.\u00a0<i>Evangelii gaudium<\/i>, 83.<br \/>\n[23] Cf. Barsanufio,\u00a0<i>Epistol\u00e1rio<\/i>, in: V. Cutro \u2013 M. T. Szwemin,\u00a0<i>Necessidade de paternidade<\/i>, Vars\u00f3via 2018, p. 124.<br \/>\n[24]\u00a0<i>A arte de purificar o cora\u00e7\u00e3o<\/i>, Roma 1999, p. 47.<br \/>\n[25] Exort. ap.\u00a0<i>Evangelii gaudium<\/i>, 2.<br \/>\n[26] Exort. ap.\u00a0<i>Gaudete et exsultate<\/i>, 137.<br \/>\n[27] Exort. ap.\u00a0<i>Evangelii gaudium<\/i>, 1.<br \/>\n[28]\u00a0<i>Ibid.<\/i>, 3.<br \/>\n[29] J. M. Bergoglio,\u00a0<i>Reflex\u00f5es em esperan\u00e7a<\/i>, Cidade do Vaticano, p. 26.<br \/>\n[30] Exort. ap.\u00a0<i>Evangelii gaudium<\/i>, 94.<br \/>\n[31]\u00a0<i>Encontro com o clero, pessoas de vida consagrada e membros de conselhos pastorais<\/i>, Assis, 4 de outubro de 2013.<br \/>\n[32] Cf. Exort. ap.\u00a0<i>Evangelii gaudium<\/i>, 268-270.<br \/>\n[33] J. G. Lamadrid,\u00a0<i>Nican Mopohua<\/i>, ed. Jus, pp. 107.108; 119.<br \/>\n[34] Exort. ap.\u00a0<i>Evangelii gaudium<\/i>, 288.<br \/>\n[35] Cf. A. L. Calori,\u00a0<i>Aula F\u00falgida<\/i>, Buenos Aires 1946.<br \/>\n[36] Exort. ap.\u00a0<i>Evangelii gaudium<\/i>, 286.<br \/>\n[37]\u00a0<i>Homilia na Vig\u00edlia Pascal<\/i>, 20 de abril de 2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carta do Papa Francisco aos presb\u00edteros<\/p>\n","protected":false},"author":3,"featured_media":190248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[232],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta do Papa Francisco aos presb\u00edteros - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta do Papa Francisco aos presb\u00edteros - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Carta do Papa Francisco aos presb\u00edteros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-05T14:10:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-26T20:01:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/08\/mensagem_presbiterio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"473\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"27 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/\",\"name\":\"Carta do Papa Francisco aos presb\u00edteros - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2019-08-05T14:10:41+00:00\",\"dateModified\":\"2021-08-26T20:01:32+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta do Papa Francisco aos presb\u00edteros\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta do Papa Francisco aos presb\u00edteros - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/","og_locale":"pt_BR","og_type":"article","og_title":"Carta do Papa Francisco aos presb\u00edteros - Vida Crist\u00e3 - Franciscanos","og_description":"Carta do Papa Francisco aos presb\u00edteros","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2019-08-05T14:10:41+00:00","article_modified_time":"2021-08-26T20:01:32+00:00","og_image":[{"width":840,"height":473,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2019\/08\/mensagem_presbiterio.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"27 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/","name":"Carta do Papa Francisco aos presb\u00edteros - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2019-08-05T14:10:41+00:00","dateModified":"2021-08-26T20:01:32+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/carta-do-papa-francisco-aos-presbiteros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"Carta do Papa Francisco aos presb\u00edteros"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/1880bdd2c350b735648725ef7614736a","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/moacir\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/180797"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=180797"}],"version-history":[{"count":3,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/180797\/revisions"}],"predecessor-version":[{"id":190250,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/180797\/revisions\/190250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/190248"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=180797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=180797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=180797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}