{"id":141734,"date":"2017-09-26T11:05:51","date_gmt":"2017-09-26T14:05:51","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=141734"},"modified":"2020-05-28T12:45:54","modified_gmt":"2020-05-28T15:45:54","slug":"a-heranca-de-exclusao-na-historia-do-brasil","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/","title":{"rendered":"A heran\u00e7a de exclus\u00e3o na hist\u00f3ria do Brasil"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2017\/09\/debret.jpg\" alt=\"debret\" width=\"820\" height=\"590\" \/><\/p>\n<p><strong>Leonardo Boff (*)<\/strong><\/p>\n<p>O processo de coloniza\u00e7\u00e3o de ontem e de recoloniza\u00e7\u00e3o atual, imposta pelos pa\u00edses centrais, est\u00e1 tendo o seguinte efeito: a produ\u00e7\u00e3o, a consolida\u00e7\u00e3o e o aprofundamento de nossa depend\u00eancia e a fragilidade de nossa democracia, sempre amea\u00e7ada por algum golpe das elites endinheiradas, quando se d\u00e3o conta da ascens\u00e3o das classes populares vistas como amea\u00e7a aos altos n\u00edveis de sua alta acumula\u00e7\u00e3o. Assim foi com o golpe de 2016 atr\u00e1s do qual estavam e est\u00e3o os donos do dinheiro.<\/p>\n<p>H\u00e1 que reconhecer que continuamos periferia de pa\u00edses centrais que desde o s\u00e9culo XVI nos mant\u00e9m a eles atrelados. O Brasil n\u00e3o se sustenta, autonomamente, de p\u00e9. Ele jaz, injustamente, \u201cdeitado eternamente em ber\u00e7o espl\u00eandido\u201d. A maioria da popula\u00e7\u00e3o \u00e9 composta de sobreviventes de uma grande tribula\u00e7\u00e3o hist\u00f3rica de submetimento e de marginaliza\u00e7\u00e3o.<\/p>\n<p>A Casa grande e a Senzala constituem os gonzos te\u00f3ricos articuladores de todo o edif\u00edcio social. A maioria dos moradores da Senzala, entretanto, ainda n\u00e3o descobriu que a opul\u00eancia da Casa Grande foi constru\u00edda, com seu trabalho super-explorado, com seu sangue e com suas vidas absolutamente desgastadas.<\/p>\n<p>Nunca tivemos uma Bastilha que derrubasse os donos seculares do poder e do privil\u00e9gio e permitisse a emerg\u00eancia de um outro sujeito de poder, capaz de moldar a sociedade brasileira de forma que todos pudessem caber nela. As classes abastadas praticaram a concilia\u00e7\u00e3o entre elas, excluindo sempre o povo. O jogo nunca se mudou, apenas embaralham-se diferentemente as cartas do mesmo e \u00fanico baralho como o mostrou Marcel Burztyn, O pa\u00eds das alian\u00e7as, as elites e o continu\u00edsmo no Brasil (1990) e mais recentemente por Jess\u00e9 de Souza: \u201cAtraso das elites: da escravid\u00e3o at\u00e9 hoje em dia\u201d (2017).<\/p>\n<p>A fil\u00f3sofa Marilena Chau\u00ed resumiu sinteticamente o legado perverso desta heran\u00e7a: \u201cA sociedade brasileira \u00e9 uma sociedade autorit\u00e1ria, sociedade violenta, possui uma economia predat\u00f3ria de recursos humanos e naturais, convivendo com naturalidade com a injusti\u00e7a, a desigualdade, a aus\u00eancia de liberdade e com os espantosos \u00edndices das v\u00e1rias formas institucionalizadas \u2013 formais e informais \u2013 de exterm\u00ednio f\u00edsico e ps\u00edquico e de exclus\u00e3o social, pol\u00edtica e cultural\u201d (500 anos, cultura e pol\u00edtica no Brasil, 1993, p. 51-52). O golpe parlamentar, jur\u00eddico e medi\u00e1tico de 2016 se inscreve nesta tradi\u00e7\u00e3o.<\/p>\n<p>A ordem capitalista se encontra absolutamente hegem\u00f4nica no cen\u00e1rio da hist\u00f3ria, sem oposi\u00e7\u00e3o ou alternativa imediata a ela.<\/p>\n<p>Como nunca antes, a ordem e a cultura do capital mostram inequivocamente o seu rosto inumano, criando absurda concentra\u00e7\u00e3o de riqueza \u00e0 custa da devasta\u00e7\u00e3o da natureza, da exaust\u00e3o da for\u00e7a de trabalho e de uma estarrecedora pobreza mundial.<\/p>\n<p>H\u00e1 crescimento\/desenvolvimento sem trabalho porque a utiliza\u00e7\u00e3o crescente da informatiza\u00e7\u00e3o e da robotiza\u00e7\u00e3o dispensa o trabalho humano e cria os desempregados estruturais, hoje totalmente descart\u00e1veis. E somam-se aos milh\u00f5es nos pa\u00edses centrais e entre n\u00f3s, particularmente, ap\u00f3s o golpe parlamentar de 2016.<\/p>\n<p>O mercado mundial, caracterizado por uma concorr\u00eancia feroz, \u00e9 profundamente vitimat\u00f3rio. Quem est\u00e1 no mercado existe, quem n\u00e3o resiste, desiste, inexiste e deixa de existir. Os pa\u00edses pobres passam da depend\u00eancia para a prescind\u00eancia. S\u00e3o exclu\u00eddos da nova ordem-desordem mundial e entregues a sua pr\u00f3pria mis\u00e9ria como a \u00c1frica ou ent\u00e3o incorporados de forma subalterna como os pa\u00edses latino-americanos, notadamente, o Brasil do golpe parlamentar.<\/p>\n<p>Os inclu\u00eddos de forma agregada assistem a um drama terr\u00edvel. Veem criar-se dentro deles ilhas de bem-estar material com todas as vantagens dos pa\u00edses centrais, atendendo a cerca de 30% da popula\u00e7\u00e3o ao lado de um mar de mis\u00e9ria e de exclus\u00e3o das grandes maiorias que no Brasil alcan\u00e7am mais da metade da popula\u00e7\u00e3o. Eis a perversidade da ordem do capital, um sistema de antivida como frequentemente o tem incriminado o Papa Francisco.<\/p>\n<p>N\u00e3o devemos poupar-lhe a dureza das palavras, pois a taxa de iniquidade social para grande parte da humanidade se apresenta insustent\u00e1vel para um senso de uma \u00e9tica m\u00ednima e de compaix\u00e3o solid\u00e1ria.<\/p>\n<p>Uma raz\u00e3o a mais para nos convencermos de que n\u00e3o h\u00e1 futuro para o Brasil inserido nesta forma na globaliza\u00e7\u00e3o econ\u00f4mico-financeira, excludente e destruidora da esperan\u00e7a como est\u00e1 sendo imposta com a m\u00e1xima celeridade pelo novo governo ileg\u00edtimo.<\/p>\n<p>H\u00e1 que se buscar um outro paradigma diferente e alternativo n\u00e3o s\u00f3 para o Brasil mas para o mundo. Lentamente est\u00e1 sendo gestado nos movimentos de base e em sectores progressistas do mundo inteiro com sensibilidade ecol\u00f3gico-social, fundada no cuidado e na responsabilidade coletiva. Caso contr\u00e1rio podemos ser conduzidos por um caminho sem retorno.<\/p>\n<p><strong>(*) Leonardo Boff \u00e9 articulista do JB on line e escreveu: A Grande Transforma\u00e7\u00e3o na sociedade, na economia e da ecologia,2014.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Leonardo Boff<\/p>\n","protected":false},"author":1,"featured_media":141735,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A heran\u00e7a de exclus\u00e3o na hist\u00f3ria do Brasil - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A heran\u00e7a de exclus\u00e3o na hist\u00f3ria do Brasil - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Leonardo Boff\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-26T14:05:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-28T15:45:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2018\/10\/debret.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/\",\"name\":\"A heran\u00e7a de exclus\u00e3o na hist\u00f3ria do Brasil - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2017-09-26T14:05:51+00:00\",\"dateModified\":\"2020-05-28T15:45:54+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A heran\u00e7a de exclus\u00e3o na hist\u00f3ria do Brasil\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A heran\u00e7a de exclus\u00e3o na hist\u00f3ria do Brasil - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/","og_locale":"pt_BR","og_type":"article","og_title":"A heran\u00e7a de exclus\u00e3o na hist\u00f3ria do Brasil - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Leonardo Boff","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2017-09-26T14:05:51+00:00","article_modified_time":"2020-05-28T15:45:54+00:00","og_image":[{"width":820,"height":590,"url":"https:\/\/franciscanos.org.br\/vidacrista\/wp-content\/uploads\/2018\/10\/debret.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/","name":"A heran\u00e7a de exclus\u00e3o na hist\u00f3ria do Brasil - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2017-09-26T14:05:51+00:00","dateModified":"2020-05-28T15:45:54+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/a-heranca-de-exclusao-na-historia-do-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"A heran\u00e7a de exclus\u00e3o na hist\u00f3ria do Brasil"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/141734"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=141734"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/141734\/revisions"}],"predecessor-version":[{"id":184916,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/141734\/revisions\/184916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media\/141735"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=141734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=141734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=141734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}