{"id":120270,"date":"2016-11-09T14:12:25","date_gmt":"2016-11-09T16:12:25","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=120270"},"modified":"2020-05-29T09:55:55","modified_gmt":"2020-05-29T12:55:55","slug":"trump-e-o-muro-francisco-e-a-ponte","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/","title":{"rendered":"Trump \u00e9 o muro, Francisco \u00e9 a ponte"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2016\/11\/eleicao.jpg\" alt=\"eleicao\" width=\"812\" height=\"397\" \/><\/p>\n<p><strong>Roberto Malvezzi\u00a0<\/strong><\/p>\n<p>Francisco j\u00e1 repetiu v\u00e1rias vezes que estamos numa 3\u00aa Guerra Mundial. Sua opini\u00e3o n\u00e3o \u00e9 fantasiosa ou irrespons\u00e1vel. Ele \u00e9 a \u00fanica lideran\u00e7a mundial que tem uma leitura do momento atual da humanidade.<\/p>\n<p>Francisco fala a partir da guerra na S\u00edria, no Afeganist\u00e3o, em outras partes do mundo e, sobretudo, a partir das v\u00edtimas das guerras, dos imigrantes e \u201cdesplazados\u201d pelas cat\u00e1strofes socioambientais. Fala a partir dos sem-teto, sem-terra e sem trabalho. Lembra ainda dos idosos, dos doentes, das crian\u00e7as, dos descartados da sociedade contempor\u00e2nea.<\/p>\n<p>Fala a partir das indiferen\u00e7as, dos ego\u00edsmos, dos isolacionismos, dos fascismos de toda ordem. De uma sociedade baseada no consumismo, de um \u201cproducionismo\u201d que faz da Terra uma lixeira.<\/p>\n<p>Mesmo assim n\u00e3o se desespera. Diz que movimentos sociais do mundo inteiro, na\u00e7\u00f5es ind\u00edgenas, lutadores da paz e da justi\u00e7a s\u00e3o a esperan\u00e7a. Ele se re\u00fane com eles, os convida a lutarem para superar a ditadura do dinheiro. Prop\u00f5e a solidariedade, a partilha, a fraternidade, o acolhimento do diferente e o cuidado com a Terra como caminho para a paz.<\/p>\n<p>Se Hillary tem liga\u00e7\u00e3o com a ind\u00fastria das armas, se ajudou montar o golpe no Brasil, agora pouco interessa. Com a elei\u00e7\u00e3o de Trump, a humanidade revela sua face mais alucinante. Quem det\u00e9m a fabulosa riqueza j\u00e1 produzida se mostra desesperado em salvaguardar sua \u201cqualidade de vida\u201d. O modo \u00e9 a guerra, as discrimina\u00e7\u00f5es, os xenofobismos, os muros, a elimina\u00e7\u00e3o do outro, do diferente, daqueles que s\u00e3o os bodes expiat\u00f3rios, para serem demonizados e responsabilizados pelas insanidades de quem tem o comando. Por\u00e9m, nenhuma na\u00e7\u00e3o sozinha hoje comanda a humanidade.<\/p>\n<p>Trump \u00e9 o muro, Francisco \u00e9 a ponte.<\/p>\n<p><strong>Publicado em:\u00a0<a href=\"http:\/\/robertomalvezzi.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/robertomalvezzi.com.br\/<\/a><\/strong><\/p>\n<blockquote><p><strong>Roberto Malvezzi (\u201cGog\u00f3\u201d),<\/strong> nasceu em 1953, no munic\u00edpio de Potirendaba, S\u00e3o Paulo. \u00c9 graduado em Estudos Sociais e em Filosofia pela Faculdade Salesiana de Filosofia, Ci\u00eancias e Letras de Lorena, em S\u00e3o Paulo. Tamb\u00e9m \u00e9 graduado em Teologia pelo Instituto Teol\u00f3gico de S\u00e3o Paulo. Chegou ao interior da Bahia em Janeiro de 1979, para ficar um m\u00eas nas comunidades rurais de Campo Alegre de Lourdes, divisa com o Piau\u00ed. Era um trabalho organizado pela par\u00f3quia da cidade.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Artigo de Roberto Malvezzi <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump \u00e9 o muro, Francisco \u00e9 a ponte - Vida Crist\u00e3 - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump \u00e9 o muro, Francisco \u00e9 a ponte - Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Artigo de Roberto Malvezzi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/\" \/>\n<meta property=\"og:site_name\" content=\"Vida Crist\u00e3 - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-09T16:12:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-29T12:55:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2016\/11\/eleicao.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/\",\"name\":\"Vida Crist\u00e3 - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/\",\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/\",\"name\":\"Trump \u00e9 o muro, Francisco \u00e9 a ponte - Vida Crist\u00e3 - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#website\"},\"datePublished\":\"2016-11-09T16:12:25+00:00\",\"dateModified\":\"2020-05-29T12:55:55+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/vidacrista\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump \u00e9 o muro, Francisco \u00e9 a ponte\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump \u00e9 o muro, Francisco \u00e9 a ponte - Vida Crist\u00e3 - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/","og_locale":"pt_BR","og_type":"article","og_title":"Trump \u00e9 o muro, Francisco \u00e9 a ponte - Vida Crist\u00e3 - Franciscanos","og_description":"Artigo de Roberto Malvezzi","og_url":"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/","og_site_name":"Vida Crist\u00e3 - Franciscanos","article_published_time":"2016-11-09T16:12:25+00:00","article_modified_time":"2020-05-29T12:55:55+00:00","og_image":[{"url":"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2016\/11\/eleicao.jpg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website","url":"https:\/\/franciscanos.org.br\/vidacrista\/","name":"Vida Crist\u00e3 - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/vidacrista\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/","url":"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/","name":"Trump \u00e9 o muro, Francisco \u00e9 a ponte - Vida Crist\u00e3 - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#website"},"datePublished":"2016-11-09T16:12:25+00:00","dateModified":"2020-05-29T12:55:55+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/vidacrista\/trump-e-o-muro-francisco-e-a-ponte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/vidacrista\/"},{"@type":"ListItem","position":2,"name":"Trump \u00e9 o muro, Francisco \u00e9 a ponte"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/133632ca93cec555316a35f76ab4153b","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/vidacrista\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/vidacrista\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/120270"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/comments?post=120270"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/120270\/revisions"}],"predecessor-version":[{"id":184995,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/posts\/120270\/revisions\/184995"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/media?parent=120270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/categories?post=120270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/vidacrista\/wp-json\/wp\/v2\/tags?post=120270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}