{"id":6598,"date":"2011-11-23T16:17:32","date_gmt":"2011-11-23T16:17:32","guid":{"rendered":"http:\/\/new.franciscanos.org.br\/?p=6598"},"modified":"2018-11-12T11:23:58","modified_gmt":"2018-11-12T13:23:58","slug":"o-senhor-nos-fala-na-caminhada","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/","title":{"rendered":"O Senhor nos fala na caminhada"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Documentos da Ordem<\/p>\n","protected":false},"author":1,"featured_media":160428,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O Senhor nos fala na caminhada - Quem Somos - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Senhor nos fala na caminhada - Quem Somos - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Documentos da Ordem\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/\" \/>\n<meta property=\"og:site_name\" content=\"Quem Somos - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-23T16:17:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-12T13:23:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/quemsomos\/wp-content\/uploads\/2011\/11\/2042_180412-150x78-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"78\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/\",\"url\":\"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/\",\"name\":\"O Senhor nos fala na caminhada - Quem Somos - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/quemsomos\/#website\"},\"datePublished\":\"2011-11-23T16:17:32+00:00\",\"dateModified\":\"2018-11-12T13:23:58+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/quemsomos\/#\/schema\/person\/6da599b8d75dc0039c6cb2f57ca9ee82\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/quemsomos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Senhor nos fala na caminhada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/quemsomos\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/quemsomos\/\",\"name\":\"Quem Somos - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/quemsomos\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/quemsomos\/#\/schema\/person\/6da599b8d75dc0039c6cb2f57ca9ee82\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/quemsomos\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/quemsomos\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Senhor nos fala na caminhada - Quem Somos - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/","og_locale":"pt_BR","og_type":"article","og_title":"O Senhor nos fala na caminhada - Quem Somos - Franciscanos","og_description":"Documentos da Ordem","og_url":"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/","og_site_name":"Quem Somos - Franciscanos","article_published_time":"2011-11-23T16:17:32+00:00","article_modified_time":"2018-11-12T13:23:58+00:00","og_image":[{"width":150,"height":78,"url":"https:\/\/franciscanos.org.br\/quemsomos\/wp-content\/uploads\/2011\/11\/2042_180412-150x78-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/","url":"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/","name":"O Senhor nos fala na caminhada - Quem Somos - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/quemsomos\/#website"},"datePublished":"2011-11-23T16:17:32+00:00","dateModified":"2018-11-12T13:23:58+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/quemsomos\/#\/schema\/person\/6da599b8d75dc0039c6cb2f57ca9ee82"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/quemsomos\/o-senhor-nos-fala-na-caminhada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/quemsomos\/"},{"@type":"ListItem","position":2,"name":"O Senhor nos fala na caminhada"}]},{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/quemsomos\/#website","url":"https:\/\/franciscanos.org.br\/quemsomos\/","name":"Quem Somos - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/quemsomos\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/quemsomos\/#\/schema\/person\/6da599b8d75dc0039c6cb2f57ca9ee82","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/quemsomos\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/quemsomos\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/quemsomos\/wp-json\/wp\/v2\/posts\/6598"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/quemsomos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/quemsomos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/quemsomos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/quemsomos\/wp-json\/wp\/v2\/comments?post=6598"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/quemsomos\/wp-json\/wp\/v2\/posts\/6598\/revisions"}],"predecessor-version":[{"id":160429,"href":"https:\/\/franciscanos.org.br\/quemsomos\/wp-json\/wp\/v2\/posts\/6598\/revisions\/160429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/quemsomos\/wp-json\/wp\/v2\/media\/160428"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/quemsomos\/wp-json\/wp\/v2\/media?parent=6598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/quemsomos\/wp-json\/wp\/v2\/categories?post=6598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/quemsomos\/wp-json\/wp\/v2\/tags?post=6598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}