{"id":9328,"date":"2011-12-15T09:25:17","date_gmt":"2011-12-15T11:25:17","guid":{"rendered":"http:\/\/new.franciscanos.org.br\/?p=9328"},"modified":"2020-03-19T11:05:27","modified_gmt":"2020-03-19T14:05:27","slug":"memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html","title":{"rendered":"Mem\u00f3ria da Arte franciscana na cidade do Rio de Janeiro"},"content":{"rendered":"<p><a href=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2011\/12\/1525_151211.jpg\"><br \/>\n<\/a>Foi lan\u00e7ado no dia 8 de dezembro, no Convento Santo Ant\u00f4nio do Rio de Janeiro, o livro \u201cMem\u00f3ria da Arte Franciscana na Cidade do Rio de Janeiro: convento e Igreja de Santo Ant\u00f4nio e Igreja da Ordem Terceira de S\u00e3o Francisco da Penit\u00eancia&#8221;, dos autores Anna Maria Fausto Monteiro de Carvalho, Rosa Maria Costa Ribeiro e Cesar Augusto Tovar Silva, professores do Curso de Especializa\u00e7\u00e3o em Hist\u00f3ria da Arte e Arquitetura no Brasil, da PUC-Rio, que dedicaram cinco anos ao projeto. A obra contou com a participa\u00e7\u00e3o do pesquisador e muse\u00f3logo Frei Roger Brun\u00f3rio, da Prov\u00edncia da Imaculada Concei\u00e7\u00e3o, e tem edi\u00e7\u00e3o bil\u00edngue, oferecendo ainda com 250 imagens, entre fotos atuais, reprodu\u00e7\u00f5es de obras de viajantes, mapas de \u00e9poca e plantas de arquitetura.<\/p>\n<p>O livro descreve em min\u00facias os espa\u00e7os das constru\u00e7\u00f5es, o contexto e as mudan\u00e7as de suas muitas reformas e mesmo epis\u00f3dios mais recentes, como as escava\u00e7\u00f5es da d\u00e9cada de 1980, que trouxeram \u00e0 tona um acervo de quatro mil pe\u00e7as. S\u00e3o cap\u00edtulos inteiros tamb\u00e9m dedicados \u00e0 talha, \u00e0 imagin\u00e1ria, \u00e0 pintura e \u00e0 azulejaria, artes por excel\u00eancia da decora\u00e7\u00e3o dos interiores das igrejas e capelas do Brasil colonial. Al\u00e9m, claro, da hist\u00f3ria da pr\u00f3pria Ordem Franciscana.<\/p>\n<p>O livro registra ainda todo o processo de revitaliza\u00e7\u00e3o do complexo arquitet\u00f4nico e seu entorno. A publica\u00e7\u00e3o marca a estreia da editora Artway, dedicada \u00e0 mem\u00f3ria da arte no Rio de Janeiro.<\/p>\n<p>Segundo Ant\u00f4nio Edmilson Martins Rodrigues, professor da PUC-Rio, a import\u00e2ncia hist\u00f3rica e art\u00edstica do objeto tratado nesta obra fez com que a equipe de pesquisadores definisse como refer\u00eancias temporais o per\u00edodo que compreende o s\u00e9culo XVII at\u00e9 a segunda d\u00e9cada do s\u00e9culo XIX. Ele \u00e9 justificado porque abrange a doa\u00e7\u00e3o aos franciscanos do morro Santo Ant\u00f4nio, com a constru\u00e7\u00e3o de sua casa-ermida e da capela inicial dos Irm\u00e3os Terceiros e o momento de maior prest\u00edgio da Ordem Franciscana, quando foram modificados o convento e sua igreja e constru\u00eddos a igreja e o cemit\u00e9rio da Penit\u00eancia. Este \u00faltimo marco coincide com a presen\u00e7a da Fam\u00edlia Real portuguesa na cidade e no papel que a Ordem e as constru\u00e7\u00f5es desempenharam no espa\u00e7o pol\u00edtico e cultural do Rio de Janeiro.<\/p>\n<p><a href=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2011\/12\/1525_151211.jpg\"><img loading=\"lazy\" class=\"alignleft\" title=\"Capa livro\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2011\/12\/1525_151211.jpg\" alt=\"\" width=\"300\" height=\"336\" \/><\/a>Para o guardi\u00e3o do Convento Santo Ant\u00f4nio, Frei Ivo M\u00fcller, este &#8220;bel\u00edssimo livro, al\u00e9m de resgatar elementos da hist\u00f3ria franciscana, da vida conventual e social, abre o universo do conhecimento para entender todo o complexo arquitet\u00f4nico com a sua mais variada express\u00e3o hist\u00f3rica e art\u00edstica. \u00c9, sem d\u00favida, a partir desse estudo que o leitor poder\u00e1 entender uma gama de significados simb\u00f3licos, espaciais e art\u00edsticos expressos nas capelas do claustro, na igreja conventual e nos demais espa\u00e7os ora reserva os aos religiosos&#8221;, explica Frei Ivo, acrescentando que &#8220;n\u00f3s, franciscanos, temos o compromisso de conservar e preservar este patrim\u00f4nio que \u00e9 ao mesmo tempo religioso e cultural&#8221;.<\/p>\n<p>Frei Clar\u00eancio Neotti, que foi o guardi\u00e3o anterior do Convento, conta como nasceu o projeto antes de o Convento celebrar 400 anos em 2008. &#8220;Sab\u00edamos que n\u00e3o pod\u00edamos ficar apenas numa celebra\u00e7\u00e3o interna nem apenas prolong\u00e1-la numa festa local. O Convento Santo Ant\u00f4nio \u00e9 o maior e mais valoroso monumento franciscano da cidade do Rio de Janeiro, com uma vantagem excepcional: ter sido sempre habitado pela mesma fam\u00edlia franciscana. Algumas decis\u00f5es est\u00e1vamos, ent\u00e3o, tomando: o invent\u00e1rio e a cataloga\u00e7\u00e3o oficial dos bens art\u00edsticos, um projeto de restauro e de revitaliza\u00e7\u00e3o de todo o Morro de Santo Ant\u00f4nio, onde, al\u00e9m do Convento, se situava e se situa a mais velha igreja do Rio de Janeiro (a de Santo Ant\u00f4nio) e a mais completa igreja barroca do Brasil (a da Ordem Terceira de S\u00e3o Francisco da Penit\u00eancia). Foi nesse momento de elabora\u00e7\u00e3o de planos que algum anjo ser\u00e1fico iluminou e trouxe ao Convento a professora e historiadora de arte Anna Maria Monteiro de Carvalho. Trazia a proposta de um aprofundado estudo sobre o Convento, que seria feito por especialistas da Pontif\u00edcia Universidade Cat\u00f3lica do Rio de Janeiro nos campos da espiritualidade, hist\u00f3ria, cultura e arte. Anna me garantia a seriedade das pesquisas. Eu abriria as portas do monumento aos pesquisadores. Juntos sair\u00edamos \u00e0 procura de parceiros financiadores do trabalho&#8221;, conta Frei Clar\u00eancio. O livro tem o patroc\u00ednio do BNDES, Piraqu\u00ea e Minist\u00e9rio da Cultura.<\/p>\n<p>Segundo Frei Clar\u00eancio, n\u00e3o foi poss\u00edvel concluir o livro em 2008. &#8220;Artistas, cientistas e m\u00edsticos n\u00e3o podem ser pressionados pelo tempo. Suas obras, por\u00e9m, costumam perdurar e marcar os tempos&#8221;.<\/p>\n<p>Frei Clar\u00eancio tem raz\u00e3o. O livro resgata a mem\u00f3ria do Rio de Janeiro: o papel que teve, na sua cultura e sociedade, o complexo arquitet\u00f4nico do Convento de Santo Ant\u00f4nio e da Ordem Terceira de S\u00e3o Francisco da Penit\u00eancia, situados no atual Largo da Carioca. Trata-se de um registro \u00e0 altura de sua grandiosidade.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cultura Franciscana<\/p>\n","protected":false},"author":1,"featured_media":210824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[1604],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mem\u00f3ria da Arte franciscana na cidade do Rio de Janeiro - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mem\u00f3ria da Arte franciscana na cidade do Rio de Janeiro - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Cultura Franciscana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-15T11:25:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-19T14:05:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2011\/12\/1525_151211.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2011\/12\/1525_151211.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2011\/12\/1525_151211.jpg\",\"width\":273,\"height\":182},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html\",\"name\":\"Mem\u00f3ria da Arte franciscana na cidade do Rio de Janeiro - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html#primaryimage\"},\"datePublished\":\"2011-12-15T11:25:17+00:00\",\"dateModified\":\"2020-03-19T14:05:27+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mem\u00f3ria da Arte franciscana na cidade do Rio de Janeiro\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mem\u00f3ria da Arte franciscana na cidade do Rio de Janeiro - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html","og_locale":"pt_BR","og_type":"article","og_title":"Mem\u00f3ria da Arte franciscana na cidade do Rio de Janeiro - Not\u00edcias - Franciscanos","og_description":"Cultura Franciscana","og_url":"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2011-12-15T11:25:17+00:00","article_modified_time":"2020-03-19T14:05:27+00:00","og_image":[{"width":273,"height":182,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2011\/12\/1525_151211.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2011\/12\/1525_151211.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2011\/12\/1525_151211.jpg","width":273,"height":182},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html","name":"Mem\u00f3ria da Arte franciscana na cidade do Rio de Janeiro - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html#primaryimage"},"datePublished":"2011-12-15T11:25:17+00:00","dateModified":"2020-03-19T14:05:27+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/memoria-da-arte-franciscana-na-cidade-do-rio-de-janeiro.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Mem\u00f3ria da Arte franciscana na cidade do Rio de Janeiro"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/9328"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=9328"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/9328\/revisions"}],"predecessor-version":[{"id":221949,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/9328\/revisions\/221949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/210824"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=9328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=9328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=9328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}