{"id":79157,"date":"2015-02-10T07:35:21","date_gmt":"2015-02-10T09:35:21","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=79157"},"modified":"2020-06-24T11:59:49","modified_gmt":"2020-06-24T14:59:49","slug":"frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html","title":{"rendered":"Frei Jos\u00e9 e os novos desafios da Miss\u00e3o de Angola"},"content":{"rendered":"<p><strong><a href=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2015\/02\/8205.jpg\"><img loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2015\/02\/8205.jpg\" alt=\"820\" width=\"461\" height=\"261\" \/><\/a><\/strong><\/p>\n<p><strong>Moacir Beggo<\/strong><\/p>\n<p><em>O presidente da Funda\u00e7\u00e3o Imaculada M\u00e3e de Deus de Angola, Frei Jos\u00e9 Ant\u00f4nio dos Santos, hoje tem como palavra-chave de sua rotina o verbo CONSOLIDAR. \u00c9 com esse pensamento que ele participa da consolida\u00e7\u00e3o do belo trabalho mission\u00e1rio da Funda\u00e7\u00e3o, ou seja, fazer com que o j\u00e1 foi realizado durante estes 25 anos de presen\u00e7a franciscana consiga produzir frutos em terras angolanas. Os frutos, contudo, s\u00e3o abundantes como se pode ver pelo celeiro vocacional que se tornou a Miss\u00e3o nos \u00faltimos anos. Nesta entrevista, Frei Jos\u00e9 Ant\u00f4nio fala do passado, do presente e do futuro da Miss\u00e3o. Acompanhe!<\/em><\/p>\n<p><strong><a href=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2015\/02\/logo-angola.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-79160\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2015\/02\/logo-angola.jpg\" alt=\"logo-angola\" width=\"127\" height=\"129\" \/><\/a>Site Franciscanos<\/strong> &#8211; <em>Que cen\u00e1rio religioso, pol\u00edtico e social o sr. encontrou em Angola quando chegou como mission\u00e1rio h\u00e1 14 anos?<\/em><\/p>\n<p><strong>Frei Jos\u00e9 Ant\u00f4nio dos Santos<\/strong> &#8211; Todo o cen\u00e1rio politico, religioso e social era marcado pela guerra civil, que se estendia j\u00e1 por v\u00e1rios anos, com momentos de maior ou menor intensidade. A guerra destruiu, al\u00e9m das estruturas f\u00edsicas, tamb\u00e9m muito das estruturas familiares, com o constante deslocamento das fam\u00edlias e, dessa forma, muito das refer\u00eancias culturais. Os v\u00e1rios anos de guerra determinaram a realidade pol\u00edtica fortemente marcada pela desconfian\u00e7a que impedia qualquer tipo empreendimento e, portanto, dificultava o avan\u00e7o econ\u00f4mico e social do pa\u00eds. As estradas eram prec\u00e1rias, impedindo a livre circula\u00e7\u00e3o de mercadorias, por vezes at\u00e9 mesmo os produtos mais b\u00e1sicos. O ambiente religioso era bastante intenso. Lembro-me de uma prece que era repetida ao final de todas as missas e celebra\u00e7\u00f5es lit\u00fargicas. Era uma s\u00faplica pela paz. O povo repetia aquelas palavras em voz alta e forte. A vibra\u00e7\u00e3o presente na ora\u00e7\u00e3o demonstrava a esperan\u00e7a que todos tinham de que, um dia, a paz iria chegar.<\/p>\n<p><strong>Site Franciscanos<\/strong><em>\u00a0&#8211; O que mudou neste tempo?<\/em><\/p>\n<p><strong>Frei Jos\u00e9<\/strong> &#8211; Acredito que \u00e9 poss\u00edvel afirmar que quase tudo mudou. Sa\u00edmos de um per\u00edodo marcado pela guerra que destruiu todo o pa\u00eds, para um momento de grandes esperan\u00e7as na reconstru\u00e7\u00e3o. H\u00e1 um avan\u00e7o muito grande na reforma e amplia\u00e7\u00e3o das cidades, constru\u00e7\u00e3o de moradias populares, hospitais, escolas etc. Acredito que o grande desafio neste momento \u00e9 a manuten\u00e7\u00e3o de tudo o que est\u00e1 sendo feito. Quando terminou a guerra, o governo sugeriu que a Igreja ajudasse no processo de reconstru\u00e7\u00e3o nacional, sobretudo no setor da educa\u00e7\u00e3o e da sa\u00fade. A Igreja realmente tem procurado ajudar nestas duas \u00e1reas. Nossa miss\u00e3o franciscana tem se envolvido neste processo, sobretudo, atrav\u00e9s das escolas paroquiais, que acolhem as crian\u00e7as e adolescentes mais carentes que, de outra forma, muito possivelmente, ficariam sem estudar.<\/p>\n<p><strong>Site Franciscanos<\/strong><em>\u00a0&#8211; Que balan\u00e7o o sr. faz deste trabalho na miss\u00e3o?<\/em><\/p>\n<p><strong>Frei Jos\u00e9<\/strong> &#8211; O balan\u00e7o \u00e9 positivo. Inicialmente, havia muita expectativa em torno do que fazer e como fazer. Fui enviado para a fraternidade do Postulantado (Viana) para ajudar na forma\u00e7\u00e3o, como vice-mestre dos postulantes. Ao chegar, j\u00e1 pelo meio do caminho, recebi a not\u00edcia de que o confrade que estava \u00e0 frente da fraternidade e da forma\u00e7\u00e3o, havia pedido para se retirar da miss\u00e3o e ir para outro projeto mission\u00e1rio da Ordem.<\/p>\n<p>Avaliando todo o meu itiner\u00e1rio na miss\u00e3o, acredito que foi o momento mais dif\u00edcil de todos. Chegar a outro pa\u00eds, rec\u00e9m-sa\u00eddo da forma\u00e7\u00e3o, e cair dentro desse tipo de situa\u00e7\u00e3o totalmente inesperada. Ningu\u00e9m sabia quem iria substituir o confrade. O processo formativo do grupo de postulantes j\u00e1 seguia avan\u00e7ado. A d\u00favida pairava no ar. No meu cora\u00e7\u00e3o meditava e me perguntava: que pai \u00e9 esse que abandona os filhos em meio ao vendaval.<\/p>\n<p>Havia muito boa vontade dos frades que permaneceram em ajudar a encontrar uma solu\u00e7\u00e3o, dar apoio, ajudar, por\u00e9m, durante quase dois anos, o que aconteceu foi uma sucess\u00e3o de reajustamentos na fraternidade que a tornava inconstante. Mesmo rec\u00e9m-formado, percebia que esse ambiente n\u00e3o ajudava em nada a forma\u00e7\u00e3o. Finalmente, as coisas foram se ajustando e, um novo confrade, j\u00e1 com experi\u00eancia em forma\u00e7\u00e3o chegou e ajudou a fazer a transi\u00e7\u00e3o. Passei estes 6 anos iniciais na fraternidade de Viana. Durante esse tempo de miss\u00e3o, meu programa de trabalho tinha escrito em letras bem grandes sobre minha mesa: APRENDIZADO. Queria lembrar sempre que estava ali, naquele momento, mais para aprender do que para ensinar.<\/p>\n<p>Algumas coisas me ajudaram muito neste momento: a acolhida, a abertura e o esp\u00edrito fraterno por parte dos confrades que j\u00e1 estavam na miss\u00e3o; a partilha e a amizade dos confrades que foram junto comigo para a miss\u00e3o; o Curso para Mission\u00e1rios, oferecido pela Confer\u00eancia Episcopal, que nos apresentava um pouco de tudo: oportunidade para conhecer um pouco da cultura, das l\u00ednguas locais, da organiza\u00e7\u00e3o econ\u00f4mica, pol\u00edtica e religiosa, mas, sobretudo, para conhecer outros mission\u00e1rios, rec\u00e9m-chegados de outras congrega\u00e7\u00f5es e assim partilhar expectativas e experi\u00eancias; a alegria dos nossos formandos e o seu entusiasmo e busca por cultivar a voca\u00e7\u00e3o franciscana; os tempos de trabalho pastoral junto \u00e0s aldeias de Malange, com os frades estudantes, no per\u00edodo p\u00f3s-guerra. Todas essas experi\u00eancias ajudaram a conhecer um pouco da realidade de nossa miss\u00e3o. Hoje, a palavra-chave do meu trabalho tem sido CONSOLIDAR. Ou seja, tentar fazer com que o que j\u00e1 foi realizado durante estes 25 anos consiga produzir frutos e assim, aos poucos, a Funda\u00e7\u00e3o v\u00e1 se consolidando, cada vez mais, em terras angolanas.<\/p>\n<p>Desde quando cheguei a Angola que procuro estudar um pouco da sua hist\u00f3ria. Comecei com o processo de chegada dos primeiros europeus at\u00e9 o processo de independ\u00eancia. Depois percebi a necessidade de descobrir um pouco o processo de fixa\u00e7\u00e3o dos v\u00e1rios povos de origem bantu no territ\u00f3rio, pois isso nos ajuda a entender um pouco da cultura ou culturas locais. Atualmente tenho pesquisado sobre os outros momentos em que houve presen\u00e7a de frades menores ou de algum dos grupos de frades que depois se integraram \u00e0 OFM. Foram v\u00e1rios os momentos, como podem comprovar algumas ru\u00ednas de antigos conventos ou a lista dos bispos da cidade de Luanda, pelo menos 6 eram franciscanos. Alguns vieram diretamente de Portugal, outros j\u00e1 eram mission\u00e1rios. Isso indica a presen\u00e7a dos frades. Por\u00e9m, pouco dessa hist\u00f3ria foi conservada, mas, conhec\u00ea-la nos ajuda a entender o que \u00e9 necess\u00e1rio fazer para que a presen\u00e7a atual seja realmente duradoura e produza frutos de verdadeira evangeliza\u00e7\u00e3o, de promo\u00e7\u00e3o da dignidade da pessoa humana.<\/p>\n<p><strong><a href=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2015\/02\/011.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-79164\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2015\/02\/011.jpg\" alt=\"01\" width=\"419\" height=\"374\" \/><\/a>Site Franciscanos<\/strong><em>\u00a0&#8211; Hoje, como presidente da Funda\u00e7\u00e3o, quais os principais desafios da miss\u00e3o?<\/em><\/p>\n<p><strong>Frei Jos\u00e9<\/strong> &#8211; No momento em que nos preparamos para celebrar os 25 anos da atual presen\u00e7a dos frades menores em Angola, podemos afirmar que passamos do per\u00edodo de \u201cinstala\u00e7\u00e3o e reconhecimento\u201d do terreno. Assim, surge o grande desafio que \u00e9 a consolida\u00e7\u00e3o do que foi instalado e reconhecido. Com isso, o maior desafio \u00e9 ter frades em n\u00famero suficiente para oferecermos um trabalho na \u00e1rea pastoral e formativa de qualidade para que o nosso servi\u00e7o de evangeliza\u00e7\u00e3o possa realmente ser o lugar onde o frade menor e todos aqueles que com ele se encontram possam sempre sair realizados em sua miss\u00e3o. Sabemos que tudo \u00e9 um construir constante, mas, nos encontramos no momento em que o maior desafio n\u00e3o \u00e9 somente construir, mas manter o que j\u00e1 foi edificado. N\u00e3o falamos apenas das constru\u00e7\u00f5es de pedra e cimento, mas, sobretudo da constru\u00e7\u00e3o espiritual da Funda\u00e7\u00e3o.<\/p>\n<p>Nossas par\u00f3quias cresceram, n\u00e3o em extens\u00e3o territorial, mas, em n\u00famero de pessoas, que passaram a residir nelas por causa do processo de deslocamento das popula\u00e7\u00f5es que se iniciou logo nos primeiros anos do p\u00f3s-guerra e vem se intensificando cada vez mais. A paroquia de Malange, por exemplo, h\u00e1 bem pouco tempo (tr\u00eas ou quatro anos) tinha poucas resid\u00eancias. Atualmente, para todo lado que se olha se v\u00ea uma nova constru\u00e7\u00e3o. O mesmo pode ser dito das outras duas par\u00f3quias. O Kimbo S\u00e3o Francisco (em Luanda) v\u00ea o n\u00famero de peregrinos aumentar todos os dias. Antes, receb\u00edamos pessoas da grande Luanda, hoje h\u00e1 fi\u00e9is vindos mesmo de outras regi\u00f5es.<\/p>\n<p>Na forma\u00e7\u00e3o, o n\u00famero de vocacionados tem aumentado. Isso nos ajuda a fazer uma melhor sele\u00e7\u00e3o inicial. Ou aproveitamos o bom momento que a gra\u00e7a nos concede ou talvez nos arrependamos depois. Acrescenta-se a isso o fato de que o \u00edndice de perseveran\u00e7a tem sido bastante alto. Por\u00e9m, a inconst\u00e2ncia no n\u00famero de formadores tem sido uma pr\u00e1tica. Isso empobrece a nossa capacidade de acolher e ajudar no processo de discernimento e anima\u00e7\u00e3o vocacional. Al\u00e9m disso, as constantes mudan\u00e7as fazem com que n\u00e3o se gerem experi\u00eancia e continuidade nos processos formativos. Muitas vezes acabamos por experimentar de novo aquilo que o passado j\u00e1 comprovou ser ineficiente.<\/p>\n<p><strong>Site Franciscanos<\/strong><em>&#8211; A Funda\u00e7\u00e3o vive um bom momento vocacional, fale sobre esse \u201cceleiro vocacional\u201d na miss\u00e3o.<\/em><\/p>\n<p><strong>Frei Jos\u00e9<\/strong> &#8211; O atual bom momento vocacional \u00e9 resultado do trabalho de todos os frades ao longo destes 25 anos. Outros fatores que tamb\u00e9m t\u00eam contribu\u00eddo para tal foi o crescimento no n\u00famero de escolas que possibilitam aos jovens terminar o ensino fundamental e, por vezes, o ensino m\u00e9dio e assim estarem aptos a entrar em um semin\u00e1rio ou casa de forma\u00e7\u00e3o. No nosso caso espec\u00edfico, o apoio das religiosas nas regi\u00f5es onde n\u00e3o temos presen\u00e7a tem sido fundamental. O material vocacional, sobretudo os subs\u00eddios impressos contribuem para que os jovens que nos procuram venham j\u00e1 com uma ideia geral sobre o que significa ser frade menor. A cria\u00e7\u00e3o de uma coordena\u00e7\u00e3o mais centralizada da Pastoral Vocacional que ajuda na anima\u00e7\u00e3o local tamb\u00e9m tem ajudado a promover mais visitas \u00e0s fam\u00edlias etc., algo muito importante na acolhida dos jovens vocacionados por aqui.<\/p>\n<p><strong>Site Franciscanos<\/strong><em>\u00a0&#8211; Por que quis ser mission\u00e1rio?<\/em><\/p>\n<p><strong>Frei Jos\u00e9<\/strong> &#8211; O desejo de ser mission\u00e1rio surgiu j\u00e1 no primeiro ano de forma\u00e7\u00e3o, durante o aspirantado. Os primeiros frades tinham sido enviados para a miss\u00e3o em Angola havia pouco tempo. Os relat\u00f3rios, as not\u00edcias falavam das primeiras experi\u00eancias, das dificuldades e eram entusiasmantes. Ent\u00e3o surgiu a primeira ideia de tamb\u00e9m ir para Angola.<\/p>\n<p>Essa ideia foi refor\u00e7ada durante o tempo de noviciado com a leitura das biografias dos frades que chegaram para a reforma da Prov\u00edncia. Durante os momentos de medita\u00e7\u00e3o l\u00edamos essas biografias e era um momento onde pod\u00edamos viajar at\u00e9 a miss\u00e3o e pensar como tudo tinha sido e como tudo poderia vir a ser se tom\u00e1ssemos a decis\u00e3o de seguir para a miss\u00e3o. No \u00faltimo ano da Teologia, conversei com o ministro provincial da \u00e9poca e ele disse que se eu quisesse realmente ir, que escrevesse uma carta. Em 8 de dezembro de 2000 recebi a transfer\u00eancia para a miss\u00e3o. Na verdade, quis ser mission\u00e1rio por acreditar que poderia aprender muito vivendo dentro de uma realidade e cultura diferentes, por acreditar que todos somos chamados a ser mission\u00e1rios e porque tenho claro que o carisma franciscano pode ajudar a construir uma sociedade mais justa e mais fraterna, sobretudo em um lugar onde a palavra guerra, no passado, era mais usada do que a palavra paz.<\/p>\n<p><strong>Site Franciscanos<\/strong><em>\u00a0&#8211; Como se deu o seu discernimento vocacional? Por que escolheu ser franciscano?<\/em><\/p>\n<p><strong>Frei Jos\u00e9<\/strong> &#8211; A descoberta da voca\u00e7\u00e3o religiosa como possibilidade de realiza\u00e7\u00e3o existencial se deu quando ainda era bem crian\u00e7a, no primeiro dia de catequese. A arquidiocese de Niter\u00f3i, da qual sou origin\u00e1rio, vivia um momento de trabalho vocacional bastante intenso, pois, na \u00e9poca, faltavam voca\u00e7\u00f5es. Havia um pequeno caderno vocacional e o catequista o usava nos primeiros encontros. Pois bem, o primeiro encontro falava sobre a voca\u00e7\u00e3o de Samuel, quando Deus chama Samuel pelo nome. Naquele dia senti que talvez esse poderia ser meu caminho.<\/p>\n<p>Passou muito tempo e uma religiosa catequista franciscana me questionou sobre a possibilidade de ser franciscano e me levou at\u00e9 aos frades. No primeiro encontro com os frades tive a certeza de que queria mesmo ser franciscano. Muitos foram os que me ajudaram neste processo de descoberta. Hoje, cada vez que visto o h\u00e1bito e o vejo cada vez mais velho, desgastado e surrado, lembro com carinho de todas essas pessoas e tenho clara a certeza de que foi a melhor e mais acertada decis\u00e3o que j\u00e1 tomei na vida. Sobre por que escolhi ser franciscano poderia dizer muitas coisas, mas acho que posso resumir da seguinte maneira: nos momentos de alegria ou de dificuldade ser franciscano me realiza, me sustenta espiritualmente e me d\u00e1 for\u00e7as para continuar a caminhada. O modo de vida e o ideal de S\u00e3o Francisco, dos irm\u00e3os menores e itinerantes, me fez encontrar sentido para a caminhada.<\/p>\n<p><strong>Site Franciscanos<\/strong><em>\u00a0&#8211; O que voc\u00ea diria para os frades e leigos que querem se tornar mission\u00e1rios em Angola?<\/em><\/p>\n<p><strong>Frei Jos\u00e9<\/strong> &#8211; Cada um tem a sua pr\u00f3pria medida, mas todos podemos doar um pouco de nosso tempo e de nossa vida como frades menores e como crist\u00e3os para a miss\u00e3o. J\u00e1 tivemos irm\u00e3os que ficaram na miss\u00e3o durante dois anos ou at\u00e9 menos e fizeram muito. At\u00e9 hoje as pessoas t\u00eam uma boa lembran\u00e7a deles. N\u00e3o importa o tempo que voc\u00ea pode oferecer: um ano, dois, tr\u00eas&#8230; a vida inteira. O que importa \u00e9 ser capaz de fazer algo, sobretudo, neste momento em que a miss\u00e3o cresce. Esse tempo, se bem aproveitado, ajudar\u00e1 a consolidar nossa Funda\u00e7\u00e3o mission\u00e1ria. E depois teremos irm\u00e3os angolanos que, por si, tocar\u00e3o a miss\u00e3o. \u00c9 necess\u00e1rio ir sem a pretens\u00e3o de que resolveremos tudo. Vamos para ajudar a regar as sementes j\u00e1 lan\u00e7adas em terra boa e com a plena certeza de que fazer crescer \u00e9 obra do pr\u00f3prio Deus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevista<\/p>\n","protected":false},"author":1,"featured_media":219857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[758],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Frei Jos\u00e9 e os novos desafios da Miss\u00e3o de Angola - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frei Jos\u00e9 e os novos desafios da Miss\u00e3o de Angola - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Entrevista\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-10T09:35:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-24T14:59:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2015\/02\/8205.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2015\/02\/8205.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2015\/02\/8205.jpg\",\"width\":273,\"height\":182},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html\",\"name\":\"Frei Jos\u00e9 e os novos desafios da Miss\u00e3o de Angola - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html#primaryimage\"},\"datePublished\":\"2015-02-10T09:35:21+00:00\",\"dateModified\":\"2020-06-24T14:59:49+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frei Jos\u00e9 e os novos desafios da Miss\u00e3o de Angola\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frei Jos\u00e9 e os novos desafios da Miss\u00e3o de Angola - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html","og_locale":"pt_BR","og_type":"article","og_title":"Frei Jos\u00e9 e os novos desafios da Miss\u00e3o de Angola - Not\u00edcias - Franciscanos","og_description":"Entrevista","og_url":"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2015-02-10T09:35:21+00:00","article_modified_time":"2020-06-24T14:59:49+00:00","og_image":[{"width":273,"height":182,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2015\/02\/8205.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2015\/02\/8205.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2015\/02\/8205.jpg","width":273,"height":182},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html","name":"Frei Jos\u00e9 e os novos desafios da Miss\u00e3o de Angola - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html#primaryimage"},"datePublished":"2015-02-10T09:35:21+00:00","dateModified":"2020-06-24T14:59:49+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/frei-jose-antonio-e-os-novos-desafios-da-missao-de-angola.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Frei Jos\u00e9 e os novos desafios da Miss\u00e3o de Angola"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/79157"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=79157"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/79157\/revisions"}],"predecessor-version":[{"id":223828,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/79157\/revisions\/223828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/219857"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=79157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=79157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=79157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}