{"id":58082,"date":"2014-05-28T07:38:42","date_gmt":"2014-05-28T10:38:42","guid":{"rendered":"http:\/\/new.franciscanos.org.br\/?p=58082"},"modified":"2019-07-03T14:13:37","modified_gmt":"2019-07-03T17:13:37","slug":"dupla-festa-em-santo-amaro-da-imperatriz","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html","title":{"rendered":"Dupla festa na Par\u00f3quia de Santo Amaro da Imperatriz"},"content":{"rendered":"<h4 style=\"text-align: left;\"><img loading=\"lazy\" class=\"size-full wp-image-58087 alignright\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2014\/05\/69_240414_stoamaro1.jpg\" alt=\"69_240414_stoamaro\" width=\"366\" height=\"847\" \/><em>\u201cDeixa a Bandeira passar, deixa a Bandeira entrar, \u00e9 o Esp\u00edrito Santo chegando, chegando para te aben\u00e7oar. Junta a tua fam\u00edlia, e prepara o teu lar! Numa salva de flores, promessas,\u00a0 louvores, vamos ofertar\u201d.<\/em><\/h4>\n<p style=\"text-align: left;\" align=\"center\"><strong>Frei Daniel Dellandrea<\/strong><\/p>\n<p style=\"text-align: left;\">A Festa do Divino em Santo Amaro da Imperatriz ocorre todos os anos no final da semana de Pentecostes. \u00c9 considerada a maior festa do Divino da grande Florian\u00f3polis. J\u00e1 h\u00e1 muitos anos, na missa das 19h do dia da P\u00e1scoa, \u00e9 realizado o envio das Bandeiras do Divino Esp\u00edrito Santo. Para o povo da Par\u00f3quia de Santo Amaro, \u00e9 sinal de que as tradicionais novenas ter\u00e3o in\u00edcio e a grandiosa festa do Divino se aproxima.<\/p>\n<p style=\"text-align: left;\">O s\u00edmbolo que se destaca \u00e9 a Bandeira do Divino que percorre ruas e casas de nossa Par\u00f3quia. A hist\u00f3ria da caminhada da bandeira inicia-se nos A\u00e7ores chegando ao Litoral Catarinense e tamb\u00e9m a Santo Amaro j\u00e1 em 1854, no mesmo ano da cria\u00e7\u00e3o da Par\u00f3quia de Santo Amaro, no dia 29 de maio. Tanto ontem quanto hoje a Bandeira continua tendo a sua import\u00e2ncia, porque os costumes e as tradi\u00e7\u00f5es passaram de gera\u00e7\u00e3o em gera\u00e7\u00e3o.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" class=\"alignnone wp-image-58085\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2014\/05\/60_240414_stoamaro.jpg\" alt=\"60_240414_stoamaro\" width=\"365\" height=\"239\" \/><\/p>\n<p style=\"text-align: left;\">Neste ano, completam-se 160 anos da Par\u00f3quia e de uma bel\u00edssima festa que apresenta como heran\u00e7a a religiosidade e a cultura a\u00e7oriana e tamb\u00e9m a hist\u00f3rica visita da Imperatriz por estas terras. Para a nossa Par\u00f3quia, os 50 dias do Tempo Pascal tornam-se uma verdadeira miss\u00e3o popular. A Bandeira do Divino percorre as ruas e casas. Muitas pessoas recordam que,\u00a0 ainda crian\u00e7as, viam a Bandeira do Divino chegar pelas m\u00e3os dos procuradores nas casas dos pais, av\u00f3s&#8230; a fim de aben\u00e7oar e levar gra\u00e7as do Esp\u00edrito Santo para quem a recebe.<\/p>\n<p style=\"text-align: left;\">Em todas as noites, a visita da Bandeira \u00e9 celebrada por aquela comunidade ou rua com a tradicional Novena A\u00e7oriana. As pessoas se re\u00fanem em uma casa, cantam ora\u00e7\u00f5es e hinos ao Divino, confraternizam-se e realizam o tradicional leil\u00e3o das massas (tipo de p\u00e3o doce com ervas em forma de p\u00e9, cora\u00e7\u00e3o, bra\u00e7o, cabe\u00e7a&#8230; de acordo com a gra\u00e7a alcan\u00e7ada).<\/p>\n<p style=\"text-align: left;\">Ap\u00f3s o leil\u00e3o, a Fam\u00edlia Machado, na voz do v\u00f4 e da v\u00f3, faz seus filhos e netos tocarem viol\u00e3o, tambor e violino, dando acordes para o repente em honra ao Divino Esp\u00edrito Santo, que se caracteriza pelo improviso \u2013 os cantadores fazem os versos \u201cde repente\u201d, incluindo versos do Esp\u00edrito Santo na inten\u00e7\u00e3o da fam\u00edlia que cumpre a promessa com a novena em sua casa.<\/p>\n<p style=\"text-align: left;\">No final, a b\u00ean\u00e7\u00e3o do \u201cpadre\u201d n\u00e3o pode faltar. Neste ano, s\u00e3o 6 Bandeiras do Divino, com 27 procuradores da Bandeira e est\u00e3o programadas 53 novenas para os 50 dias do Tempo Pascal.<\/p>\n<p style=\"text-align: left;\">Talvez o objetivo primeiro da Bandeira do Divino seria de convidar a todos para a Festa de Pentecostes e, num passado n\u00e3o t\u00e3o distante, era o de buscar uma prenda para a realiza\u00e7\u00e3o das festividades. Hoje, sua fun\u00e7\u00e3o \u00e9 ainda mais importante:\u00a0 a de levar a b\u00ean\u00e7\u00e3o da sa\u00fade a todas as pessoas que abrem as portas de suas casas e animar o povo na viv\u00eancia da f\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Festa do Divino em Santo Amaro da Imperatriz<\/p>\n","protected":false},"author":1,"featured_media":207211,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[703],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dupla festa na Par\u00f3quia de Santo Amaro da Imperatriz - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dupla festa na Par\u00f3quia de Santo Amaro da Imperatriz - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Festa do Divino em Santo Amaro da Imperatriz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-28T10:38:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-03T17:13:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2014\/05\/60_240414_stoamaro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2014\/05\/60_240414_stoamaro.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2014\/05\/60_240414_stoamaro.jpg\",\"width\":273,\"height\":181},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html\",\"name\":\"Dupla festa na Par\u00f3quia de Santo Amaro da Imperatriz - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html#primaryimage\"},\"datePublished\":\"2014-05-28T10:38:42+00:00\",\"dateModified\":\"2019-07-03T17:13:37+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dupla festa na Par\u00f3quia de Santo Amaro da Imperatriz\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dupla festa na Par\u00f3quia de Santo Amaro da Imperatriz - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html","og_locale":"pt_BR","og_type":"article","og_title":"Dupla festa na Par\u00f3quia de Santo Amaro da Imperatriz - Not\u00edcias - Franciscanos","og_description":"Festa do Divino em Santo Amaro da Imperatriz","og_url":"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2014-05-28T10:38:42+00:00","article_modified_time":"2019-07-03T17:13:37+00:00","og_image":[{"width":273,"height":181,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2014\/05\/60_240414_stoamaro.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2014\/05\/60_240414_stoamaro.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2014\/05\/60_240414_stoamaro.jpg","width":273,"height":181},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html","name":"Dupla festa na Par\u00f3quia de Santo Amaro da Imperatriz - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html#primaryimage"},"datePublished":"2014-05-28T10:38:42+00:00","dateModified":"2019-07-03T17:13:37+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/dupla-festa-em-santo-amaro-da-imperatriz.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Dupla festa na Par\u00f3quia de Santo Amaro da Imperatriz"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/58082"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=58082"}],"version-history":[{"count":0,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/58082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/207211"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=58082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=58082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=58082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}