{"id":47999,"date":"2013-10-27T20:44:56","date_gmt":"2013-10-27T22:44:56","guid":{"rendered":"http:\/\/new.franciscanos.org.br\/?p=47999"},"modified":"2019-02-04T13:29:30","modified_gmt":"2019-02-04T15:29:30","slug":"missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html","title":{"rendered":"Missa de A\u00e7\u00e3o de Gra\u00e7as marca os 90 anos em Luzerna"},"content":{"rendered":"<p><img loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2013\/10\/alto3.jpg\" alt=\"Foto Moacir Beggo\" width=\"820\" height=\"328\" \/><\/p>\n<p><strong>Moacir Beggo<\/strong><\/p>\n<p><strong>Luzerna\u00a0 (SC)<\/strong> &#8211; A presen\u00e7a franciscana dos Frades Menores da Prov\u00edncia da Imaculada Concei\u00e7\u00e3o \u00e9 marcante no Oeste Catarinense. Nas trilhas deixadas pelas sand\u00e1lias dos mission\u00e1rios de S\u00e3o Francisco de Assis, entre eles o Servo de Deus Frei Bruno Linden, nasceram vilas e cidades. Luzerna \u00e9 uma dessas cidades e, neste domingo (27\/10), celebrou duplamente dois momentos importantes para a comunidade: 90 anos de presen\u00e7a franciscana e 80 anos de funda\u00e7\u00e3o da Par\u00f3quia.<\/p>\n<p>\u00c0s 9h30, o bispo diocesano Dom M\u00e1rio Marquez, que \u00e9 filho da terra, o Vig\u00e1rio Provincial Frei Est\u00eav\u00e3o Ottenbreit, os Definidores Frei Jo\u00e3o Mannes e Frei Germano Guesser, o Vig\u00e1rio paroquial Leo Severino Schmidt, sacerdotes de toda a Prov\u00edncia, da Diocese de Joa\u00e7aba, religiosos e religiosas, e o povo foram convidados pelo p\u00e1roco Nolvi Dalla Costa a se dirigirem \u00e0 frente da Igreja para a b\u00ean\u00e7\u00e3o da imagem do Padroeiro S\u00e3o Jo\u00e3o Batista, que foi colocada na torre da igreja. &#8220;As igrejas mais antigas j\u00e1 eram constru\u00eddas com o pedestal na parte externa, para que se colocasse a imagem do Padroeiro&#8221;, explicou Frei Nolvi.<\/p>\n<p><img loading=\"lazy\" class=\"alignright size-full wp-image-48002\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2013\/10\/meio11.jpg\" alt=\"Foto Moacir Beggo\" width=\"400\" height=\"399\" \/>\u00a0A imagem, doada pelo empres\u00e1rio M\u00e1rcio Dalla Lana, foi esculpida pelo luzernense Cl\u00e1udio Silva, conhecido principalmente pela cria\u00e7\u00e3o da grande escultura de Frei Bruno em Joa\u00e7aba. Ap\u00f3s a b\u00ean\u00e7\u00e3o de Dom M\u00e1rio, todos foram convidados a entrarem na igreja para iniciar a Santa Missa.\u00a0 Antes, as 18 comunidades da Par\u00f3quia marcaram presen\u00e7a na celebra\u00e7\u00e3o trazendo, em prociss\u00e3o, um banner com a imagem de cada de um de seus padroeiros.<\/p>\n<p>D. M\u00e1rio saudou a todos, especialmente a Frei Est\u00eav\u00e3o, representando a Prov\u00edncia da Imaculada, que foi pioneira na evangeliza\u00e7\u00e3o nestas terras a Oeste do Estado de Santa Catarina. &#8220;Estamos aqui num momento de a\u00e7\u00e3o de gra\u00e7as, de celebra\u00e7\u00e3o da vida e da f\u00e9, de louvor por esta data jubilar. \u00c9 um momento de j\u00fabilo e de alegria!&#8221;, comemorou o bispo, que tamb\u00e9m \u00e9 Filho da Ordem de S\u00e3o Francisco de Assis, j\u00e1 que ingressou na Ordem dos Frades Menores Capuchinhos. &#8220;Eu creio que todos n\u00f3s, que aqui estamos, fomos movidos pela f\u00e9, como tamb\u00e9m os nossos antepassados&#8221;, disse. Em 1923 chegavam os primeiros frades vindo da regi\u00e3o de Palmas, no Paran\u00e1, para dar assist\u00eancia \u00e0 pequena vila de Luzerna. Mais tarde, em 1933, foi criada a Par\u00f3quia S\u00e3o Jo\u00e3o Batista.<\/p>\n<p>D. M\u00e1rio lembrou que a celebra\u00e7\u00e3o acontecia no Ano da F\u00e9, que foi proclamado pelo Papa em\u00e9rito Bento XVI e que ser\u00e1 conclu\u00eddo pelo Papa Francisco. &#8220;E percebemos que, em poucos meses, o Papa Francisco tem dado ao mundo inteiro uma nova luz, esperan\u00e7a, um direcionamento para a Igreja, com certeza, inspirado em S\u00e3o Francisco de Assis&#8221;, disse.<\/p>\n<p><img loading=\"lazy\" class=\"alignleft size-full wp-image-48003\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2013\/10\/meio4.jpg\" alt=\"Foto Moacir Beggo\" width=\"400\" height=\"267\" \/>&#8220;Mais de 800 anos depois, S\u00e3o Francisco vem exercendo na humanidade uma influ\u00eancia muito forte e marcante para a humanidade. Ele \u00e9 t\u00e3o atual que parece ser do nosso tempo&#8221;, disse, lembrando que a fraternidade \u00e9 uma das marcas principais deixadas por este santo.\u00a0 &#8220;Ele apresenta para n\u00f3s um indicativo, Jesus Cristo, que \u00e9 o centro da nossa vida crist\u00e3&#8221;, acrescentou D. M\u00e1rio, n\u00e3o se cansando de agradecer aos Filhos de S\u00e3o Francisco por este trabalho mission\u00e1rio nesta regi\u00e3o catarinense. Segundo o bispo, que na \u00faltima semana fez v\u00e1rias celebra\u00e7\u00f5es no interior e em cidades vizinhas, p\u00f4de comprovar as marcas deixadas pelos frades, especialmente na sua Diocese.<\/p>\n<p>Por sua vez, Frei Est\u00eav\u00e3o disse que esse trabalho mission\u00e1rio e itinerante dos frades n\u00e3o seria poss\u00edvel sem o carinho, o amor e o acolhimento do povo. &#8220;Ao longo desses noventa anos, e principalmente os queridos antepassados de voc\u00eas, que muitos j\u00e1 n\u00e3o est\u00e3o mais aqui, acolheram esses frades e n\u00e3o s\u00f3 com um abra\u00e7o, um bom dia, com uma comida partilhada, mas principalmente abriram o seu cora\u00e7\u00e3o para receberem o que os frades anunciavam: o Evangelho de Jesus Cristo&#8221;, disse.<\/p>\n<p><img loading=\"lazy\" class=\"alignright size-full wp-image-48006\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2013\/10\/andre.jpg\" alt=\"Foto Moacir Beggo\" width=\"400\" height=\"267\" \/>&#8220;Estamos, hoje, festejando 90 anos da presen\u00e7a de franciscana e esta semana Dom M\u00e1rio vai nos dar um presente. Um desses frades que por aqui andou, durante esses 90 anos, um deles, \u00e9 Frei Bruno! (<i>o povo aplaude sem parar ao ouvir o nome de Frei Bruno<\/i>). Nesta quarta-feira que vem, D. M\u00e1rio vai abrir solenemente o processo de beatifica\u00e7\u00e3o deste Servo de Deus&#8221;, completou Frei Est\u00eav\u00e3o, n\u00e3o poupando agradecimento a todos. O in\u00edcio do processo de beatifica\u00e7\u00e3o de Frei Bruno acontecer\u00e1 \u00a0na Catedral Santa Terezinha de Joa\u00e7aba, \u00e0s 15 horas.<\/p>\n<p>Entre as autoridades, falou o prefeito Mois\u00e9s Diersnann, que \u00a0parabenizou a todos pelas datas jubilares. &#8220;\u00c9 um momento importante para a nossa comunidade. O desenvolvimento desta cidade est\u00e1 atrelado a esta data t\u00e3o importante&#8221;, disse. Neivaldo Luiz Deitos, coordenador do Conselho de Pastoral, falou em nome de todos os conselhos, pastorais e movimentos.<\/p>\n<p>Uma celebra\u00e7\u00e3o t\u00e3o bela e t\u00e3o bem preparada, conduzida com perfei\u00e7\u00e3o pelo p\u00e1roco Frei Nolvi Dalla Costa, reservou para o final um momento de muita emo\u00e7\u00e3o. O garoto Lucas Desid\u00e9rio Celso, vestido como um frade franciscano, veio do fundo da igreja cantando a &#8220;Cantiga por Francisco&#8221;, de Pe. Zezinho. Afinado e com muita tranquilidade, Lucas emocionou e arrancou aplausos do povo. Na verdade, ele j\u00e1 \u00e9 um &#8220;quase profissional&#8221;. Segundo a m\u00e3e Elisandra, ele canta desde os 4 anos e costuma ser convidado para cantar em festas e formaturas.<\/p>\n<p>Antes de a festa continuar com um churrasco no Sal\u00e3o Paroquial, Frei Nolvi convidou a todos para a b\u00ean\u00e7\u00e3o do novo audit\u00f3rio da Par\u00f3quia. Segundo o p\u00e1roco, ainda faltam as cadeiras e obra dever\u00e1 estar totalmente conclu\u00edda em janeiro pr\u00f3ximo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presen\u00e7a franciscana<\/p>\n","protected":false},"author":1,"featured_media":199403,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[1317],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Missa de A\u00e7\u00e3o de Gra\u00e7as marca os 90 anos em Luzerna - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Missa de A\u00e7\u00e3o de Gra\u00e7as marca os 90 anos em Luzerna - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Presen\u00e7a franciscana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-27T22:44:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-04T15:29:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2013\/10\/alto3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2013\/10\/alto3.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2013\/10\/alto3.jpg\",\"width\":273,\"height\":181},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html\",\"name\":\"Missa de A\u00e7\u00e3o de Gra\u00e7as marca os 90 anos em Luzerna - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html#primaryimage\"},\"datePublished\":\"2013-10-27T22:44:56+00:00\",\"dateModified\":\"2019-02-04T15:29:30+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Missa de A\u00e7\u00e3o de Gra\u00e7as marca os 90 anos em Luzerna\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Missa de A\u00e7\u00e3o de Gra\u00e7as marca os 90 anos em Luzerna - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html","og_locale":"pt_BR","og_type":"article","og_title":"Missa de A\u00e7\u00e3o de Gra\u00e7as marca os 90 anos em Luzerna - Not\u00edcias - Franciscanos","og_description":"Presen\u00e7a franciscana","og_url":"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2013-10-27T22:44:56+00:00","article_modified_time":"2019-02-04T15:29:30+00:00","og_image":[{"width":273,"height":181,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2013\/10\/alto3.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2013\/10\/alto3.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2013\/10\/alto3.jpg","width":273,"height":181},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html","name":"Missa de A\u00e7\u00e3o de Gra\u00e7as marca os 90 anos em Luzerna - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html#primaryimage"},"datePublished":"2013-10-27T22:44:56+00:00","dateModified":"2019-02-04T15:29:30+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/missa-de-acao-de-gracas-marca-os-90-anos-de-presenca-franciscana-em-luzerna.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Missa de A\u00e7\u00e3o de Gra\u00e7as marca os 90 anos em Luzerna"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/47999"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=47999"}],"version-history":[{"count":0,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/47999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/199403"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=47999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=47999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=47999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}