{"id":266806,"date":"2026-05-06T11:15:49","date_gmt":"2026-05-06T14:15:49","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=266806"},"modified":"2026-05-06T11:15:49","modified_gmt":"2026-05-06T14:15:49","slug":"que-ninguem-fique-excluido-da-mesa-comum","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html","title":{"rendered":"\u201cQue ningu\u00e9m fique exclu\u00eddo da mesa comum\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"aligncenter wp-image-266807 size-large\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-1024x575.jpg\" alt=\"\" width=\"1024\" height=\"575\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-1024x575.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-1536x863.jpg 1536w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-2048x1151.jpg 2048w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-150x84.jpg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-scaled.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">O Papa Le\u00e3o XIV dedicou sua inten\u00e7\u00e3o de ora\u00e7\u00e3o para o m\u00eas de maio ao tema da fome, convidando fi\u00e9is e pessoas de boa vontade a rezarem \u201cpor uma alimenta\u00e7\u00e3o para todos\u201d e a assumirem atitudes concretas de solidariedade. <\/span><em><strong><a href=\"https:\/\/www.vaticannews.va\/pt\/papa\/news\/2026-04\/papa-leao-xiv-video-intencao-oracao-mes-maio-2026-alimentos.html\">As informa\u00e7\u00f5es s\u00e3o do Vatican News<\/a><\/strong><span style=\"font-weight: 400;\">.<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400;\">A proposta, divulgada por meio da iniciativa \u201cReza com o Papa\u201d, chama a aten\u00e7\u00e3o para a necessidade de transformar h\u00e1bitos cotidianos e enfrentar um dos desafios mais urgentes da atualidade.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na mensagem, o Pont\u00edfice reconhece o contraste entre a abund\u00e2ncia e o desperd\u00edcio de alimentos e a realidade de milh\u00f5es de pessoas que ainda passam fome. Diante disso, prop\u00f5e uma mudan\u00e7a de mentalidade: valorizar cada alimento, adotar um consumo mais simples e fortalecer a partilha, compreendendo os bens da terra como um dom destinado a todos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O Papa tamb\u00e9m incentiva comunidades e institui\u00e7\u00f5es a promoverem iniciativas concretas, como campanhas de conscientiza\u00e7\u00e3o e bancos alimentares para reduzir o desperd\u00edcio e\u00a0 transformar \u201ca l\u00f3gica do consumo ego\u00edsta numa cultura de solidariedade\u201d.<\/span> <span style=\"font-weight: 400;\">Ao concluir a inten\u00e7\u00e3o de ora\u00e7\u00e3o, o Papa retoma um apelo: que ningu\u00e9m seja exclu\u00eddo da \u201cmesa comum\u201d.\u00a0<\/span><\/p>\n<p><b>Inseguran\u00e7a alimentar em n\u00fameros<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Segundo o relat\u00f3rio <\/span><strong><a href=\"https:\/\/www.wfp.org\/publications\/wfp-global-outlook\">WFP 2026 Global Outlook, do Programa Alimentar Mundial, cerca de 318 milh\u00f5es de pessoas<\/a><\/strong><span style=\"font-weight: 400;\"> poder\u00e3o enfrentar n\u00edveis severos de fome em 2026, com a possibilidade de <\/span><strong><a href=\"https:\/\/es.wfp.org\/noticias\/wfp-preve-que-la-inseguridad-alimentaria-podria-alcanzar-niveles-record-como-consecuencia\">outros 45 milh\u00f5es<\/a><\/strong><span style=\"font-weight: 400;\"> serem empurrados para essa condi\u00e7\u00e3o devido a conflitos, especialmente no M\u00e9dio Oriente.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 o <\/span><strong><a href=\"https:\/\/openknowledge.fao.org\/items\/9a576e6b-faa7-414a-919f-8265bc6196c3\">\u201cO Estado da Seguran\u00e7a Alimentar e da Nutri\u00e7\u00e3o no Mundo 2025\u201d<\/a><\/strong><span style=\"font-weight: 400;\">, estudo elaborado por ag\u00eancias como FAO, UNICEF e OMS, aponta que 673 milh\u00f5es de pessoas passaram fome em 2024, enquanto cerca de 2,3 bilh\u00f5es viviam em situa\u00e7\u00e3o de inseguran\u00e7a alimentar.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por fim, o cen\u00e1rio se agrava diante do contraste com o desperd\u00edcio: mais de 1 bilh\u00e3o de toneladas de alimentos s\u00e3o descartadas anualmente no mundo, segundo <\/span><strong><a href=\"https:\/\/www.un.org\/es\/cr%C3%B3nica-onu\/convertir-la-prevenci%C3%B3n-del-desperdicio-de-alimentos-en-una-soluci%C3%B3n-clim%C3%A1tica-escalable\">o Programa das Na\u00e7\u00f5es Unidas para o Meio Ambiente<\/a><\/strong><span style=\"font-weight: 400;\">, evidenciando um paradoxo que refor\u00e7a a urg\u00eancia de a\u00e7\u00f5es concretas em favor da partilha e da justi\u00e7a social.<\/span><\/p>\n<p><b>Ora\u00e7\u00e3o<\/b><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Senhor da cria\u00e7\u00e3o,<br \/>\n<\/span><span style=\"font-weight: 400;\">Tu nos deste a terra f\u00e9rtil e, com ela, o nosso p\u00e3o de cada dia,<br \/>\n<\/span><span style=\"font-weight: 400;\">como sinal do teu amor e da tua provid\u00eancia.<br \/>\n<\/span><span style=\"font-weight: 400;\">Hoje reconhecemos com dor<br \/>\n<\/span><span style=\"font-weight: 400;\">que milh\u00f5es de irm\u00e3os e irm\u00e3s continuam a passar fome,<br \/>\n<\/span><span style=\"font-weight: 400;\">enquanto tanto alimento \u00e9 desperdi\u00e7ado nas nossas mesas.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desperta em n\u00f3s uma nova consci\u00eancia:<br \/>\n<\/span><span style=\"font-weight: 400;\">que aprendamos a agradecer cada alimento,<br \/>\n<\/span><span style=\"font-weight: 400;\">a consumir com simplicidade,<br \/>\n<\/span><span style=\"font-weight: 400;\">a partilhar com alegria,<br \/>\n<\/span><span style=\"font-weight: 400;\">e a cuidar dos frutos da terra como um dom teu,<br \/>\n<\/span><span style=\"font-weight: 400;\">destinado a todos, n\u00e3o apenas a alguns.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pai bondoso,<br \/>\n<\/span><span style=\"font-weight: 400;\">torna-nos capazes de transformar a l\u00f3gica do consumo ego\u00edsta<br \/>\n<\/span><span style=\"font-weight: 400;\">em cultura de solidariedade.<br \/>\n<\/span><span style=\"font-weight: 400;\">Que as nossas comunidades promovam gestos concretos:<br \/>\n<\/span><span style=\"font-weight: 400;\">campanhas de sensibiliza\u00e7\u00e3o, bancos alimentares,<br \/>\n<\/span><span style=\"font-weight: 400;\">e um estilo de vida s\u00f3brio e respons\u00e1vel.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tu que nos enviaste o teu amado Filho Jesus,<br \/>\n<\/span><span style=\"font-weight: 400;\">p\u00e3o partido para a vida do mundo,<br \/>\n<\/span><span style=\"font-weight: 400;\">d\u00e1-nos um cora\u00e7\u00e3o novo, faminto de justi\u00e7a e sedento de fraternidade.<br \/>\n<\/span><span style=\"font-weight: 400;\">Que ningu\u00e9m fique exclu\u00eddo da mesa comum<br \/>\n<\/span><span style=\"font-weight: 400;\">e que o teu Esp\u00edrito nos ensine a olhar para o p\u00e3o<br \/>\n<\/span><span style=\"font-weight: 400;\">n\u00e3o como objeto de consumo,<br \/>\n<\/span><span style=\"font-weight: 400;\">mas como sinal de comunh\u00e3o e cuidado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Am\u00e9m.&#8221;<\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"Pray with the Pope: That everyone might have food | May 2026\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/-a60VaSe3tY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<hr \/>\n<p><em>Guilherme Coutinho (com informa\u00e7\u00f5es do Vatican News)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inten\u00e7\u00e3o de Ora\u00e7\u00e3o do Papa<\/p>\n","protected":false},"author":15,"featured_media":266807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cQue ningu\u00e9m fique exclu\u00eddo da mesa comum\u201d - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cQue ningu\u00e9m fique exclu\u00eddo da mesa comum\u201d - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Inten\u00e7\u00e3o de Ora\u00e7\u00e3o do Papa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-06T14:15:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1079\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guilherme Rocha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guilherme Rocha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-scaled.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-scaled.jpg\",\"width\":1920,\"height\":1079},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html\",\"name\":\"\u201cQue ningu\u00e9m fique exclu\u00eddo da mesa comum\u201d - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html#primaryimage\"},\"datePublished\":\"2026-05-06T14:15:49+00:00\",\"dateModified\":\"2026-05-06T14:15:49+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/69bb4cd273a2528548b63cccab4980a0\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cQue ningu\u00e9m fique exclu\u00eddo da mesa comum\u201d\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/69bb4cd273a2528548b63cccab4980a0\",\"name\":\"Guilherme Rocha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e480fee2377f81af36f6990ed742592a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e480fee2377f81af36f6990ed742592a?s=96&d=mm&r=g\",\"caption\":\"Guilherme Rocha\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/guilhermerocha\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cQue ningu\u00e9m fique exclu\u00eddo da mesa comum\u201d - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html","og_locale":"pt_BR","og_type":"article","og_title":"\u201cQue ningu\u00e9m fique exclu\u00eddo da mesa comum\u201d - Not\u00edcias - Franciscanos","og_description":"Inten\u00e7\u00e3o de Ora\u00e7\u00e3o do Papa","og_url":"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2026-05-06T14:15:49+00:00","og_image":[{"width":1920,"height":1079,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-scaled.jpg","type":"image\/jpeg"}],"author":"Guilherme Rocha","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Guilherme Rocha","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-scaled.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/05\/Captura-de-tela-2026-05-06-111200.-fotor-enhance-20260506111248-scaled.jpg","width":1920,"height":1079},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html","name":"\u201cQue ningu\u00e9m fique exclu\u00eddo da mesa comum\u201d - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html#primaryimage"},"datePublished":"2026-05-06T14:15:49+00:00","dateModified":"2026-05-06T14:15:49+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/69bb4cd273a2528548b63cccab4980a0"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/que-ninguem-fique-excluido-da-mesa-comum.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"\u201cQue ningu\u00e9m fique exclu\u00eddo da mesa comum\u201d"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/69bb4cd273a2528548b63cccab4980a0","name":"Guilherme Rocha","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e480fee2377f81af36f6990ed742592a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e480fee2377f81af36f6990ed742592a?s=96&d=mm&r=g","caption":"Guilherme Rocha"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/guilhermerocha"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/266806"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=266806"}],"version-history":[{"count":5,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/266806\/revisions"}],"predecessor-version":[{"id":266812,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/266806\/revisions\/266812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/266807"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=266806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=266806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=266806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}