{"id":263543,"date":"2026-01-13T09:59:14","date_gmt":"2026-01-13T12:59:14","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=263543"},"modified":"2026-01-13T09:59:14","modified_gmt":"2026-01-13T12:59:14","slug":"sao-francisco-de-assis-uma-semente-da-vida-eterna","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html","title":{"rendered":"\u201cS\u00e3o Francisco de Assis: Uma Semente da Vida Eterna\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"aligncenter wp-image-263544 size-large\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12-1024x683.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12-450x300.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12-768x512.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12-150x100.jpg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12.jpg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p style=\"text-align: right;\"><i><span dir=\"auto\">Assis, 10 de janeiro de 2026<\/span><\/i><\/p>\n<p><strong><span dir=\"auto\">H\u00e1 oitocentos anos, Francisco de Assis deixou este mundo<\/span><\/strong><span dir=\"auto\">. Mas a semente que ele plantou continua a brotar.\u00a0<\/span><\/p>\n<p><span dir=\"auto\">S\u00e3o Paulo, em sua carta aos G\u00e1latas, escreve palavras que parecem misteriosas: &#8220;Quem semeia para o Esp\u00edrito, do Esp\u00edrito colher\u00e1 a vida eterna&#8221;. Essas palavras se cumpriram em Francisco. Depois de acolher o Esp\u00edrito de Jesus em si, a ponto de trazer em seu corpo as marcas do Crucifixo, ele pr\u00f3prio se tornou uma semente do Evangelho repleta dos frutos da vida eterna.\u00a0<\/span><\/p>\n<p><span dir=\"auto\">\u00c9 o precioso legado que ele nos deixou. Um legado que ainda hoje fala aos cora\u00e7\u00f5es e mentes da nossa gera\u00e7\u00e3o, ajudando-nos a crer no Evangelho, a &#8220;ter o Esp\u00edrito do Senhor e a sua santa atua\u00e7\u00e3o&#8221; e a tornarmo-nos sinais de paz.<\/span><\/p>\n<p><span dir=\"auto\">Com esta carta, queremos agradecer ao Senhor pela semente do Evangelho que Ele plantou na Igreja h\u00e1 800 anos, semente que permanece viva e frut\u00edfera at\u00e9 hoje. Juntos, queremos recordar alguns aspectos fundamentais desta hist\u00f3ria crist\u00e3. Estes aspectos permanecem como um legado para todos aqueles que, seguindo os passos de Francisco, desejam seguir os passos do Senhor Jesus&#8230;<\/span><\/p>\n<p style=\"text-align: center;\"><span dir=\"auto\">Pe. Massimo Fusarelli OFM,\u00a0\u00a0<\/span><i><span dir=\"auto\">Ministro Geral<\/span><\/i><br \/>\n<span dir=\"auto\">Pe. Carlos Alberto Trovarelli OFMConv,\u00a0<\/span><i><span dir=\"auto\">Ministro Geral<\/span><\/i><br \/>\n<span dir=\"auto\">Pe.\u00a0<\/span><i><\/i><span dir=\"auto\">Roberto Genuin OFMCap,\u00a0\u00a0<\/span><i><span dir=\"auto\">Ministro Geral<\/span><\/i><br \/>\n<span dir=\"auto\">Pe. Amando Trujillo Cano TOR,\u00a0<\/span><i><span dir=\"auto\">Ministro Geral<\/span><\/i><br \/>\n<span dir=\"auto\">Tibor Kauser OFS,\u00a0\u00a0<\/span><i><span dir=\"auto\">Ministra Geral<\/span><\/i><br \/>\n<span dir=\"auto\">Irm\u00e3 Daisy Kalamparamban,\u00a0<\/span><i><span dir=\"auto\">Presidente IFC-TOR<\/p>\n<p><\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ofm.org\/uploads\/Lettera_Centenario_2026_PT.pdf\"><strong>Clique aqui para ler a carta<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h3 data-path-to-node=\"2\"><b data-path-to-node=\"2\" data-index-in-node=\"0\">Relembre a abertura das celebra\u00e7\u00f5es em Assis<\/b><\/h3>\n<p data-path-to-node=\"3\">A mensagem dos Ministros Gerais aprofunda o esp\u00edrito vivido no \u00faltimo s\u00e1bado (10), quando a Fam\u00edlia Franciscana abriu oficialmente, na Bas\u00edlica de Santa Maria dos Anjos (Porziuncola), as celebra\u00e7\u00f5es pelo 800\u00ba anivers\u00e1rio da morte de S\u00e3o Francisco.<\/p>\n<p data-path-to-node=\"4\">O evento foi marcado por uma &#8220;ponte espiritual&#8221; entre o Centen\u00e1rio do C\u00e2ntico das Criaturas (2025) e o do <i data-path-to-node=\"4\" data-index-in-node=\"106\">Transitus<\/i> (2026). Durante a cerim\u00f4nia, os seis ramos da Fam\u00edlia Franciscana percorreram esta\u00e7\u00f5es tem\u00e1ticas baseadas no Testamento de Francisco, refletindo sobre miseric\u00f3rdia, ora\u00e7\u00e3o, fraternidade, trabalho, paz e b\u00ean\u00e7\u00e3o.<\/p>\n<p data-path-to-node=\"5\">Um dos marcos centrais da abertura foi o an\u00fancio do Ano Jubilar Franciscano especial, institu\u00eddo pelo Papa Le\u00e3o XIV. De 10 de janeiro de 2026 a 10 de janeiro de 2027, todos os fi\u00e9is s\u00e3o convidados a seguir o exemplo do Santo de Assis como testemunhas da paz, com a concess\u00e3o de indulg\u00eancia plen\u00e1ria aos que visitarem igrejas franciscanas ou locais de culto dedicados ao Pobrezinho ao redor do mundo.<\/p>\n<p data-path-to-node=\"6\"><a href=\"https:\/\/franciscanos.org.br\/noticias\/familia-franciscana-inicia-celebracoes-pelos-800-anos-da-morte-de-sao-francisco.html#gsc.tab=0\"><strong>Clique aqui para ler a cobertura completa da cerim\u00f4nia de abertura do Ano Jubilar<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carta da Fam\u00edlia Franciscana por ocasi\u00e3o do VIII Centen\u00e1rio do Transitus de S\u00e3o Francisco<\/p>\n","protected":false},"author":15,"featured_media":263544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cS\u00e3o Francisco de Assis: Uma Semente da Vida Eterna\u201d - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cS\u00e3o Francisco de Assis: Uma Semente da Vida Eterna\u201d - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Carta da Fam\u00edlia Franciscana por ocasi\u00e3o do VIII Centen\u00e1rio do Transitus de S\u00e3o Francisco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T12:59:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guilherme Rocha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guilherme Rocha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12.jpg\",\"width\":1536,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html\",\"name\":\"\u201cS\u00e3o Francisco de Assis: Uma Semente da Vida Eterna\u201d - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html#primaryimage\"},\"datePublished\":\"2026-01-13T12:59:14+00:00\",\"dateModified\":\"2026-01-13T12:59:14+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/69bb4cd273a2528548b63cccab4980a0\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cS\u00e3o Francisco de Assis: Uma Semente da Vida Eterna\u201d\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/69bb4cd273a2528548b63cccab4980a0\",\"name\":\"Guilherme Rocha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e480fee2377f81af36f6990ed742592a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e480fee2377f81af36f6990ed742592a?s=96&d=mm&r=g\",\"caption\":\"Guilherme Rocha\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/guilhermerocha\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cS\u00e3o Francisco de Assis: Uma Semente da Vida Eterna\u201d - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html","og_locale":"pt_BR","og_type":"article","og_title":"\u201cS\u00e3o Francisco de Assis: Uma Semente da Vida Eterna\u201d - Not\u00edcias - Franciscanos","og_description":"Carta da Fam\u00edlia Franciscana por ocasi\u00e3o do VIII Centen\u00e1rio do Transitus de S\u00e3o Francisco","og_url":"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2026-01-13T12:59:14+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12.jpg","type":"image\/jpeg"}],"author":"Guilherme Rocha","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Guilherme Rocha","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2026\/01\/Missa-Solene-Dia-de-Sao-Francisco-de-Assis-12.jpg","width":1536,"height":1024},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html","name":"\u201cS\u00e3o Francisco de Assis: Uma Semente da Vida Eterna\u201d - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html#primaryimage"},"datePublished":"2026-01-13T12:59:14+00:00","dateModified":"2026-01-13T12:59:14+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/69bb4cd273a2528548b63cccab4980a0"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/sao-francisco-de-assis-uma-semente-da-vida-eterna.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"\u201cS\u00e3o Francisco de Assis: Uma Semente da Vida Eterna\u201d"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/69bb4cd273a2528548b63cccab4980a0","name":"Guilherme Rocha","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e480fee2377f81af36f6990ed742592a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e480fee2377f81af36f6990ed742592a?s=96&d=mm&r=g","caption":"Guilherme Rocha"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/guilhermerocha"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/263543"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=263543"}],"version-history":[{"count":8,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/263543\/revisions"}],"predecessor-version":[{"id":263552,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/263543\/revisions\/263552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/263544"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=263543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=263543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=263543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}