{"id":247715,"date":"2024-05-23T13:07:40","date_gmt":"2024-05-23T16:07:40","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=247715"},"modified":"2024-05-23T14:34:46","modified_gmt":"2024-05-23T17:34:46","slug":"frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html","title":{"rendered":"Frades aprofundam reflex\u00f5es sobre os 800 anos das Chagas de S\u00e3o Francisco de Assis"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"aligncenter wp-image-247716 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-scaled.jpg\" alt=\"\" width=\"1620\" height=\"1080\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-scaled.jpg 1620w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-450x300.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-1024x683.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-768x512.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-1536x1024.jpg 1536w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-2048x1365.jpg 2048w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-150x100.jpg 150w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">O Regional dos Frades do Esp\u00edrito Santo, composto pela Par\u00f3quia Santa Clara (Colatina), pela Par\u00f3quia Nossa Senhora do Ros\u00e1rio (Vila Velha) e pelo Santu\u00e1rio de Nossa Senhora da Penha, se reuniu\u00a0 no dia 20 de maio, em Vila Velha-ES.\u00a0 \u00c9 o menor Regional da da Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil, que est\u00e1 presente em 5 estados e na Funda\u00e7\u00e3o Imaculada M\u00e3e de Deus de Angola.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O encontro, realizado na Casa Verde, um dos espa\u00e7os pertencentes ao Convento de Nossa Senhora da Penha, teve in\u00edcio com a ora\u00e7\u00e3o da manh\u00e3 e uma breve reflex\u00e3o sobre a mem\u00f3ria da Sant\u00edssima Virgem Maria, M\u00e3e da Igreja, aquela que \u00e9 a \u201cM\u00e3e da Ordem dos Menores\u201d, como recordou Frei Jos\u00e9 Clemente M\u00fcller. Na sequ\u00eancia, os freis realizaram a leitura de um trecho do livro \u201cS\u00e3o Francisco das Chagas \u2013 Dois serm\u00f5es do Pe. Ant\u00f4nio Vieira\u201d, escrito pelo Frei Clar\u00eancio Neotti, por ocasi\u00e3o dos 800 anos da Impress\u00e3o das Chagas de S\u00e3o Francisco de Assis.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O frade fez uma partilha de quatro pensamentos sobre o acontecimento de 1224 no Monte Alverne. De acordo com Frei Clar\u00eancio, \u201cO Cristo Crucificado, portanto as chagas, fazem parte do cerne da espiritualidade vivida e ensinada por S\u00e3o Francisco. Segundo, na espiritualidade de S\u00e3o Francisco, o mist\u00e9rio da Gruta de Bel\u00e9m e o mist\u00e9rio da Cruz no Calv\u00e1rio, s\u00e3o faces da mesma medalha, s\u00e3o insepar\u00e1veis. Como \u00e9 que n\u00f3s temos o pres\u00e9pio e a cruz? Como Francisco viu e como n\u00f3s estamos vendo?\u201d, questionou Frei Clar\u00eancio. Depois, completou: \u201cO terceiro pensamento \u00e9 o sofrimento. O sofrimento continua sendo mist\u00e9rio, mas ganhou por Jesus um significado e Francisco penetrou fundo neste significado, n\u00e3o pela raz\u00e3o, mas pela f\u00e9, conduzida pelo amor. E por fim, o quarto pensamento, foi que Francisco escreveu uma ora\u00e7\u00e3o em agradecimento \u00e0s chagas que recebera. Em geral, n\u00f3s pedimos a cura, normalmente todo mundo faz isso. Observem que Francisco agradece o sofrimento, ele reza em agradecimento pelas chagas\u201d, afirmou o frade.<\/span><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-247715 gallery-columns-3 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-14-scaled.jpg'><img width=\"1024\" height=\"683\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-14-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-14-1024x683.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-14-450x300.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-14-768x512.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-14-1536x1024.jpg 1536w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-14-2048x1365.jpg 2048w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-14-150x100.jpg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-14-scaled.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-16-scaled.jpg'><img width=\"1024\" height=\"683\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-16-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-16-1024x683.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-16-450x300.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-16-768x512.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-16-1536x1024.jpg 1536w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-16-2048x1365.jpg 2048w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-16-150x100.jpg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-16-scaled.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-24-scaled.jpg'><img width=\"1024\" height=\"683\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-24-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-24-1024x683.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-24-450x300.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-24-768x512.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-24-1536x1024.jpg 1536w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-24-2048x1365.jpg 2048w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-24-150x100.jpg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-24-scaled.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><span style=\"font-weight: 400;\">No segundo momento do encontro, os frades falaram sobre a vida e miss\u00e3o das fraternidades. Destacando as festas da Penha e de Pentecostes, que envolvem principalmente o Convento e o Santu\u00e1rio de Vila Velha; e as a\u00e7\u00f5es paroquiais que t\u00eam obtido cada vez mais \u00eaxito, como o trabalho de institui\u00e7\u00e3o de Ministros da Palavra, al\u00e9m do acompanhamento vocacional feito pelas duas par\u00f3quias do regional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Frei Adriano Dias do Nascimento, Frei\u00a0 Robson de Castro Guimar\u00e3es e Frei Pedro Oliveira Rodrigues partilharam suas recentes experi\u00eancias em torno da m\u00edstica e da espiritualidade franciscana vividas na It\u00e1lia, especialmente no Monte Alverne, onde fizeram uma imers\u00e3o na vida de S\u00e3o Francisco de Assis, a partir da passagem pelo principais lugares onde o Pai Ser\u00e1fico viveu e seguiu para os bra\u00e7os do Pai.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Frei Robson destacou a virtude do sil\u00eancio. Para ele, os estigmas que o Serafim Alado, imprimiu no corpo de S\u00e3o Francisco, \u00e9 como se tamb\u00e9m imprimisse no cora\u00e7\u00e3o dos visitantes. \u201cO que nos chama aten\u00e7\u00e3o, al\u00e9m da beleza da natureza em todos os lugares onde Francisco passou, \u00e9 um sil\u00eancio absoluto. Ningu\u00e9m precisa pedir que voc\u00ea fa\u00e7a sil\u00eancio, s\u00f3 contemplar diante daquele paisagem, das constru\u00e7\u00f5es, ali mesmo voc\u00ea faz esse exerc\u00edcio de silenciar para entender o que \u00e9 aquilo, que \u00e9 lugar de ora\u00e7\u00e3o, medita\u00e7\u00e3o, recolhimento e permitir que Deus nos fale atrav\u00e9s da natureza, da constru\u00e7\u00e3o. No Monte Alverne, nos deparamos com um lugar especial, sagrado, tem uma energia diferente, uma for\u00e7a, uma presen\u00e7a que os olhos corporais n\u00e3o s\u00e3o capazes de enxergar, mas tem a presen\u00e7a de algo, de uma experi\u00eancia m\u00edstica, sobrenatural que ali aconteceu e permanece. De certa forma, sa\u00edmos chagados, n\u00e3o nas m\u00e3os nem nos p\u00e9s, mas no cora\u00e7\u00e3o com aquela experi\u00eancia\u201d, contou.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Emocionado, Frei Pedro recordou que foi sua terceira oportunidade de estar em Assis. \u201c\u00c9 emocionante, toca profundamente. O mais emocionante foi ler textos de S\u00e3o Boaventura e de Tom\u00e1s de Celano. Foi uma oportunidade de visualizar mentalmente Francisco naquele lugar. O que mais me marcou foi o afeto do povo com S\u00e3o Francisco. S\u00e3o muitos peregrinos que fazem, sem sentir cansa\u00e7o, os passos de Francisco, o percurso que ele fazia a p\u00e9. Foi uma experi\u00eancia grandiosa retornar \u00e0 Assis, num momento t\u00e3o especial como este quando celebramos 800 anos da impress\u00e3o das chagas do Ser\u00e1fico Pai\u201d, testemunhou.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 Frei Adriano comemorou como uma gra\u00e7a ver de perto como S\u00e3o Francisco combinava sua miss\u00e3o com a vida de contempla\u00e7\u00e3o. \u201cFoi uma experi\u00eancia muito bonita conhecer como S\u00e3o Francisco combina sua atividade pastoral, a vida apost\u00f3lica junto das pessoas, o an\u00fancio do Evangelho e a vida de penit\u00eancia, mas, tamb\u00e9m a vida de ora\u00e7\u00e3o, de contempla\u00e7\u00e3o. Hoje, ler as fontes franciscanas, a partir de uma experi\u00eancia real e concreta, reporta-nos \u00e0quela experi\u00eancia original do pr\u00f3prio S\u00e3o Francisco\u201d, disse.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os frades que estiveram no Cap\u00edtulo das Esteiras e na Reuni\u00e3o dos Guardi\u00e3es, em Agudos (SP), fizeram uma avalia\u00e7\u00e3o dos encontros. Por fim, Frei Djalmo Fuck, coordenador do Regional, passou algumas orienta\u00e7\u00f5es sobre a Visita Can\u00f4nica, a ser realizada no m\u00eas de agosto, e pediu sugest\u00f5es para a Festa da Penha 2025.<\/span><\/p>\n<hr \/>\n<p><em>Cristian Oliveira &#8211; Convento da Penha<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Encontro Regional Esp\u00edrito Santo<\/p>\n","protected":false},"author":11,"featured_media":247716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[1822],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Frades aprofundam reflex\u00f5es sobre os 800 anos das Chagas de S\u00e3o Francisco de Assis - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frades aprofundam reflex\u00f5es sobre os 800 anos das Chagas de S\u00e3o Francisco de Assis - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Encontro Regional Esp\u00edrito Santo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-23T16:07:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-23T17:34:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adriana Rabelo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adriana Rabelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-scaled.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-scaled.jpg\",\"width\":1620,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html\",\"name\":\"Frades aprofundam reflex\u00f5es sobre os 800 anos das Chagas de S\u00e3o Francisco de Assis - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html#primaryimage\"},\"datePublished\":\"2024-05-23T16:07:40+00:00\",\"dateModified\":\"2024-05-23T17:34:46+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/d9422e83121c3ad3b0f423d195f5bb25\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frades aprofundam reflex\u00f5es sobre os 800 anos das Chagas de S\u00e3o Francisco de Assis\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/d9422e83121c3ad3b0f423d195f5bb25\",\"name\":\"Adriana Rabelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0a937b7500cd7df77540cfb8bede877d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0a937b7500cd7df77540cfb8bede877d?s=96&d=mm&r=g\",\"caption\":\"Adriana Rabelo\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/adrianarabelo\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frades aprofundam reflex\u00f5es sobre os 800 anos das Chagas de S\u00e3o Francisco de Assis - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html","og_locale":"pt_BR","og_type":"article","og_title":"Frades aprofundam reflex\u00f5es sobre os 800 anos das Chagas de S\u00e3o Francisco de Assis - Not\u00edcias - Franciscanos","og_description":"Encontro Regional Esp\u00edrito Santo","og_url":"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2024-05-23T16:07:40+00:00","article_modified_time":"2024-05-23T17:34:46+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-scaled.jpg","type":"image\/jpeg"}],"author":"Adriana Rabelo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Adriana Rabelo","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-scaled.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/05\/Encontro-Regional-dos-Frades-do-ES-20-05-2024-31-scaled.jpg","width":1620,"height":1080},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html","name":"Frades aprofundam reflex\u00f5es sobre os 800 anos das Chagas de S\u00e3o Francisco de Assis - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html#primaryimage"},"datePublished":"2024-05-23T16:07:40+00:00","dateModified":"2024-05-23T17:34:46+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/d9422e83121c3ad3b0f423d195f5bb25"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/frades-aprofundam-reflexoes-sobre-os-800-anos-das-chagas-de-sao-francisco-de-assis.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Frades aprofundam reflex\u00f5es sobre os 800 anos das Chagas de S\u00e3o Francisco de Assis"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/d9422e83121c3ad3b0f423d195f5bb25","name":"Adriana Rabelo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0a937b7500cd7df77540cfb8bede877d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a937b7500cd7df77540cfb8bede877d?s=96&d=mm&r=g","caption":"Adriana Rabelo"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/adrianarabelo"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/247715"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=247715"}],"version-history":[{"count":4,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/247715\/revisions"}],"predecessor-version":[{"id":247723,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/247715\/revisions\/247723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/247716"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=247715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=247715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=247715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}