{"id":246495,"date":"2024-02-25T22:09:41","date_gmt":"2024-02-26T01:09:41","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=246495"},"modified":"2024-03-11T08:49:34","modified_gmt":"2024-03-11T11:49:34","slug":"caminhantes-de-frei-bruno-lotam-ruas-de-joacaba","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html","title":{"rendered":"Caminhantes de Frei Bruno lotam ruas de Joa\u00e7aba\u00a0"},"content":{"rendered":"<p><i><span style=\"font-weight: 400;\"><img loading=\"lazy\" class=\"aligncenter wp-image-246496 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-scaled.jpg\" alt=\"\" width=\"1350\" height=\"1080\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-scaled.jpg 1350w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-450x360.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-1024x819.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-768x614.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-1536x1229.jpg 1536w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-2048x1638.jpg 2048w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-150x120.jpg 150w\" sizes=\"(max-width: 1350px) 100vw, 1350px\" \/>\u00a0<\/span><\/i><i><span style=\"font-weight: 400;\">Fi\u00e9is agradecem por mais um passo dado no processo de beatifica\u00e7\u00e3o do servo de Deus<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Logo que os sinos da Catedral Diocesana Santa Teresinha do Menino Jesus tocaram, \u00e0s 6h, numa manh\u00e3 tranquila de domingo, na cidade de Joa\u00e7aba, em Santa Catarina, fi\u00e9is e religiosos vindos de diferentes localidades catarinenses e tamb\u00e9m do Paran\u00e1 come\u00e7aram a se concentrar e rezar em prepara\u00e7\u00e3o para mais um ano de \u201cCaminhada Penitencial Frei Bruno\u201d. Estavam presentes os\u00a0<\/span>frades do Noviciado S\u00e3o Jos\u00e9, de Rodeio (SC) e de outros Estados, bem como padres\u00a0 diocesanos.<\/p>\n<p>O ambiente revelava um clima de alegria e, ao mesmo tempo, os olhares traziam express\u00f5es de contempla\u00e7\u00e3o, como forma de agradecer a Deus pela oportunidade de poder participar de um momento de f\u00e9. Os gestos eram de acolhida como entre irm\u00e3os e irm\u00e3s que h\u00e1 um bom tempo n\u00e3o se viam e estavam felizes com o reencontro.<\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-246497 alignleft\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-300x450.jpg\" alt=\"\" width=\"300\" height=\"450\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-300x450.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-683x1024.jpg 683w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-768x1152.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-1024x1536.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-1365x2048.jpg 1365w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-150x225.jpg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-scaled.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Assim come\u00e7ou a 34\u00aa edi\u00e7\u00e3o da caminhada mobilizando centenas de fi\u00e9is que lotaram as ruas da regi\u00e3o central de Joa\u00e7aba para louvar o servo de Deus que, para o povo, j\u00e1 \u00e9 reconhecido como santo. Convictos da miss\u00e3o proposta para o dia 25 de fevereiro, os caminhantes de Frei Bruno Linden repetiram gestos daquele que foi exemplo de f\u00e9, solidariedade e compaix\u00e3o quando rezaram e carregaram suas cruzes, uma das marcas da caminhada. Foram dezenas delas representando o sacrif\u00edcio e o calv\u00e1rio que cada filho e filha de Deus queriam expressar naquele momento de caminhada de f\u00e9, em busca da santidade. Outras pessoas tamb\u00e9m fizeram a p\u00e9 o trajeto de 4 quil\u00f4metros at\u00e9 o Cemit\u00e9rio Frei Edgar, onde est\u00e1 sepultado o Servo de Deus. Mas, dentre tantas manifesta\u00e7\u00f5es de piedade, todas tinham o objetivo de louvar a Deus e agradecer pelas gra\u00e7as alcan\u00e7adas por intercess\u00e3o de Frei Bruno.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cFrei Bruno viveu em outros lugares em Santa Catarina, mas, os \u00faltimos 5 anos da sua vida foram em Joa\u00e7aba. Quando chegou nessa cidade, o povo j\u00e1 percebia sua santidade na simplicidade, na devo\u00e7\u00e3o, no servi\u00e7o \u00e0s fam\u00edlias e ao povo. A partir disso, vemos que ele \u00e9 um exemplo para n\u00f3s. A manifesta\u00e7\u00e3o do povo \u00e9 a concretiza\u00e7\u00e3o que n\u00f3s j\u00e1 trazemos no cora\u00e7\u00e3o, de que Frei Bruno para n\u00f3s j\u00e1 \u00e9 um santo. O processo iniciado h\u00e1 12 anos para a beatifica\u00e7\u00e3o e canoniza\u00e7\u00e3o \u00e9 um tr\u00e2mite formal da Igreja que deve ser respeitado e acolhido. Mas, \u00e9 importante ver uma manifesta\u00e7\u00e3o t\u00e3o especial como essa se repetindo h\u00e1 34 anos\u201d, salientou o Ministro Provincial da Imaculada Concei\u00e7\u00e3o do Brasil, Frei Paulo Roberto Pereira, que participou pela primeira vez da caminhada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201c\u00c9 emocionante presenciar a f\u00e9 da nossa comunidade, que todos os anos se re\u00fane e coloca-se em ora\u00e7\u00e3o e penit\u00eancia, agradecendo e pedindo gra\u00e7as ao nosso querido Servo de Deus Frei Bruno\u201d, resumiu Dom Frei M\u00e1rio Marquez, bispo da Diocese de Joa\u00e7aba.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ap\u00f3s a caminhada, foi celebrada uma Santa Missa no Cemit\u00e9rio Frei Edgar, presidida por Dom Frei M\u00e1rio Marquez e concelebrada pelo Ministro Provincial da Imaculada Concei\u00e7\u00e3o do Brasil, Frei Paulo Roberto Pereira, OFM, al\u00e9m do Padre Joveci, p\u00e1roco da Par\u00f3quia Catedral Santa Teresinha do Menino Jesus, bem como outros religiosos da Diocese de Joa\u00e7aba e Freis Franciscanos.<\/span><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter wp-image-246498 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-scaled.jpg\" alt=\"\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-scaled.jpg 1620w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-450x300.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-1024x683.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-768x512.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-1536x1024.jpg 1536w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-2048x1365.jpg 2048w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-150x100.jpg 150w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p><b>Causa da beatifica\u00e7\u00e3o de Frei Bruno<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Ao final da Santa Missa, o vice-postulador para a Causa de Frei Bruno, Frei Alex Ciarnoski, OFM, detalhou o processo de beatifica\u00e7\u00e3o que est\u00e1 em fase de an\u00e1lise no Vaticano, em Roma. De acordo com Frei Alex, o processo passou por avan\u00e7os ao longo do \u00faltimo ano.\u00a0 O sacerdote destacou que \u201ca etapa diocesana foi finalmente conclu\u00edda com o documento chamado \u201cPosition\u201d, um resumo de tudo o que foi enviado para o Vaticano at\u00e9 o momento. A partir de agora, o documento ser\u00e1 analisado e a expectativa \u00e9 de que, em breve, Frei Bruno seja declarado vener\u00e1vel pela Igreja\u201d.<\/span><\/p>\n<p><img loading=\"lazy\" class=\"alignleft wp-image-246499 size-medium\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-450x300.jpg\" alt=\"\" width=\"450\" height=\"300\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-450x300.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-1024x683.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-768x512.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-1536x1024.jpg 1536w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-2048x1365.jpg 2048w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-150x100.jpg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-scaled.jpg 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Frei Alex informou ainda que, a partir de agora, \u201ca Diocese de Joa\u00e7aba nomear\u00e1 mais um Tribunal que escolher\u00e1 um milagre, dos tantos evidenciados pela devo\u00e7\u00e3o \u00e0 Frei Bruno, que ser\u00e1 enviado novamente ao Vaticano com o intuito de que ele seja reconhecido e que Frei Bruno possa chegar a sua beatifica\u00e7\u00e3o\u201d, finalizou.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O documento enviado ao Ministro Provincial, Frei Paulo Pereira, no\u00a0 dia 19 de fevereiro, pelo Postulador Geral da Ordem dos Frades Menores, respons\u00e1vel por acompanhar a causa da Beatifica\u00e7\u00e3o do Servo de Deus Frei Bruno Linden, OFM, Frei Giovan Guiseppe Califano, OFM, diz:<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u201cDe fato, \u00e9 com muita alegria que lhes informo que a Postula\u00e7\u00e3o Geral \u2013 um Escrit\u00f3rio respons\u00e1vel pelas Causas dos Santos \u2013 da Ordem dos Frades Menores, em Roma, concluiu, em janeiro de 2024, o trabalho de elabora\u00e7\u00e3o da Positio super vita et virtutibus, ou seja, a obra no qual est\u00e1 resumida toda a documenta\u00e7\u00e3o do Processo Diocesano de Joa\u00e7aba. A Positio ser\u00e1 utilizada pelos te\u00f3logos do Dicast\u00e9rio para as Causas dos Santos para expressar seu julgamento sobre a vida, as virtudes e a fama de santidade do Frei Bruno Linden, para que em breve ele seja declarado Vener\u00e1vel\u201d.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">No texto, Frei Giovan Guiseppe Califano, tamb\u00e9m recordou a vida de Frei Bruno, celebrada durante a caminhada do dia 25, data que tamb\u00e9m marcou sua partida para junto do Pai.<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u201cO Servo de Deus Frei Bruno Linden, tendo deixado sua terra natal para deixar-se conduzir onde Deus o quisesse, representa de modo excelente a natureza mission\u00e1ria da Igreja e o esp\u00edrito mission\u00e1rio da Ordem dos Frades Menores. Considerava o Brasil sua segunda p\u00e1tria e se dedicava com zelo \u00e0 prega\u00e7\u00e3o do Evangelho e ao cuidado das almas. Foi um verdadeiro pastor, rico em miseric\u00f3rdia e caridade. Todos n\u00f3s rezamos a ele no anivers\u00e1rio de seu falecimento, 25 de fevereiro, para que, com seu exemplo e intercess\u00e3o, ele nos ajude a sermos fi\u00e9is disc\u00edpulos do Senhor\u201d.<\/span><\/i><\/p>\n<hr \/>\n<p>Adriana Rabelo Rodrigues<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 11%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-246495 gallery-columns-9 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-01-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-01-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-01-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-01-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-02-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-02-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-02-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-02-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-03-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-03-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-03-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-03-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-04-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-04-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-04-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-04-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-05-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-05-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-05-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-05-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-06-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-06-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-06-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-06-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-1-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-1-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-1-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-07-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-08-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-08-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-08-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-08-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-1-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-1-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-1-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-10-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-10-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-10-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-10-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-11-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-11-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-11-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-11-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-1-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-1-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-1-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-12-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-13-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-13-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-13-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-13-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-14-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-14-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-14-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-14-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-15-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-15-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-15-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-15-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-16-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-16-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-16-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-16-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-17-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-17-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-17-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-17-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-18-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-18-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-18-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-18-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-19-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-19-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-19-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-19-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-20-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-20-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-20-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-20-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-21-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-21-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-21-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-21-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-22-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-22-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-22-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-22-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-1-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-1-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-1-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-23-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-24-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-24-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-24-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-24-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-26-scaled.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-26-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-26-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-26-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Caminhada Penitencial Frei Bruno<\/p>\n","protected":false},"author":10,"featured_media":246496,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[1991],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caminhantes de Frei Bruno lotam ruas de Joa\u00e7aba\u00a0 - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caminhantes de Frei Bruno lotam ruas de Joa\u00e7aba\u00a0 - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Caminhada Penitencial Frei Bruno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-26T01:09:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-11T11:49:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jo\u00e3o Vitor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jo\u00e3o Vitor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-scaled.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-scaled.jpg\",\"width\":1350,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html\",\"name\":\"Caminhantes de Frei Bruno lotam ruas de Joa\u00e7aba\u00a0 - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html#primaryimage\"},\"datePublished\":\"2024-02-26T01:09:41+00:00\",\"dateModified\":\"2024-03-11T11:49:34+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/8c11f06a466b856a11dd48d20600055f\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caminhantes de Frei Bruno lotam ruas de Joa\u00e7aba\u00a0\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/8c11f06a466b856a11dd48d20600055f\",\"name\":\"Jo\u00e3o Vitor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/10ba5c9713e0c323617b4309a19e3a46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/10ba5c9713e0c323617b4309a19e3a46?s=96&d=mm&r=g\",\"caption\":\"Jo\u00e3o Vitor\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/joaovitor\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caminhantes de Frei Bruno lotam ruas de Joa\u00e7aba\u00a0 - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html","og_locale":"pt_BR","og_type":"article","og_title":"Caminhantes de Frei Bruno lotam ruas de Joa\u00e7aba\u00a0 - Not\u00edcias - Franciscanos","og_description":"Caminhada Penitencial Frei Bruno","og_url":"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2024-02-26T01:09:41+00:00","article_modified_time":"2024-03-11T11:49:34+00:00","og_image":[{"width":1350,"height":1080,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-scaled.jpg","type":"image\/jpeg"}],"author":"Jo\u00e3o Vitor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jo\u00e3o Vitor","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-scaled.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2024\/02\/ROMARIA-FREI-BRUNO-09-scaled.jpg","width":1350,"height":1080},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html","name":"Caminhantes de Frei Bruno lotam ruas de Joa\u00e7aba\u00a0 - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html#primaryimage"},"datePublished":"2024-02-26T01:09:41+00:00","dateModified":"2024-03-11T11:49:34+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/8c11f06a466b856a11dd48d20600055f"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/caminhantes-de-frei-bruno-lotam-ruas-de-joacaba.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Caminhantes de Frei Bruno lotam ruas de Joa\u00e7aba\u00a0"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/8c11f06a466b856a11dd48d20600055f","name":"Jo\u00e3o Vitor","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/10ba5c9713e0c323617b4309a19e3a46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/10ba5c9713e0c323617b4309a19e3a46?s=96&d=mm&r=g","caption":"Jo\u00e3o Vitor"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/joaovitor"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/246495"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=246495"}],"version-history":[{"count":11,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/246495\/revisions"}],"predecessor-version":[{"id":246613,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/246495\/revisions\/246613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/246496"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=246495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=246495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=246495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}