{"id":245826,"date":"2023-12-13T06:48:22","date_gmt":"2023-12-13T09:48:22","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=245826"},"modified":"2023-12-13T06:48:22","modified_gmt":"2023-12-13T09:48:22","slug":"papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html","title":{"rendered":"Papa: o crist\u00e3o deve ser aberto \u00e0 Palavra de Deus e aos irm\u00e3os"},"content":{"rendered":"<div id=\"attachment_245827\" style=\"width: 1043px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-245827\" loading=\"lazy\" class=\"wp-image-245827\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/12\/audiencia_13.jpeg\" alt=\"\" width=\"1033\" height=\"581\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/12\/audiencia_13.jpeg 750w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/12\/audiencia_13-450x253.jpeg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/12\/audiencia_13-150x84.jpeg 150w\" sizes=\"(max-width: 1033px) 100vw, 1033px\" \/><p id=\"caption-attachment-245827\" class=\"wp-caption-text\"><em>Imagem: Vatican Media<\/em><\/p><\/div>\n<p>O Papa Francisco concluiu o ciclo de catequeses sobre o zelo apost\u00f3lico na Audi\u00eancia Geral, desta quarta-feira (13\/12), realizada na Sala Paulo VI.<\/p>\n<p>Durante este per\u00edodo, &#8220;nos deixamos inspirar pela Palavra de Deus, pela vida de algumas testemunhas e pelo Magist\u00e9rio recente para cultivar a paix\u00e3o pelo an\u00fancio do Evangelho&#8221;, disse Francisco, recordando que o zelo apost\u00f3lico &#8220;diz respeito a todos os crist\u00e3os, desde o in\u00edcio&#8221;. No Batismo, o celebrante diz, tocando os ouvidos e os l\u00e1bios do batizado: &#8220;O Senhor Jesus que fez os surdos ouvir e os mudos falar, te conceda que possas logo ouvir a sua palavra e professar a f\u00e9&#8221;.<\/p>\n<p>Jesus realiza um sinal prodigioso a um homem surdo. O evangelista Marcos descreve onde isso aconteceu: &#8220;No mar da Galileia. &#8220;O que esses territ\u00f3rios t\u00eam em comum?&#8221;, perguntou o Papa. &#8220;O fato de serem predominantemente habitados por pag\u00e3os&#8221;, respondeu. &#8220;Jesus \u00e9 capaz de abrir os ouvidos e a boca, ou seja, o fen\u00f4meno do mutismo e da surdez na B\u00edblia \u00e9 tamb\u00e9m metaf\u00f3rico e designa o fechamento aos apelos de Deus&#8221;, disse ainda Francisco, ressaltando que &#8220;h\u00e1 uma surdez f\u00edsica, mas na B\u00edblia quem \u00e9 surdo para a Palavra de Deus \u00e9 mudo, pois n\u00e3o comunica a Palavra de Deus&#8221;.<\/p>\n<p>Outro sinal \u00e9 indicativo: o Evangelho relata a palavra decisiva de Jesus em aramaico: Efat\u00e1 significa \u201cabre-te\u201d que se abram os ouvidos e que se abra a l\u00edngua. \u00c9 um convite dirigido n\u00e3o tanto ao surdo-mudo, que n\u00e3o podia ouvi-lo, mas aos disc\u00edpulos de ent\u00e3o e de todos os tempos.<\/p>\n<p>Tamb\u00e9m n\u00f3s, que recebemos o Efat\u00e1 do Esp\u00edrito no Batismo, somos chamados a abrir-nos. \u201cAbre-te\u201d, diz Jesus a cada fiel e \u00e0 sua Igreja: abre-te porque a mensagem do Evangelho precisa de ser testemunhada e anunciada! E isso faz pensar no comportamento do crist\u00e3o. O crist\u00e3o deve ser aberto \u00e0 Palavra de Deus e ao servi\u00e7o dos outros. Os crist\u00e3os fechados terminam sempre mal, pois n\u00e3o s\u00e3o crist\u00e3os, mas ide\u00f3logos, ide\u00f3logos do fechamento. O crist\u00e3o deve ser aberto no an\u00fancio da palavra e no acolhimento dos irm\u00e3os e irm\u00e3os.<\/p>\n<p>Segundo o Papa, &#8220;este Efat\u00e1, abrir-se, \u00e9 um convite a todos n\u00f3s. No final dos Evangelhos, Jesus nos d\u00e1 esse seu desejo mission\u00e1rio. Ir al\u00e9m, ir apascentar e pregar o Evangelho&#8221;.<\/p>\n<p>Irm\u00e3os e irm\u00e3s, sintamo-nos todos chamados, como batizados, a testemunhar e anunciar Jesus. Pe\u00e7amos a gra\u00e7a, como Igreja, de poder realizar uma convers\u00e3o pastoral e mission\u00e1ria. O Senhor, \u00e0s margens do mar da Galileia, perguntou a Pedro se ele o amava e depois pediu-lhe que apascentasse as suas ovelhas.<\/p>\n<p>Francisco convidou cada um a se perguntar: &#8220;Amo realmente o Senhor, a ponto de querer anunci\u00e1-lo? Quero ser sua testemunha ou contento-me em ser seu disc\u00edpulo? Levo a s\u00e9rio as pessoas que encontro, levo-as at\u00e9 Jesus na ora\u00e7\u00e3o? Desejo fazer algo para que a alegria do Evangelho, que transformou a minha vida, torne a deles mais bonita tamb\u00e9m?&#8221; &#8220;Pensemos nessas perguntas e sigamos adiante em nosso testemunho&#8221;, concluiu.<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News (texto de Mariangela Jaguraba)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Audi\u00eancia Geral<\/p>\n","protected":false},"author":3,"featured_media":245827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[487],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papa: o crist\u00e3o deve ser aberto \u00e0 Palavra de Deus e aos irm\u00e3os - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa: o crist\u00e3o deve ser aberto \u00e0 Palavra de Deus e aos irm\u00e3os - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Audi\u00eancia Geral\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-13T09:48:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/12\/audiencia_13.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/12\/audiencia_13.jpeg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/12\/audiencia_13.jpeg\",\"width\":750,\"height\":422},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html\",\"name\":\"Papa: o crist\u00e3o deve ser aberto \u00e0 Palavra de Deus e aos irm\u00e3os - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html#primaryimage\"},\"datePublished\":\"2023-12-13T09:48:22+00:00\",\"dateModified\":\"2023-12-13T09:48:22+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa: o crist\u00e3o deve ser aberto \u00e0 Palavra de Deus e aos irm\u00e3os\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa: o crist\u00e3o deve ser aberto \u00e0 Palavra de Deus e aos irm\u00e3os - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html","og_locale":"pt_BR","og_type":"article","og_title":"Papa: o crist\u00e3o deve ser aberto \u00e0 Palavra de Deus e aos irm\u00e3os - Not\u00edcias - Franciscanos","og_description":"Audi\u00eancia Geral","og_url":"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2023-12-13T09:48:22+00:00","og_image":[{"width":750,"height":422,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/12\/audiencia_13.jpeg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/12\/audiencia_13.jpeg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/12\/audiencia_13.jpeg","width":750,"height":422},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html","name":"Papa: o crist\u00e3o deve ser aberto \u00e0 Palavra de Deus e aos irm\u00e3os - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html#primaryimage"},"datePublished":"2023-12-13T09:48:22+00:00","dateModified":"2023-12-13T09:48:22+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-o-cristao-deve-ser-aberto-a-palavra-de-deus-e-aos-irmaos.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Papa: o crist\u00e3o deve ser aberto \u00e0 Palavra de Deus e aos irm\u00e3os"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/245826"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=245826"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/245826\/revisions"}],"predecessor-version":[{"id":245828,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/245826\/revisions\/245828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/245827"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=245826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=245826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=245826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}