{"id":244067,"date":"2023-07-14T14:25:37","date_gmt":"2023-07-14T17:25:37","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=244067"},"modified":"2023-07-14T14:25:37","modified_gmt":"2023-07-14T17:25:37","slug":"frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html","title":{"rendered":"Frei Raimundo celebra 25 anos de minist\u00e9rio presbiteral neste domingo"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-244068\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01-1024x576.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><em>Com o tema: \u201cTendo amado os seus que estavam no mundo, amou-os at\u00e9 o fim\u201d, Frei Raimundo Justiniano de Oliveira Castro foi ordenado presb\u00edtero, nas m\u00e3os de Dom Lu\u00eds Fl\u00e1vio Cappio, no dia 18 de julho de 1998. Neste domingo, \u00e0s 11h30, na Par\u00f3quia S\u00e3o Francisco de Assis, na Vila Clementino, em S\u00e3o Paulo, onde reside atualmente, Frei Raimundo celebrar\u00e1 o jubileu de 25 anos de minist\u00e9rio presbiteral. Natural de Batatais, no interior de S\u00e3o Paulo, Frei Raimundo ingressou na vida religiosa franciscana quando j\u00e1 era adulto. Nesta entrevista, ele conta um pouco de sua vida e sua forma\u00e7\u00e3o religiosa. <\/em><\/p>\n<p><strong>Site Franciscanos &#8211; Frei Raimundo, por favor, fale um pouco de sua fam\u00edlia.<\/strong><\/p>\n<p><strong>Frei Raimundo<\/strong> &#8211; Tenho uma fam\u00edlia muito bonita, natural de Batatais, no interior de S\u00e3o Paulo, onde nasci. Minha m\u00e3e, Dona Joana D&#8217;Arc, e meu pai, o sr. Abelardo, tiveram oito filhos (quatro homens e quatro mulheres), do qual eu sou segundo mais velho. Uma irm\u00e3 \u00e9 a mais velha. Eu nasci e fui criado num ber\u00e7o crist\u00e3o, principalmente pelo exemplo de minha m\u00e3e, embora meu pai n\u00e3o fosse ass\u00edduo nas Missas e outras celebra\u00e7\u00f5es da Igreja, era um homem crist\u00e3o e com quem eu tinha muita proximidade. Tamb\u00e9m me marcou muito o testemunho de minha av\u00f3 materna, a \u00fanica que eu conheci, al\u00e9m de minhas tias.<\/p>\n<p>Formamos uma fam\u00edlia numerosa e muito alegre, muito festiva, muito participativa em todos os momentos que estamos juntos. Meu pai faleceu cedo, deixou minha m\u00e3e vi\u00fava com 50 anos. Isso me levou a ter uma vida muito ativa na fam\u00edlia. Naquela \u00e9poca n\u00e3o era t\u00e3o f\u00e1cil. A pens\u00e3o do marido n\u00e3o vinha t\u00e3o r\u00e1pido, ent\u00e3o eu procurei ajudar minha m\u00e3e. Trabalhava em S\u00e3o Paulo e, com isso, ajudei-a formar tr\u00eas filhos e fazer o casamento de tr\u00eas irm\u00e3os. Minha m\u00e3e faleceu em dezembro de 2021.<\/p>\n<p>Fiquei na minha cidade at\u00e9 o final dos 18 anos. Estudei at\u00e9 o terceiro Colegial, na \u00e9poca se falava assim. Vim para S\u00e3o Paulo para trabalhar e estudar. Sempre fui muito &#8220;caxias&#8221; nos estudos e ingressei na Universidade de S\u00e3o Paulo (USP), para cursar Ci\u00eancias Cont\u00e1beis.<\/p>\n<p>Quando vim para S\u00e3o Paulo, minha irm\u00e3 j\u00e1 estava aqui, mas fui morar durante meio ano com a fam\u00edlia de minha tia. Me mudei quando tr\u00eas colegas, que estudaram comigo em Batatais, vieram tamb\u00e9m para a capital. Moramos numa pens\u00e3o e depois numa rep\u00fablica, na rua Major Diogo, no centro de S\u00e3o Paulo.<\/p>\n<p><strong>Site franciscanos &#8211; E como foi a sua vida profissional na capital?<\/strong><\/p>\n<p><strong>Frei Raimundo<\/strong> &#8211; Logo que cheguei aqui, n\u00e3o tinha conseguido emprego. Tinha passado em um concurso p\u00fablico para a Secretaria de Educa\u00e7\u00e3o, mas demorava para chamar. E quando chamou, eu havia conseguido outro emprego melhor, na pr\u00f3pria Secretaria da Educa\u00e7\u00e3o. Depois, fiz o concurso do Banco do Brasil e passei.\u00a0 Trabalhei na ag\u00eancia da Rua 7 de abril. Contudo, um primo que trabalhava na ag\u00eancia central me levou para l\u00e1, dizendo que &#8220;ali eu tinha condi\u00e7\u00f5es de fazer uma carreira melhor&#8221;. No \u00faltimo ano da faculdade, eu vi um cartaz com oferta para o cargo de auditor. Na \u00e9poca tinha tr\u00eas grandes empresas no ramo: Price, a Arthur Andersen e KPMG. Eu me inscrevi nas tr\u00eas e fui fazendo o teste de sele\u00e7\u00e3o. Passei na Price e KPMG e acabei escolhendo a Price, que eu tinha prefer\u00eancia. Ali trabalhei 10 anos, saindo aos 34 anos, em 1988, para ingressar na vida religiosa franciscana.<\/p>\n<p><strong>Site franciscanos &#8211; E como se deu o seu discernimento vocacional?<\/strong><\/p>\n<p><strong>Frei Raimundo<\/strong> &#8211; Na verdade, desde crian\u00e7a eu j\u00e1 tinha iniciado esse discernimento vocacional. E depois, com o tempo, em v\u00e1rios momentos da minha vida, essa quest\u00e3o vocacional voltava. Mas ela sempre foi forte. A decis\u00e3o ficou mais clara quando eu percebi que a miss\u00e3o com minha m\u00e3e, de encaminhar os filhos, formados ou na faculdade, estava completa. Decidi ir atr\u00e1s daquilo que queria e, aos 30 anos, come\u00e7o a levar adiante esse processo vocacional.<\/p>\n<p>Fiz uma an\u00e1lise com uma psic\u00f3loga e mostrei minha inten\u00e7\u00e3o vocacional e ela disse para ir adiante. Nessa \u00e9poca, eu morava na Pra\u00e7a Amadeu Amaral, na Bela Vista. Era pr\u00f3ximo da Igreja Imaculada Concei\u00e7\u00e3o, dos Frades Capuchinhos, na avenida Brigadeiro Luiz Ant\u00f4nio. Frequentei muito a igreja da Imaculada. Era amigo dos capuchinhos e de modo particular de Frei Lino, um frade muito ativo naquela igreja. Participava de c\u00edrculos b\u00edblicos, que na \u00e9poca eram ministrados pela Ana Flora Anderson e Gilberto Gorgulho [frade dominicano que, em companhia do Cardeal Dom Paulo Evaristo Arns, atuou na defesa dos direitos humanos durante a ditadura militar, programou e coordenou um vasto programa para a forma\u00e7\u00e3o de ministros da palavra, envolvendo milhares de pessoas na Arquidiocese de S\u00e3o Paulo]. Eu tamb\u00e9m fazia parte do Grupo de Jovens e da Pastoral do Leitorato.<\/p>\n<p>Mas na hora de iniciar o meu acompanhamento vocacional, fui procurar o Convento S\u00e3o Francisco. Se voc\u00ea me perguntar o porqu\u00ea, eu digo que n\u00e3o sei. N\u00e3o tenho uma explica\u00e7\u00e3o, embora eu frequentava muito o Convento S\u00e3o Francisco durante a semana. Eu sempre arrumava um jeito de passar ali, onde conheci o Frei Pedro Pinheiro, que trabalhava na portaria do Convento. Eu conversava muito com ele. E tamb\u00e9m conversava com o Frei Lu\u00eds Fernando de Mendon\u00e7a, orientador vocacional do Convento, mas conversava sem dizer que eu tinha interesse na vida religiosa. Fui deixando a vida correr.<\/p>\n<p><strong>Site Franciscanos &#8211; Voc\u00ea chegou a ter d\u00favidas sobre a Ordem que escolheria? Voc\u00ea j\u00e1 conhecia S\u00e3o Francisco de Assis? <\/strong><\/p>\n<p><strong>Frei Raimundo <\/strong>&#8211; N\u00e3o, eu queria ser franciscano. Quem me apresentou S\u00e3o Francisco foi Santo Ant\u00f4nio. A\u00ed volto l\u00e1 na minha inf\u00e2ncia. Tinha uma senhora que era amiga da minha m\u00e3e e que ia, todas as ter\u00e7as-feiras, em nossa casa e ela me levava para uma capelinha de Santo Ant\u00f4nio que tinha em Batatais. A\u00ed eu fui atr\u00e1s de saber quem era Santo Ant\u00f4nio. E quando eu li sobre este santo, vi que ele era franciscano e da Ordem de S\u00e3o Francisco de Assis. Fui, ent\u00e3o, em busca de conhecer tamb\u00e9m este santo fundador. Ent\u00e3o, eu sou franciscano, porque conheci S\u00e3o Francisco via Santo Ant\u00f4nio.<\/p>\n<p><strong>Site Franciscanos &#8211; Como foi o seu caminho formativo religioso franciscano?<\/strong><\/p>\n<p><strong>Frei Raimundo<\/strong> &#8211; Fiz os Encontros Vocacionais no Convento S\u00e3o Francisco, at\u00e9 o final de 1987, com o Frei Lu\u00eds Fernando, depois de um ano e meio de acompanhamento. Segui, ent\u00e3o, para o Sevoa (Semin\u00e1rio de Voca\u00e7\u00f5es Adultas, em Guaratinguet\u00e1), em 1988. Ali fiz um ano de Aspirantando e um de Postulantado. Eu fiz parte da \u00faltima turma que fez o segundo ano de Sevoa. Naquele tempo ainda existia o Semin\u00e1rio de Agudos, e durante dois meses convivemos com a turma dali que \u00edamos para o Noviciado, em Rodeio.<\/p>\n<p>O Noviciado foi o melhor ano de minha vida. Dizem que \u00e9 a &#8220;ano da prova\u00e7\u00e3o&#8221;, mas para mim foi o &#8220;ano da gra\u00e7a&#8221;. E de fato foi o ano da gra\u00e7a. Ali, eu me debrucei sobre a vida de S\u00e3o Francisco, ali eu me encantei com a espiritualidade franciscana, tendo como mestre Frei Uli (Dom Leonardo Steiner, Arcebispo de Manaus). Eu j\u00e1 gostava da espiritualidade, mas ali fui entender por que S\u00e3o Francisco \u00e9 esse santo atual depois de 800 anos. O mestre abriu muitos caminhos para conhecermos S\u00e3o Francisco. Ele \u00e9, de fato, um santo para todas as \u00e9pocas, para todas as pessoas e para tudo ele apresenta uma possibilidade nova. Sou grato a Deus por ter passado pelo Noviciado e com a ajuda do Mestre Frei Uli, com quem tive uma rela\u00e7\u00e3o muito boa.<\/p>\n<p>Depois fui para Rondinha. No come\u00e7o foi tenso, pois parecia outro mundo. Mas foi s\u00f3 no primeiro semestre. Depois j\u00e1 me acostumei e gostei muito de viver em Rondinha. Ali, o irm\u00e3o de Frei Uli, Frei Wilson Steiner, foi meu mestre e Frei Fid\u00eancio, vice-mestre. Havia uma grande Fraternidade a servi\u00e7o da forma\u00e7\u00e3o.<\/p>\n<p>Cheguei em Petr\u00f3polis, para cursar a Teologia, um pouco assustado e perdido no primeiro semestre. Mas depois me encontrei e me encantei. O Convento do Sagrado\/ITF \u00e9 uma das casas, junto com o Noviciado, que mais me marcaram. Lembro-me que, na \u00faltima Missa de formatura, dei um testemunho em que citei o teor da carta de S\u00e3o Francisco a Santo Ant\u00f4nio: \u201cGostaria muito que ensinasse aos irm\u00e3os a Sagrada Teologia, contanto que neste estudo, n\u00e3o extingam o esp\u00edrito da santa ora\u00e7\u00e3o e da devo\u00e7\u00e3o\u201d. Petr\u00f3polis\/Sagrado\/ITF foi a Casa que me fez ver a import\u00e2ncia da Teologia, da ora\u00e7\u00e3o e da devo\u00e7\u00e3o na vida do frade menor. \u00a0Tive \u00a0bons mestres, professores amigos. Tempo saudoso vivido em Petr\u00f3polis!<\/p>\n<p><strong>Site Franciscanos &#8211; E como foi a ordena\u00e7\u00e3o presbiteral?<\/strong><\/p>\n<p><strong>Frei Raimundo<\/strong> &#8211; Com o lema: \u201cTendo amado os seus que estavam no mundo, amou-os at\u00e9 o fim\u201d, fui ordenado em Batatais, por Dom Lu\u00eds Fl\u00e1vio Cappio, no dia 18 de julho de 1998. Mandei um convite para Dom Cappio, mas disse que n\u00e3o poder\u00e1 vir. Disse que n\u00e3o esquece de mim porque fui um dos primeiros que ele ordenou. Desde aquele dia, disse que reza por mim. Todo mundo ficou muito encantado com a sua celebra\u00e7\u00e3o.<\/p>\n<p>Comecei meu minist\u00e9rio na forma\u00e7\u00e3o. Fui transferido para o Semin\u00e1rio de Agudos. Ali fiquei tr\u00eas anos. Gostava, mesmo sendo uma responsabilidade enorme que reca\u00eda sobre os formadores. Fiquei ali at\u00e9 2000 e fui para o Semin\u00e1rio Frei Galv\u00e3o, em Guaratinguet\u00e1. Dali fui para Universidade S\u00e3o Francisco, em Bragan\u00e7a Paulista. Na \u00e9poca, a Fraternidade morava em Campinas. Fiquei dez meses e depois vim para o Convento S\u00e3o Francisco para trabalhar no economato. Mas na \u00e9poca havia a necessidade de um vice-mestre em Rondinha e fiquei s\u00f3 dois meses em S\u00e3o Paulo. Fiquei de 2003 a 2006 em Rondinha. Com a doen\u00e7a de Frei Jurandir Cristofolini, voltei para S\u00e3o Paulo para trabalhar no Economato junto com Frei M\u00e1rio Luiz Tagliari. E com isso vou completar seis tri\u00eanios trabalhando aqui.<\/p>\n<p><strong>Site Franciscanos &#8211; Como \u00e9 celebrar o jubileu de 25 anos de vida presbiteral? <\/strong><\/p>\n<p><strong>Frei Raimundo<\/strong> &#8211; Tenho mais coisas bonitas do que n\u00e3o boas. Porque eu me realizo na minha voca\u00e7\u00e3o franciscana e sacerdotal. Claro, muitas coisinhas ficaram pelo caminho. Todo mundo tem problemas. Alguns entraves, mas para mim j\u00e1 est\u00e3o em alto mar, quer dizer j\u00e1 passaram debaixo da minha ponte e o rio levou adiante. Tenho alegria de ter convivido com frades muito bons, que marcaram a minha vida. Essa conviv\u00eancia em fraternidade \u00e9 ess\u00eancia da vida que escolhi.<\/p>\n<p>Aqui, como vice-ec\u00f4nomo, mexo com os n\u00fameros, mas gra\u00e7as a Deus tem a Par\u00f3quia do lado para exercer o meu minist\u00e9rio.<\/p>\n<p>Gostaria de destacar tamb\u00e9m que, desses 25 anos, \u00a0em 18 deles fui assistente espiritual das Irm\u00e3s Clarissas, ou melhor, da Federa\u00e7\u00e3o dos Mosteiros das Clarissas do Brasil. Aprender com elas foi muito interessante porque, por mais que voc\u00ea fale que \u00e9 assim, assado, a l\u00f3gica no mosteiro \u00e9 diferente. Elas vivem em fun\u00e7\u00e3o do tempo da Liturgia das Horas.<\/p>\n<p>Tamb\u00e9m gostaria de destacar os formandos que fizeram parte de minha vida. Frei Claudino Gilz foi comigo at\u00e9 Petr\u00f3polis. Frei Lu\u00eds Aliberti ingressou no mesmo ano do Noviciado. Ele, contudo, ficou mais um tempo no Noviciado. E tamb\u00e9m os ex-frades que foram muito bons na vida da gente.<\/p>\n<p><strong>Site Franciscanos &#8211; Como o sr. define Frei Raimundo?<\/strong><\/p>\n<p><strong>Frei Raimundo<\/strong> &#8211; Eu sou uma pessoa muito reflexiva. Sempre fui. Sempre gostei de estudar e de ler. N\u00e3o sou uma pessoa que vive num casulo, mas sou mais introspectivo e gosto dos momentos de fraternidade e dos momentos em fam\u00edlia. Geralmente n\u00e3o ocupo cargos de lideran\u00e7a, mas prefiro ficar na retaguarda, porque nessa posi\u00e7\u00e3o enxergo melhor as coisas e posso ajudar mais. Fui vice-mestre e vice-ec\u00f4nomo.<\/p>\n<p><strong>Site Franciscanos &#8211; Trabalhando muitos anos na \u00e1rea econ\u00f4mica e financeira, como sr. v\u00ea a &#8220;Economia de Francisco&#8221;?<\/strong><\/p>\n<p><strong>Frei Raimundo <\/strong>&#8211; Um ponto importante deste encontro promovido pelo Papa Francisco, em Assis, creio, \u00e9 refor\u00e7ar a solidariedade e o clamor dos povos. Meu pai foi um homem muito solid\u00e1rio na vida. Foi educador e diretor de escola. Eu lembro muito dele procurando e lutando pela inclus\u00e3o das crian\u00e7as pobres porque na minha cidade existia apenas um col\u00e9gio do Estado que tinha at\u00e9 o colegial. E ele, como diretor, conseguiu trazer o prim\u00e1rio para a noite. O Papa, com a &#8220;Economia de Francisco&#8221;, quer incluir as pessoas e traz\u00ea-las para dentro da sociedade, tirando-as da zona de pobreza e mis\u00e9ria.<\/p>\n<p><strong>Site Franciscanos &#8211; E o Pontificado do Papa Francisco, como o sr. avalia?<\/strong><\/p>\n<p><strong>Frei Raimundo<\/strong> &#8211; Uma coisa que chama aten\u00e7\u00e3o \u00e9 sua sensibilidade \u00e0s nossas dores, fraquezas e problemas. No in\u00edcio do seu Pontificado, ele sinalizou com uma diretriz importante para a vida da Igreja: estar em sa\u00edda. Eu at\u00e9 percebi a <em>Igreja em sa\u00edda<\/em> numa \u00e9poca, mas agora parece que ela est\u00e1 ficando mais fechada, mesmo com ele pedindo. Mas n\u00f3s temos que lembrar que a Igreja est\u00e1 sempre em sa\u00edda. Ela vai ao encontro, ela cuida, ela tem compaix\u00e3o. O Papa est\u00e1 sempre em sa\u00edda porque vai a lugares do mundo que ningu\u00e9m foi. Ele vai justamente para mostrar a face do Cristo l\u00e1 onde a vida est\u00e1 fraturada. Al\u00e9m disso, o Papa Francisco tem essa identifica\u00e7\u00e3o com S\u00e3o Francisco de Assis. Suas enc\u00edclicas revelam isso: <em>Laudato Si&#8217;, Fratelli tutti<\/em> e a <em>Evangelii Gaudium<\/em>.<\/p>\n<p><strong>Site Franciscanos &#8211; Dos Papas que conheceu, quem chamou sua aten\u00e7\u00e3o?<\/strong><\/p>\n<p><strong>Frei Raimundo<\/strong> &#8211; O Papa Francisco est\u00e1 sendo muito audacioso e corajoso colocando a espiritualidade franciscana a servi\u00e7o da Igreja e da humanidade. Um Papa que me marcou muito foi o Paulo VI, porque ele poderia ter engavetado o Conc\u00edlio Vaticano II, mas ele colocou-o em pr\u00e1tica, porque achava que o caminho da Igreja era o do Conc\u00edlio.\u00a0 H\u00e1 not\u00edcias que ele enfrentou muitas resist\u00eancias. O Jo\u00e3o Paulo I queria continuar a linha do Pontificado de Paulo VI.<\/p>\n<p>J\u00e1 de Jo\u00e3o Paulo II todo mundo fala que \u00e9 muito fechado, mas quando vi uma exposi\u00e7\u00e3o na pra\u00e7a S\u00e3o Pedro, fiquei impactado com tantos lugares e viagens que fez no seu Pontificado. Do Bento XVI s\u00e3o profundas suas enc\u00edclicas e, sobretudo, o Ano Paulino, que foi importante para a Igreja. No final, o gesto dele na ren\u00fancia entrou para a hist\u00f3ria. Com isso, mostrou o seu desapego.<\/p>\n<p><strong>Site Franciscanos &#8211; Como formador que j\u00e1 foi, o sr. acha que existe uma crise vocacional na vida religiosa e na Igreja?<\/strong><\/p>\n<p><strong>Frei Raimundo<\/strong> &#8211; N\u00e3o acho que seja crise, mas um momento de dificuldade. Um momento de sombra. E tamb\u00e9m a mudan\u00e7a de \u00e9poca. Estamos no meio de uma revolu\u00e7\u00e3o tecnol\u00f3gica. Lembro que quando era formador em Rondinha, num Conselho de Forma\u00e7\u00e3o, n\u00f3s discutimos o dia inteiro se o formando poderia ter ou n\u00e3o celular. E era \u00e9poca daqueles celulares grandes. Um ano depois, fui pregar um retiro para as Irm\u00e3s de Petr\u00f3polis. Quando cheguei l\u00e1, vi os estudantes do tempo da Teologia com celulares e notebooks. E \u00e9 normal mesmo que tenha ocorrido, pois se trata de uma ferramenta de trabalho, necess\u00e1ria para os estudos, a comunica\u00e7\u00e3o e at\u00e9 ora\u00e7\u00e3o.<\/p>\n<p><strong>Site Franciscanos &#8211; O que voc\u00ea diria a um jovem que deseja seguir os passos de Francisco de Assis?<\/strong><\/p>\n<p><strong>Frei Raimundo<\/strong> &#8211; Eu diria que vale a pena. Ele vem para seguir Jesus Cristo ao modo de Francisco. N\u00e3o precisa ser santo, mas mesmo com defeitos pode seguir a Francisco de Assis. Como lembra o &#8220;Espelho da Perfei\u00e7\u00e3o&#8221;, S\u00e3o Francisco descreve o frade perfeito citando a virtude de cada frade.\u00a0 N\u00e3o existe um frade com todas as virtudes. \u00c9 a virtude de cada um que vai formar o frade perfeito. Eu n\u00e3o vou poder exigir que todos tenham as dez virtudes. A perfei\u00e7\u00e3o \u00e9 uma meta.<\/p>\n<p>Nesses escritos, Francisco dizia que seria bom frade menor aquele que tivesse a vida e as qualidades destes santos frades: isto \u00e9: \u201c<strong>a f\u00e9<\/strong> de Frei Bernardo, que a teve de forma perfeita com o amor \u00e0 pobreza; a <strong>simplicidade e a pureza <\/strong>de Frei Le\u00e3o, que foi realmente de uma pureza sant\u00edssima; a <strong>cortesia<\/strong> de Frei \u00c2ngelo, que foi o primeiro cavaleiro que veio para a ordem e que era ornado de toda a cortesia e bondade; o aspecto <strong>gracioso e o senso natural com a fala bonita e devota<\/strong> de Frei Masseo; a <strong>mente elevada em contempla\u00e7\u00e3o<\/strong> que Frei Eg\u00eddio teve at\u00e9 a m\u00e1xima perfei\u00e7\u00e3o; a virtuosa e constante <strong>ora\u00e7\u00e3o<\/strong> de Frei Rufino, que rezava sempre, sem interrup\u00e7\u00e3o: mesmo dormindo ou fazendo alguma coisa tinha sempre seu esp\u00edrito com o Senhor; a <strong>paci\u00eancia <\/strong>de Frei Jun\u00edpero, que atingiu um estado perfeito de paci\u00eancia, por causa da perfeita verdade da pr\u00f3pria vileza, que tinha continuamente diante dos olhos, e um ardente desejo de imitar a Cristo no caminho da cruz; o <strong>vigor corporal e espiritual<\/strong> de Frei Jo\u00e3o das Laudes, que, naquele tempo, ultrapassou todos os homens em for\u00e7a f\u00edsica; a <strong>caridade<\/strong> de Frei Rog\u00e9rio, cuja vida inteira e comportamento estavam no fervor da caridade; e a <strong>solicitude<\/strong> de Frei L\u00facio, que teve grand\u00edssima solicitude e n\u00e3o queria morar quase um m\u00eas no mesmo lugar, mas quando lhe agradava ficar num lugar, imediatamente se afastava e dizia: \u201cN\u00e3o temos morada aqui (cf. Hb 13,14), mas no c\u00e9u\u201d.<\/p>\n<hr \/>\n<p><em>Moacir Beggo<\/em><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-244069\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_02.jpg\" alt=\"\" width=\"1280\" height=\"1360\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_02.jpg 1016w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_02-424x450.jpg 424w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_02-964x1024.jpg 964w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_02-768x816.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_02-150x159.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevista<\/p>\n","protected":false},"author":3,"featured_media":244068,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[758,1],"tags":[2149],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Frei Raimundo celebra 25 anos de minist\u00e9rio presbiteral neste domingo - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frei Raimundo celebra 25 anos de minist\u00e9rio presbiteral neste domingo - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Entrevista\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-14T17:25:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html\",\"name\":\"Frei Raimundo celebra 25 anos de minist\u00e9rio presbiteral neste domingo - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html#primaryimage\"},\"datePublished\":\"2023-07-14T17:25:37+00:00\",\"dateModified\":\"2023-07-14T17:25:37+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frei Raimundo celebra 25 anos de minist\u00e9rio presbiteral neste domingo\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frei Raimundo celebra 25 anos de minist\u00e9rio presbiteral neste domingo - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html","og_locale":"pt_BR","og_type":"article","og_title":"Frei Raimundo celebra 25 anos de minist\u00e9rio presbiteral neste domingo - Not\u00edcias - Franciscanos","og_description":"Entrevista","og_url":"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2023-07-14T17:25:37+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/07\/raimundo_01.jpg","width":1280,"height":720},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html","name":"Frei Raimundo celebra 25 anos de minist\u00e9rio presbiteral neste domingo - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html#primaryimage"},"datePublished":"2023-07-14T17:25:37+00:00","dateModified":"2023-07-14T17:25:37+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/frei-raimundo-celebra-25-anos-de-ministerio-presbiteral-neste-domingo.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Frei Raimundo celebra 25 anos de minist\u00e9rio presbiteral neste domingo"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/244067"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=244067"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/244067\/revisions"}],"predecessor-version":[{"id":244070,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/244067\/revisions\/244070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/244068"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=244067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=244067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=244067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}