{"id":243207,"date":"2023-05-12T07:32:20","date_gmt":"2023-05-12T10:32:20","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=243207"},"modified":"2023-05-13T12:06:23","modified_gmt":"2023-05-13T15:06:23","slug":"ser-antes-de-tudo-irmao-menor","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html","title":{"rendered":"Ser, antes de tudo, irm\u00e3o menor"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-243208\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01-1024x576.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>\u201cO guardi\u00e3o \u00e9, antes de tudo um frade menor, um irm\u00e3o que serve \u00e0 fraternidade, um administrador, n\u00e3o apenas dos bens, mas, sobretudo, de rela\u00e7\u00f5es, da vida fraterna, do esp\u00edrito de ora\u00e7\u00e3o e devo\u00e7\u00e3o, da nossa forma de vida\u201d. Com estas palavras de motiva\u00e7\u00e3o, o Ministro Provincial, Frei Paulo Roberto Pereira, abriu a Reuni\u00e3o de Guardi\u00e3es e Coordenadores de 2023. O encontro come\u00e7ou na noite de segunda-feira, dia 8 de maio, e foi conclu\u00eddo com a almo\u00e7o da quinta-feira, dia 11 de maio. Esta primeira etapa contou com a participa\u00e7\u00e3o dos confrades que vivem no Brasil. A reuni\u00e3o com os guardi\u00e3es das Fraternidades em Angola ser\u00e1 celebrada no m\u00eas de julho, por ocasi\u00e3o da visita do Ministro Provincial \u00e0 Funda\u00e7\u00e3o Imaculada M\u00e3e de Deus.<\/p>\n<p><strong>\u00a0<\/strong><strong>DI\u00c1LOGO A PARTIR DAS PROVOCA\u00c7\u00d5ES DO MINISTRO GERAL<\/strong><\/p>\n<p>Como primeira tarefa, os irm\u00e3os se dividiram em grupos para estudo e reflex\u00e3o das observa\u00e7\u00f5es do Ministro Geral, Frei Massimo Fusarelli, por ocasi\u00e3o de sua visita \u00e0 Prov\u00edncia, ao final de janeiro e in\u00edcio de fevereiro deste ano. Foram abordados os seguintes assuntos: vida pessoal dos frades, Forma\u00e7\u00e3o e Estudos, Evangeliza\u00e7\u00e3o e Miss\u00e3o, Funda\u00e7\u00e3o Imaculada M\u00e3e de Deus, em Angola, Economia e Administra\u00e7\u00e3o. Diversos destes temas tamb\u00e9m depois retornaram e foram aprofundados nos dias seguintes.<\/p>\n<p>Seguem algumas observa\u00e7\u00f5es colhidas a partir do estudo.<\/p>\n<p>&#8211; O cuidado com a sa\u00fade ps\u00edquica dos frades \u00e9 um tema a ser trabalhado mais insistentemente, buscando o amadurecimento e a preven\u00e7\u00e3o ao agravamento de poss\u00edveis problemas nesta \u00e1rea. N\u00e3o deixa de refletir a crise de valores e de sentido que a sociedade como um todo enfrenta atualmente. \u00c9 importante que o assunto seja tematizado em encontros e reuni\u00f5es.<\/p>\n<p>&#8211; As m\u00faltiplas demandas e exig\u00eancias do dia a dia podem levar o irm\u00e3o a se desligar do cuidado consigo e com os outros, levando-o a uma esp\u00e9cie de esgotamento.<\/p>\n<p>&#8211; Recordou-se da import\u00e2ncia da identidade carism\u00e1tica em nossa vida e na forma de evangelizar (sentido de perten\u00e7a). A perda de sentido pode levar o frade a buscar preencher este vazio interior em outros expedientes que contrariam a pr\u00f3pria consagra\u00e7\u00e3o: dinheiro, afetividade desintegrada, idolatria do bem-estar, indol\u00eancia, entre outros.<\/p>\n<p>&#8211; O desafio de recuperar o belo e o curativo que existe na forma de vida franciscana, abra\u00e7ando com carinho e seriedade o compromisso com a Forma\u00e7\u00e3o Permanente.<\/p>\n<p>\u00ad- Em rela\u00e7\u00e3o \u00e0 Forma\u00e7\u00e3o e aos Estudos, h\u00e1 grande expectativa para o F\u00f3rum que vai ocorrer no m\u00eas de setembro deste ano. Espera-se que seja momento de se trabalhar a fundo desafios urgentes, como a diminui\u00e7\u00e3o acelerada do n\u00famero de formandos, a revis\u00e3o do processo formativo para que seja mais vivencial, a amadurecimento da compress\u00e3o integrada de Forma\u00e7\u00e3o Inicial e Forma\u00e7\u00e3o Permanente, o encaminhamento das grandes estruturas, entre outros temas que v\u00e3o ser abordados.<\/p>\n<p>&#8211; No que diz respeito \u00e0 miss\u00e3o evangelizadora, chamou aten\u00e7\u00e3o do Ministro a complexidade e o tamanho das obras que historicamente a Prov\u00edncia construiu nas \u00e1reas da Educa\u00e7\u00e3o, Comunica\u00e7\u00e3o e Assist\u00eancia aos empobrecidos. Ele orientou os frades para um cuidado especial com estas presen\u00e7as, a fim de que o carisma franciscano seja o grande norteador de todas as a\u00e7\u00f5es e fa\u00e7a parte do n\u00facleo decis\u00f3rio de cada entidade. Pediu ainda que o trabalho tenha a fraternidade como marca fundamental e que se evitem o personalismo e a perpetua\u00e7\u00e3o dos irm\u00e3os nos servi\u00e7os que realizam.<\/p>\n<p>&#8211; A Funda\u00e7\u00e3o Imaculada M\u00e3e de Deus, em Angola, \u00e9 sinal de b\u00ean\u00e7\u00e3o na hist\u00f3ria da Prov\u00edncia. O florescimento de voca\u00e7\u00f5es angolanas revela a fecundidade do empenho mission\u00e1rio dos frades que inauguraram a presen\u00e7a da Ordem neste pa\u00eds e da resposta generosa do povo angolano \u00e0 proposta de seguimento de Cristo ao modo de Francisco.\u00a0 A quest\u00e3o da autonomia da Funda\u00e7\u00e3o enquanto entidade deve estar no horizonte da caminhada, como dimens\u00e3o a ser trabalhada com fidelidade e dedica\u00e7\u00e3o.<\/p>\n<p><strong>&#8211; <\/strong>A dimens\u00e3o administrativa e econ\u00f4mica tamb\u00e9m possui relevo no que diz respeito \u00e0 forma de vida franciscana. O uso consciente dos bens, o caixa comum, a solidariedade com os pobres, o compromisso de viver a partir do pr\u00f3prio trabalho, sem reter nada para si, s\u00e3o os grandes norteadores para o frade menor neste particular, que deve ser sempre encarado a partir do esp\u00edrito de convers\u00e3o. A Prov\u00edncia tem crescido nesta reflex\u00e3o, notando-se a necessidade de que a pr\u00e1tica acompanhe cada vez mais a maturidade que se alcan\u00e7a neste exerc\u00edcio.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-243209\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_02.jpg\" alt=\"\" width=\"1024\" height=\"584\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_02.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_02-450x257.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_02-768x438.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_02-150x86.jpg 150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>INDICA\u00c7\u00d5ES PARA O F\u00d3RUM DA FORMA\u00c7\u00c3O<\/strong><\/p>\n<p>Com a condu\u00e7\u00e3o do Secret\u00e1rio para a Forma\u00e7\u00e3o e os Estudos, Frei Marcos Ant\u00f4nio de Andrade, os guardi\u00e3es discutiram e apresentaram propostas para o F\u00f3rum, a se realizar entre 7 e 10 de setembro de 2023, tendo em vista que tamb\u00e9m constituem um \u201cgrupo focal\u201d a ser ouvido e considerado em vista da prepara\u00e7\u00e3o do encontro. Detendo-se especificamente sobre a quest\u00e3o da Forma\u00e7\u00e3o Permanente, o grupo destacou os seguintes pontos:<\/p>\n<p>&#8211; A Prov\u00edncia tem se empenhado na oferta de subs\u00eddios e propostas para provocar e iluminar a reflex\u00e3o das fraternidades. Os frades nem sempre os abra\u00e7am com o empenho esperado.<\/p>\n<p>&#8211; Ligar a Forma\u00e7\u00e3o Permanente a iniciativas mission\u00e1rias, com experi\u00eancias espec\u00edficas. Imers\u00e3o em situa\u00e7\u00f5es de desafios e que exigissem do frade um esfor\u00e7o formativo e de aprimoramento para tal.<\/p>\n<p>&#8211; Desafio de furar uma bolha funcional que leva o irm\u00e3o a certa impermeabilidade, n\u00e3o se deixando interpelar pela realidade na qual est\u00e1 inserido.<\/p>\n<p>&#8211; Na Forma\u00e7\u00e3o Permanente, levar em conta tamb\u00e9m o cultivo pessoal e o cuidado para n\u00e3o se ater apenas \u00e0 programa\u00e7\u00e3o institu\u00edda.<\/p>\n<p>&#8211; Estudo e aprimoramento profissional para qualificar a miss\u00e3o. Busca de atualiza\u00e7\u00e3o reiterada e constante.<\/p>\n<p>&#8211; A Forma\u00e7\u00e3o Permanente pode atuar mais proativamente na indica\u00e7\u00e3o de irm\u00e3os para o aprofundamento em tem\u00e1ticas espec\u00edficas: vida de forma\u00e7\u00e3o e estudos.<\/p>\n<p>&#8211; Iniciativa, intensidade, prioridade. Reinventar-se e atualizar-se.<\/p>\n<p>&#8211; Amor \u00e0 voca\u00e7\u00e3o como dimens\u00e3o do testemunho.<\/p>\n<p>&#8211; Franciscanismo pr\u00e1tico e vivencial.<\/p>\n<p>&#8211; O que fazer para animar e provocar os irm\u00e3os acomodados? Como vencer a l\u00f3gica do \u201cse n\u00e3o atrapalha est\u00e1 bom\u201d?<\/p>\n<p>&#8211; Todas as Fraternidades s\u00e3o casas de Forma\u00e7\u00e3o, lugar de constru\u00e7\u00e3o do frade menor no concreto da realidade.<\/p>\n<p>&#8211; O Projeto Fraterno de Vida e Miss\u00e3o, sua clareza e aprimoramento v\u00e3o oferecer mais clareza em rela\u00e7\u00e3o ao projeto comum da consagra\u00e7\u00e3o franciscana. Assim como o Projeto pessoal elaborado \u00e0 luz deste primeiro.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-243214\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_06.jpg\" alt=\"\" width=\"1024\" height=\"458\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_06.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_06-450x201.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_06-768x344.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_06-150x67.jpg 150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>ECONOMIA E ADMINISTRA\u00c7\u00c3O DE BENS\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p>Al\u00e9m de ser uma iniciativa formativa e fraterna, a Reuni\u00e3o dos Guardi\u00e3es ainda possui <em>status <\/em>de Assembleia da Prov\u00edncia enquanto institui\u00e7\u00e3o civil. Por este motivo h\u00e1 tamb\u00e9m o espa\u00e7o para apresenta\u00e7\u00e3o e discuss\u00e3o das contas, escuta e an\u00e1lise do parecer do Conselho Fiscal e aprova\u00e7\u00e3o das contas do exerc\u00edcio do ano anterior, o que ocorreu conforme prescrevem os Estatutos da entidade. Na apresenta\u00e7\u00e3o dos n\u00fameros, em nome da equipe do Economato, o Ec\u00f4nomo, Frei Robson Luiz Scudela, tamb\u00e9m buscou recordar e destacar alguns aspectos da Economia compreendida e praticada de acordo com o carisma franciscano, deixando claro que este tema precisa ser assumido a partir da forma de vida professada pelos irm\u00e3os.<\/p>\n<p>Fundamentado no texto \u201cA administra\u00e7\u00e3o franciscana da economia: subs\u00eddio do Definit\u00f3rio Geral sobre o uso solid\u00e1rio e \u00e9tico de nossos recursos econ\u00f4micos\u201d, Frei Robson recordou as tr\u00eas finalidades dos recursos para a Ordem: &#8211; Manuten\u00e7\u00e3o dos religiosos e das estruturas de governo e anima\u00e7\u00e3o, e na evangeliza\u00e7\u00e3o e manuten\u00e7\u00e3o das obras apost\u00f3licas; &#8211; Partilha crist\u00e3 dos bens e solidariedade, &#8211; Como fundo de reserva para a sustentabilidade. Explicou ainda que os recursos s\u00e3o oriundos de tr\u00eas fontes: &#8211; O trabalho dos irm\u00e3os; &#8211; As doa\u00e7\u00f5es; &#8211; As receitas patrimoniais, ressaltando que tudo \u00e9 para ser aplicado nas finalidades que j\u00e1 foram expostas e deve ser fruto sempre de atividades l\u00edcitas e \u00e9ticas. A sobriedade, a profecia e a partilha s\u00e3o valores que n\u00e3o podem estar dissociados do modo como cada frade e fraternidade procuram gerir os recursos.<\/p>\n<p>Frei Robson tamb\u00e9m recordou que as Diretrizes para a Administra\u00e7\u00e3o Econ\u00f4mica e Financeira da Fraternidade provincial, local e entidades, aprovadas no Cap\u00edtulo Provincial de 2021, s\u00e3o o instrumento que rege a lida de cada irm\u00e3o e de cada inst\u00e2ncia com a gest\u00e3o dos bens. Destacou ainda que colocar em pr\u00e1tica integralmente o que este documento prescreve segue como desafio a ser abordado com transpar\u00eancia e coragem. Diante das reflex\u00f5es propostas e com a palavra de exorta\u00e7\u00e3o do Ministro Provincial, a Assembleia aprovou alguns encaminhamentos pr\u00e1ticos e prazos para que as determina\u00e7\u00f5es das diretrizes sejam assumidas o quanto antes, a saber:<\/p>\n<p>&#8211; Os bens que cada irm\u00e3o recebe por seu trabalho pertencem \u00e0 fraternidade e devem ser colocados em comum: sal\u00e1rios, aposentadorias, c\u00f4ngruas, direitos autorais, etc;<\/p>\n<p>&#8211; As necessidades cotidianas e extraordin\u00e1rias devem ser supridas pelo caixa comum. Nenhum frade deve ter reservas consigo.<\/p>\n<p>&#8211; No caso em que o irm\u00e3o seja obrigado a possuir uma conta banc\u00e1ria, por conta de pagamentos a receber ou outros motivos, seja sempre em conjunto com outro confrade.<\/p>\n<p>&#8211; Toda e qualquer ajuda financeira que seja necess\u00e1rio oferecer aos pais ou a outros familiares deve ser solicitada \u00e0 fraternidade local para que os encaminhamentos sejam dados;<\/p>\n<p>&#8211; O Cap\u00edtulo Local \u00e9 o lugar por excel\u00eancia da presta\u00e7\u00e3o de contas e de os irm\u00e3os tratarem sobre o tema da administra\u00e7\u00e3o e economia dos bens da fraternidade.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-243217\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_08.jpg\" alt=\"\" width=\"980\" height=\"1171\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_08.jpg 904w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_08-377x450.jpg 377w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_08-857x1024.jpg 857w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_08-768x918.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_08-150x179.jpg 150w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/p>\n<p><strong>TUTELA DE MENORES E ADULTOS VULNER\u00c1VEIS<\/strong><\/p>\n<p>Em nome da comiss\u00e3o constitu\u00edda pelo Ministro Provincial para acompanhar este assunto, Frei Fid\u00eancio Vanboemmel, que tamb\u00e9m \u00e9 Moderador da Forma\u00e7\u00e3o Permanente, apresentou aos confrades a atualiza\u00e7\u00e3o dos procedimentos previstos no caso de den\u00fancias de abuso. Lembrou que o principal objetivo do trabalho \u00e9 prevenir qualquer tipo de conduta abusiva e promover que todos os ambientes onde a vida da Prov\u00edncia se desenvolve sejam marcados pela seguran\u00e7a, pelo respeito e pelo cuidado de todos, de maneira ainda mais atenta daqueles que s\u00e3o mais vulner\u00e1veis.<\/p>\n<p>Frei Fid\u00eancio partilhou tamb\u00e9m um panorama geral do <em>Motu Proprio \u201cVos estis lux mundi\u201d, <\/em>do Papa Francisco, de 25 de mar\u00e7o deste ano, no qual o Sumo Pont\u00edfice atualiza e refor\u00e7a a pol\u00edtica de cuidado adotada pela Igreja, com toler\u00e2ncia zero para qualquer tipo de abuso, especialmente contra crian\u00e7as e adultos vulner\u00e1veis. Tanto este documento quanto o regulamento da Comiss\u00e3o Disciplinar apregoam a corresponsabilidade de todos os frades na preven\u00e7\u00e3o e no combate a esta pr\u00e1tica. Por conta da atualiza\u00e7\u00e3o do <em>Motu Proprio<\/em>, a comiss\u00e3o tamb\u00e9m fez altera\u00e7\u00f5es no regulamento interno da Prov\u00edncia que, apresentadas \u00e0 assembleia, foram unanimemente aprovadas. Outra mudan\u00e7a foi no formul\u00e1rio para den\u00fancias de poss\u00edveis casos que est\u00e1 \u00e0 disposi\u00e7\u00e3o de todos publicado num link que se encontra na p\u00e1gina inicial do site <em>Franciscanos<\/em>.<\/p>\n<p><strong>OS CUIDADOS COM A SA\u00daDE E O ATENDIMENTO AOS IRM\u00c3OS ENFERMOS<\/strong><\/p>\n<p>Sobre este tema, Frei Paulo Roberto Pereira, apresentou alguns encaminhamentos propostos pela comiss\u00e3o que tem se ocupado em estudar o assunto. Algumas observa\u00e7\u00f5es partilhadas foram:<\/p>\n<p>&#8211; Todas as fraternidades se constituem como casa de cuidado aos irm\u00e3os enfermos. No entanto, h\u00e1 situa\u00e7\u00f5es que exigem um acompanhamento mais pr\u00f3ximo e especializado. Nestes casos \u00e9 que se fazem necess\u00e1rios ambientes preparados para este tipo de atendimento.<\/p>\n<p>&#8211; Na Prov\u00edncia, para casos de depend\u00eancia acentuada, j\u00e1 existe a Fraternidade de Bragan\u00e7a Paulista, que vem cumprindo com compet\u00eancia e ternura fraterna a tarefa de cuidado. Agora, para confrades que tenham ainda relativa autonomia mas demandem cuidados pouco mais atentos, indicam-se que sejam preparadas as Fraternidades do Semin\u00e1rio Santo Ant\u00f4nio, em Agudos, SP, e do Semin\u00e1rio S\u00e3o Francisco, em Ituporanga, SC. H\u00e1 tamb\u00e9m a possibilidade de a Fraternidade Bom Jesus dos Perd\u00f5es, em Curitiba, acolher irm\u00e3os para atendimentos pontuais de maior complexidade, como cirurgias e outros procedimentos mais invasivos, dada a estrutura local j\u00e1 adaptada para acompanhar este tipo de caso. A assembleia aprovou que os encaminhamentos nesta dire\u00e7\u00e3o sejam levados adiante.<\/p>\n<p>&#8211; Foi refor\u00e7ada, ainda, a orienta\u00e7\u00e3o que j\u00e1 existe de que cada frade mantenha junto \u00e0 fraternidade local uma pasta que contenha os principais dados relativos \u00e0 sa\u00fade: exames, medicamentos dos quais faz uso, cirurgias pelas quais j\u00e1 passou etc. Esta medida facilita o atendimento e o acesso \u00e0s informa\u00e7\u00f5es em situa\u00e7\u00f5es de emerg\u00eancia.<\/p>\n<p>&#8211; Outra indica\u00e7\u00e3o \u00e9 o encaminhamento para que cada frade assine um \u201cTermo de autoriza\u00e7\u00e3o para cuidados m\u00e9dicos e funeral\u201d, confiando \u00e0 fraternidade a tarefa de responder pelo confrade nestas situa\u00e7\u00f5es. Seria importante facilitador para o encaminhamento destes tr\u00e2mites diante da lei civil. A assembleia aprovou a indica\u00e7\u00e3o e considerou fundamental a ades\u00e3o de toda a fraternidade.<\/p>\n<p>&#8211; Haver\u00e1, tamb\u00e9m nesta dire\u00e7\u00e3o, a ado\u00e7\u00e3o de uma nova carteirinha de frade para comprovar o v\u00ednculo com a Prov\u00edncia e a Ordem. Al\u00e9m das informa\u00e7\u00f5es b\u00e1sicas, este documento trar\u00e1 um <em>QR-Code<\/em> onde a perten\u00e7a do irm\u00e3o \u00e0 entidade poder\u00e1 ser conferida. Em breve ser\u00e1 enviada e o per\u00edodo de validade vence a cada celebra\u00e7\u00e3o de Cap\u00edtulo Provincial. A indica\u00e7\u00e3o foi aprovada por unanimidade.<\/p>\n<p><strong> <img loading=\"lazy\" class=\"alignnone size-full wp-image-243215\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_03.jpg\" alt=\"\" width=\"1100\" height=\"675\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_03.jpg 1100w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_03-450x276.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_03-1024x628.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_03-768x471.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_03-150x92.jpg 150w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/strong><\/p>\n<p><strong>JUBILEUS DA ORDEM<\/strong><\/p>\n<p>No contexto do tempo jubilar da Ordem dos Frades Menores (2023-2026), em nome da comiss\u00e3o respons\u00e1vel, Frei Gustavo Wayand Medella, Vig\u00e1rio Provincial, partilhou com a assembleia o que j\u00e1 foi realizado diante do proposto para celebrar os diversos jubileus franciscanos dos pr\u00f3ximos anos.<\/p>\n<p>&#8211; Na Prov\u00edncia, os trabalhos tiveram in\u00edcio e 2022, com a celebra\u00e7\u00e3o dos 200 anos da morte de Santo Ant\u00f4nio de Santana Galv\u00e3o. Por conta da data relativa \u00e0 hist\u00f3ria do primeiro santo brasileiro, diversas iniciativas foram realizadas. A realiza\u00e7\u00e3o da Caminhada Franciscana da Juventude, entre Aparecida e Guaratinguet\u00e1, o retiro dos frades <em>Under Ten<\/em>, uma s\u00e9rie de celebra\u00e7\u00f5es no Santu\u00e1rio e no Semin\u00e1rio Frei Galv\u00e3o e tamb\u00e9m um momento especial de recorda\u00e7\u00e3o e reflex\u00e3o no F\u00f3rum para a Evangeliza\u00e7\u00e3o, al\u00e9m de outras iniciativas no \u00e2mbito local das Fraternidades e presen\u00e7as evangelizadoras.<\/p>\n<p>&#8211; Para celebrar os 800 anos de aprova\u00e7\u00e3o da Regra Bulada (2023), a Prov\u00edncia convocou o Ano Vocacional, cujo lema \u00e9 \u201cCom Francisco, chamados a servir\u201d, aberto, no Brasil e em Angola, no dia 08 de dezembro de 2022. Uma ora\u00e7\u00e3o especial foi preparada e enviada \u00e0s Fraternidades, al\u00e9m da proposta de um percurso formativo para estudo pessoal e em fraternidade a partir de artigos tem\u00e1ticos sobre Regra publicado nas <em>Comunica\u00e7\u00f5es.<\/em> Diversas festas importantes na vida da Prov\u00edncia tamb\u00e9m apresentaram a tem\u00e1tica vocacional.<\/p>\n<p>&#8211; Em rela\u00e7\u00e3o aos 800 anos da iniciativa do Pres\u00e9pio de Greccio, tamb\u00e9m em 2023, diversas iniciativas j\u00e1 est\u00e3o sendo planejadas e executadas. No in\u00edcio do segundo semestre, uma carta com propostas concretas para a celebra\u00e7\u00e3o ser\u00e1 enviada \u00e0 Fraternidade Provincial.<\/p>\n<p>&#8211; Dentre as iniciativas previstas para este tempo jubilar, est\u00e1 o Cap\u00edtulo das Esteiras da Ordem, a ser celebrado em Assis, no ano de 2025. O encontro deve ser precedido por uma iniciativa em \u00e2mbito provincial, a se celebrar at\u00e9 o meio de 2024. Haver\u00e1 um processo preparat\u00f3rio nas Fraternidades para tal. A novidade ser\u00e1 o envio para participa\u00e7\u00e3o de irm\u00e3s religiosas da Fam\u00edlia Franciscana e de irm\u00e3os da Ordem Franciscana Secular. O Cap\u00edtulo das Esteiras, em n\u00edvel provincial, est\u00e1 previsto para entre os dias 29 de abril a 03 de maio de 2024, a ser celebrado no Semin\u00e1rio Santo Ant\u00f4nio, em Agudos.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-243207 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiaes_01.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiaes_01-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiaes_01-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiaes_01-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiaes_02.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiaes_02-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiaes_02-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiaes_02-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_05.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_05-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_05-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_05-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><em>(toque nas imagens para ampli\u00e1-las)<\/em><\/p>\n<p><strong>ATUALIZA\u00c7\u00c3O E ELABORA\u00c7\u00c3O DO <em>CURRICULUM VITAE<\/em><\/strong><\/p>\n<p>Em Comunica\u00e7\u00e3o oficial partilhada com a Assembleia, datada de 5 de maio de 2023, o Ministro Provincial convida os confrades \u00e0 elabora\u00e7\u00e3o e\/ou atualiza\u00e7\u00e3o do <em>Curriculum Vitae<\/em>. Trata-se de tarefa importante que vem refor\u00e7ar a convic\u00e7\u00e3o de que a hist\u00f3ria pessoal de cada confrade est\u00e1 na ess\u00eancia da hist\u00f3ria da pr\u00f3pria Prov\u00edncia e, \u201csob esta perspectiva, preservar esta riqueza hist\u00f3rica \u00e9 uma responsabilidade com o legado hist\u00f3rico da Ordem\u201d (trecho da carta).<\/p>\n<p>Na caminhada provincial, \u201ccomo forma de registro pessoal, nos anos de 1982 e 1998, os frades da Prov\u00edncia realizaram um trabalho de composi\u00e7\u00e3o de um <em>Curriculum Vitae<\/em>, no qual partilharam informa\u00e7\u00f5es sobre a fase de vida anterior ao ingresso na Ordem, experi\u00eancias do tempo da Forma\u00e7\u00e3o Inicial, observa\u00e7\u00f5es a respeito da vida religiosa franciscana e da evangeliza\u00e7\u00e3o\u201d.<\/p>\n<p>Desta vez a ideia \u00e9 propor a composi\u00e7\u00e3o de um curr\u00edculo mais sint\u00e9tico. Poder\u00e1 ser preenchido e entregue de variadas formas, a fim de facilitar o acesso a todos os frades: novo <em>Curriculum Vitae<\/em> poder\u00e1 ser preenchido pelo formul\u00e1rio no Google Forms, atrav\u00e9s do link compartilhado, poder\u00e1 ser digitado e enviado (em formato <em>doc<\/em> ou <em>pdf<\/em>), ou impresso e preenchido a m\u00e3o. O prazo previsto para entrega ser\u00e1 o dia 31 de julho de 2023.<\/p>\n<p><strong> <img loading=\"lazy\" class=\"alignnone size-full wp-image-243210\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_04.jpg\" alt=\"\" width=\"1100\" height=\"825\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_04.jpg 1100w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_04-450x338.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_04-1024x768.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_04-768x576.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_04-150x113.jpg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_04-600x450.jpg 600w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/strong><\/p>\n<p><strong>MOMENTO CELEBRATIVO<\/strong><\/p>\n<p>O Encontro de guardi\u00e3es tamb\u00e9m foi marcado por uma liturgia s\u00f3bria e bem celebrada. As missas, sempre \u00e0s 7h, contaram com a presid\u00eancia de Frei Ademir Sanquetti, no primeiro dia, como guardi\u00e3o da casa anfitri\u00e3, por Frei Luiz Iakovacz, jubilando que completa 50 anos de Ordena\u00e7\u00e3o Sacerdotal em 2023, e por Frei Josemberg Cardozo Aranha, guardi\u00e3o do Noviciado, representando as Casas de Forma\u00e7\u00e3o. Nas celebra\u00e7\u00f5es, o som solene e orante do grande \u00f3rg\u00e3o de tubos da Capela Central abrilhantava ainda mais a a\u00e7\u00e3o lit\u00fargica. A ora\u00e7\u00e3o das V\u00e9speras se realizava na pr\u00f3pria sala de reuni\u00f5es.<\/p>\n<p>Outra iniciativa que conferiu aspecto de proximidade e partilha ao encontro foi a possibilidade de, no in\u00edcio de cada sess\u00e3o, alguns guardi\u00e3es livremente fizessem uma breve partilha de vida e miss\u00e3o das Fraternidades das quais est\u00e3o a servi\u00e7o. Momentos marcantes da espontaneidade e da singeleza pr\u00f3prias da vida franciscana. Ao final, com a b\u00ean\u00e7\u00e3o de envio do Ministro Provincial, os irm\u00e3os retornaram com alegria e vigor para a vida e a miss\u00e3o cotidiana nas Fraternidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reuni\u00e3o de Guardi\u00e3es e Coordenadores<\/p>\n","protected":false},"author":3,"featured_media":243208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[2132],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ser, antes de tudo, irm\u00e3o menor - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ser, antes de tudo, irm\u00e3o menor - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Reuni\u00e3o de Guardi\u00e3es e Coordenadores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-12T10:32:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-13T15:06:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html\",\"name\":\"Ser, antes de tudo, irm\u00e3o menor - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html#primaryimage\"},\"datePublished\":\"2023-05-12T10:32:20+00:00\",\"dateModified\":\"2023-05-13T15:06:23+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ser, antes de tudo, irm\u00e3o menor\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ser, antes de tudo, irm\u00e3o menor - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html","og_locale":"pt_BR","og_type":"article","og_title":"Ser, antes de tudo, irm\u00e3o menor - Not\u00edcias - Franciscanos","og_description":"Reuni\u00e3o de Guardi\u00e3es e Coordenadores","og_url":"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2023-05-12T10:32:20+00:00","article_modified_time":"2023-05-13T15:06:23+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/05\/guardiao_01.jpg","width":1280,"height":720},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html","name":"Ser, antes de tudo, irm\u00e3o menor - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html#primaryimage"},"datePublished":"2023-05-12T10:32:20+00:00","dateModified":"2023-05-13T15:06:23+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/ser-antes-de-tudo-irmao-menor.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Ser, antes de tudo, irm\u00e3o menor"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/243207"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=243207"}],"version-history":[{"count":5,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/243207\/revisions"}],"predecessor-version":[{"id":243222,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/243207\/revisions\/243222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/243208"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=243207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=243207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=243207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}