{"id":242279,"date":"2023-02-26T10:06:19","date_gmt":"2023-02-26T13:06:19","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=242279"},"modified":"2023-02-26T10:06:19","modified_gmt":"2023-02-26T13:06:19","slug":"papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html","title":{"rendered":"Papa: Jesus nos ensina a defender a unidade com Deus e entre n\u00f3s dos ataques do &#8220;divisor&#8221;"},"content":{"rendered":"<div id=\"attachment_242280\" style=\"width: 1510px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-242280\" loading=\"lazy\" class=\"wp-image-242280 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26.jpeg\" alt=\"\" width=\"1500\" height=\"844\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26.jpeg 1500w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26-450x253.jpeg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26-1024x576.jpeg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26-768x432.jpeg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26-150x84.jpeg 150w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><p id=\"caption-attachment-242280\" class=\"wp-caption-text\">Imagem: Vatican Media<\/p><\/div>\n<p>De quem e de que maneira o diabo separa, os tr\u00eas poderosos &#8220;venenos&#8221; que usa para destruir a unidade com Deus e entre n\u00f3s e o que fazer para vencer suas tenta\u00e7\u00f5es e ins\u00eddias. Em s\u00edntese, foi o que o Papa prop\u00f4s em sua reflex\u00e3o neste I Domingo da Quaresma, antes da ora\u00e7\u00e3o do Angelus.<\/p>\n<p><strong>O diabo sempre quer criar divis\u00e3o<\/strong><\/p>\n<p>O Evangelho de Mateus (Mt 4, 1-11) proposto pela liturgia do dia, apresenta Jesus no deserto sendo tentado pelo diabo. Francisco, dirigindo-se aos fi\u00e9is reunidos na Pra\u00e7a S\u00e3o Pedro, explica inicialmente que diabo significa &#8220;divisor&#8221;, ele &#8220;sempre quer criar divis\u00e3o&#8221;. E \u00e9 o que se prop\u00f5e a fazer em rela\u00e7\u00e3o a Jesus.<\/p>\n<p>Mas &#8211; pergunta o Papa &#8211; de quem o diabo quer separar Jesus, e de que maneira?<\/p>\n<p>&#8220;Depois de ter recebido o Batismo de Jo\u00e3o no Jord\u00e3o &#8211; recorda Francisco -, Jesus foi chamado pelo Pai &#8220;meu Filho amado&#8221; e o Esp\u00edrito Santo desceu sobre ele na forma de pomba&#8221;:<\/p>\n<p>O Evangelho apresenta-nos assim as tr\u00eas Pessoas divinas unidas no amor. E n\u00e3o s\u00f3: o pr\u00f3prio Jesus dir\u00e1 ter vindo ao mundo para nos tornar participantes da unidade que existe entre Ele e o Pai. O diabo, ao inv\u00e9s disso, faz o contr\u00e1rio: entra em cena para separar Jesus do Pai e distanci\u00e1-lo de sua miss\u00e3o de unidade por n\u00f3s. Divide sempre<\/p>\n<p><strong>Apego, desconfian\u00e7a, poder<\/strong><\/p>\n<p>Francisco ent\u00e3o explica de que maneira o diabo tenta fazer isso: O diabo quer se aproveitar da condi\u00e7\u00e3o humana de Jesus, que est\u00e1 fraco porque jejuou quarenta dias e teve fome. O maligno ent\u00e3o tenta incutir nele tr\u00eas poderosos &#8220;venenos&#8221;, para paralisar sua miss\u00e3o de unidade. E esses venenos s\u00e3o o apego, a desconfian\u00e7a e o poder.<\/p>\n<p>Sobre o veneno do apego \u00e0s coisas, \u00e0s necessidades, o Papa diz: Com um racioc\u00ednio persuasivo, o diabo tenta sugestionar Jesus: \u201cTens fome, porque deves jejuar? Ou\u00e7a a tua necessidade e satisfa\u00e7a-a, tens o direito e tamb\u00e9m tens o poder: transforme as pedras em p\u00e3o\u201d.<\/p>\n<p>Depois o segundo veneno, a desconfian\u00e7a: \u201cTens certeza \u2013 insinua o maligno \u2013 de que o Pai quer o teu bem? Coloque-o \u00e0 prova, chantageie-o! Lan\u00e7a-te do ponto mais alto do templo e faz com que ele fa\u00e7a o que tu queres.&#8221;<\/p>\n<p>Por fim, o terceiro veneno, o poder: \u201cTu n\u00e3o precisas do teu Pai! Por que esperar por seus dons? Siga os crit\u00e9rios do mundo, pegue tudo para si e ser\u00e1s poderoso!\u201d.<\/p>\n<p><strong>Separar-nos de Deus e nos dividir como irm\u00e3os<\/strong><\/p>\n<p>&#8220;\u00c9 terr\u00edvel!&#8221;, exclama Francisco, chamando a aten\u00e7\u00e3o para o fato de que o diabo usa em rela\u00e7\u00e3o a n\u00f3s esses mesmos tr\u00eas poderosos venenos para nos separar de Deus e nos dividir como irm\u00e3os:<\/p>\n<p>O apego \u00e0s coisas, a desconfian\u00e7a e a sede de poder s\u00e3o tr\u00eas tenta\u00e7\u00f5es difundidas e perigosas que o dem\u00f4nio usa para nos separar do Pai e n\u00e3o nos fazer sentir mais irm\u00e3os e irm\u00e3s entre n\u00f3s, para levar-nos \u00e0 solid\u00e3o e ao desespero. Isso quer fazer o diabo, isso quer fazer a n\u00f3s: levar-nos ao desespero!<\/p>\n<p><strong>Palavra de Deus, ant\u00eddoto contra as tenta\u00e7\u00f5es<\/strong><\/p>\n<p>Mas o Santo Padre tamb\u00e9m recorda como Jesus vence as tenta\u00e7\u00f5es: &#8220;Evitando discutir com o diabo e respondendo com a Palavra de Deus. Isto \u00e9 importante: n\u00e3o se discute com o diabo, n\u00e3o se dialoga com o diabo. Jesus o confronta com a Palavra de Deus&#8221;. E &#8220;cita tr\u00eas frases da Escritura que falam de liberdade das coisas, de confian\u00e7a e de servi\u00e7o a Deus, tr\u00eas frases opostas \u00e0s tenta\u00e7\u00f5es. Nunca dialoga com o diabo, n\u00e3o negocia com ele, mas refuta suas insinua\u00e7\u00f5es com as Palavras ben\u00e9ficas da Escritura&#8221;: \u00c9 um convite tamb\u00e9m para n\u00f3s: com o diabo n\u00e3o se discute! N\u00e3o se negocia, n\u00e3o se dialoga; ele n\u00e3o \u00e9 derrotado tratando com ele, \u00e9 mais forte do que n\u00f3s. O diabo o derrotamos opondo a ele com f\u00e9 a Palavra divina. Deste modo Jesus nos ensina a defender a unidade com Deus e entre n\u00f3s dos ataques do divisor. A Palavra Divina que \u00e9 a resposta de Jesus \u00e0 tenta\u00e7\u00e3o do diabo.<\/p>\n<p>Como costuma fazer ao final de suas reflex\u00f5es dominicais, Francisco prop\u00f5e que nos perguntemos: Que lugar a Palavra de Deus ocupa na minha vida? Recorro \u00e0 Palavra de Deus em minhas lutas espirituais? Se tenho um v\u00edcio ou tenta\u00e7\u00e3o recorrente, por que, buscando ajuda, n\u00e3o procuro um vers\u00edculo da Palavra de Deus que responda a esse v\u00edcio? Depois, quando vem a tenta\u00e7\u00e3o, eu o recito, o rezo confiando na gra\u00e7a de Cristo. Experimentemos fazer isso, nos ajudar\u00e1 nas tenta\u00e7\u00f5es porque, entre as vozes que se agitam dentro de n\u00f3s, ressoar\u00e1 aquela ben\u00e9fica da Palavra de Deus.<\/p>\n<p>Que Maria &#8211; foi seu pedido ao concluir &#8211; que acolheu a Palavra de Deus e com sua humildade derrotou a soberba do divisor, acompanhe-nos na luta espiritual da Quaresma.<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News (texto de Jackson Erpen)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angelus<\/p>\n","protected":false},"author":3,"featured_media":242280,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[403],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papa: Jesus nos ensina a defender a unidade com Deus e entre n\u00f3s dos ataques do &quot;divisor&quot; - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa: Jesus nos ensina a defender a unidade com Deus e entre n\u00f3s dos ataques do &quot;divisor&quot; - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Angelus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-26T13:06:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26.jpeg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26.jpeg\",\"width\":1500,\"height\":844},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html\",\"name\":\"Papa: Jesus nos ensina a defender a unidade com Deus e entre n\u00f3s dos ataques do \\\"divisor\\\" - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html#primaryimage\"},\"datePublished\":\"2023-02-26T13:06:19+00:00\",\"dateModified\":\"2023-02-26T13:06:19+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa: Jesus nos ensina a defender a unidade com Deus e entre n\u00f3s dos ataques do &#8220;divisor&#8221;\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa: Jesus nos ensina a defender a unidade com Deus e entre n\u00f3s dos ataques do \"divisor\" - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html","og_locale":"pt_BR","og_type":"article","og_title":"Papa: Jesus nos ensina a defender a unidade com Deus e entre n\u00f3s dos ataques do \"divisor\" - Not\u00edcias - Franciscanos","og_description":"Angelus","og_url":"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2023-02-26T13:06:19+00:00","og_image":[{"width":1500,"height":844,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26.jpeg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26.jpeg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2023\/02\/papa_angelus_26.jpeg","width":1500,"height":844},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html","name":"Papa: Jesus nos ensina a defender a unidade com Deus e entre n\u00f3s dos ataques do \"divisor\" - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html#primaryimage"},"datePublished":"2023-02-26T13:06:19+00:00","dateModified":"2023-02-26T13:06:19+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-jesus-nos-ensina-a-defender-a-unidade-com-deus-e-entre-nos-dos-ataques-do-divisor.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Papa: Jesus nos ensina a defender a unidade com Deus e entre n\u00f3s dos ataques do &#8220;divisor&#8221;"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/242279"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=242279"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/242279\/revisions"}],"predecessor-version":[{"id":242281,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/242279\/revisions\/242281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/242280"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=242279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=242279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=242279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}