{"id":240089,"date":"2022-10-09T07:46:06","date_gmt":"2022-10-09T10:46:06","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=240089"},"modified":"2022-10-09T07:58:57","modified_gmt":"2022-10-09T10:58:57","slug":"papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html","title":{"rendered":"Papa: &#8220;A exclus\u00e3o dos emigrantes \u00e9 nojenta, \u00e9 pecaminosa, \u00e9 criminosa&#8221;"},"content":{"rendered":"<div id=\"attachment_240090\" style=\"width: 1510px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-240090\" loading=\"lazy\" class=\"wp-image-240090 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09.jpeg\" alt=\"\" width=\"1500\" height=\"844\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09.jpeg 1500w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09-450x253.jpeg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09-1024x576.jpeg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09-768x432.jpeg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09-150x84.jpeg 150w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><p id=\"caption-attachment-240090\" class=\"wp-caption-text\"><em>\u00a0 \u00a0 \u00a0 \u00a0 Imagem: Vatican Media<\/em><\/p><\/div>\n<p>O Papa Francisco celebrou a missa de canoniza\u00e7\u00e3o de Jo\u00e3o Batista Scalabrini e Art\u00eamides Zatti, neste domingo (09\/10), na Pra\u00e7a S\u00e3o Pedro.<\/p>\n<p>O Papa iniciou sua homilia com o epis\u00f3dio do Evangelho, da liturgia deste domingo, em que dez leprosos caminham juntos e v\u00e3o ao encontro de Jesus que os cura, mas somente um deles volta \u00abglorificando a Deus em voz alta\u00bb e agradece a Jesus. Era um samaritano, um estrangeiro.<\/p>\n<p>A seguir, Francisco se deteve em dois aspectos dessa passagem do Evangelho: caminhar juntos e agradecer. O Papa ressalta que &#8220;no in\u00edcio da narra\u00e7\u00e3o, n\u00e3o h\u00e1 nenhuma distin\u00e7\u00e3o entre o samaritano e os outros nove. Fala-se simplesmente de dez leprosos, que formam um grupo e, sem divis\u00e3o, v\u00e3o ao encontro de Jesus. Como sabemos, a lepra n\u00e3o era apenas uma \u00falcera f\u00edsica, mas tamb\u00e9m uma \u00abdoen\u00e7a social\u00bb, porque naquele tempo, por medo do cont\u00e1gio, os leprosos deviam estar fora da comunidade. N\u00e3o podiam entrar nos centros habitados, mas eram mantidos \u00e0 dist\u00e2ncia, relegados \u00e0s margens da vida social e at\u00e9 religiosa. Caminhando juntos, estes leprosos clamam contra uma sociedade que os exclui. O samaritano, apesar de ser considerado her\u00e9tico, \u00abestrangeiro\u00bb, faz grupo com os outros. A doen\u00e7a e a fragilidade comuns fazem cair as barreiras e superar toda a exclus\u00e3o, como nos recordou na primeira Leitura, Naaman, o s\u00edrio, que apesar de ser rico e poderoso, para se curar teve de mergulhar no rio onde se banhavam todos os outros&#8221;.<\/p>\n<p>Como nos faz bem tirar as nossas armaduras exteriores, as nossas barreiras defensivas e tomar um bom banho de humildade, recordando-nos de que todos somos fr\u00e1geis por dentro e necessitados de cura, todos somos irm\u00e3os! Lembremo-nos disto: a f\u00e9 crist\u00e3 sempre nos pede para caminhar junto com os outros, para nunca ser caminhantes solit\u00e1rios; sempre nos convida a sair de n\u00f3s mesmos rumo a Deus e aos irm\u00e3os, sem nunca nos fecharmos em n\u00f3s mesmos; sempre nos pede para nos reconhecermos necessitados de cura e perd\u00e3o, e partilharmos as fragilidades de quem vive ao nosso redor, sem nos sentirmos superiores.<\/p>\n<p>O Papa nos convidou a verificar se, &#8220;na nossa vida, nas nossas fam\u00edlias, nos nossos lugares de trabalho e de conviv\u00eancia di\u00e1ria, somos capazes de caminhar junto com os outros, ouvir, superar a tenta\u00e7\u00e3o de nos entrincheirarmos na nossa autorreferencialidade e pensarmos s\u00f3 nas nossas necessidades&#8221;.<\/p>\n<p>&#8220;Mas caminhar juntos&#8221;, disse ainda o Pont\u00edfice, &#8220;ser \u00absinodais\u00bb, \u00e9 tamb\u00e9m a voca\u00e7\u00e3o da Igreja&#8221;.<\/p>\n<p>Perguntemo-nos at\u00e9 que ponto somos realmente comunidades abertas e inclusivas em rela\u00e7\u00e3o a todos; se conseguimos trabalhar juntos, padres e leigos, a servi\u00e7o do Evangelho; se temos uma atitude acolhedora \u2013 feita n\u00e3o s\u00f3 de palavras, mas de gestos concretos \u2013 tanto para com os distantes quanto para com todos os que se aproximam de n\u00f3s, sentindo-se in\u00e1beis por causa dos seus percursos de vida conturbada. Fazemo-los sentir parte da comunidade, ou exclu\u00edmo-los?<\/p>\n<p>Francisco disse ter medo, quando v\u00ea &#8220;comunidades crist\u00e3s que dividem o mundo em bons e maus, em santos e pecadores&#8221;. Com isso, &#8220;acaba-se por se sentir melhor que os outros e manter fora a muitos que Deus quer abra\u00e7ar&#8221;. O Papa disse que \u00e9 importante &#8220;incluir sempre tanto na Igreja quanto na sociedade, ainda caraterizada por tantas desigualdades e marginaliza\u00e7\u00f5es. Incluir todos&#8221;.<\/p>\n<p>Hoje, no dia em que Scalabrini se torna santo, gostaria de pensar nos emigrantes. A exclus\u00e3o dos emigrantes \u00e9 escandalosa. Ali\u00e1s, a exclus\u00e3o dos emigrantes \u00e9 criminosa, faz com que morram diante de n\u00f3s. E assim, hoje temos o Mediterr\u00e2neo que \u00e9 o maior cemit\u00e9rio do mundo. A exclus\u00e3o dos emigrantes \u00e9 nojenta, \u00e9 pecaminosa, \u00e9 criminosa. N\u00e3o abrir as portas para quem precisa&#8230; &#8220;N\u00e3o os exclu\u00edmos, os mandamos embora&#8221;, para os campos de concentra\u00e7\u00e3o, onde s\u00e3o explorados e vendidos como escravos. Irm\u00e3os e irm\u00e3s, hoje pensamos em nossos emigrantes, aqueles que morrem e aqueles que s\u00e3o capazes de entrar. N\u00f3s os recebemos como irm\u00e3os ou os exploramos? Deixo esta pergunta.<\/p>\n<p>A seguir, o Papa se deteve no aspecto: agradecer. &#8220;No grupo dos dez leprosos, h\u00e1 apenas um que, ao ver-se curado, regressa para louvar a Deus e manifestar a sua gratid\u00e3o a Jesus. Enquanto os outros nove ficam purificados, mas prosseguem pelo seu caminho, esquecendo-se d\u2019Aquele que os curou. O samaritano faz do dom recebido o princ\u00edpio de um novo caminho: regressa para junto de Quem o sarou, vai conhecer Jesus de perto, inicia uma rela\u00e7\u00e3o com Ele. Assim, a sua atitude de gratid\u00e3o n\u00e3o \u00e9 um simples gesto de cortesia, mas o in\u00edcio de um percurso de gratid\u00e3o: prostra-se aos p\u00e9s de Cristo, isto \u00e9, faz um gesto de adora\u00e7\u00e3o, reconhecendo que Jesus \u00e9 o Senhor e que \u00e9 mais importante do que a cura recebida&#8221;.<\/p>\n<p>Esta \u00e9 uma grande li\u00e7\u00e3o tamb\u00e9m para n\u00f3s, que todos os dias nos beneficiamos dos dons de Deus, mas frequentemente prosseguimos pela nossa estrada esquecendo-nos de cultivar uma rela\u00e7\u00e3o viva com Ele. Trata-se de uma grave doen\u00e7a espiritual: dar tudo como garantido, inclusive a f\u00e9, mesmo a nossa rela\u00e7\u00e3o com Deus, a ponto de nos tornarmos crist\u00e3os que deixaram de se maravilhar, j\u00e1 n\u00e3o sabem dizer \u00abobrigado\u00bb, n\u00e3o se mostram agradecidos, n\u00e3o sabem ver as maravilhas do Senhor. E acaba-se, assim, por pensar que tudo o que recebemos diariamente seja \u00f3bvio e devido. Ao contr\u00e1rio, a gratid\u00e3o, o saber dizer \u00abobrigado\u00bb nos leva a afirmar a presen\u00e7a de Deus-amor e tamb\u00e9m a reconhecer a import\u00e2ncia dos outros, vencendo o descontentamento e a indiferen\u00e7a que nos embrutecem o cora\u00e7\u00e3o.<\/p>\n<p>&#8220;\u00c9 fundamental saber agradecer&#8221;, reiterou o Papa. &#8220;Devemos diariamente dar gra\u00e7as ao Senhor, sabermos em cada dia agradecer uns aos outros: na fam\u00edlia, por aquelas pequenas coisas que \u00e0s vezes recebemos sem nos interrogar sequer de onde prov\u00eam; nos locais que frequentamos quotidianamente, pelos in\u00fameros servi\u00e7os de que usufru\u00edmos e pelas pessoas que nos apoiam; nas nossas comunidades crist\u00e3s, pelo amor de Deus que experimentamos atrav\u00e9s da proximidade de irm\u00e3os e irm\u00e3s que muitas vezes em sil\u00eancio rezam, oferecem, sofrem, caminham conosco. Por favor, n\u00e3o esque\u00e7amos esta palavra-chave: obrigado&#8221;, sublinhou Francisco.<\/p>\n<p>Os dois Santos, canonizados hoje, nos lembram a import\u00e2ncia de caminhar juntos e saber agradecer. O Bispo Scalabrini, que fundou uma Congrega\u00e7\u00e3o para o cuidado dos emigrantes, duas: uma masculina e outra feminina, afirmava que, no caminhar comum daqueles que emigram, \u00e9 preciso n\u00e3o ver s\u00f3 problemas, mas tamb\u00e9m um des\u00edgnio da Provid\u00eancia: \u00abPrecisamente por causa da migra\u00e7\u00e3o for\u00e7ada pelas persegui\u00e7\u00f5es \u2013 disse ele \u2013, a Igreja superou as fronteiras de Jerusal\u00e9m e de Israel e tornou-se \u201ccat\u00f3lica\u201d; gra\u00e7as \u00e0s migra\u00e7\u00f5es de hoje, a Igreja ser\u00e1 instrumento de paz e comunh\u00e3o entre os povos\u00bb. H\u00e1 uma migra\u00e7\u00e3o, neste momento, aqui na Europa, que nos faz sofrer muito e nos leva a abrir nossos cora\u00e7\u00f5es: a migra\u00e7\u00e3o de ucranianos que fogem da guerra. N\u00e3o nos esque\u00e7amos hoje da martirizada Ucr\u00e2nia. Scalabrini olhava mais al\u00e9m, olhava l\u00e1 para diante, para um mundo e uma Igreja sem barreiras, sem estrangeiros. Por sua vez, o irm\u00e3o salesiano Artemide Zatti foi um exemplo vivo de gratid\u00e3o: curado da tuberculose, dedicou toda a sua vida a favorecer os outros, a cuidar com amor e ternura dos doentes. Conta-se que o viram carregar aos ombros o corpo morto de um dos seus doentes. Cheio de gratid\u00e3o por tudo o que havia recebido, quis dizer o seu \u00abobrigado\u00bb ocupando-se das feridas dos outros.<\/p>\n<p>O Papa concluiu, convidando a rezar &#8220;para que estes nossos santos irm\u00e3os nos ajudem a caminhar juntos, sem muros de divis\u00e3o; e a cultivar esta nobreza de alma t\u00e3o agrad\u00e1vel a Deus que \u00e9 a gratid\u00e3o&#8221;.<\/p>\n<hr \/>\n<h3>A MENSAGEM DO PAPA COM A CANONIZA\u00c7\u00c3O DE JO\u00c3O BATISTA SCALABRINI<\/h3>\n<p>Por ocasi\u00e3o da canoniza\u00e7\u00e3o do Beato Jo\u00e3o Batista Scalabrini em 9 de outubro, o Superior-geral dos Scalabrinianos, Pe. Leonir Chiarello, comenta a decis\u00e3o do Papa Francisco de realizar o rito sem a comprova\u00e7\u00e3o de um segundo milagre:<\/p>\n<p>\u201cA mensagem que o Papa Francisco quer transmitir ao mundo e \u00e0 Igreja com a canoniza\u00e7\u00e3o de Scalabrini sem um segundo milagre \u00e9 a correponsabilidade da Igreja local, do bispo com a sociedade civil e os atores pol\u00edticos, governos, na governan\u00e7a das migra\u00e7\u00f5es. Por outro lado, o Scalabrini bispo, comprometido com a migra\u00e7\u00e3o, a vis\u00e3o dele \u00e9 que atrav\u00e9s da migra\u00e7\u00e3o, que \u00e9 um fen\u00f4meno estrutural das sociedades modernas, se realiza o plano de Deus da fraternidade universal. Na sua vis\u00e3o teol\u00f3gica das migra\u00e7\u00f5es, Scalabrini reconhece que no encontro das diferentes nacionalidades vai se construindo aquela comunh\u00e3o universal de todas as nacionalidades, que no fundo \u00e9 o plano de Deus que n\u00f3s vivamos todos em fraternidade. Aquilo que hoje o Papa Francisco fala da Casa Comum e da Fratelli tutti, da fraternidade universal, n\u00f3s poder\u00edamos dizer que Scalabrini vislumbrou isso atrav\u00e9s da migra\u00e7\u00e3o. A migra\u00e7\u00e3o \u00e9 um fen\u00f4meno em que as pessoas v\u00e3o se encontrando, de diferentes culturas e religi\u00f5es, e v\u00e3o construindo essa fraternidade universal. Em s\u00edntese, Scalabrini santo \u00e9 um convite a reconhecermo-nos todos como migrantes no mundo e reconhecer nos migrantes pessoas que fazem parte da fam\u00edlia universal e, por isso, elas t\u00eam a mesma dignidade dos que est\u00e3o vivendo no mesmo pa\u00eds e somos convidados a construir fraternidade com eles.<\/p>\n<p>Um carisma \u201cbrasileiro\u201d, pois seja o ramo masculino, seja o ramo feminino, temos superiores brasileiros.<\/p>\n<p>Scalabrini enviou os primeiros mission\u00e1rios padres ao Brasil e depois aos Estados Unidos. E para as primeiras mission\u00e1rias scalabrinianas foi criada a Congrega\u00e7\u00e3o no Brasil. Ent\u00e3o hoje eu e a superiora-geral, Ir. Neusa do Brasil, procuramos levar adiante essa heran\u00e7a deste grande carisma e desta grande miss\u00e3o na Igreja e no mundo.<\/p>\n<hr \/>\n<h3>UM PAI PARA OS MIGRANTES<\/h3>\n<p>A Superiora-geral das Mission\u00e1rias de S\u00e3o Carlos Borromeu, Ir. Neusa de F\u00e1tima Mariano, agradece ao Papa Francisco por dar \u00e0 Igreja &#8220;um pai para os migrantes&#8221; e comenta a sensibilidade feminina no acolhimento das mulheres e crian\u00e7as migrantes:<\/p>\n<p>Para n\u00f3s, mission\u00e1rias de S\u00e3o Carlos Borromeu, com toda a fam\u00edlia scalabriniana, todos os migrantes e refugiados, acolhemos com muita alegria, com o cora\u00e7\u00e3o cheio de gratid\u00e3o a Deus esse dom que nos foi concedido com a canoniza\u00e7\u00e3o de Jo\u00e3o Batista Scalabrini. Foi, de fato, uma surpresa, uma not\u00edcia inesperada que n\u00f3s acolhemos com muita alegria, agradecemos ao Papa Francisco por esse reconhecimento, por conceder \u00e0 Igreja um pai para os migrantes. E n\u00f3s vivemos este tempo como um tempo de gra\u00e7a e de j\u00fabilo.<\/p>\n<p>O beato viu al\u00e9m n\u00e3o s\u00f3 no carisma junto aos migrantes, mas na confian\u00e7a que depositou nas mulheres: No projeto de Scalabrini, havia esta dimens\u00e3o j\u00e1 tinha no in\u00edcio da sua miss\u00e3o de fundar uma Congrega\u00e7\u00e3o para acompanhar os migrantes que partiam para as Am\u00e9ricas. Justamente nesta dimens\u00e3o, n\u00f3s percebemos como o projeto de Scalabrini \u00e9 completo. Ele percebe nas migra\u00e7\u00f5es essa necessidade de ter essa sensibilidade com aqueles que s\u00e3o os mais fr\u00e1geis, os mais vulner\u00e1veis da migra\u00e7\u00e3o. Por isso, n\u00f3s como congrega\u00e7\u00e3o feminina com carisma espec\u00edfico, estamos fazendo uma escolha priorit\u00e1ria para acompanhar as mulheres e crian\u00e7as, que s\u00e3o aqueles mais fr\u00e1geis da migra\u00e7\u00e3o. Desta forma, podemos dizer que Scalabrini tinha esta vis\u00e3o, j\u00e1 presente no seu projeto, da presen\u00e7a da mulher consagrada para fazer a diferen\u00e7a na acolhida e na sensibilidade \u00e0s dores e aos dramas presentes na migra\u00e7\u00e3o.<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News (texto de Mariangela Jaguraba)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santa Missa de Canoniza\u00e7\u00e3o de Jo\u00e3o Batista Scalabrini e Art\u00eamides Zatti<\/p>\n","protected":false},"author":3,"featured_media":240090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[2065],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papa: &quot;A exclus\u00e3o dos emigrantes \u00e9 nojenta, \u00e9 pecaminosa, \u00e9 criminosa&quot; - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa: &quot;A exclus\u00e3o dos emigrantes \u00e9 nojenta, \u00e9 pecaminosa, \u00e9 criminosa&quot; - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Santa Missa de Canoniza\u00e7\u00e3o de Jo\u00e3o Batista Scalabrini e Art\u00eamides Zatti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-09T10:46:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-09T10:58:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09.jpeg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09.jpeg\",\"width\":1500,\"height\":844},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html\",\"name\":\"Papa: \\\"A exclus\u00e3o dos emigrantes \u00e9 nojenta, \u00e9 pecaminosa, \u00e9 criminosa\\\" - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html#primaryimage\"},\"datePublished\":\"2022-10-09T10:46:06+00:00\",\"dateModified\":\"2022-10-09T10:58:57+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa: &#8220;A exclus\u00e3o dos emigrantes \u00e9 nojenta, \u00e9 pecaminosa, \u00e9 criminosa&#8221;\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa: \"A exclus\u00e3o dos emigrantes \u00e9 nojenta, \u00e9 pecaminosa, \u00e9 criminosa\" - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html","og_locale":"pt_BR","og_type":"article","og_title":"Papa: \"A exclus\u00e3o dos emigrantes \u00e9 nojenta, \u00e9 pecaminosa, \u00e9 criminosa\" - Not\u00edcias - Franciscanos","og_description":"Santa Missa de Canoniza\u00e7\u00e3o de Jo\u00e3o Batista Scalabrini e Art\u00eamides Zatti","og_url":"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2022-10-09T10:46:06+00:00","article_modified_time":"2022-10-09T10:58:57+00:00","og_image":[{"width":1500,"height":844,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09.jpeg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09.jpeg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/10\/missa_09.jpeg","width":1500,"height":844},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html","name":"Papa: \"A exclus\u00e3o dos emigrantes \u00e9 nojenta, \u00e9 pecaminosa, \u00e9 criminosa\" - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html#primaryimage"},"datePublished":"2022-10-09T10:46:06+00:00","dateModified":"2022-10-09T10:58:57+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-exclusao-dos-emigrantes-e-nojenta-e-pecaminosa-e-criminosa.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Papa: &#8220;A exclus\u00e3o dos emigrantes \u00e9 nojenta, \u00e9 pecaminosa, \u00e9 criminosa&#8221;"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/240089"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=240089"}],"version-history":[{"count":2,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/240089\/revisions"}],"predecessor-version":[{"id":240092,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/240089\/revisions\/240092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/240090"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=240089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=240089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=240089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}