{"id":239444,"date":"2022-09-01T13:16:33","date_gmt":"2022-09-01T16:16:33","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=239444"},"modified":"2022-12-31T12:55:04","modified_gmt":"2022-12-31T15:55:04","slug":"papa-a-liturgia-nao-e-coisa-de-museu-esta-viva","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html","title":{"rendered":"Papa: a liturgia n\u00e3o \u00e9 coisa de museu, est\u00e1 viva"},"content":{"rendered":"<div id=\"attachment_239445\" style=\"width: 760px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-239445\" loading=\"lazy\" class=\"wp-image-239445 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/09\/audiencia_liturgia.jpeg\" alt=\"\" width=\"750\" height=\"422\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/09\/audiencia_liturgia.jpeg 750w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/09\/audiencia_liturgia-450x253.jpeg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/09\/audiencia_liturgia-150x84.jpeg 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><p id=\"caption-attachment-239445\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <em>\u00a0 Imagem: Vatican Media<\/em><\/p><\/div>\n<p>O Papa Francisco recebeu em audi\u00eancia, nesta quinta-feira (1\u00b0\/09), na Sala Clementina, no Vaticano, os membros da Associa\u00e7\u00e3o italiana de Professores e Cultores de Liturgia, por ocasi\u00e3o de seus 50 anos de funda\u00e7\u00e3o.<\/p>\n<p>No in\u00edcio de seu discurso, Francisco agradeceu \u00e0s pessoas que, 50 anos atr\u00e1s, &#8220;tiveram a coragem de tomar a iniciativa e dar vida a essa realidade&#8221;. Agradeceu &#8220;aos que participaram neste meio s\u00e9culo, dando sua contribui\u00e7\u00e3o para a reflex\u00e3o sobre a vida lit\u00fargica da Igreja&#8221;, e &#8220;pela contribui\u00e7\u00e3o que a Associa\u00e7\u00e3o deu ao acolhimento na It\u00e1lia da reforma lit\u00fargica inspirada no Conc\u00edlio Vaticano II&#8221;.<\/p>\n<p>O Papa encorajou os membros da Associa\u00e7\u00e3o italiana de Professores e Cultores de Liturgia a levarem adiante a atividade de estudo e pesquisa no di\u00e1logo entre os membros do organismo e com os outros, &#8220;pois a teologia tamb\u00e9m pode e deve ter um estilo sinodal, envolvendo as diversas disciplinas teol\u00f3gicas e das ci\u00eancias humanas, &#8220;criando redes&#8221; com as institui\u00e7\u00f5es que, mesmo fora da It\u00e1lia, cultivam e promovem estudos lit\u00fargicos&#8221;.<\/p>\n<p><strong>A liturgia \u00e9 um organismo vivo<\/strong><br \/>\nSegundo o Papa, nesse sentido \u00e9 indispens\u00e1vel o prop\u00f3sito do organismo &#8220;de se manter \u00e0 escuta das comunidades crist\u00e3s, para que seu trabalho nunca seja separado das expectativas e necessidades do Povo de Deus. Esse povo, do qual fazemos parte, sempre precisa ser formado, crescer, mas em si mesmo possui esse senso de f\u00e9, o <em>sensus fidei,<\/em> que o ajuda a discernir o que vem de Deus e que realmente o leva a Ele, tamb\u00e9m na esfera lit\u00fargica&#8221;.<\/p>\n<p>A liturgia \u00e9 obra de Cristo e da Igreja, e como tal \u00e9 um organismo vivo, como uma planta que n\u00e3o pode ser transcurada ou maltratada. N\u00e3o \u00e9 um monumento de m\u00e1rmore ou bronze, n\u00e3o \u00e9 uma coisa de museu. A liturgia est\u00e1 viva como uma planta, e deve ser cultivada com cuidado. E tamb\u00e9m, a liturgia \u00e9 alegre, com a alegria do Esp\u00edrito, n\u00e3o de uma festa mundana, com a alegria do Esp\u00edrito. \u00c9 por isso que n\u00e3o se entende, por exemplo, uma teologia f\u00fanebre: n\u00e3o funciona. \u00c9 alegre, porque canta louvor ao Senhor.<\/p>\n<p><strong>Voltar o olhar para o Senhor sem virar as costas para o mundo<\/strong><br \/>\n&#8220;Por esse motivo, o seu trabalho de discernimento e pesquisa n\u00e3o pode separar a dimens\u00e3o acad\u00eamica da dimens\u00e3o pastoral e espiritual&#8221;, frisou o Papa. &#8220;Uma das principais contribui\u00e7\u00f5es do Conc\u00edlio Vaticano II foi a de tentar superar o div\u00f3rcio entre teologia e pastoral, entre f\u00e9 e vida&#8221;.<\/p>\n<p>Hoje, mais do que nunca, precisamos de uma vis\u00e3o elevada da liturgia, que n\u00e3o se reduza a examinar detalhe de rubrica: uma liturgia que n\u00e3o seja mundana, mas que fa\u00e7a elevar os olhos para o c\u00e9u, para sentir que o mundo e a vida s\u00e3o habitados pelo Mist\u00e9rio de Cristo; e, ao mesmo tempo, uma liturgia com &#8220;p\u00e9s no ch\u00e3o&#8221;, <em>propter homines<\/em>, n\u00e3o distante da vida, n\u00e3o com aquela exclusividade mundana: n\u00e3o. Isso n\u00e3o tem nada a ver, mas s\u00e9ria, pr\u00f3xima das pessoas. Portanto, as duas coisas juntas: voltar o olhar para o Senhor sem virar as costas para o mundo.<\/p>\n<p><strong>A tradi\u00e7\u00e3o \u00e9 a garantia do futuro<\/strong><br \/>\nA seguir, Francisco recordou Romano Guardini, &#8220;que se destacou por sua capacidade de difundir as aquisi\u00e7\u00f5es do movimento lit\u00fargico fora da esfera acad\u00eamica, de forma acess\u00edvel, para que todo fiel, come\u00e7ando pelos jovens, pudesse crescer no conhecimento vivo e experiencial do significado teol\u00f3gico e espiritual da liturgia&#8221;. &#8220;Que sua figura e sua abordagem \u00e0 educa\u00e7\u00e3o lit\u00fargica, tanto moderna quanto cl\u00e1ssica, sejam um ponto de refer\u00eancia para voc\u00eas, para que seu estudo una intelig\u00eancia cr\u00edtica e sabedoria espiritual, fundamento b\u00edblico e arraigamento eclesial, abertura \u00e0 interdisciplinaridade e atitude pedag\u00f3gica&#8221;.<\/p>\n<p>O progresso na compreens\u00e3o e tamb\u00e9m na celebra\u00e7\u00e3o lit\u00fargica deve estar sempre arraigado na tradi\u00e7\u00e3o, que sempre leva a pessoa adiante naquele sentido que o Senhor quer. H\u00e1 um esp\u00edrito que n\u00e3o \u00e9 o da verdadeira tradi\u00e7\u00e3o: o esp\u00edrito mundano do retrocesso, agora na moda: pensar que voltar \u00e0s ra\u00edzes significa caminhar para tr\u00e1s. N\u00e3o, s\u00e3o coisas diferentes. Se voc\u00ea volta \u00e0s ra\u00edzes, as ra\u00edzes levam voc\u00ea para cima, sempre. Como a \u00e1rvore que cresce a partir do que vem de suas ra\u00edzes. Voltar \u00e0s ra\u00edzes, porque a tradi\u00e7\u00e3o \u00e9 a garantia do futuro. &#8220;N\u00e3o somos pessoas que caminham para tr\u00e1s.&#8221; N\u00e3o. Ir adiante de acordo com a linha dada pela tradi\u00e7\u00e3o.<\/p>\n<p>Por fim, &#8220;a coisa mais importante: que seu estudo da liturgia seja imbu\u00eddo de ora\u00e7\u00e3o e experi\u00eancia viva da Igreja que celebra, de modo que a liturgia &#8220;pensada&#8221; possa fluir sempre, como de uma linfa vital, da liturgia vivida&#8221;, disse o Papa. &#8220;A teologia \u00e9 feita com a mente aberta e ao mesmo tempo &#8220;de joelhos&#8221;. Isso vale para todas as disciplinas teol\u00f3gicas, mas ainda mais para a sua, que tem como objeto o ato de celebrar a beleza e a grandeza do mist\u00e9rio de Deus que se doa a n\u00f3s&#8221;, concluiu Francisco.<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News (texto de Mariangela Jaguraba)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Audi\u00eancia <\/p>\n","protected":false},"author":3,"featured_media":239445,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[487],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papa: a liturgia n\u00e3o \u00e9 coisa de museu, est\u00e1 viva - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa: a liturgia n\u00e3o \u00e9 coisa de museu, est\u00e1 viva - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Audi\u00eancia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-01T16:16:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-31T15:55:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/09\/audiencia_liturgia.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/09\/audiencia_liturgia.jpeg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/09\/audiencia_liturgia.jpeg\",\"width\":750,\"height\":422},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html\",\"name\":\"Papa: a liturgia n\u00e3o \u00e9 coisa de museu, est\u00e1 viva - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html#primaryimage\"},\"datePublished\":\"2022-09-01T16:16:33+00:00\",\"dateModified\":\"2022-12-31T15:55:04+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa: a liturgia n\u00e3o \u00e9 coisa de museu, est\u00e1 viva\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa: a liturgia n\u00e3o \u00e9 coisa de museu, est\u00e1 viva - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html","og_locale":"pt_BR","og_type":"article","og_title":"Papa: a liturgia n\u00e3o \u00e9 coisa de museu, est\u00e1 viva - Not\u00edcias - Franciscanos","og_description":"Audi\u00eancia","og_url":"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2022-09-01T16:16:33+00:00","article_modified_time":"2022-12-31T15:55:04+00:00","og_image":[{"width":750,"height":422,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/09\/audiencia_liturgia.jpeg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/09\/audiencia_liturgia.jpeg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/09\/audiencia_liturgia.jpeg","width":750,"height":422},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html","name":"Papa: a liturgia n\u00e3o \u00e9 coisa de museu, est\u00e1 viva - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html#primaryimage"},"datePublished":"2022-09-01T16:16:33+00:00","dateModified":"2022-12-31T15:55:04+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-liturgia-nao-e-coisa-de-museu-esta-viva.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Papa: a liturgia n\u00e3o \u00e9 coisa de museu, est\u00e1 viva"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/239444"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=239444"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/239444\/revisions"}],"predecessor-version":[{"id":239446,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/239444\/revisions\/239446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/239445"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=239444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=239444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=239444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}