{"id":239382,"date":"2022-08-28T08:37:16","date_gmt":"2022-08-28T11:37:16","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=239382"},"modified":"2022-08-28T08:37:16","modified_gmt":"2022-08-28T11:37:16","slug":"papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html","title":{"rendered":"Papa no Perd\u00e3o Celestino: humildade e mansid\u00e3o para testemunhar a miseric\u00f3rdia"},"content":{"rendered":"<div id=\"attachment_239383\" style=\"width: 1010px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-239383\" loading=\"lazy\" class=\"wp-image-239383 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila4.jpeg\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila4.jpeg 1000w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila4-450x253.jpeg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila4-768x432.jpeg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila4-150x84.jpeg 150w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><p id=\"caption-attachment-239383\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<em> \u00a0Imagens: Vatican Media<\/em><\/p><\/div>\n<p>Na Bas\u00edlica de Collemaggio em L\u2019Aquila, o Papa Francisco presidiu a Santa Missa na segunda etapa da sua visita pastoral neste domingo, 28 de agosto. Aos falar aos fi\u00e9is na sua homilia o Papa iniciou recordando que os Santos s\u00e3o uma fascinante explica\u00e7\u00e3o do Evangelho. Pois suas vidas, disse Francisco, s\u00e3o o ponto privilegiado a partir do qual podemos vislumbrar a boa nova que Jesus veio proclamar, ou seja, que Deus \u00e9 nosso Pai e todos somos amados por Ele. Este \u00e9 o cora\u00e7\u00e3o do Evangelho, e Jesus \u00e9 a prova deste Amor, de sua encarna\u00e7\u00e3o, de seu rosto.<\/p>\n<p><strong>A grandeza de Celestino V<\/strong><br \/>\n\u201cHoje celebramos a Eucaristia em um dia especial para esta cidade e esta Igreja: o Perd\u00e3o Celestino\u201d. Lembramos erroneamente a figura de Celestino V como &#8220;aquele que fez a grande recusa&#8221;, segundo a express\u00e3o de Dante na Divina Com\u00e9dia; mas Celestino V n\u00e3o era o homem do &#8220;n\u00e3o&#8221;, ele era o homem do &#8220;sim&#8221;. \u201cDe fato\u201d, explica ainda Francisco, \u201cn\u00e3o h\u00e1 outra maneira de realizar a vontade de Deus a n\u00e3o ser assumindo a for\u00e7a dos humildes\u201d.<\/p>\n<p><strong>A for\u00e7a dos humildes<\/strong><br \/>\n\u201cA humildade\u201d, disse, \u201cn\u00e3o consiste em nos desvalorizarmos, mas naquele realismo saud\u00e1vel que nos faz reconhecer nosso potencial e tamb\u00e9m nossas mis\u00e9rias. Partindo precisamente de nossas mis\u00e9rias, a humildade nos faz desviar o olhar de n\u00f3s mesmos e voltar nosso olhar para Deus, Aquele que pode fazer tudo e tamb\u00e9m obt\u00e9m para n\u00f3s o que n\u00e3o podemos ter por n\u00f3s mesmos\u201d.<\/p>\n<p>\u201cA for\u00e7a dos humildes \u00e9 o Senhor, n\u00e3o as estrat\u00e9gias, os meios humanos, as l\u00f3gicas deste mundo\u201d<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-239384\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila2.jpeg\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila2.jpeg 1000w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila2-450x253.jpeg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila2-768x432.jpeg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila2-150x84.jpeg 150w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u201cNeste sentido\u201d, pondera o Papa, \u201cCelestino V foi uma corajosa testemunha do Evangelho, porque nenhuma l\u00f3gica de poder poderia prend\u00ea-lo e administr\u00e1-lo. Nele admiramos uma Igreja livre das l\u00f3gicas do mundo e testemunhamos plenamente o nome de Deus que \u00e9 a Miseric\u00f3rdia.<\/p>\n<p><strong>A miseric\u00f3rdia<\/strong><br \/>\nH\u00e1 muitos s\u00e9culo que L\u2019Aquila, mant\u00e9m vivo o dom que o pr\u00f3prio Papa Celestino V lhe deixou. \u201c\u00c9 o privil\u00e9gio de lembrar a todos que com a miseric\u00f3rdia, e somente com a miseric\u00f3rdia, a vida de cada homem e de cada mulher pode ser vivida com alegria\u201d.<\/p>\n<p>\u201cMiseric\u00f3rdia \u00e9 a experi\u00eancia de sentir-se acolhido, restaurado, fortalecido, curado, encorajado. Ser perdoado \u00e9 experimentar aqui e agora o que mais se aproxima da ressurrei\u00e7\u00e3o. O perd\u00e3o vai da morte \u00e0 vida, da experi\u00eancia da ang\u00fastia e da culpa \u00e0 da liberdade e da alegria\u201d<\/p>\n<p><strong>Compreender a dor dos outros<\/strong><br \/>\nFalando aos presentes que sofreram por causa do terremoto de 2009, Francisco recordou que \u201caqueles que sofreram devem ser capazes de valorizar seu pr\u00f3prio sofrimento, devem compreender que na escurid\u00e3o que viveram, tamb\u00e9m lhes foi dado o dom de compreender a dor dos outros\u201d. Recordando aos presentes:<\/p>\n<p><strong>\u201cVoc\u00eas podem cuidar da miseric\u00f3rdia porque sofreram a experi\u00eancia da mis\u00e9ria\u201d<\/strong><\/p>\n<p>Refletindo que \u201ctodos na vida, sem necessariamente experimentar um terremoto, podem, por assim dizer, experimentar um \u2018terremoto da alma\u2019, que os coloca em contato com sua pr\u00f3pria fragilidade, suas pr\u00f3prias limita\u00e7\u00f5es, sua pr\u00f3pria mis\u00e9ria\u201d. \u201cNesta experi\u00eancia&#8221;, disse, &#8220;pode-se perder tudo, mas tamb\u00e9m se pode aprender a verdadeira humildade. Nessas circunst\u00e2ncias, a pessoa pode se deixar enfurecer pela vida, ou pode aprender a mansid\u00e3o\u201d.<\/p>\n<p>\u201cHumildade e mansid\u00e3o, portanto, s\u00e3o as caracter\u00edsticas de algu\u00e9m cuja tarefa \u00e9 guardar e testemunhar a miseric\u00f3rdia\u201d<\/p>\n<p><strong>Servir e n\u00e3o ser servido<\/strong><br \/>\nPor fim o Papa recordou a todos os presentes: \u201cO crist\u00e3o sabe que sua vida n\u00e3o \u00e9 uma carreira \u00e0 maneira deste mundo, mas uma carreira \u00e0 maneira de Cristo, que dir\u00e1 de si mesmo que veio para servir e n\u00e3o para ser servido (cf. Mc 10, 45). Enquanto n\u00e3o compreendermos que a revolu\u00e7\u00e3o do Evangelho reside neste tipo de liberdade, continuaremos a testemunhar guerras, viol\u00eancia e injusti\u00e7a, que nada mais s\u00e3o do que o sintoma externo de uma falta de liberdade interior. Onde n\u00e3o h\u00e1 liberdade interior, ego\u00edsmo, individualismo, se sobrep\u00f5em interesse pr\u00f3prio e opress\u00e3o&#8221;.<\/p>\n<hr \/>\n<h3><img loading=\"lazy\" class=\"alignnone size-full wp-image-239385\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila.jpeg\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila.jpeg 1000w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila-450x253.jpeg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila-768x432.jpeg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila-150x84.jpeg 150w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/h3>\n<h3>Papa em L&#8217;Aquila: a mem\u00f3ria \u00e9 a for\u00e7a de um povo<\/h3>\n<p>O primeiro compromisso do Papa Francisco na sua chegada \u00e0 cidade de L\u2019Aquila neste domingo, 28 de agosto, foi uma sauda\u00e7\u00e3o aos familiares das v\u00edtimas do terremoto de 2009. O encontro foi realizado no patamar da Catedral da cidade, logo ap\u00f3s uma visita privada no interior da mesma. O Papa iniciou com as seguintes palavras: \u201cQuero expressar minha solidariedade a suas fam\u00edlias e a toda a sua comunidade, que enfrentou com grande dignidade as consequ\u00eancias desse tr\u00e1gico acontecimento\u201d.<\/p>\n<p>Ao agradecer sobre o testemunho de f\u00e9 da popula\u00e7\u00e3o disse &#8220;mesmo na dor e na perplexidade que pertencem \u00e0 nossa f\u00e9 como peregrinos, voc\u00eas fixaram seu olhar em Cristo, crucificado e ressuscitado, que por seu amor resgatou da insensatez a dor e a morte\u201d.<\/p>\n<p>\u201cJesus os colocou de volta nos bra\u00e7os do Pai, que n\u00e3o deixa cair nem uma l\u00e1grima em v\u00e3o, nem mesmo uma!, mas as recolhe todas no seu cora\u00e7\u00e3o misericordioso\u201d.<\/p>\n<p>Em seguida agradeceu a constru\u00e7\u00e3o da Capela da Mem\u00f3ria afirmando: \u201cA mem\u00f3ria \u00e9 a for\u00e7a de um povo, e quando essa mem\u00f3ria \u00e9 iluminada pela f\u00e9, aquele povo n\u00e3o permanece prisioneiro do passado, mas caminha no presente, rumo ao futuro, permanecendo sempre apegado \u00e0s suas ra\u00edzes e valorizando as experi\u00eancias passadas, boas e ruins\u201d.<\/p>\n<p>\u201cNo trabalho de reconstru\u00e7\u00e3o\u201d, disse ainda o Papa, \u201cas igrejas merecem aten\u00e7\u00e3o especial. Elas s\u00e3o patrim\u00f4nio da comunidade, n\u00e3o apenas no sentido hist\u00f3rico e cultural, mas tamb\u00e9m no sentido identit\u00e1rio&#8221;.<\/p>\n<p>\u201cEssas pedras est\u00e3o impregnadas de f\u00e9 e de valores do povo; e os templos tamb\u00e9m s\u00e3o lugares propulsores de sua vida, de sua esperan\u00e7a\u201d.<\/p>\n<p>Por fim agradeceu a presen\u00e7a da delega\u00e7\u00e3o dos c\u00e1rceres da regi\u00e3o de Abru\u00e7os com as seguintes palavras: \u201cVejo em voc\u00eas um sinal de esperan\u00e7a, porque nas pris\u00f5es h\u00e1 muitas, demasiadas v\u00edtimas. Hoje, aqui, voc\u00eas s\u00e3o um sinal de esperan\u00e7a na reconstru\u00e7\u00e3o humana e social\u201d.<\/p>\n<p>Ao encontrar os familiares das v\u00edtimas do terremoto de 2009, Francisco agradeceu as obras de reconstru\u00e7\u00e3o da cidade recordando a todos que &#8220;a mem\u00f3ria \u00e9 a for\u00e7a de um povo, e quando essa mem\u00f3ria \u00e9 iluminada pela f\u00e9, aquele povo n\u00e3o permanece prisioneiro do passado, mas caminha no presente, rumo ao futuro&#8221;.<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News (texto de Jane Nogara)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visita Pastoral<\/p>\n","protected":false},"author":3,"featured_media":239383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[2048],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papa no Perd\u00e3o Celestino: humildade e mansid\u00e3o para testemunhar a miseric\u00f3rdia - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa no Perd\u00e3o Celestino: humildade e mansid\u00e3o para testemunhar a miseric\u00f3rdia - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Visita Pastoral\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-28T11:37:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila4.jpeg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila4.jpeg\",\"width\":1000,\"height\":563},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html\",\"name\":\"Papa no Perd\u00e3o Celestino: humildade e mansid\u00e3o para testemunhar a miseric\u00f3rdia - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html#primaryimage\"},\"datePublished\":\"2022-08-28T11:37:16+00:00\",\"dateModified\":\"2022-08-28T11:37:16+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa no Perd\u00e3o Celestino: humildade e mansid\u00e3o para testemunhar a miseric\u00f3rdia\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa no Perd\u00e3o Celestino: humildade e mansid\u00e3o para testemunhar a miseric\u00f3rdia - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html","og_locale":"pt_BR","og_type":"article","og_title":"Papa no Perd\u00e3o Celestino: humildade e mansid\u00e3o para testemunhar a miseric\u00f3rdia - Not\u00edcias - Franciscanos","og_description":"Visita Pastoral","og_url":"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2022-08-28T11:37:16+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila4.jpeg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila4.jpeg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/08\/aquila4.jpeg","width":1000,"height":563},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html","name":"Papa no Perd\u00e3o Celestino: humildade e mansid\u00e3o para testemunhar a miseric\u00f3rdia - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html#primaryimage"},"datePublished":"2022-08-28T11:37:16+00:00","dateModified":"2022-08-28T11:37:16+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-no-perdao-celestino-humildade-e-mansidao-para-testemunhar-a-misericordia.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Papa no Perd\u00e3o Celestino: humildade e mansid\u00e3o para testemunhar a miseric\u00f3rdia"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/239382"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=239382"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/239382\/revisions"}],"predecessor-version":[{"id":239386,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/239382\/revisions\/239386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/239383"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=239382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=239382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=239382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}