{"id":237150,"date":"2022-04-04T06:47:03","date_gmt":"2022-04-04T09:47:03","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=237150"},"modified":"2022-04-04T06:47:03","modified_gmt":"2022-04-04T09:47:03","slug":"papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html","title":{"rendered":"Papa: &#8220;N\u00f3s n\u00e3o aprendemos, estamos apaixonados pelas guerras e pelo esp\u00edrito de Caim&#8221;"},"content":{"rendered":"<div id=\"attachment_237151\" style=\"width: 1510px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-237151\" loading=\"lazy\" class=\"wp-image-237151 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04.jpeg\" alt=\"\" width=\"1500\" height=\"844\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04.jpeg 1500w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04-450x253.jpeg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04-1024x576.jpeg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04-768x432.jpeg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04-150x84.jpeg 150w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><p id=\"caption-attachment-237151\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<em> \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Imagem: Vatican Media<\/em><\/p><\/div>\n<p>&#8220;N\u00e3o aprendemos! Que o Senhor tenha piedade de n\u00f3s, de todos n\u00f3s, todos n\u00f3s somos culpados&#8221;! O Papa Francisco com os jornalistas no voo de retorno de Malta, depois de recordar o que o impressionou sobre a acolhida da ilha, retorna a falar sobre a guerra.<\/p>\n<p><em>Andrea Rossitto (TVM)<br \/>\nObrigado por sua presen\u00e7a em Malta, minha pergunta \u00e9 sobre a surpresa desta manh\u00e3 na capela onde est\u00e1 enterrado S\u00e3o Giorgio Preca. O que o motivou a fazer esta surpresa aos malteses e o que se recordar\u00e1 desta visita a Malta. E ainda, como est\u00e1 sua sa\u00fade? N\u00f3s o vimos durante esta viagem muito intensa. Correu tudo bem, digamos. Muito obrigado.<\/em><\/p>\n<p>A minha sa\u00fade \u00e9 um pouco caprichosa, tenho este problema com meu joelho que traz problemas na caminhada, \u00e9 um pouco chato, mas est\u00e1 melhorando, pelo menos eu posso andar. Duas semanas atr\u00e1s, eu n\u00e3o podia fazer nada. \u00c9 uma coisa lenta, vamos ver se melhora, mas h\u00e1 a d\u00favida de que nesta idade voc\u00ea n\u00e3o sabe como isso vai acabar, vamos esperar que corra tudo bem. E depois sobre Malta: fiquei feliz com a visita, vi as realidades de Malta, vi um entusiasmo impressionante do povo, seja em Gozo, seja em Malta La Valletta e nos outros lugares. Um grande entusiasmo nas ruas me surpreendeu, foi um pouco breve, o problema que eu vi para voc\u00eas e tamb\u00e9m um dos problemas \u00e9 a migra\u00e7\u00e3o. O problema dos migrantes \u00e9 s\u00e9rio porque Gr\u00e9cia, Chipre, Malta, It\u00e1lia, Espanha, s\u00e3o os pa\u00edses mais pr\u00f3ximos da \u00c1frica e do Oriente M\u00e9dio e aterrissam aqui, eles chegam aqui, os migrantes devem ser sempre acolhidos!<\/p>\n<p>O problema \u00e9 que cada governo tem que dizer quantos podem receber normalmente para viver ali. Para isso voc\u00ea precisa de um acordo com os pa\u00edses da Europa e nem todos eles est\u00e3o dispostos a receber os migrantes. Esquecemos que a Europa foi feita por migrantes, certo? Mas \u00e9 assim que as coisas s\u00e3o, mas pelo menos n\u00e3o deixar todo o peso para esses pa\u00edses vizinhos que s\u00e3o t\u00e3o generosos, e Malta \u00e9 um deles. Hoje eu estive no centro de acolhida de migrantes e as coisas que ouvi l\u00e1 s\u00e3o terr\u00edveis, o sofrimento dessas pessoas para chegar aqui e depois os lagers, h\u00e1 lagers, que est\u00e3o na costa l\u00edbica, quando s\u00e3o mandadas de volta. Isso parece criminoso, n\u00e3o parece? \u00c9 por isso que eu acho que \u00e9 um problema que toca o cora\u00e7\u00e3o de todos. Assim como a Europa est\u00e1 abrindo espa\u00e7o t\u00e3o generosamente para os ucranianos que batem \u00e0 porta, assim tamb\u00e9m para os outros que v\u00eam do Mediterr\u00e2neo. Este \u00e9 um ponto com o qual terminei a visita e me tocou muito, porque ouvi os testemunhos, os sofrimentos que s\u00e3o mais ou menos como aqueles que eu acho que lhes disse que est\u00e3o naquele pequeno livro que saiu, &#8220;Hermanito&#8221; em espanhol, &#8220;Irm\u00e3ozinho&#8221;, e toda a Via-Sacra destas pessoas. Um que falou hoje teve que pagar quatro vezes, pe\u00e7o-lhes que pensem sobre isto. Obrigado<\/p>\n<p><em>Jorge Antelo Barcia (RNA)<\/em><br \/>\n<em>No voo que nos levou a Malta, o senhor disse a um colega que uma viagem a Kiev estava sobre a mesa e j\u00e1 em Malta fez refer\u00eancias \u00e0 sua proximidade ao povo ucraniano, e na sexta-feira em Roma o presidente da Pol\u00f4nia deixou a porta aberta para uma viagem \u00e0 fronteira com a Pol\u00f4nia. Hoje ficamos impressionados com as imagens vindas de Bucha, uma localidade perto de Kiev, abandonada pelo ex\u00e9rcito russo, onde os ucranianos encontraram dezenas de cad\u00e1veres jogados na rua, alguns com as m\u00e3os atadas, como se tivessem sido &#8220;executados&#8221;. Parece que hoje sua presen\u00e7a ali seja cada vez mais necess\u00e1ria. O senhor acha que uma viagem como esta \u00e9 poss\u00edvel? E quais condi\u00e7\u00f5es teriam que ser cumpridas para que o senhor fosse l\u00e1?<\/em><\/p>\n<p>Obrigado por me dar esta not\u00edcia de hoje que eu ainda n\u00e3o sabia. A guerra \u00e9 sempre uma crueldade, uma coisa desumana, que vai contra o esp\u00edrito humano, eu n\u00e3o digo crist\u00e3o, humano. \u00c9 o esp\u00edrito de Caim, o esp\u00edrito &#8216;Caimista&#8217;&#8230; Estou disposto a fazer tudo o que precisa ser feito, e a Santa S\u00e9, especialmente o lado diplom\u00e1tico, o cardeal Parolin e dom Gallagher, est\u00e3o fazendo tudo, mas tudo, n\u00e3o se pode publicar tudo o que eles fazem, por prud\u00eancia, por confidencialidade, mas estamos no limite do nosso trabalho. Entre as possibilidades est\u00e1 a viagem: h\u00e1 duas viagens poss\u00edveis: uma delas me pediu o presidente da Pol\u00f4nia para enviar o cardeal Krajewski para visitar os ucranianos que foram recebidos na Pol\u00f4nia. Ele j\u00e1 foi duas vezes, levou duas ambul\u00e2ncias e ficou com eles, mas far\u00e1 isso em outra ocasi\u00e3o, ele est\u00e1 disposto a fazer isso. A outra viagem que algu\u00e9m me perguntou, mais de um, eu disse com sinceridade que eu tinha em mente de faz\u00ea-la, que h\u00e1 sempre a minha disponibilidade, n\u00e3o h\u00e1 o n\u00e3o, eu estou dispon\u00edvel. O que pensa sobre uma viagem, a pergunta era assim: &#8220;ouvimos dizer que o senhor estava pensando em uma viagem \u00e0 Ucr\u00e2nia&#8221;, eu disse que ela est\u00e1 sobre a mesa, est\u00e1 ali como uma das propostas que chegaram, mas n\u00e3o sei se poder\u00e1 ser feita, se \u00e9 conveniente faz\u00ea-la e se seria para o melhor ou se \u00e9 conveniente faz\u00ea-la e devo faz\u00ea-la, tudo isso est\u00e1 no ar. Depois h\u00e1 tempo, se tinha pensado em um encontro com o Patriarca Kirill, se est\u00e1 trabalhando para isso, se est\u00e1 trabalhando, e est\u00e1 se pensando no Oriente M\u00e9dio para faz\u00ea-lo, estas s\u00e3o as coisas como elas s\u00e3o agora.<\/p>\n<p><em>Gerry O\u2019Connel (America Magazine)<\/em><\/p>\n<p><em>Durante esta viagem, o senhor v\u00e1rias vezes falou da guerra. A pergunta que todos fazem desde o in\u00edcio da guerra \u00e9 se o senhor falou com o presidente Putin e se n\u00e3o, o que lhe diria hoje?<\/em><\/p>\n<p>As coisas que disse \u00e0s autoridades de cada lado s\u00e3o p\u00fablicas. Nada do que disse \u00e9 reservado para mim. Quando falei com o Patriarca, ele depois fez uma bela declara\u00e7\u00e3o daquilo que dissemos. Falei com o presidente da R\u00fassia no final do ano, quando ele me ligou para as felicita\u00e7\u00f5es. Falei duas vezes com o presidente da Ucr\u00e2nia. Depois, no primeiro dia de guerra pensei que deveria ir \u00e0 embaixada russa para falar com o embaixador, que \u00e9 o representante do povo e fazer minhas perguntas e dizer as minhas impress\u00f5es sobre o caso. Estes foram os contatos oficiais que tive. Com a R\u00fassia, fiz atrav\u00e9s da embaixada. Tamb\u00e9m falei com o arcebispo-mor de Kiev, Dom Schevchuck. Falei ainda com regularidade a cada dois ou tr\u00eas dias com um de voc\u00eas, Elisabetta Piqu\u00e9, que estava em Lviv e agora est\u00e1 em Odessa. Ela me diz como est\u00e3o as coisas. Falei tamb\u00e9m com o reitor do semin\u00e1rio. Mas como disse, estou em contato tamb\u00e9m com um de voc\u00eas. Falando deste tema, gostaria de dar os meus p\u00easames pelos colegas de voc\u00eas que morreram. Estejam de que parte estejam, n\u00e3o interessa. Mas o trabalho de voc\u00eas \u00e9 pelo bem comum e essas pessoas morreram em servi\u00e7o pelo bem comum. Pela informa\u00e7\u00e3o. N\u00e3o nos esque\u00e7amos deles. Foram corajosos e eu rezo por eles para que o Senhor lhes d\u00ea o pr\u00eamio pelo seu trabalho. Estes foram os contatos feitos at\u00e9 agora.<br \/>\nMas qual seria a mensagem para Putin se tivesse a possibilidade (de falar com ele)?<br \/>\nAs mensagens que dei a todas as autoridades s\u00e3o as que fiz publicamente. N\u00e3o tenho linguagem dupla. Fa\u00e7o sempre o mesmo. Creio que na sua pergunta exista tamb\u00e9m uma d\u00favida sobre guerras justas e injustas. Toda guerra nasce de uma injusti\u00e7a, sempre. Porque h\u00e1 o esquema da guerra. N\u00e3o h\u00e1 o esquema da paz. Por exemplo, fazer investimentos para comprar as armas. Dizem: mas precisamos delas para nos defender. Este \u00e9 o esquema da guerra. Quando Segunda Guerra Mundial acabou, todos respiraram o \u201cnunca mais a guerra\u201d e a paz. Come\u00e7ou uma onda de trabalho pela paz tamb\u00e9m com a boa vontade de n\u00e3o dar as armas, as armas at\u00f4micas naquele momento, pela paz, depois de Hiroshima e Nagasaki. Havia uma grande boa vontade.<\/p>\n<p>Setenta anos depois, esquecemos tudo isso. \u00c9 assim que o esquema da guerra se imp\u00f5e. Havia muitas esperan\u00e7as no trabalho das Na\u00e7\u00f5es Unidas na \u00e9poca. Mas o esquema de guerra se imp\u00f4s mais uma vez. N\u00f3s n\u00e3o podemos pensar outro esquema, n\u00e3o estamos mais acostumados a pensar no esquema da paz. Houve grandes personagens, como Ghandi e outros que menciono no final da enc\u00edclica \u201cFratelli tutti\u201d, que apostaram no esquema da paz. Mas n\u00f3s fomos teimosos como humanidade. Somos apaixonados pelas guerras, pelo esp\u00edrito de Caim. N\u00e3o por acaso, no in\u00edcio da B\u00edblica h\u00e1 este problema: o esp\u00edrito \u201ccaimista\u201d de matar ao inv\u00e9s do esp\u00edrito da paz. Pai, n\u00e3o se pode! Conto algo pessoal de quando estive em 2014 em Redipuglia e vi os nomes dos jovens, eu chorei. Realmente chorei de amargura. Depois, um ou dois anos depois, para o dia de Finados fui celebrar em Anzio e vi os nomes dos jovens mortos ali. Todos jovens e tamb\u00e9m ali chorei. Realmente. \u00c9 preciso chorar sobre os t\u00famulos. H\u00e1 algo que respeito porque existe um problema pol\u00edtico. Quando houve a celebra\u00e7\u00e3o do desembarque na Normandia, os chefes de Estado se reuniram para comemorar. Mas n\u00e3o lembro se algu\u00e9m citou os 30 mil jovens que ficaram ali na praia. A juventude n\u00e3o conta. Isso me faz pensar. Estou entristecido. N\u00e3o aprendemos. Que o Senhor tenha piedade de n\u00f3s, de todos n\u00f3s. Todos somos culpados!<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevista<\/p>\n","protected":false},"author":3,"featured_media":237151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[1140],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papa: &quot;N\u00f3s n\u00e3o aprendemos, estamos apaixonados pelas guerras e pelo esp\u00edrito de Caim&quot; - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa: &quot;N\u00f3s n\u00e3o aprendemos, estamos apaixonados pelas guerras e pelo esp\u00edrito de Caim&quot; - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Entrevista\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-04T09:47:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04.jpeg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04.jpeg\",\"width\":1500,\"height\":844},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html\",\"name\":\"Papa: \\\"N\u00f3s n\u00e3o aprendemos, estamos apaixonados pelas guerras e pelo esp\u00edrito de Caim\\\" - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html#primaryimage\"},\"datePublished\":\"2022-04-04T09:47:03+00:00\",\"dateModified\":\"2022-04-04T09:47:03+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa: &#8220;N\u00f3s n\u00e3o aprendemos, estamos apaixonados pelas guerras e pelo esp\u00edrito de Caim&#8221;\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa: \"N\u00f3s n\u00e3o aprendemos, estamos apaixonados pelas guerras e pelo esp\u00edrito de Caim\" - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html","og_locale":"pt_BR","og_type":"article","og_title":"Papa: \"N\u00f3s n\u00e3o aprendemos, estamos apaixonados pelas guerras e pelo esp\u00edrito de Caim\" - Not\u00edcias - Franciscanos","og_description":"Entrevista","og_url":"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2022-04-04T09:47:03+00:00","og_image":[{"width":1500,"height":844,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04.jpeg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04.jpeg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2022\/04\/voo_04.jpeg","width":1500,"height":844},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html","name":"Papa: \"N\u00f3s n\u00e3o aprendemos, estamos apaixonados pelas guerras e pelo esp\u00edrito de Caim\" - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html#primaryimage"},"datePublished":"2022-04-04T09:47:03+00:00","dateModified":"2022-04-04T09:47:03+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-nos-nao-aprendemos-estamos-apaixonados-pelas-guerras-e-pelo-espirito-de-caim.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Papa: &#8220;N\u00f3s n\u00e3o aprendemos, estamos apaixonados pelas guerras e pelo esp\u00edrito de Caim&#8221;"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/237150"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=237150"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/237150\/revisions"}],"predecessor-version":[{"id":237152,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/237150\/revisions\/237152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/237151"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=237150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=237150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=237150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}