{"id":235121,"date":"2021-11-12T09:18:39","date_gmt":"2021-11-12T12:18:39","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=235121"},"modified":"2021-11-12T12:57:34","modified_gmt":"2021-11-12T15:57:34","slug":"papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html","title":{"rendered":"Papa aos pobres em Assis: &#8220;Estamos aqui precisamente para aprender com o que S\u00e3o Francisco fez\u201d"},"content":{"rendered":"<div id=\"attachment_235122\" style=\"width: 1290px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-235122\" loading=\"lazy\" class=\"wp-image-235122 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211-1024x576.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><p id=\"caption-attachment-235122\" class=\"wp-caption-text\"><em>\u00a0 \u00a0 Imagens: Vatican Media<\/em><\/p><\/div>\n<p>Por ocasi\u00e3o do Encontro de ora\u00e7\u00e3o e testemunho da quinta edi\u00e7\u00e3o do Dia Mundial dos Pobres o Papa Francisco foi a Assis nesta sexta-feira, 12 de novembro. Depois de ouvir os testemunhos de alguns presentes e do momento especial de ora\u00e7\u00e3o o Papa dirigiu algumas palavras aos presentes.<\/p>\n<p>Francisco iniciou agradecendo a presen\u00e7a de todos em Assis e recordando que a cidade de Assis \u201ctem impresso o rosto de S\u00e3o Francisco\u201d que recebeu o chamado para viver o Evangelho \u00e0 letra. E disse que embora a sua santidade de alguma forma nos assusta porque parece imposs\u00edvel imit\u00e1-la, devemos recordar certos momentos da sua vida que valem mais do que os serm\u00f5es. E falou dos pequenos sacrif\u00edcios os \u201cfioretti\u201d que o Santo fazia, que foram reunidos para mostrar a beleza da sua voca\u00e7\u00e3o: \u201csomos atra\u00eddos por esta simplicidade de cora\u00e7\u00e3o e de vida: \u00e9 a pr\u00f3pria atra\u00e7\u00e3o de Cristo, do Evangelho\u201d. O Papa recordou uma dessas passagens quando Francisco vivendo na pobreza extrema conseguia alguma coisa para comer embora fosse pouca ele sempre a considerava como \u201cum tesouro do qual n\u00e3o se sentia digno\u201d, e dizia: \u201c\u00c9 precisamente isto que considero um grande tesouro, porque n\u00e3o h\u00e1 nada, mas o que temos nos foi dado pela Provid\u00eancia (&#8230;) Este \u00e9 o ensinamento que S\u00e3o Francisco nos d\u00e1: saber contentar-se com o pouco que temos e partilh\u00e1-lo com os outros\u201d<\/p>\n<p><strong>Homens e mulheres pedras vivas da Igreja<\/strong><br \/>\nAo recordar que o encontro se realizava na Porci\u00fancula, uma das pequenas igrejas que S\u00e3o Francisco pensou em restaurar, o Papa disse: \u201cEle nunca teria pensado que o Senhor lhe pedisse para dar a sua vida para renovar n\u00e3o a igreja feita de pedras, mas a de pessoas, de homens e mulheres que s\u00e3o as pedras vivas da Igreja. E se estamos aqui hoje \u00e9 precisamente para aprender com o que S\u00e3o Francisco fez\u201d.<\/p>\n<p><strong>Marginaliza\u00e7\u00e3o espiritual<\/strong><br \/>\nS\u00e3o Francisco \u201cpassava muito tempo nesta pequena igreja a rezar\u201d, continuou o Papa, \u201crecolhia-se aqui em sil\u00eancio e escutava o Senhor, o que Deus queria dele. Tamb\u00e9m n\u00f3s viemos aqui para isto: queremos pedir ao Senhor que ou\u00e7a o nosso grito e venha em nosso aux\u00edlio. N\u00e3o esque\u00e7amos que a primeira marginaliza\u00e7\u00e3o de que os pobres sofrem \u00e9 espiritual\u201d. O Papa recordou e agradeceu a todos os que ajudam os pobres, e disse que fica muito feliz quando \u201cas pessoas param para falar e \u00e0s vezes rezar com eles\u201d.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-235123\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_1.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_1.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_1-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_1-1024x576.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_1-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_1-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Em seguida falou da acolhida. \u201cAcolher significa abrir a porta, a porta da casa e a porta do cora\u00e7\u00e3o, e permitir \u00e0queles que batem \u00e0 porta de entrar. E que podem sentir-se \u00e0 vontade, sem medo. Onde existe um verdadeiro sentido de fraternidade, existe tamb\u00e9m a experi\u00eancia sincera de acolhimento\u201d<\/p>\n<p><strong>A fraqueza pode se tornar uma for\u00e7a que melhora o mundo<\/strong><br \/>\nNeste ponto do discurso o Papa falou sobre o encontro.<\/p>\n<p>\u201cEncontrar-se \u00e9 a primeira coisa, ou seja, ir ao encontro uns dos outros com o cora\u00e7\u00e3o aberto e a m\u00e3o estendida. Sabemos que cada um de n\u00f3s precisa do outro, e mesmo a fraqueza, se experimentada em conjunto, pode tornar-se uma for\u00e7a que melhora o mundo\u201d<\/p>\n<p>O Pont\u00edfice em seguida abordou a quest\u00e3o dos que afirmam que os respons\u00e1veis pela pobreza s\u00e3o os pobres&#8230;. al\u00e9m da \u201chipocrisia dos que querem se enriquecer para al\u00e9m das medidas, se coloca a culpa sobre os ombros dos mais fracos\u201d. E para contrastar o Papa afirmou com veem\u00eancia: \u201c\u00c9 tempo que seja restitu\u00edda a palavra aos pobres, porque durante demasiado tempo os seus pedidos n\u00e3o foram ouvidos. \u00c9 tempo que se abram os olhos para ver o estado de desigualdade em que vivem tantas fam\u00edlias. \u00c9 tempo de arrega\u00e7ar as mangas para restituir dignidade atrav\u00e9s da cria\u00e7\u00e3o de empregos. \u00c9 tempo que se volte a se escandalizar diante da realidade de crian\u00e7as famintas, escravizadas, tiradas das \u00e1guas quando naufragam, v\u00edtimas inocentes de todo o tipo de viol\u00eancia. \u00c9 tempo que cessem as viol\u00eancias contra as mulheres e as mulheres sejam respeitadas e n\u00e3o tratadas como mercadoria. \u00c9 tempo que se rompa o c\u00edrculo da indiferen\u00e7a para retornar a descobrir a beleza do encontro e do di\u00e1logo\u201d.<\/p>\n<p><strong>Coragem e sinceridade<\/strong><br \/>\nEm seguida o Papa comentou os testemunhos das pessoas pobres agradecendo sua coragem e sinceridade. \u201cCoragem, porque quiseram partilhar com todos n\u00f3s, mesmo que fa\u00e7am parte da sua vida pessoal; sinceridade, porque se mostraram como s\u00e3o e abriram o seu cora\u00e7\u00e3o com o desejo de serem compreendidos\u201d.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-235124\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_3.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_3.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_3-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_3-1024x576.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_3-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211_3-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><strong>Esperan\u00e7a e resist\u00eancia<\/strong><br \/>\n\u201cPercebi um grande sentido de esperan\u00e7a. A marginaliza\u00e7\u00e3o, o sofrimento da doen\u00e7a e da solid\u00e3o, a falta de muitos meios necess\u00e1rios n\u00e3o os impediu de olharem com os olhos cheios de gratid\u00e3o para as pequenas coisas que lhes permitiram de resistir\u201d<\/p>\n<p>Por fim o Papa falou sobre resistir al\u00e9m da esperan\u00e7a: \u201cEsta \u00e9 a segunda impress\u00e3o que eu percebi e que deriva da esperan\u00e7a. O que significa resistir? Ter a for\u00e7a para continuar apesar de tudo. A resistir n\u00e3o \u00e9 uma a\u00e7\u00e3o passiva, pelo contr\u00e1rio, requer coragem para empreender um novo caminho sabendo que dar\u00e1 frutos\u201d.<\/p>\n<p>Concluindo disse: \u201cPe\u00e7amos ao Senhor que nos ajude sempre a encontrar a serenidade e a alegria. Aqui na Porci\u00fancula, S\u00e3o Francisco ensina-nos a alegria que vem de olhar para quem est\u00e1 pr\u00f3ximo como a um companheiro de viagem que nos compreende e nos apoia, tal como n\u00f3s somos para ele ou ela\u201d.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-235128 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_mariana.jpg\" alt=\"\" width=\"900\" height=\"506\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_mariana.jpg 900w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_mariana-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_mariana-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_mariana-150x84.jpg 150w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<h3><strong>As vozes emocionadas dos pobres que compartilham f\u00e9, alegria e dor com Francisco<\/strong><\/h3>\n<p>O encontro de ora\u00e7\u00e3o do Papa Francisco com os pobres na Porci\u00fancula \u00e9 como uma ponte de acolhimento longa mais de 800 anos que conecta, o que o Pobrezinho de Assis testemunhava junto com os primeiros frades, Clara de Assis e a f\u00e9, ao drama dos pobres de hoje ao lado do Pont\u00edfice. No gesto dos tr\u00eas pobres que entregam o manto ao Papa no adro da Bas\u00edlica de Santa Maria dos Anjos \u00e9 como se realmente existisse o jovem Francisco que ainda n\u00e3o abra\u00e7ou a cruz e come\u00e7ou a consertar a Igreja de Cristo.<\/p>\n<p><strong>O manto que S\u00e3o Francisco doa ao nobre ca\u00eddo<\/strong><br \/>\nEm 1204, o filho de Pietro di Bernardone \u00e9 um jovem inquieto, vaidoso e bem vestido, mas tamb\u00e9m sens\u00edvel e generoso, como conta S\u00e3o Boaventura e, ao encontrar um nobre ca\u00eddo, tem &#8220;piedade dele&#8221;. Ele tira o lindo vestido que acabou de comprar para si com o dinheiro de seu pai comerciante e o d\u00e1 ao cavaleiro.<\/p>\n<p><strong>Com Jennifer, Luciano e Abrhaley o primeiro abra\u00e7o<\/strong><br \/>\nO jovem Francisco reaparece em Jennifer Amadin da Associa\u00e7\u00e3o Madalena, ligada ao Irm\u00e3o, movimento franc\u00eas que desejou fortemente este encontro, que depois da doa\u00e7\u00e3o do manto, l\u00ea uma sauda\u00e7\u00e3o ao Papa, escrita numa folha de papel. Luciano, um romeno que mora em Roma, ajudado pela Caritas, digitou o que deveria dizer ao Papa num telefone celular. O terceiro foi Abrhaley Tesfagergs Habte. Ele \u00e9 um refugiado cego da Eritreia que oferece a Francisco o bast\u00e3o do peregrino e aperta sua m\u00e3o. O Papa reza com ele e escuta sua hist\u00f3ria que vem do cora\u00e7\u00e3o.<\/p>\n<p><strong>Florence, Thibault e Celeste: em miss\u00e3o com os \u00faltimos<\/strong><br \/>\nDepois da ora\u00e7\u00e3o silenciosa do Papa na Porci\u00fancula, seguem-se os testemunhos dos pobres e dos que com eles compartilham suas vidas. Como Florence e Thibault Jarry, com a pequena Celeste, que ainda n\u00e3o completou 4 meses. Eles s\u00e3o um jovem casal de mission\u00e1rios entre os \u00faltimos da periferia de Paris. Ela conta que conheceu Thibault seis anos atr\u00e1s no Chile, onde ambos, por conta pr\u00f3pria, tinham ido em miss\u00e3o com a Miseric\u00f3rdia, associa\u00e7\u00e3o fundada pelo casal franco-brasileiro Roman e Renate de Chateauvieux e fruto das palavras do Papa Francisco no Angelus de 17 de mar\u00e7o de 2013: \u201cA miseric\u00f3rdia muda o mundo, torna-o mais justo e menos frio\u201d. Em seguida, Thibault contou como depois de um ano de miss\u00e3o, de volta \u00e0 Fran\u00e7a, eles se confiaram ao Senhor para viver uma vida simples e pediram para serem enviados como casal mission\u00e1rio. \u201cNem sempre \u00e9 f\u00e1cil\u201d, confessa, \u201cdeixar-nos ir ao que Deus preparou para n\u00f3s. Testemunhamos a alegria de partilhar a vida quotidiana dos nossos vizinhos de bairro, feridos por uma grande pobreza material, mas tamb\u00e9m espiritual e de relacionamento. \u00c9 o Senhor que nos espera por meio dos pobres\u201d.<\/p>\n<p><strong>Sebastian: da viol\u00eancia e das drogas ao ressurgiu com Cristo<\/strong><br \/>\nNa grande Bas\u00edlica ressoa tamb\u00e9m a comovida voz de Sebastian del Valle Diaz, de Toledo, que lembro a av\u00f3 que lhe transmitiu a f\u00e9 e o amor pelo ros\u00e1rio, mas tamb\u00e9m a forma\u00e7\u00e3o militar que o transformou num rapaz violento, que acabou no tr\u00e1fico de drogas. Depois a pris\u00e3o e, depois de outras reca\u00eddas, a convers\u00e3o durante a pandemia, que o levou \u00e0 experi\u00eancia de saber que Deus cuida de cada um. &#8220;Hoje&#8221;, disse ele, &#8220;sou um mendigo do amor e da miseric\u00f3rdia de Deus. Jesus Cristo me ressuscitou!&#8221;<\/p>\n<p><strong>Gabriel, batizado aos 60 anos: &#8220;Agora busco a santidade&#8221;<\/strong><br \/>\nO coro da Associa\u00e7\u00e3o Irm\u00e3o, com 13 cantores e m\u00fasicos, entoa o c\u00e2none de Taiz\u00e9 &#8220;Aben\u00e7oa Senhor minha alma&#8221;, enquanto o ex-morador de rua parisiense Gabriel Barbier, da APA, Association pour l&#8217;Amiti\u00e9, toma a palavra. Aos 60 anos, ele que vem de uma fam\u00edlia ate\u00edsta, foi batizado. &#8220;N\u00f3s, pobres de esp\u00edrito&#8221;, disse ele, &#8220;podemos encontrar a nossa for\u00e7a em Cristo. Ele \u00e9 a nossa maior riqueza. \u00c0s vezes nos vemos ridicularizados pelo mundo, mas eu sou um lutador. Conheci o desespero num mundo cada vez mais impiedoso, mas encontrei o amor de Deus&#8221;. Com o batismo, \u201cJesus transformou-me, a ponto de me fazer desejar a santidade. O meu receio \u00e9 n\u00e3o conseguir invocar a Deus nas tenta\u00e7\u00f5es\u201d. E concluiu com uma ora\u00e7\u00e3o: \u201cMaria, d\u00e1-me a gra\u00e7a de pensar sempre em ti e de te invocar. &#8216;Vem em meu aux\u00edlio&#8221;.<\/p>\n<p><strong>Da Pol\u00f4nia Sebastian: &#8220;Deus me deu uma nova vida&#8221;<\/strong><br \/>\nSebastian Olczak, 37 anos, fala polon\u00eas. At\u00e9 aos 16 anos viveu uma vida normal, numa fam\u00edlia cat\u00f3lica, depois experimentou droga e \u00e1lcool. \u201cTive problemas com a lei e perdi o respeito por mim e pelos outros\u201d. Desde 2007, era um sem-teto. Depois, a Associa\u00e7\u00e3o Obra de Socorro de S\u00e3o Pio se aproximou dele, mas demorou um pouco para se entregar a ela e a Deus. \u201cNo final\u201d, confessou ele, \u201cadmiti que sozinho eu n\u00e3o conseguia e implorei a Deus que me desse uma vida nova. E Deus n\u00e3o me deu as costas. Ele me mostrou uma vida f\u00e1cil, mas n\u00e3o necessariamente feliz. A gra\u00e7a de Deus \u00e9 hoje a minha experi\u00eancia cotidiana\u201d. \u201cAntes eu me odiava\u201d, concluiu, \u201ce agora me aceito e me sinto um homem livre, que olha para si mesmo e para os outros atrav\u00e9s do amor de Deus. Tenho consci\u00eancia de que ainda me espera um grande trabalho sobre mim\u201d.<\/p>\n<p><strong>Farzaneh, voz de dor e orgulho das mulheres afeg\u00e3s<\/strong><br \/>\nNas palavras de Farzaneh Razavi, acolhida em Foligno pela Caritas e pela Arca do Mediterr\u00e2neo, h\u00e1 o sofrimento de todas as mulheres afeg\u00e3s, esmagadas por &#8220;uma sociedade patriarcal e mis\u00f3gina, que bloqueou &#8220;sonhos e aspira\u00e7\u00f5es&#8221;. Ela chegou \u00e0 It\u00e1lia em agosto, ap\u00f3s o retorno dos Talib\u00e3s ao poder, &#8220;para se levantar com firmeza e seguir em frente&#8221;, mas com o cora\u00e7\u00e3o ela ainda est\u00e1 &#8220;com as jovens do dormit\u00f3rio da Universidade de Cabul que hoje n\u00e3o podem ir \u00e0 universidade, comprar p\u00e3o, ir \u00e0 padaria e se divirtir\u201d. Farzaneh disse ao Papa que est\u00e1 preocupada com a sua fam\u00edlia que ficou no Afeganist\u00e3o e explicou que a sua vida l\u00e1 estava em perigo, tamb\u00e9m por ser filha de hazari mu\u00e7ulmanos xiitas, e por isso perseguida duas vezes. Ela agradeceu \u00e0 Igreja italiana por t\u00ea-la ajudado e salvado sua vida e a de muitas outras pessoas como ela, e disse que come\u00e7ou uma nova vida aqui, tentando ser \u00fatil para ela, sua fam\u00edlia e a It\u00e1lia. Olhando para a pobreza e a fome, que &#8220;tiram a vida a milh\u00f5es de pessoas&#8221;, a jovem espera &#8220;que o mundo adote uma abordagem global para resolver este problema e n\u00e3o deixe o povo afeg\u00e3o sozinho&#8221;.<\/p>\n<p><strong>Abdul faz apelo para salvar os filhos que ficaram em Cabul<\/strong><br \/>\nDepois dela, outro afeg\u00e3o, Qadery Abdul Razaq, em Foligno com sua esposa Salima, explicou que foi salvo pelo governo italiano, depois de ter trabalhado por 11 anos em Cabul para o Unicef \u200b\u200bcomo soci\u00f3logo. Abdul agradeceu tamb\u00e9m \u00e0 Caritas local &#8220;pelo acolhimento, pela casa&#8221; e por tudo o que precisam&#8221; e aos jovens trabalhadores &#8220;que nos tratam como seus pais e n\u00f3s como filhos&#8221;, mas diz estar muito preocupado &#8220;com parte da nossa fam\u00edlia que permaneceu no Afeganist\u00e3o&#8221;. Em l\u00e1grimas, ele se lembrou dos quatro filhos deixados em seu pa\u00eds&#8221; que colaboraram durante anos com o Ex\u00e9rcito italiano, e do outro que foi morto pelos Talib\u00e3s e outro ainda que \u00e9 refugiado na Turquia. Precisamos de sua ajuda, Santo Padre, para salvar eles tamb\u00e9m&#8221;.<\/p>\n<p><strong>A dor de Mariana, apegada aos filhos criados com amor<\/strong><br \/>\nPor fim, da Rom\u00eania o testemunho de Mariana, 43 anos, que chegou \u00e0 It\u00e1lia 15 anos atr\u00e1s. Hoje, numa cadeira de rodas acompanhada por seus filhos de 24 e 22 anos. Ela contou, apesar da dor muito forte, que veio para a It\u00e1lia para ser cuidadora, deixando os dois filhos com o marido. Quando ele morreu, ela os trouxe consigo para a It\u00e1lia, mas 11 anos atr\u00e1s a doen\u00e7a chegou, uma &#8220;s\u00edndrome dolorosa devastadora na coluna lombar e nas pernas, que abalou sua vida familiar e sua vida profissional. A cirurgia piorou a situa\u00e7\u00e3o e Mariana hoje est\u00e1 inv\u00e1lida. A provid\u00eancia para ela e para os seus filhos foi a Caritas, cuja ajuda lhe permitiu viver com dignidade e alguns m\u00e9dicos &#8220;que Deus p\u00f4s em meu caminho&#8221;, disse ela, que a tratam gratuitamente. Mas Deus deu a ela for\u00e7a para criar os dois filhos \u201cque hoje fazem de tudo para mim, a cuidadora, a empregada, a cozinheira, eles me d\u00e3o banho. Encontro for\u00e7as para seguir este calv\u00e1rio em Jesus. Estou sofrendo h\u00e1 11 anos, n\u00e3o recuperei a sa\u00fade, mas suporto essas dores com uma dose de morfina para &#8220;cavalo&#8221;, que tira apenas 20 por cento da dor. Agrade\u00e7o ao Pe. Eduardo que nunca me abandonou e, sobretudo, a Deus pela for\u00e7a que ainda me d\u00e1\u201d.<\/p>\n<p><strong>Quinhentos pobres, muitas hist\u00f3rias de todo o mundo<\/strong><br \/>\nOs quinhentos pobres protagonistas do encontro com o Papa Francisco est\u00e3o ligados \u00e0 Caritas da Umbria e \u00e0 Associa\u00e7\u00e3o francesa Irm\u00e3o, e os de Roma \u00e0 Esmolaria Apost\u00f3lica, Caritas, C\u00edrculo S\u00e3o Pedro, Comunidade de Santo Eg\u00eddio, Coordena\u00e7\u00e3o Regional da Fam\u00edlia Vicentina, Centro Astalli e Acli.<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News (texto de Jane Nogara e Alessandro Di Bussolo )<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Encontro de ora\u00e7\u00e3o e testemunho em Assis<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[1937],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papa aos pobres em Assis: &quot;Estamos aqui precisamente para aprender com o que S\u00e3o Francisco fez\u201d - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa aos pobres em Assis: &quot;Estamos aqui precisamente para aprender com o que S\u00e3o Francisco fez\u201d - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Encontro de ora\u00e7\u00e3o e testemunho em Assis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-12T12:18:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-12T15:57:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211.jpg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html\",\"name\":\"Papa aos pobres em Assis: \\\"Estamos aqui precisamente para aprender com o que S\u00e3o Francisco fez\u201d - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html#primaryimage\"},\"datePublished\":\"2021-11-12T12:18:39+00:00\",\"dateModified\":\"2021-11-12T15:57:34+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa aos pobres em Assis: &#8220;Estamos aqui precisamente para aprender com o que S\u00e3o Francisco fez\u201d\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa aos pobres em Assis: \"Estamos aqui precisamente para aprender com o que S\u00e3o Francisco fez\u201d - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html","og_locale":"pt_BR","og_type":"article","og_title":"Papa aos pobres em Assis: \"Estamos aqui precisamente para aprender com o que S\u00e3o Francisco fez\u201d - Not\u00edcias - Franciscanos","og_description":"Encontro de ora\u00e7\u00e3o e testemunho em Assis","og_url":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2021-11-12T12:18:39+00:00","article_modified_time":"2021-11-12T15:57:34+00:00","og_image":[{"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211.jpg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/11\/assis_1211.jpg","width":1280,"height":720},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html","name":"Papa aos pobres em Assis: \"Estamos aqui precisamente para aprender com o que S\u00e3o Francisco fez\u201d - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html#primaryimage"},"datePublished":"2021-11-12T12:18:39+00:00","dateModified":"2021-11-12T15:57:34+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-pobres-em-assis-estamos-aqui-precisamente-para-aprender-com-o-que-sao-francisco-fez.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Papa aos pobres em Assis: &#8220;Estamos aqui precisamente para aprender com o que S\u00e3o Francisco fez\u201d"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/235121"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=235121"}],"version-history":[{"count":4,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/235121\/revisions"}],"predecessor-version":[{"id":235129,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/235121\/revisions\/235129"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=235121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=235121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=235121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}