{"id":234936,"date":"2021-10-24T08:06:51","date_gmt":"2021-10-24T11:06:51","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=234936"},"modified":"2021-10-24T09:54:43","modified_gmt":"2021-10-24T12:54:43","slug":"papa-pedir-tudo-a-jesus-pois-ele-tudo-pode","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html","title":{"rendered":"Papa: pedir tudo a Jesus, pois Ele tudo pode"},"content":{"rendered":"<div id=\"attachment_234937\" style=\"width: 1010px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-234937\" loading=\"lazy\" class=\"wp-image-234937 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/10\/angelus_2410.jpg\" alt=\"\" width=\"1000\" height=\"562\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/10\/angelus_2410.jpg 1000w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/10\/angelus_2410-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/10\/angelus_2410-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/10\/angelus_2410-150x84.jpg 150w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><p id=\"caption-attachment-234937\" class=\"wp-caption-text\"><em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Imagem: Vatican Media<\/em><\/p><\/div>\n<p>\u201cQuando a f\u00e9 \u00e9 viva, a ora\u00e7\u00e3o \u00e9 sincera: n\u00e3o mendiga trocados, n\u00e3o se reduz \u00e0s necessidades do momento. A Jesus, que tudo pode, deve ser pedido tudo. Ele n\u00e3o v\u00ea a hora para derramar sua gra\u00e7a e sua alegria em nossos cora\u00e7\u00f5es\u201d.<\/p>\n<p>A f\u00e9 concreta, insistente e corajosa de Bartimeu nos foi apresentada como exemplo pelo Papa Francisco, ao refletir no Angelus deste 30\u00ba Domingo do Tempo Comum sobre a narrativa apresentada no Evangelho de Marcos (Mc 10, 46-52).<\/p>\n<p>Dirigindo-se aos milhares de fi\u00e9is e turistas reunidos na Pra\u00e7a S\u00e3o Pedro, em um belo domingo de outono, o Papa come\u00e7a destacando a import\u00e2ncia deste encontro entre Bartimeu &#8211; \u201cum cego que mendiga ao longo do caminho\u201d \u2013 e Jesus, que se preparava para entrar em Jerusal\u00e9m para a P\u00e1scoa.<\/p>\n<p><strong>A f\u00e9, raiz do milagre<\/strong><\/p>\n<p>Se os gritos de Bartimeu &#8220;Filho de Davi, Jesus, tem piedade de mim&#8221; incomodaram a multid\u00e3o e os ap\u00f3stolos, n\u00e3o passaram desapercebidos de Jesus, que percebe que sua voz \u201c\u00e9 cheia de f\u00e9, uma f\u00e9 que n\u00e3o tem medo de insistir, de bater no cora\u00e7\u00e3o de Deus, apesar da incompreens\u00e3o e repreens\u00f5es. E aqui \u2013 ressaltou o Papa &#8211; est\u00e1 a raiz do milagre. Na verdade, Jesus lhe disse: \u2018A tua f\u00e9 te curou\u2019\u201d.<\/p>\n<p>Ou seja, \u201ca f\u00e9 de Bartimeu, transparece pela sua ora\u00e7\u00e3o. N\u00e3o \u00e9 uma ora\u00e7\u00e3o t\u00edmida, uma ora\u00e7\u00e3o convencional. Antes de tudo, ele chama o Senhor de &#8220;Filho de Davi&#8221;, isto \u00e9, o reconhece como Messias, o Rei que vem ao mundo. Depois o chama pelo nome, com confian\u00e7a: &#8220;Jesus&#8221;. N\u00e3o tem medo dele, n\u00e3o se distancia. E assim, de cora\u00e7\u00e3o, grita ao Deus amigo todo o seu drama: \u201ctem piedade de mim!\u201d.<\/p>\n<p>N\u00e3o pede algum trocado como faz com os transeuntes. N\u00e3o, n\u00e3o. \u00c0quele que tudo pode, pede tudo. \u00c0s pessoas pede trocados, a Jesus, que pode fazer tudo, pede tudo: \u201ctem piedade de mim, tem piedade de tudo o que sou\u201d. N\u00e3o pede uma gra\u00e7a, mas apresenta a si mesmo: pede miseric\u00f3rdia para a sua pessoa, para a sua vida. N\u00e3o \u00e9 um pedido pequeno, mas \u00e9 bel\u00edssimo, porque invoca a piedade, isto \u00e9, a compaix\u00e3o, a miseric\u00f3rdia de Deus, a sua ternura.<\/p>\n<p><strong>Apresentar-se inteiramente ao Senhor, como somos<\/strong><\/p>\n<p>\u201cBartimeu n\u00e3o usa muitas palavras &#8211; recorda Francisco &#8211; diz o essencial e confia-se no amor de Deus, que pode fazer a sua vida voltar a florescer realizando o que \u00e9 imposs\u00edvel aos homens\u201d: Por isso, n\u00e3o pede esmola ao Senhor, mas manifesta tudo, a sua cegueira e o seu sofrimento, que iam al\u00e9m do n\u00e3o poder ver. A cegueira era a ponta do iceberg, mas em seu cora\u00e7\u00e3o haveria feridas, humilha\u00e7\u00f5es, sonhos desfeitos, erros, remorsos. E ele rezava com o cora\u00e7\u00e3o.<\/p>\n<p>&#8220;E n\u00f3s &#8211; pergunta o Papa &#8211; quando pedimos uma gra\u00e7a a Deus, colocamos tamb\u00e9m na ora\u00e7\u00e3o a nossa pr\u00f3pria hist\u00f3ria: as feridas, as humilha\u00e7\u00f5es, os sonhos desfeitos, os erros, os remorsos?&#8221;<\/p>\n<p>Ao sugerir que fa\u00e7amos nossa a ora\u00e7\u00e3o \u201cFilho de David, Jesus, tem piedade de mim!\u201d, o Papa exorta a nos perguntarmos: &#8220;Como vai a minha ora\u00e7\u00e3o?&#8221;: \u00c9 ora\u00e7\u00e3o corajosa, tem a boa insist\u00eancia daquela de Bartimeu, sabe &#8220;agarrar&#8221; o Senhor que passa, ou contenta-se em dar-lhe uma sauda\u00e7\u00e3o formal de vez em quando, quando me lembro? Estas ora\u00e7\u00f5es mornas n\u00e3o ajudam nada.<\/p>\n<p><strong>F\u00e9 viva, ora\u00e7\u00e3o sincera<\/strong><\/p>\n<p>Depois \u2013 acrescentou Francisco &#8211; tamb\u00e9m podemos nos perguntar se \u201cnossa ora\u00e7\u00e3o \u00e9 \u201csubstanciosa\u201d, exp\u00f5e o cora\u00e7\u00e3o diante do Senhor: levo a ele a hist\u00f3ria e os rostos da minha vida? Ou \u00e9 an\u00eamica, superficial, feito de rituais sem afeto e sem cora\u00e7\u00e3o?\u201c: Quando a f\u00e9 \u00e9 viva, a ora\u00e7\u00e3o \u00e9 sincera: n\u00e3o mendiga trocados, n\u00e3o se reduz \u00e0s necessidades do momento. A Jesus, que tudo pode, tudo deve ser pedido. N\u00e3o se esque\u00e7am disso. A Jesus que tudo pode, deve ser pedido tudo, com a minha insist\u00eancia diante d&#8217;Ele. Ele n\u00e3o v\u00ea a hora para derramar sua gra\u00e7a e sua alegria em nossos cora\u00e7\u00f5es, mas infelizmente somos n\u00f3s que mantemos dist\u00e2ncia, talvez por timidez, ou pregui\u00e7a ou descren\u00e7a. Tantos de n\u00f3s, quando rezamos, n\u00e3o acreditamos que o Senhor pode realizar o milagre.<\/p>\n<p>Para ilustrar o resultado de uma ora\u00e7\u00e3o insistente e expectante, o Papa voltou a contar uma hist\u00f3ria ocorrida quando era arcebispo na Argentina: com a filha pequena desenganada pelos m\u00e9dicos, um pai viajou 70 km em um \u00f4nibus at\u00e9 um Santu\u00e1rio mariano. Mesmo estando fechado, ele passou a noite agarrado \u00e0s grades do port\u00e3o rezando e clamando: &#8220;Senhor, salva-a. Senhor, d\u00e1 a ela a vida&#8221;. Ao voltar ao hospital na manh\u00e3 seguinte, encontrou a esposa que chorava, mas n\u00e3o de tristeza: &#8220;N\u00e3o se entende, n\u00e3o se entende. Os m\u00e9dico dizem algo estranho: parece curada&#8221;. &#8220;Aquele grito daquele homem que pedia tudo, foi ouvido pelo Senhor que lhe havia dado tudo&#8221;, disse o Papa, acrescentando: &#8220;Esta n\u00e3o \u00e9 uma hist\u00f3ria, eu vi isso&#8221;.<\/p>\n<p>\u201cMas temos coragem na ora\u00e7\u00e3o? Pe\u00e7amos tudo \u00e0quele que pode dar tudo, como Bartimeu, que \u00e9 um grande mestre, um grande mestre na ora\u00e7\u00e3o nisto.\u201d<\/p>\n<p>Que Bartimeu \u2013 disse ao concluir &#8211; seja um exemplo para n\u00f3s com a sua f\u00e9 concreta, insistente e corajosa. E que Nossa Senhora, a Virgem orante, nos ensine a dirigir-nos a Deus de todo o cora\u00e7\u00e3o, confiando que Ele escuta atentamente cada ora\u00e7\u00e3o.<\/p>\n<p><strong>BEATOS E DIA MUNDIAL DAS MISS\u00d5ES<\/strong><\/p>\n<p>Ontem, em Brescia, foi beatificada a Irm\u00e3 L\u00facia da Imaculada, religiosa das Servas da Caridade. Mulher mansa e acolhedora, que faleceu em 1954 aos 45 anos, ap\u00f3s uma vida passada ao servi\u00e7o dos outros, mesmo quando a doen\u00e7a debilitou o seu corpo, mas n\u00e3o o seu esp\u00edrito. E hoje em Rimini \u00e9 beatificada a jovem Sandra Sabattini, estudante de medicina, que faleceu aos 22 anos em um acidente de carro. Menina alegre, animada por uma grande caridade e pela ora\u00e7\u00e3o quotidiana, dedicou-se com entusiasmo ao servi\u00e7o dos mais fracos na esteira do carisma do Servo de Deus Dom Oreste Benzi. \u00c0s duas merecem um aplauso. Todos juntos!<\/p>\n<p>Hoje, Dia Mundial das Miss\u00f5es, olhamos para estes dois novos Beatos como testemunhas que anunciaram o Evangelho com a vida. E com gratid\u00e3o dirijo a minha sauda\u00e7\u00e3o aos numerosos mission\u00e1rios e mission\u00e1rias &#8211; sacerdotes, religiosos e religiosas e fi\u00e9is leigos &#8211; que na linha da frente despendem as suas energias ao servi\u00e7o da Igreja, pagando pessoalmente &#8211; por vezes a um pre\u00e7o elevado &#8211; pelo seu testemunho. E o fazem n\u00e3o para fazer proselitismo, mas para dar testemunho do Evangelho em suas vidas em terras que n\u00e3o conhecem Jesus. Muito obrigado aos mission\u00e1rios! Um grande aplauso a eles tamb\u00e9m, a todos! Sa\u00fado tamb\u00e9m os seminaristas do Col\u00e9gio Urbano.<\/p>\n<p><strong>Ajudemos os refugiados na L\u00edbia, ou\u00e7o seus gritos!<\/strong><\/p>\n<p>Na Pra\u00e7a S\u00e3o Pedro, ao final do Angelus, Francisco denunciou as condi\u00e7\u00f5es desumanas em que se encontram milhares de refugiados e requerentes de asilo no pa\u00eds do norte da \u00c1frica, a L\u00edbia. Fez apelo \u00e0 comunidade internacional para que d\u00ea prioridade ao resgate de vidas no mar e garanta rotas migrat\u00f3rias regulares e acesso aos procedimentos de asilo: \u201cPor um fim ao regresso dos migrantes a pa\u00edses inseguros\u201d<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News (texto de Jackson Erpen)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angelus<\/p>\n","protected":false},"author":3,"featured_media":234937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[403],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papa: pedir tudo a Jesus, pois Ele tudo pode - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa: pedir tudo a Jesus, pois Ele tudo pode - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Angelus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-24T11:06:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-24T12:54:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/10\/angelus_2410.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/10\/angelus_2410.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/10\/angelus_2410.jpg\",\"width\":1000,\"height\":562},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html\",\"name\":\"Papa: pedir tudo a Jesus, pois Ele tudo pode - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html#primaryimage\"},\"datePublished\":\"2021-10-24T11:06:51+00:00\",\"dateModified\":\"2021-10-24T12:54:43+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa: pedir tudo a Jesus, pois Ele tudo pode\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa: pedir tudo a Jesus, pois Ele tudo pode - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html","og_locale":"pt_BR","og_type":"article","og_title":"Papa: pedir tudo a Jesus, pois Ele tudo pode - Not\u00edcias - Franciscanos","og_description":"Angelus","og_url":"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2021-10-24T11:06:51+00:00","article_modified_time":"2021-10-24T12:54:43+00:00","og_image":[{"width":1000,"height":562,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/10\/angelus_2410.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/10\/angelus_2410.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/10\/angelus_2410.jpg","width":1000,"height":562},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html","name":"Papa: pedir tudo a Jesus, pois Ele tudo pode - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html#primaryimage"},"datePublished":"2021-10-24T11:06:51+00:00","dateModified":"2021-10-24T12:54:43+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-pedir-tudo-a-jesus-pois-ele-tudo-pode.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Papa: pedir tudo a Jesus, pois Ele tudo pode"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/234936"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=234936"}],"version-history":[{"count":3,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/234936\/revisions"}],"predecessor-version":[{"id":234941,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/234936\/revisions\/234941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/234937"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=234936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=234936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=234936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}