{"id":234375,"date":"2021-09-17T09:47:51","date_gmt":"2021-09-17T12:47:51","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=234375"},"modified":"2021-09-17T09:47:51","modified_gmt":"2021-09-17T12:47:51","slug":"papa-na-evangelizacao-sejam-apaixonados-e-criativos","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html","title":{"rendered":"Papa: &#8220;Na evangeliza\u00e7\u00e3o sejam apaixonados e criativos&#8221;"},"content":{"rendered":"<div id=\"attachment_234376\" style=\"width: 1010px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-234376\" loading=\"lazy\" class=\"wp-image-234376 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/09\/audiencia_170921.jpg\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/09\/audiencia_170921.jpg 1000w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/09\/audiencia_170921-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/09\/audiencia_170921-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/09\/audiencia_170921-150x84.jpg 150w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><p id=\"caption-attachment-234376\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <em>\u00a0 \u00a0 \u00a0 \u00a0Imagem: Vatican Media<\/em><\/p><\/div>\n<p>Na manh\u00e3 desta sexta-feira (17) o Papa Francisco recebeu na Sala Clementina os respons\u00e1veis pelas Comiss\u00f5es das Confer\u00eancias Episcopais da Europa sobre o novo Diret\u00f3rio para a Catequese publicado no ano passado. Francisco agradeceu a iniciativa liderada por Dom Rino Fisichella e esclareceu que, \u201ctamb\u00e9m ser\u00e1 estendida \u00e0s Confer\u00eancias Episcopais dos outros continentes, para que o caminho catequ\u00e9tico comum possa ser enriquecido pelas muitas experi\u00eancias locais\u201d. Ao recordar sua recente participa\u00e7\u00e3o na conclus\u00e3o do Congresso Eucar\u00edstico Internacional de Budapeste disse: \u201cN\u00e3o podemos esquecer que o lugar privilegiado da catequese \u00e9 justamente a celebra\u00e7\u00e3o eucar\u00edstica, onde irm\u00e3os e irm\u00e3s se re\u00fanem para descobrir cada vez mais os diferentes caminhos da presen\u00e7a de Deus nas suas vidas\u201d.<\/p>\n<p><strong>Cristo os chamou para serem disc\u00edpulos mission\u00e1rios<\/strong><br \/>\nFrancisco enfatiza as afirma\u00e7\u00f5es do novo Diret\u00f3rio ao explicar: \u201cA catequese n\u00e3o \u00e9 uma comunica\u00e7\u00e3o abstrata de conhecimentos te\u00f3ricos a serem memorizados como se fossem f\u00f3rmulas matem\u00e1ticas ou qu\u00edmicas. \u00c9 antes a experi\u00eancia mistag\u00f3gica dos que aprendem a encontrar seus irm\u00e3os e irm\u00e3s onde eles vivem e trabalham, porque eles mesmos encontraram Cristo, que os chamou a se tornarem disc\u00edpulos mission\u00e1rios\u201d.<\/p>\n<p>Destacando este ponto o Papa continuou: \u201cFoi por isso que institu\u00ed o minist\u00e9rio de catequista. Para que a comunidade crist\u00e3 sinta a necessidade de despertar esta voca\u00e7\u00e3o e de experimentar o servi\u00e7o de alguns homens e mulheres que, vivendo da celebra\u00e7\u00e3o da Eucaristia, possam sentir mais viva a paix\u00e3o de transmitir a f\u00e9 como evangelizadores\u201d<\/p>\n<p>\u201cO catequista e a catequista \u2013 ponderou Francisco &#8211; s\u00e3o testemunhas que se colocam a servi\u00e7o da comunidade crist\u00e3, para apoiar o aprofundamento da f\u00e9 no concreto da vida di\u00e1ria. S\u00e3o pessoas que incansavelmente proclamam o Evangelho da miseric\u00f3rdia; pessoas capazes de criar os la\u00e7os necess\u00e1rios de acolhida e de proximidade que permitem apreciar melhor a Palavra de Deus e celebrar o mist\u00e9rio eucar\u00edstico, oferecendo os frutos das boas obras\u201d.<\/p>\n<p><strong>Escutar o povo entender o povo que recebe o an\u00fancio<\/strong><br \/>\nAo falar sobre as novas perspectivas do caminho da evangeliza\u00e7\u00e3o, o Papa reiterou que \u201ca evangeliza\u00e7\u00e3o n\u00e3o \u00e9 uma mera repeti\u00e7\u00e3o do passado\u201d. Os grandes santos evangelizadores foram criativos, afirmou.<\/p>\n<p>\u201cIsso requer saber escutar o povo, os povos aos quais se est\u00e1 anunciando: escutar sua cultura, sua hist\u00f3ria; escutar n\u00e3o superficialmente, j\u00e1 pensando nas respostas pr\u00e9-prontas que temos em nossa mem\u00f3ria, n\u00e3o! Escutar realmente, e comparar essas culturas, essas l\u00ednguas, mesmo e sobretudo as n\u00e3o faladas, as n\u00e3o expressas, com a Palavra de Deus, com Jesus Cristo, o Evangelho vivo\u201d<\/p>\n<p>O Papa concluiu questionando novamente, como o fez recentemente na Eslov\u00e1quia: \u201cEsta n\u00e3o ser\u00e1 a tarefa mais urgente da Igreja entre os povos da Europa? A grande tradi\u00e7\u00e3o crist\u00e3 do continente n\u00e3o deve se tornar uma rel\u00edquia hist\u00f3rica, sen\u00e3o n\u00e3o \u00e9 mais &#8220;tradi\u00e7\u00e3o&#8221;! A tradi\u00e7\u00e3o ou est\u00e1 viva ou n\u00e3o existe. Portanto, apaixonados e criativos impulsionados pelos Esp\u00edrito Santo\u201d.<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News (texto de Jane Nogara)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diret\u00f3rio para a Catequese<\/p>\n","protected":false},"author":3,"featured_media":234376,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[1904],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papa: &quot;Na evangeliza\u00e7\u00e3o sejam apaixonados e criativos&quot; - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa: &quot;Na evangeliza\u00e7\u00e3o sejam apaixonados e criativos&quot; - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Diret\u00f3rio para a Catequese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-17T12:47:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/09\/audiencia_170921.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/09\/audiencia_170921.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/09\/audiencia_170921.jpg\",\"width\":1000,\"height\":563},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html\",\"name\":\"Papa: \\\"Na evangeliza\u00e7\u00e3o sejam apaixonados e criativos\\\" - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html#primaryimage\"},\"datePublished\":\"2021-09-17T12:47:51+00:00\",\"dateModified\":\"2021-09-17T12:47:51+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa: &#8220;Na evangeliza\u00e7\u00e3o sejam apaixonados e criativos&#8221;\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa: \"Na evangeliza\u00e7\u00e3o sejam apaixonados e criativos\" - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html","og_locale":"pt_BR","og_type":"article","og_title":"Papa: \"Na evangeliza\u00e7\u00e3o sejam apaixonados e criativos\" - Not\u00edcias - Franciscanos","og_description":"Diret\u00f3rio para a Catequese","og_url":"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2021-09-17T12:47:51+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/09\/audiencia_170921.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/09\/audiencia_170921.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/09\/audiencia_170921.jpg","width":1000,"height":563},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html","name":"Papa: \"Na evangeliza\u00e7\u00e3o sejam apaixonados e criativos\" - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html#primaryimage"},"datePublished":"2021-09-17T12:47:51+00:00","dateModified":"2021-09-17T12:47:51+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-na-evangelizacao-sejam-apaixonados-e-criativos.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Papa: &#8220;Na evangeliza\u00e7\u00e3o sejam apaixonados e criativos&#8221;"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/234375"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=234375"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/234375\/revisions"}],"predecessor-version":[{"id":234377,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/234375\/revisions\/234377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/234376"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=234375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=234375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=234375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}