{"id":231308,"date":"2021-03-29T17:43:53","date_gmt":"2021-03-29T20:43:53","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=231308"},"modified":"2022-12-31T12:54:28","modified_gmt":"2022-12-31T15:54:28","slug":"francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html","title":{"rendered":"Francisco: os sacerdotes devem ter um olhar de ternura, reconcilia\u00e7\u00e3o e fraternidade"},"content":{"rendered":"<div id=\"attachment_231309\" style=\"width: 1290px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-231309\" loading=\"lazy\" class=\"wp-image-231309 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29-1024x576.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><p id=\"caption-attachment-231309\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<em> \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Imagem: Vatican Media<\/em><\/p><\/div>\n<p>O Papa Francisco recebeu em audi\u00eancia nesta segunda-feira (29\/03), na Sala Clementina, no Vaticano, os membros da Comunidade do Pontif\u00edcio Col\u00e9gio Mexicano.<\/p>\n<p>O Pont\u00edfice iniciou o seu discurso, recordando o seu encontro com o povo mexicano durante sua viagem apost\u00f3lica ao M\u00e9xico, em 2016, &#8220;que de certa forma se renova a cada ano com a celebra\u00e7\u00e3o da Solenidade de Nossa Senhora de Guadalupe aqui na Bas\u00edlica Vaticana&#8221;, disse ele.<\/p>\n<p>A seguir, Francisco ressaltou que os problemas atuais exigem dos sacerdotes a necessidade de se configurarem ao Senhor e ao olhar de amor com que Ele nos contempla. &#8220;Ao conformar o nosso olhar com o seu, o nosso se transforma em olhar de ternura, reconcilia\u00e7\u00e3o e fraternidade&#8221;, disse o Papa, destacando esses tr\u00eas pontos.<\/p>\n<p><strong>Aut\u00eantica compaix\u00e3o<\/strong><br \/>\nO primeiro, &#8220;a necessidade de ter um olhar de ternura com que nosso Deus Pai v\u00ea os problemas que afligem a sociedade: viol\u00eancia, desigualdades sociais e econ\u00f4micas, polariza\u00e7\u00e3o, corrup\u00e7\u00e3o e falta de esperan\u00e7a, especialmente entre os jovens&#8221;. &#8220;A configura\u00e7\u00e3o cada vez mais profunda com o Bom Pastor desperta em cada sacerdote uma aut\u00eantica compaix\u00e3o, tanto pelas ovelhas a ele confiadas quanto por aquelas que se extraviaram. Somente deixando-nos moldar por Ele se intensifica a nossa caridade pastoral, onde ningu\u00e9m \u00e9 exclu\u00eddo de nossa solicitude e ora\u00e7\u00e3o&#8221;, sublinhou Francisco.<\/p>\n<p><strong>Comprometer-se com o restabelecimento da justi\u00e7a<\/strong><br \/>\nEm segundo lugar, o Papa destacou que &#8220;\u00e9 preciso ter um olhar de reconcilia\u00e7\u00e3o&#8221;.<\/p>\n<p>As dificuldades sociais que estamos atravessando, as enormes diferen\u00e7as e a corrup\u00e7\u00e3o exigem de n\u00f3s um olhar que nos torne capazes de tecer juntos os v\u00e1rios fios que se fragilizaram ou foram cortados na tilma multicolorida de culturas que comp\u00f5em o tecido social e religioso da na\u00e7\u00e3o, prestando aten\u00e7\u00e3o, sobretudo, \u00e0queles que foram descartados por causa de suas ra\u00edzes ind\u00edgenas ou de sua particular religiosidade popular. N\u00f3s pastores somos chamados a ajudar a reconstruir rela\u00e7\u00f5es respeitosas e construtivas entre pessoas, grupos humanos e culturas dentro da sociedade, propondo a todos &#8220;deixar-se reconciliar por Deus&#8221; e comprometer-se com o restabelecimento da justi\u00e7a.<\/p>\n<p><strong>Um olhar que facilite a comunh\u00e3o<\/strong><br \/>\nPor fim, &#8220;o nosso tempo atual nos impele a ter uma vis\u00e3o de fraternidade. Os desafios que enfrentamos s\u00e3o de tal magnitude que abrangem o tecido social e a realidade globalizada interconectada pelas redes sociais e os meios de comunica\u00e7\u00e3o. Por isso, junto com Cristo, Servo e Pastor, devemos ser capazes de ter uma vis\u00e3o de conjunto e unidade, que nos impulsiona a criar fraternidade, que nos permite evidenciar os pontos de conex\u00e3o e intera\u00e7\u00e3o no cora\u00e7\u00e3o das culturas e na comunidade eclesial&#8221;.<\/p>\n<p>Um olhar que facilite a comunh\u00e3o e a participa\u00e7\u00e3o fraterna, que anime e oriente os fi\u00e9is a respeitarem a nossa Casa comum e serem construtores de um mundo novo, em colabora\u00e7\u00e3o com todos os homens e mulheres de boa vontade. Para ser assim, precisamos da luz da f\u00e9 e da sabedoria de quem sabe \u201ctirar as sand\u00e1lias\u201d para contemplar o mist\u00e9rio de Deus e, desse ponto de vista, ler os sinais dos tempos.<\/p>\n<p><strong>N\u00e3o subestimar as tenta\u00e7\u00f5es mundanas<\/strong><br \/>\nSegundo o Papa, &#8220;\u00e9 fundamental harmonizar na forma\u00e7\u00e3o permanente as dimens\u00f5es acad\u00eamica, espiritual, humana e pastoral. Ao mesmo tempo, precisamos nos conscientizar de nossas defici\u00eancias pessoais e comunit\u00e1rias, bem como das neglig\u00eancias e faltas que temos que corrigir em nossa vida. Somos chamados a n\u00e3o subestimar as tenta\u00e7\u00f5es mundanas que podem levar a um conhecimento pessoal insuficiente, a atitudes autorreferenciais, ao consumismo e \u00e0s v\u00e1rias formas de evas\u00e3o de nossas responsabilidades&#8221;.<\/p>\n<p>O Papa concluiu, pedindo a Nossa Senhora de Guadalupe e a S\u00e3o Jos\u00e9 para que cuidem de todo o Clero do M\u00e9xico e da comunidade do Pontif\u00edcio Col\u00e9gio Mexicano.<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News (texto de Mariangela Jaguraba)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Papa recebe o Pontif\u00edcio Col\u00e9gio Mexicano de Roma<\/p>\n","protected":false},"author":3,"featured_media":231310,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[487],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Francisco: os sacerdotes devem ter um olhar de ternura, reconcilia\u00e7\u00e3o e fraternidade - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Francisco: os sacerdotes devem ter um olhar de ternura, reconcilia\u00e7\u00e3o e fraternidade - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Papa recebe o Pontif\u00edcio Col\u00e9gio Mexicano de Roma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-29T20:43:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-31T15:54:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29d.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29d.jpg\",\"width\":800,\"height\":560},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html\",\"name\":\"Francisco: os sacerdotes devem ter um olhar de ternura, reconcilia\u00e7\u00e3o e fraternidade - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html#primaryimage\"},\"datePublished\":\"2021-03-29T20:43:53+00:00\",\"dateModified\":\"2022-12-31T15:54:28+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Francisco: os sacerdotes devem ter um olhar de ternura, reconcilia\u00e7\u00e3o e fraternidade\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Francisco: os sacerdotes devem ter um olhar de ternura, reconcilia\u00e7\u00e3o e fraternidade - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html","og_locale":"pt_BR","og_type":"article","og_title":"Francisco: os sacerdotes devem ter um olhar de ternura, reconcilia\u00e7\u00e3o e fraternidade - Not\u00edcias - Franciscanos","og_description":"Papa recebe o Pontif\u00edcio Col\u00e9gio Mexicano de Roma","og_url":"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2021-03-29T20:43:53+00:00","article_modified_time":"2022-12-31T15:54:28+00:00","og_image":[{"width":800,"height":560,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29d.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29d.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/papa_29d.jpg","width":800,"height":560},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html","name":"Francisco: os sacerdotes devem ter um olhar de ternura, reconcilia\u00e7\u00e3o e fraternidade - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html#primaryimage"},"datePublished":"2021-03-29T20:43:53+00:00","dateModified":"2022-12-31T15:54:28+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/francisco-os-sacerdotes-devem-ter-um-olhar-de-ternura-reconciliacao-e-fraternidade.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Francisco: os sacerdotes devem ter um olhar de ternura, reconcilia\u00e7\u00e3o e fraternidade"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/231308"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=231308"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/231308\/revisions"}],"predecessor-version":[{"id":231311,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/231308\/revisions\/231311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/231310"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=231308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=231308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=231308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}