{"id":231139,"date":"2021-03-14T08:26:30","date_gmt":"2021-03-14T11:26:30","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=231139"},"modified":"2021-03-14T08:26:30","modified_gmt":"2021-03-14T11:26:30","slug":"papa-a-pratica-do-bem-sempre-vem-a-luz","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html","title":{"rendered":"Papa: a pr\u00e1tica do bem sempre vem \u00e0 luz"},"content":{"rendered":"<div id=\"attachment_231140\" style=\"width: 1290px\" class=\"wp-caption alignright\"><img aria-describedby=\"caption-attachment-231140\" loading=\"lazy\" class=\"wp-image-231140 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14-1024x576.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><p id=\"caption-attachment-231140\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<em> Imagem: Vatican Media<\/em><\/p><\/div>\n<p>Na ora\u00e7\u00e3o mariana do Angelus deste IV Domingo de Quaresma (14\/03) o Papa Francisco refletiu sobre o Evangelho do dia que nos diz que Deus amou tanto o mundo que entregou o Seu \u00fanico Filho. Por essa raz\u00e3o \u00e9 o domingo \u201cLaetare\u201d &#8220;, ou seja, &#8220;Alegrai-vos&#8221;. O dom de Deus \u00e9 para que \u201ctodo o que nele cr\u00ea n\u00e3o pere\u00e7a, mas tenha a vida eterna&#8221;. O Papa explicou que \u201cesta alegre mensagem est\u00e1 no cora\u00e7\u00e3o da f\u00e9 crist\u00e3: o amor de Deus encontrou seu \u00e1pice ao doar o Filho \u00e0 humanidade fraca e pecadora\u201d. Francisco continuou:<\/p>\n<p>\u201cJesus coloca em crise esta expectativa ao se apresentar sob tr\u00eas aspectos: o do Filho do homem exaltado na cruz; o do Filho de Deus enviado ao mundo para a salva\u00e7\u00e3o; e o da luz que distingue os que seguem a verdade dos que seguem a mentira\u201d<\/p>\n<p><strong>Filho do homem exaltado na cruz<\/strong><br \/>\n\u201cJesus se apresenta antes de tudo como o Filho do Homem\u201d explica o Papa e que o texto de Jo\u00e3o (3, 14-21) \u201calude \u00e0 hist\u00f3ria da serpente de bronze que, pela vontade de Deus, foi criada por Mois\u00e9s no deserto quando o povo foi atacado por serpentes venenosas; quem foi mordido e olhou para a serpente de bronze foi curado. Da mesma forma, Jesus foi levantado na cruz e os que acreditam n\u2019Ele foram curados do pecado e vivem.<\/p>\n<p><strong>Filho de Deus enviado ao mundo<\/strong><br \/>\n\u201cDeus Pai ama os homens ao ponto de &#8220;dar&#8221; o seu Filho: ele o deu na Encarna\u00e7\u00e3o e o deu ao entreg\u00e1-lo \u00e0 morte. O objetivo do dom de Deus \u00e9 a vida eterna dos homens: de fato, Deus envia seu Filho ao mundo n\u00e3o para conden\u00e1-lo, mas para que o mundo possa ser salvo por meio de Jesus. A miss\u00e3o de Jesus \u00e9 uma miss\u00e3o de salva\u00e7\u00e3o, para todos\u201d.<\/p>\n<p><strong>Jesus se d\u00e1 o nome de \u201cluz\u201d<\/strong><br \/>\n\u201cA vinda de Jesus ao mundo provoca uma escolha: quem escolhe as trevas enfrentar\u00e1 um julgamento de condena\u00e7\u00e3o, quem escolhe a luz ter\u00e1 um julgamento de salva\u00e7\u00e3o\u201d afirma o Papa ao explicar este terceiro aspecto.<\/p>\n<p>\u201cO julgamento \u00e9 a consequ\u00eancia da livre escolha de cada um: quem pratica o mal procura as trevas, quem faz a verdade, ou seja, pratica o bem, vem \u00e0 luz\u201d<\/p>\n<p>Nesta Quaresma, afirmou o Santo Padre, somos chamados a fazer isso, ou seja, \u201caproximarmo-nos da luz para fazer boas obras\u201d. \u201cAcolher a luz em nossa consci\u00eancia, particularmente no Sacramento da Reconcilia\u00e7\u00e3o, para abrir os nossos cora\u00e7\u00f5es ao infinito amor de Deus, \u00e0 sua miseric\u00f3rdia cheia de ternura e de bondade. Desta forma, encontraremos a verdadeira alegria e poderemos nos alegrar com o perd\u00e3o de Deus que regenera e d\u00e1 vida\u201d.<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News (texto de Jane Nogara)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angelus<\/p>\n","protected":false},"author":3,"featured_media":231141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[403],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papa: a pr\u00e1tica do bem sempre vem \u00e0 luz - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa: a pr\u00e1tica do bem sempre vem \u00e0 luz - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Angelus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-14T11:26:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14d.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14d.jpg\",\"width\":800,\"height\":560},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html\",\"name\":\"Papa: a pr\u00e1tica do bem sempre vem \u00e0 luz - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html#primaryimage\"},\"datePublished\":\"2021-03-14T11:26:30+00:00\",\"dateModified\":\"2021-03-14T11:26:30+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa: a pr\u00e1tica do bem sempre vem \u00e0 luz\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa: a pr\u00e1tica do bem sempre vem \u00e0 luz - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html","og_locale":"pt_BR","og_type":"article","og_title":"Papa: a pr\u00e1tica do bem sempre vem \u00e0 luz - Not\u00edcias - Franciscanos","og_description":"Angelus","og_url":"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2021-03-14T11:26:30+00:00","og_image":[{"width":800,"height":560,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14d.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14d.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/03\/angelus_14d.jpg","width":800,"height":560},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html","name":"Papa: a pr\u00e1tica do bem sempre vem \u00e0 luz - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html#primaryimage"},"datePublished":"2021-03-14T11:26:30+00:00","dateModified":"2021-03-14T11:26:30+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-a-pratica-do-bem-sempre-vem-a-luz.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Papa: a pr\u00e1tica do bem sempre vem \u00e0 luz"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/231139"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=231139"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/231139\/revisions"}],"predecessor-version":[{"id":231142,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/231139\/revisions\/231142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/231141"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=231139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=231139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=231139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}