{"id":230564,"date":"2021-01-27T12:10:54","date_gmt":"2021-01-27T15:10:54","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=230564"},"modified":"2021-01-27T13:07:01","modified_gmt":"2021-01-27T16:07:01","slug":"frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html","title":{"rendered":"Frei C\u00e9sar aos postulantes: &#8220;N\u00e3o deixem a gra\u00e7a de Deus passar em v\u00e3o na vida de voc\u00eas&#8221;!"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone wp-image-230565 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01-1.jpg\" alt=\"\" width=\"1280\" height=\"762\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01-1.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01-1-450x268.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01-1-1024x610.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01-1-768x457.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01-1-150x89.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><strong>Guaratinguet\u00e1 (SP)<\/strong> &#8211; \u201cO Postulantado \u00e9 justamente esse tempo de experimentar essa vida em fraternidade, abra\u00e7ando os valores da vida religiosa franciscana. Ent\u00e3o, que esse tempo nesta casa, dado a voc\u00eas como um tempo muito precioso, seja abra\u00e7ado com alegria, com ousadia e vivido com muita intensidade. N\u00e3o deixem a gra\u00e7a de Deus passar em v\u00e3o na vida de voc\u00eas\u201d! Foi com esta motiva\u00e7\u00e3o que o Ministro Provincial, Frei C\u00e9sar K\u00fclkamp, explicou a quinze jovens da Prov\u00edncia da Imaculada Concei\u00e7\u00e3o do Brasil o significado da nova etapa formativa que teve in\u00edcio nesta quarta-feira, 27 de janeiro, no Semin\u00e1rio Frei Galv\u00e3o de Guaratinguet\u00e1 (SP). Depois do per\u00edodo de anima\u00e7\u00e3o vocacional e do discernimento na etapa do Aspirantado, como postulantes na Ordem dos Frades Menores (OFM), esses jovens viver\u00e3o, neste ano, uma rotina de ora\u00e7\u00e3o, trabalho, estudo, vida em fraternidade, tudo em vista se aprofundarem no conhecimento de todos os elementos que s\u00e3o pr\u00f3prios da Vida Franciscana e do Noviciado que vir\u00e1 em seguida. Em Angola, esta etapa do Postulantado ter\u00e1 in\u00edcio no pr\u00f3ximo dia 11 de fevereiro.<\/p>\n<p>O rito de admiss\u00e3o se deu dentro da Ora\u00e7\u00e3o da Manh\u00e3 (<em>Laudes<\/em>), \u00e0s 7h30, na presen\u00e7a da Fraternidade do Semin\u00e1rio e de frades da Prov\u00edncia, numa celebra\u00e7\u00e3o fraterna, simples e muito simb\u00f3lica. Foram acolhidos pelo Ministro Provincial, pelo mestre Frei Walter de Carvalho J\u00fanior e pela Fraternidade formadora, os postulantes: Almiro Luna Xavier, \u00a0Erick Eduardo dos Santos, Felipe Miguel Fiamoncini, Felipe Zaros, Filipo Carpi Gir\u00e3o, Francisco Barbosa Mouzinho Junior, Higor Augusto dos Santos, Lucas Alfredo Teston, Luiz Felipe Gouveia Palandi, Marcos Antonio de Morais Junior, Marcos Paulo Pacheco Barbosa, \u00a0Paulo Vitor da Silva, Samuel Cavalcanti do Amaral, Vilmar Jos\u00e9 Bittencourt J\u00fanior e Yure de Oliveira Telles Souza.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-230567 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_09.jpg\" alt=\"\" width=\"1280\" height=\"681\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_09.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_09-450x239.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_09-1024x545.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_09-768x409.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_09-150x80.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>&#8220;Queridos postulantes! Agora j\u00e1 podemos cham\u00e1-los de postulantes depois de acolh\u00ea-los em nome de toda a Prov\u00edncia para formarem fraternidade conosco, para experimentarem de uma forma mais intensa a nossa vida, seguindo os passos de Jesus Cristo, do modo como conseguiu S\u00e3o Francisco de Assis. Assim como voc\u00eas acabaram de pedir e acabaram de receber a acolhida desta Prov\u00edncia da Imaculada Concei\u00e7\u00e3o&#8221;, saudou o Ministro Provincial.<\/p>\n<p>Frei C\u00e9sar fez sua reflex\u00e3o tendo como base o texto do Evangelho de S\u00e3o Mateus (19,16). &#8220;N\u00f3s ouvimos como inspira\u00e7\u00e3o e como orienta\u00e7\u00e3o para a nossa vida a Palavra de Deus, a palavra do Evangelho, que hoje nos traz a hist\u00f3ria de um jovem, um jovem como voc\u00eas, que tamb\u00e9m um dia quis dar um passo a mais na sua vida e teve um encontro com o pr\u00f3prio Cristo. \u00c9 chamado o jovem rico do Evangelho de Mateus. E esse jovem foi considerado bom pelo pr\u00f3prio Cristo que o convida para ser seu disc\u00edpulo, seguir seus passos, e ele justamente questiona o que poderia fazer a mais para viver na Lei de Deus&#8221;, lembrou Frei C\u00e9sar. Segundo o texto do Evangelho, o jovem j\u00e1 seguia os mandamentos, as leis mas era preciso dar um passo decisivo para ser verdadeiramente crist\u00e3o, disc\u00edpulo e seguidor de Jesus Cristo, que era desapropriar-se, deixar os seus bens, d\u00e1-los aos pobres e seguir os passos de Jesus. &#8220;E ele, diante disso, n\u00e3o teve outra atitude sen\u00e3o a tristeza, o fechamento, porque nos diz o texto do Evangelho que ele tinha muitos bens. E mesmo diante do convite do pr\u00f3prio Cristo, ele n\u00e3o foi capaz de dar esse passo ousado, generoso, corajoso. Esse texto do Evangelho foi escrito no per\u00edodo em que os judeus convertidos \u00e0 f\u00e9 crist\u00e3 tamb\u00e9m viviam esse dilema do apego \u00e0s antigas leis; abra\u00e7avam o cristianismo, eram batizados, preparados, mas n\u00e3o conseguiam se libertar das leis, do legalismo de toda a tradi\u00e7\u00e3o judaica. Ent\u00e3o, na verdade, o Evangelho nos indica que essas pessoas eram religiosas, cumpridoras da lei, mas ainda n\u00e3o conseguiam ser crist\u00e3s. E talvez esse seja tamb\u00e9m o desafio para o nosso tempo. O pr\u00f3prio Papa Francisco j\u00e1 nos disse que existe muita religi\u00e3o, muita religiosidade, mas falta cristianismo, abra\u00e7ado como verdade \u00e0 proposta do pr\u00f3prio Cristo&#8221;, explicou o Ministro Provincial.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-230568 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_02.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_02.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_02-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_02-1024x576.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_02-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_02-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Frei C\u00e9sar, ent\u00e3o, lembrou que depois da hist\u00f3ria desse jovem rico, um outro jovem na cidade de Assis, Francisco, tamb\u00e9m recebeu esse convite de seguir os passos do Cristo. Segundo o Ministro Provincial, esse processo de convers\u00e3o do jovem de Assis, assim como desses jovens postulantes, de abra\u00e7ar mais plenamente a vida crist\u00e3 e assimilar esse esp\u00edrito de vida franciscana, n\u00e3o \u00e9 outra coisa sen\u00e3o o pr\u00f3prio Evangelho, a pessoa de Jesus Cristo. &#8220;Mas Francisco teve outros sonhos na sua vida: sonhos de grandeza, de fama, de riqueza, de prest\u00edgio. E por isso ele vai buscar esses sonhos at\u00e9 que ele tem um outro grande sonho na caminhada que fazia para ir \u00e0 guerra. O caminho daquela \u00e9poca para a fama, para alcan\u00e7ar t\u00edtulos de nobreza era o da guerra. E nesse caminho, ele tem um outro sonho que o faz repensar seus pr\u00f3prios sonhos. E foi na cidadezinha de Spoleto, como nos conta a legenda, que em sonho ele \u00e9 questionado: &#8216;Quem pode dar uma recompensa maior a voc\u00ea? Um grande Senhor ou um escravo?&#8217; E ele logo responde que \u00e9 o Senhor. Ent\u00e3o, essa mesma voz lhe pergunta: &#8216;Por que voc\u00ea est\u00e1 perseguindo o escravo, aquele que n\u00e3o pode oferecer essas recompensas?&#8217;\u00a0 Essa legenda quer nos mostrar esse processo de revis\u00e3o de valores de todas as coisas. E Francisco, nesse processo, vai chegar a esta compreens\u00e3o de que buscar o Cristo vale mais do que todos os outros sonhos que ele tinha na vida. Mas esse buscar o Cristo \u00e9 um processo tamb\u00e9m de assumir esses valores para confrontar tudo aquilo que ele tinha, ou aqueles bens que aquele jovem rico tinha&#8221;, situou Frei C\u00e9sar.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-230574 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_11.jpg\" alt=\"\" width=\"1280\" height=\"909\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_11.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_11-450x320.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_11-1024x727.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_11-768x545.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_11-150x107.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Francisco, ent\u00e3o, diante do sonho de grandeza que tinha, envolve-se com o valor da minoridade, da pobreza. Diante de sonhos individualistas, de fama, de prest\u00edgio, vai destacar o sonho de fraternidade e assim cada uma das dimens\u00f5es franciscanas v\u00eam justamente para colaborar no processo de convers\u00e3o de S\u00e3o Francisco de Assis. Que ele at\u00e9 mesmo nos diz que \u00e9 o seu processo. E n\u00f3s precisamos descobrir o nosso&#8221;, exortou.<\/p>\n<p>Frei C\u00e9sar fez alguns questionamentos diante das dificuldades para abra\u00e7ar o caminho de Jesus Cristo. &#8220;Diante desses bens, quais as dimens\u00f5es, os valores crist\u00e3os que n\u00f3s precisamos abra\u00e7ar com mais for\u00e7a?\u00a0 Francisco vai \u00e0 nossa frente, j\u00e1 \u00e9 uma inspira\u00e7\u00e3o e nos indica o pr\u00f3prio caminho. Mas n\u00f3s mesmos precisamos nos confrontarmo-nos: quais s\u00e3o os bens? Talvez, um de voc\u00eas, um de n\u00f3s, tenha muitas riquezas para deixar, mas a gente pode ter outros bens. Podem ser as nossas pr\u00f3prias ideias, convic\u00e7\u00f5es, as nossas origens, como a gente j\u00e1 conversava ontem \u00e0 noite; podem ser legalismos, formas de viver a pr\u00f3pria religiosidade. Tem tantas outras coisas que n\u00f3s precisamos deixar, para ent\u00e3o, sim, abra\u00e7ar o caminho de Jesus Cristo; para ent\u00e3o, sim, viver com intensidade esse caminho, que \u00e9 de expropria\u00e7\u00e3o de n\u00f3s mesmos, dos nossos bens. Mas \u00e9 um caminho que leva tamb\u00e9m \u00e0 partilha nas palavras do pr\u00f3prio Evangelho. Partilhar com os pobres o nosso pouco que seja e seguir os passos do Cristo de uma forma radical. Seguir no Evangelho significa ir at\u00e9 o caminho da cruz, onde n\u00f3s temos a express\u00e3o m\u00e1xima do amor de Jesus Cristo, a sua entrega total&#8221;, orientou.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-230570 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_04.jpg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_04.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_04-450x338.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_04-1024x768.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_04-768x576.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_04-150x113.jpg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_04-600x450.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>&#8220;Ent\u00e3o, que n\u00f3s possamos vencer esses contravalores que fazem parte da nossa pr\u00f3pria constitui\u00e7\u00e3o e abra\u00e7ar essa proposta livre, verdadeira, generosa de Jesus Cristo, como j\u00e1 o fez S\u00e3o Francisco, mas que n\u00f3s precisamos tamb\u00e9m fazer, tamb\u00e9m descobrir. N\u00f3s temos como modelo a pr\u00f3pria M\u00e3e de Deus, que mesmo sem conhecer muitas coisas, recebe tamb\u00e9m um convite da parte de Deus para deixar projetos, outros caminhos, e tornar-se a m\u00e3e do Senhor. Ela \u00e9 Padroeira da nossa Ordem, da nossa Prov\u00edncia, e que ela seja tamb\u00e9m inspira\u00e7\u00e3o de vida crist\u00e3 para cada um de voc\u00eas e intercessora nos momentos mais dif\u00edceis neste processo de convers\u00e3o. E contem, ao mesmo tempo, com essa dimens\u00e3o franciscana que \u00e9 a vida de fraternidade entre voc\u00eas mesmos, com a Fraternidade que voc\u00eas receberam e com a Fraternidade da nossa Prov\u00edncia&#8221;, completou Frei C\u00e9sar.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-230571 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_07.jpg\" alt=\"\" width=\"1280\" height=\"843\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_07.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_07-450x296.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_07-1024x674.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_07-768x506.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_07-150x99.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>No rito de admiss\u00e3o, os quinze foram chamados e apresentados ao Provincial pelo guardi\u00e3o e Definidor Frei Jo\u00e3o Francisco da Silva. Interrogados pelo Ministro Provincial, eles fizeram o pedido para ingressarem neste tempo da forma\u00e7\u00e3o e ouviram esta resposta: \u201cCom as palavras de Jesus vos recebo, dizendo \u2018Vinde e vede\u2019! De bom grado vos acolhemos nesta casa de forma\u00e7\u00e3o para o tempo do Postulantado. Aqui podereis discernir com clareza a vossa voca\u00e7\u00e3o e fazer a experi\u00eancia da nossa vida de fraternidade e de minoridade a servi\u00e7o da Igreja\u201d. Depois, ajoelhados, rezaram a Ora\u00e7\u00e3o de S\u00e3o Francisco diante do Crucifixo de S\u00e3o Dami\u00e3o e receberam o Tau de S\u00e3o Francisco. \u00a0Passando esta etapa, no Noviciado, esses jovens ir\u00e3o receber o h\u00e1bito franciscano, no formato de Tau tamb\u00e9m.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-230572 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_10.jpg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_10.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_10-450x338.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_10-1024x768.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_10-768x576.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_10-150x113.jpg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_10-600x450.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>No final, Frei C\u00e9sar falou da responsabilidade no acompanhamento de cada um dos postulantes nesta Fraternidade do Postulantado. &#8220;Voc\u00eas foram acolhidos pela Fraternidade Provincial, mais amplamente pela Ordem dos Frades Menores, mas queremos confiar esse acompanhamento de cada um de voc\u00eas especialmente ao mestre Frei Walter J\u00fanior. Voc\u00eas t\u00eam aqui nesta casa o suporte e a for\u00e7a neste trabalho de Frei Jo\u00e3o Francisco da Silva, nosso guardi\u00e3o; Frei Claudino Dal&#8217;Mago, nosso vice-mestre; Frei Walter Hugo, professor e nossa refer\u00eancia. \u00c9 uma Fraternidade bastante privilegiada na nossa Prov\u00edncia. Muito bem composta e voc\u00eas t\u00eam muitas refer\u00eancias com quem contar: Frei Virg\u00edlio Pereira de Souza, Frei Alexandre Rohling, Frei Alisson Zanetti, Frei Diego Melo e Frei Roberto Ishara, que est\u00e3o em miss\u00e3o no Santu\u00e1rio Frei Galv\u00e3o, mas partilham a vida nesta casa. E neste ano, Frei Jo\u00e3o Maria dos Santos acabou de chegar aqui, um homem que j\u00e1 foi mestre de novi\u00e7os. N\u00f3s recebemos tamb\u00e9m Frei Ruan Felipe Sguissardi fazendo seu Ano Mission\u00e1rio. Quero, em nome de todos os Frades da Prov\u00edncia, confiar a esta Fraternidade a forma\u00e7\u00e3o desses jovens. Que Deus aben\u00e7oe esta Fraternidade no testemunho generoso e na forma\u00e7\u00e3o\u201d.<\/p>\n<hr \/>\n<p><em>Moacir Beggo e Nicolas Nathan (fotos)<\/em><\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-230573 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_08.jpg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_08.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_08-450x338.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_08-1024x768.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_08-768x576.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_08-150x113.jpg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_08-600x450.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p style=\"text-align: center;\"><strong>VEJA MAIS FOTOS DA CELEBRA\u00c7\u00c3O<\/strong><\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-230564 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/01-3.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/01-3-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/01-3-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/01-3-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/02-2.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/02-2-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/02-2-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/02-2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/03-2.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/03-2-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/03-2-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/03-2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/04-2.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/04-2-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/04-2-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/04-2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/05-2.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/05-2-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/05-2-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/05-2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/06-3.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/06-3-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/06-3-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/06-3-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/07-1.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/07-1-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/07-1-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/07-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/09-1.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/09-1-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/09-1-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/09-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/10-1.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/10-1-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/10-1-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/10-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/11.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/11-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/11-300x300.jpg 300w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/11-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Forma\u00e7\u00e3o e Estudos<\/p>\n","protected":false},"author":3,"featured_media":230566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[155],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Frei C\u00e9sar aos postulantes: &quot;N\u00e3o deixem a gra\u00e7a de Deus passar em v\u00e3o na vida de voc\u00eas&quot;! - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frei C\u00e9sar aos postulantes: &quot;N\u00e3o deixem a gra\u00e7a de Deus passar em v\u00e3o na vida de voc\u00eas&quot;! - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Forma\u00e7\u00e3o e Estudos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-27T15:10:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-27T16:07:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01d-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01d-1.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01d-1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html\",\"name\":\"Frei C\u00e9sar aos postulantes: \\\"N\u00e3o deixem a gra\u00e7a de Deus passar em v\u00e3o na vida de voc\u00eas\\\"! - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html#primaryimage\"},\"datePublished\":\"2021-01-27T15:10:54+00:00\",\"dateModified\":\"2021-01-27T16:07:01+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frei C\u00e9sar aos postulantes: &#8220;N\u00e3o deixem a gra\u00e7a de Deus passar em v\u00e3o na vida de voc\u00eas&#8221;!\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frei C\u00e9sar aos postulantes: \"N\u00e3o deixem a gra\u00e7a de Deus passar em v\u00e3o na vida de voc\u00eas\"! - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html","og_locale":"pt_BR","og_type":"article","og_title":"Frei C\u00e9sar aos postulantes: \"N\u00e3o deixem a gra\u00e7a de Deus passar em v\u00e3o na vida de voc\u00eas\"! - Not\u00edcias - Franciscanos","og_description":"Forma\u00e7\u00e3o e Estudos","og_url":"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2021-01-27T15:10:54+00:00","article_modified_time":"2021-01-27T16:07:01+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01d-1.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01d-1.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/guara_01d-1.jpg","width":800,"height":600},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html","name":"Frei C\u00e9sar aos postulantes: \"N\u00e3o deixem a gra\u00e7a de Deus passar em v\u00e3o na vida de voc\u00eas\"! - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html#primaryimage"},"datePublished":"2021-01-27T15:10:54+00:00","dateModified":"2021-01-27T16:07:01+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/frei-cesar-aos-postulantes-nao-deixem-a-graca-de-deus-passar-em-vao-na-vida-de-voces.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Frei C\u00e9sar aos postulantes: &#8220;N\u00e3o deixem a gra\u00e7a de Deus passar em v\u00e3o na vida de voc\u00eas&#8221;!"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/230564"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=230564"}],"version-history":[{"count":2,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/230564\/revisions"}],"predecessor-version":[{"id":230587,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/230564\/revisions\/230587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/230566"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=230564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=230564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=230564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}