{"id":230237,"date":"2021-01-04T07:18:39","date_gmt":"2021-01-04T10:18:39","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=230237"},"modified":"2021-01-04T10:39:40","modified_gmt":"2021-01-04T13:39:40","slug":"epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html","title":{"rendered":"Epifania: Frei Medella pede para &#8220;ser  luz na vida do outro&#8221; nesse tempo de pandemia"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone wp-image-230238 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04-1024x576.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><strong>Petr\u00f3polis (RJ) \u2013<\/strong> Neste domingo (3\/01), dia em que a Igreja do Brasil celebra a Solenidade da Epifania do Senhor, \u00a0a comunidade do Convento e da Par\u00f3quia do Sagrado reuniram-se, \u00e0s 10 horas, para a Celebra\u00e7\u00e3o Eucar\u00edstica, presidida pelo Vig\u00e1rio Provincial da Prov\u00edncia da Imaculada Concei\u00e7\u00e3o, Frei Gustavo Medella, e concelebrada pelo vig\u00e1rio paroquial, Frei Ab\u00edlio Antunes do Amaral. A Celebra\u00e7\u00e3o, transmitida pela R\u00e1dio Imperial e pela p\u00e1gina do Facebook da Par\u00f3quia, teve Frei Lauro Both e Frei Felipe Carretta na anima\u00e7\u00e3o.<\/p>\n<p>Segundo o celebrante, a data oficial dos Santos Reis \u00e9 originalmente celebrada no dia 6 de janeiro, mas por quest\u00f5es pastorais a Igreja do Brasil ajusta sempre para o domingo mais pr\u00f3ximo.<\/p>\n<p>Frei Gustavo lembrou que a liturgia apresenta com destaque o tema da luz e da estrela. &#8220;Na 1\u00aa leitura, vemos uma profecia de muita esperan\u00e7a para aquele povo que vivia a dura experi\u00eancia do ex\u00edlio&#8221;, destacou.<\/p>\n<p>&#8220;No Evangelho, o tema da luz volta com a figura da estrela que brilha e guia os magos que v\u00e3o ao encontro do Rei nascido&#8221;, explicou. &#8220;Em nosso tempo precisamos ter muito cuidado e muito discernimento para perceber se nos guiamos pela luz verdadeira que \u00e9 a luz de Deus, ou por luzes perif\u00e9ricas, passageiras e ilus\u00f3rias que nos levam a um grande vazio&#8221;, disse o frade, lembrando que a sociedade vive um forte esp\u00edrito de cobran\u00e7a, poder, desempenho e produtividade. \u201cPrecisamos parar e interromper essa l\u00f3gica\u201d, disse.<\/p>\n<p>Frei Medella lembrou ainda que todas as instru\u00e7\u00f5es de cuidado em rela\u00e7\u00e3o \u00e0 pandemia fazem parte do compromisso de ser luz na vida do outro. \u201cPor isso, todos os esfor\u00e7os em rela\u00e7\u00e3o \u00e0 vacina, \u00e0 cura, ao tratamento devem sempre ser um direito universal, independente das amarras de lucro, do mercado, mas algo facultado e oferecido a todos, sem exce\u00e7\u00e3o\u201d, enfatizou.<\/p>\n<p>A celebra\u00e7\u00e3o teve continuidade com a liturgia eucar\u00edstica, onde se celebrou a manifesta\u00e7\u00e3o de Cristo na carne, mas tamb\u00e9m a todos os povos e, assim, a universalidade de sua Salva\u00e7\u00e3o. No final, Frei Gustavo agradeceu a presen\u00e7a de todos e desejou esperan\u00e7a neste novo ano que se inicia. Frei Ab\u00edlio concedeu a b\u00ean\u00e7\u00e3o final, encerrando a Missa.<\/p>\n<hr \/>\n<p><em>Frei Augusto Luiz Gabriel<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par\u00f3quia do Sagrado Cora\u00e7\u00e3o de Jesus de Petr\u00f3polis<\/p>\n","protected":false},"author":3,"featured_media":230239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[1218,190],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Epifania: Frei Medella pede para &quot;ser luz na vida do outro&quot; nesse tempo de pandemia - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Epifania: Frei Medella pede para &quot;ser luz na vida do outro&quot; nesse tempo de pandemia - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Par\u00f3quia do Sagrado Cora\u00e7\u00e3o de Jesus de Petr\u00f3polis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-04T10:18:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-04T13:39:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04d.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04d.jpg\",\"width\":800,\"height\":600},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html\",\"name\":\"Epifania: Frei Medella pede para \\\"ser luz na vida do outro\\\" nesse tempo de pandemia - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html#primaryimage\"},\"datePublished\":\"2021-01-04T10:18:39+00:00\",\"dateModified\":\"2021-01-04T13:39:40+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Epifania: Frei Medella pede para &#8220;ser luz na vida do outro&#8221; nesse tempo de pandemia\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Epifania: Frei Medella pede para \"ser luz na vida do outro\" nesse tempo de pandemia - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html","og_locale":"pt_BR","og_type":"article","og_title":"Epifania: Frei Medella pede para \"ser luz na vida do outro\" nesse tempo de pandemia - Not\u00edcias - Franciscanos","og_description":"Par\u00f3quia do Sagrado Cora\u00e7\u00e3o de Jesus de Petr\u00f3polis","og_url":"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2021-01-04T10:18:39+00:00","article_modified_time":"2021-01-04T13:39:40+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04d.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04d.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2021\/01\/medella_04d.jpg","width":800,"height":600},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html","name":"Epifania: Frei Medella pede para \"ser luz na vida do outro\" nesse tempo de pandemia - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html#primaryimage"},"datePublished":"2021-01-04T10:18:39+00:00","dateModified":"2021-01-04T13:39:40+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/epifania-frei-medella-pede-para-ser-luz-na-vida-do-outro-nesse-tempo-de-pandemia.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Epifania: Frei Medella pede para &#8220;ser luz na vida do outro&#8221; nesse tempo de pandemia"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/230237"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=230237"}],"version-history":[{"count":2,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/230237\/revisions"}],"predecessor-version":[{"id":230250,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/230237\/revisions\/230250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/230239"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=230237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=230237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=230237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}