{"id":228277,"date":"2020-09-09T08:18:44","date_gmt":"2020-09-09T11:18:44","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=228277"},"modified":"2021-08-29T10:43:35","modified_gmt":"2021-08-29T13:43:35","slug":"francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html","title":{"rendered":"Francisco: O verdadeiro amor n\u00e3o conhece a cultura do descarte"},"content":{"rendered":"<div id=\"attachment_228278\" style=\"width: 1290px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-228278\" loading=\"lazy\" class=\"wp-image-228278 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909.jpg 1280w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909-1024x576.jpg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909-768x432.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909-150x84.jpg 150w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><p id=\"caption-attachment-228278\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Imagens: Vatican Media<\/em><\/p><\/div>\n<p><strong>Cidade do Vaticano<\/strong> &#8211; \u201cCurar o mundo\u201d. Amor e bem comum. Este foi o tema da catequese do Papa Francisco na Audi\u00eancia Geral, desta quarta-feira (09\/09), realizada no P\u00e1tio S\u00e3o D\u00e2maso, situado dentro do Vaticano. Nesta segunda Audi\u00eancia Geral p\u00fablica desde o in\u00edcio da pandemia de coronav\u00edrus, Francisco ressaltou que \u201ca crise que estamos vivendo por causa da pandemia afeta a todos. Podemos sair melhores dela se todos juntos buscarmos o bem comum. Pelo contr\u00e1rio, sairemos piores\u201d.<\/p>\n<p>Infelizmente, estamos assistindo ao surgimento de interesses de parte. Por exemplo, h\u00e1 quem deseje apropriar-se de poss\u00edveis solu\u00e7\u00f5es, como no caso das vacinas, e depois vend\u00ea-las a outros. Algumas pessoas se aproveitam da situa\u00e7\u00e3o para fomentar divis\u00f5es: para procurar vantagens econ\u00f4micas ou pol\u00edticas, gerando ou aumentando os conflitos. Outros simplesmente n\u00e3o se importam com o sofrimento dos outros, passam adiante e seguem o seu caminho. S\u00e3o devotos de P\u00f4ncio Pilatos. Lavam as m\u00e3os.<\/p>\n<p><strong>Resposta crist\u00e3 \u00e0 pandemia<\/strong><br \/>\nSegundo o Pont\u00edfice, \u201ca resposta crist\u00e3 \u00e0 pandemia e \u00e0s consequentes crises socioecon\u00f4micas se baseia no amor, antes de tudo, no amor de Deus que sempre nos precede. Ele nos ama por primeiro. Ele sempre nos precede no amor e nas solu\u00e7\u00f5es. Ele nos ama incondicionalmente, e quando aceitamos este amor divino, podemos responder de forma semelhante\u201d.<\/p>\n<p>&#8220;Amo n\u00e3o s\u00f3 aqueles que me amam: a minha fam\u00edlia, os meus amigos, o meu grupo, mas tamb\u00e9m aqueles que n\u00e3o me amam, amo tamb\u00e9m aqueles que n\u00e3o me conhecem, ou que s\u00e3o estrangeiros, e tamb\u00e9m aqueles que me fazem sofrer ou que considero inimigos. Esta \u00e9 a sabedoria crist\u00e3, este \u00e9 o ensinamento de Jesus. O ponto mais alto da santidade \u00e9 amar o inimigo, mas n\u00e3o \u00e9 f\u00e1cil. N\u00e3o \u00e9 f\u00e1cil. Claro, amar todos, inclusive os inimigos, \u00e9 dif\u00edcil, diria que \u00e9 uma arte! Mas \u00e9 uma arte que pode ser aprendida e melhorada. O verdadeiro amor, que nos torna fecundos e livres, \u00e9 sempre expansivo e inclusivo. Este amor cuida, cura e faz bem. Muitas vezes uma car\u00edcia faz mais bem do que muitos argumentos, uma car\u00edcia de perd\u00e3o e n\u00e3o muitos argumentos para se defender. \u00c9 o amor inclusivo que cura&#8221;.<\/p>\n<p><strong>O amor inclusivo \u00e9 social, \u00e9 familiar, \u00e9 pol\u00edtico<\/strong><br \/>\nO Papa disse ainda que \u201co amor n\u00e3o se limita \u00e0s rela\u00e7\u00f5es entre duas ou tr\u00eas pessoas, amigos, ou fam\u00edlia. Inclui as rela\u00e7\u00f5es c\u00edvicas e pol\u00edticas, incluindo a rela\u00e7\u00e3o com a natureza. Sendo n\u00f3s seres sociais e pol\u00edticos, uma das mais altas express\u00f5es de amor \u00e9 o amor social e pol\u00edtico, que \u00e9 decisivo para o desenvolvimento humano e para enfrentar qualquer tipo de crise&#8221;.<\/p>\n<p>\u201cSabemos que o amor fecunda fam\u00edlias e amizades; mas \u00e9 bom lembrar que tamb\u00e9m fecunda rela\u00e7\u00f5es sociais, culturais, econ\u00f4micas e pol\u00edticas, permitindo-nos construir uma \u201cciviliza\u00e7\u00e3o do amor\u201d, como gostava de dizer S\u00e3o Paulo VI e, na sua esteira, S\u00e3o Jo\u00e3o Paulo II.\u201d<\/p>\n<p>&#8220;Sem esta inspira\u00e7\u00e3o, a cultura do ego\u00edsmo, da indiferen\u00e7a, do descarte, prevalece, a cultura da indiferen\u00e7a, o descarte, ou seja, descartar quem eu n\u00e3o quero bem, aquele que n\u00e3o posso amar ou aqueles que me parecem ser in\u00fateis na sociedade. Hoje, na entrada, um casal me disse: &#8216;Reze por n\u00f3s, pois temos um filho deficiente&#8217;. Eu perguntei: Quantos anos ele tem? &#8216;Muitos&#8217;. O que fazem? &#8216;N\u00f3s o acompanhamos, n\u00f3s o ajudamos&#8217;. Toda uma vida inteira de pais para aquele filho deficiente. Isso \u00e9 amor. Os inimigos, os advers\u00e1rios pol\u00edticos, mesmo no nosso parecer, parecem ser deficientes pol\u00edticos, sociais. Parecem ser. Somente Deus sabe se eles s\u00e3o ou n\u00e3o. N\u00f3s devemos am\u00e1-los, devemos dialogar, devemos construir esta civiliza\u00e7\u00e3o do amor, esta civiliza\u00e7\u00e3o pol\u00edtica, social, de unidade de toda a humanidade. Pelo contr\u00e1rio, haver\u00e1 guerras, divis\u00f5es, invejas, at\u00e9 mesmo guerras na fam\u00edlia. O amor inclusivo \u00e9 social, \u00e9 familiar, \u00e9 pol\u00edtico. O amor permeia tudo.&#8221;<\/p>\n<p>O coronav\u00edrus nos mostra que o verdadeiro bem para cada um \u00e9 um bem comum, n\u00e3o somente individual e, vice-versa, o bem comum \u00e9 um verdadeiro bem para a pessoa. Se uma pessoa busca apenas o seu pr\u00f3prio bem, ela \u00e9 ego\u00edsta. Ao inv\u00e9s disso, a pessoa \u00e9 mais, \u00e9 mais nobre, quando o seu pr\u00f3prio bem a abre a todos, e o compartilha. A sa\u00fade n\u00e3o \u00e9 apenas individual, mas tamb\u00e9m um bem p\u00fablico. Uma sociedade saud\u00e1vel \u00e9 aquela que cuida da sa\u00fade de todos, de todos.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-228280\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909_1.jpg\" alt=\"\" width=\"1009\" height=\"672\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909_1.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909_1-450x300.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909_1-768x512.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909_1-150x100.jpg 150w\" sizes=\"(max-width: 1009px) 100vw, 1009px\" \/><\/p>\n<p><strong>O verdadeiro amor n\u00e3o conhece a cultura do descarte<\/strong><br \/>\n\u201cUm v\u00edrus que n\u00e3o conhece barreiras, fronteiras, distin\u00e7\u00f5es culturais nem pol\u00edticas deve ser enfrentado com um amor sem barreiras, fronteiras nem distin\u00e7\u00f5es. Este amor pode gerar estruturas sociais que nos encorajam a partilhar em vez de competir, que nos permitem incluir os mais vulner\u00e1veis em vez de os descartar, e que nos ajudam a expressar o melhor da nossa natureza humana e n\u00e3o o pior. O verdadeiro amor n\u00e3o conhece a cultura do descarte. N\u00e3o sabe o que \u00e9\u201d, sublinhou Francisco.<\/p>\n<p>Segundo o Papa, \u201cquando amamos e geramos criatividade, confian\u00e7a e solidariedade, ent\u00e3o emergem iniciativas concretas para o bem comum. E isto \u00e9 verdade tanto em n\u00edvel de pequenas e grandes comunidades como em n\u00edvel internacional. O que se faz na fam\u00edlia, no bairro, nos vilarejos, nas grades cidades e internacionalmente \u00e9 a mesma coisa. \u00c9 a mesma semente que cresce, cresce e d\u00e1 fruto. Se voc\u00ea na fam\u00edlia, no bairro come\u00e7a com a inveja, com a luta, ser\u00e1 guerra no final. Ao inv\u00e9s, se voc\u00ea come\u00e7ar com amor, compartilhando amor, perd\u00e3o, ser\u00e1 amor e perd\u00e3o para todos. A seguir, acrescentou: &#8220;Pelo contr\u00e1rio, se as solu\u00e7\u00f5es para a pandemia tiverem a marca do ego\u00edsmo, quer de pessoas, empresas ou na\u00e7\u00f5es, talvez consigamos sair do coronav\u00edrus, mas certamente n\u00e3o da crise humana e social que o v\u00edrus evidenciou e acentuou. Portanto, aten\u00e7\u00e3o a n\u00e3o construir sobre areia! Para construir uma sociedade saud\u00e1vel, inclusiva, justa e pac\u00edfica, devemos faz\u00ea-lo sobre a rocha do bem comum. O bem comum \u00e9 uma rocha. E esta \u00e9 a tarefa de todos, e n\u00e3o apenas de alguns especialistas. Santo Tom\u00e1s de Aquino disse que a promo\u00e7\u00e3o do bem comum \u00e9 um dever de justi\u00e7a que recai sobre todos os cidad\u00e3os. Todo cidad\u00e3o \u00e9 respons\u00e1vel pelo bem comum. E, para os crist\u00e3os, \u00e9 tamb\u00e9m uma miss\u00e3o. Como ensina Santo In\u00e1cio de Loyola, orientar os nossos esfor\u00e7os di\u00e1rios para o bem comum \u00e9 uma forma de receber e difundir a gl\u00f3ria de Deus&#8221;.<\/p>\n<p><strong>Uma boa pol\u00edtica \u00e9 poss\u00edvel<\/strong><br \/>\n\u201cInfelizmente\u201d, disse ainda Francisco, \u201ca pol\u00edtica muitas vezes n\u00e3o goza de boa reputa\u00e7\u00e3o, e n\u00f3s sabemos porqu\u00ea. Isso n\u00e3o significa que os pol\u00edticos sejam todos maus, n\u00e3o, n\u00e3o estou dizendo isso. Estou dizendo que, infelizmente, a pol\u00edtica muitas vezes n\u00e3o tem uma boa reputa\u00e7\u00e3o&#8221;.<\/p>\n<p>\u201cMas n\u00e3o nos devemos resignar a esta vis\u00e3o negativa, mas reagir demonstrando com fatos que uma boa pol\u00edtica \u00e9 poss\u00edvel, ali\u00e1s, indispens\u00e1vel, aquela que coloca no centro a pessoa humana e o bem comum\u201d.<\/p>\n<p>&#8220;\u00c9 poss\u00edvel na medida em que cada cidad\u00e3o e, em particular, aqueles que assumem compromissos e encargos sociais e pol\u00edticos, enra\u00edzam as suas a\u00e7\u00f5es em princ\u00edpios \u00e9ticos e os animam com amor social e pol\u00edtico. Os crist\u00e3os, especialmente os fi\u00e9is leigos, s\u00e3o chamados a dar bom testemunho disso e podem faz\u00ea-lo atrav\u00e9s da virtude da caridade, cultivando a sua intr\u00ednseca dimens\u00e3o social&#8221;.<\/p>\n<p>O Papa concluiu sua catequese, afirmando que \u201cchegou o momento de aumentar o nosso amor social, contribuindo todos, come\u00e7ando pela nossa pequenez. O bem comum requer a participa\u00e7\u00e3o de todos. Se cada um contribuir com a sua parte, e se ningu\u00e9m for exclu\u00eddo, podemos regenerar boas rela\u00e7\u00f5es no \u00e2mbito comunit\u00e1rio, nacional e internacional e tamb\u00e9m em harmonia com o meio ambiente. Assim, nos nossos gestos, mesmo os mais humildes, algo da imagem de Deus que levamos dentro de n\u00f3s se tornar\u00e1 vis\u00edvel, porque Deus \u00e9 Trindade. Deus \u00e9 amor. Esta \u00e9 a mais bonita defini\u00e7\u00e3o de Deus que est\u00e1 na B\u00edblia, dada a n\u00f3s pelo ap\u00f3stolo Jo\u00e3o que tanto amava Jesus: Deus \u00e9 amor. Com a sua ajuda, podemos curar o mundo trabalhando juntos para o bem comum, n\u00e3o apenas para o meu bem, mas para o bem comum de todos\u201d.<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News ( texto Mariangela Jaguraba)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Audi\u00eancia Geral<\/p>\n","protected":false},"author":3,"featured_media":228279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[487],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Francisco: O verdadeiro amor n\u00e3o conhece a cultura do descarte - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Francisco: O verdadeiro amor n\u00e3o conhece a cultura do descarte - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Audi\u00eancia Geral\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-09T11:18:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-29T13:43:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909d.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909d.jpg\",\"width\":800,\"height\":600},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html\",\"name\":\"Francisco: O verdadeiro amor n\u00e3o conhece a cultura do descarte - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html#primaryimage\"},\"datePublished\":\"2020-09-09T11:18:44+00:00\",\"dateModified\":\"2021-08-29T13:43:35+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Francisco: O verdadeiro amor n\u00e3o conhece a cultura do descarte\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Francisco: O verdadeiro amor n\u00e3o conhece a cultura do descarte - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html","og_locale":"pt_BR","og_type":"article","og_title":"Francisco: O verdadeiro amor n\u00e3o conhece a cultura do descarte - Not\u00edcias - Franciscanos","og_description":"Audi\u00eancia Geral","og_url":"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2020-09-09T11:18:44+00:00","article_modified_time":"2021-08-29T13:43:35+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909d.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909d.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2020\/09\/audiencia_0909d.jpg","width":800,"height":600},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html","name":"Francisco: O verdadeiro amor n\u00e3o conhece a cultura do descarte - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html#primaryimage"},"datePublished":"2020-09-09T11:18:44+00:00","dateModified":"2021-08-29T13:43:35+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/francisco-o-verdadeiro-amor-nao-conhece-a-cultura-do-descarte.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Francisco: O verdadeiro amor n\u00e3o conhece a cultura do descarte"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/228277"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=228277"}],"version-history":[{"count":2,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/228277\/revisions"}],"predecessor-version":[{"id":233960,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/228277\/revisions\/233960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/228279"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=228277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=228277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=228277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}