{"id":213842,"date":"2019-11-11T14:18:34","date_gmt":"2019-11-11T17:18:34","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=213842"},"modified":"2021-04-19T22:38:47","modified_gmt":"2021-04-20T01:38:47","slug":"e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html","title":{"rendered":"\u201c\u00c9 importante que n\u00f3s, franciscanos,\u00a0assumamos a nossa responsabilidade neste momento\u201d\u00a0"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone wp-image-213845 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_2.jpg\" alt=\"\" width=\"890\" height=\"500\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_2.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_2-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_2-768x431.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_2-150x84.jpg 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/p>\n<p><b>Frei Augusto Luiz Gabriel<\/b><\/p>\n<p><b>Petr\u00f3polis (RJ) &#8211; <\/b><span style=\"font-weight: 400;\">Rec\u00e9m-chegada de Roma, onde participou do S\u00ednodo para a Amaz\u00f4nia, como auditora integralmente<\/span><b>, <\/b><i><span style=\"font-weight: 400;\">Moema Miranda,<\/span><\/i> <i><span style=\"font-weight: 400;\">atual professora da disciplina Conflitos S\u00f3cioambientais do Instituto Teol\u00f3gico Franciscano (ITF) de Petr\u00f3polis (RJ), fala nesta entrevista deste momento hist\u00f3rico para a Igreja, especialmente para a Igreja da Am\u00e9rica Latina.\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Com um sorriso largo no rosto e o sentimento de miss\u00e3o cumprida, Moema tem\u00a0 plena consci\u00eancia de que o S\u00ednodo foi um \u201cponto de chegada, mas tamb\u00e9m \u00e9 um ponto de partida\u201d. Moema se emociona ao falar do Papa Francisco, que para ela \u00e9 \u00a0 uma pessoa iluminada pelo Esp\u00edrito Santo! \u201c\u00c9 um homem l\u00facido e com uma for\u00e7a impressionante. [&#8230;] Pela sua humildade ele se faz um com o Pai\u201d.<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Moema foi enf\u00e1tica ao afirmar que todo o caminho da Igreja na Amaz\u00f4nia \u00e9 marcado pelo caminho \u2018martirial\u2019 que se faz em nome do Evangelho de Jesus Cristo. Segundo ela, o sangue dos m\u00e1rtires espalha as sementes. \u201cNeste S\u00ednodo para a Amaz\u00f4nia as barreiras n\u00e3o existiram, a presen\u00e7a de quem estava do lado de fora, acompanhando e rezando, criou de fato uma comunh\u00e3o com a presen\u00e7a do Esp\u00edrito Santo\u201d.\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Franciscana, leiga, mulher e antrop\u00f3loga, Moema acredita que o tempo de retomar o compromisso franciscano pela Casa Comum \u00e9 agora. \u201cSejamos n\u00f3s, a partir de nosso carisma, atores, atrizes, irm\u00e3os e irm\u00e3s neste grande pacto pela Amaz\u00f4nia e pela vida\u201d, destacou.\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Moema fez mestrado e p\u00f3s-gradua\u00e7\u00e3o em Antropologia Social pelo Museu Nacional, da Universidade Federal do Rio de Janeiro (UFRJ). Foi ministra da Fraternidade Santo Ant\u00f4nio (RJ) da Ordem Franciscana Secular e integra a secretaria da Rede \u201cIgrejas e Minera\u00e7\u00e3o\u201d da CNBB.\u00a0<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Ela tamb\u00e9m faz parte da coordena\u00e7\u00e3o nacional do Sinfrajupe (Servi\u00e7o Interfranciscano de Justi\u00e7a Paz e Ecologia) e assessora a Rede Eclesial Pan-Amaz\u00f4nica (REPAM), al\u00e9m de participar do grupo de estudos de Ecotelogia do ITF. Atuou at\u00e9 agosto de 2017 no Instituto Brasileiro de An\u00e1lises Sociais e Econ\u00f4micas (Ibase). Atualmente est\u00e1 fazendo o doutorado em quest\u00f5es ambientais pela PUC do Rio de Janeiro.<\/span><\/i><\/p>\n<h2><strong>Acompanhe a entrevista!<\/strong><\/h2>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-213843 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119.jpg\" alt=\"\" width=\"890\" height=\"550\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119-450x278.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119-768x475.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119-150x93.jpg 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><b>Site Franciscanos: <\/b><i><span style=\"font-weight: 400;\">N\u00f3s sabemos que a Igreja, desde o Conc\u00edlio de Jerusal\u00e9m (At 15), vivencia a sinodalidade em suas discuss\u00f5es. Como \u00e9 para voc\u00ea reviver essa experi\u00eancia que at\u00e9 os primeiros ap\u00f3stolos viveram?\u00a0<\/span><\/i><\/p>\n<p><b>Moema Miranda: <\/b><span style=\"font-weight: 400;\">Primeiro \u00e9 uma experi\u00eancia muito emocionante. Se teve uma coisa que em todo tempo da participa\u00e7\u00e3o &#8211; tanto no processo de prepara\u00e7\u00e3o como durante a realiza\u00e7\u00e3o do S\u00ednodo &#8211; ficou muito clara \u00e9 a presen\u00e7a forte de como a comunidade \u00e9 comunh\u00e3o. E comunh\u00e3o s\u00f3 se faz em comunidade; ningu\u00e9m comunga sozinho. O processo de sinodalidade na Igreja passou por diferentes momentos na hist\u00f3ria. De certa forma, o que o Papa Francisco est\u00e1 fazendo \u00e9 a retomada de um processo que tinha sido vivificado por Paulo VI no Conc\u00edlio Vaticano II. O Papa Francisco n\u00e3o s\u00f3 est\u00e1 revivendo a proposta que remonta ao in\u00edcio da nossa Igreja, como est\u00e1 aumentando e fortalecendo determinados aspectos que s\u00e3o essenciais para que o S\u00ednodo de fato se tornasse um momento de escuta forte e de uma escuta que se torne proposta. Desde todo processo preparat\u00f3rio do S\u00ednodo at\u00e9 durante o S\u00ednodo, aberto j\u00e1 com a presen\u00e7a do Esp\u00edrito Santo, foi muito forte a sensa\u00e7\u00e3o e percep\u00e7\u00e3o de comunh\u00e3o e comunidade: \u201cOnde tr\u00eas ou mais estiverem reunidos em nome de Deus, Ele a\u00ed est\u00e1\u201d.\u00a0<\/span><\/p>\n<p><b>Site Franciscanos: <\/b><i><span style=\"font-weight: 400;\">Ao seu ver, que import\u00e2ncia tem o S\u00ednodo para Amaz\u00f4nia na Igreja, para os povos que l\u00e1 residem e\u00a0 para n\u00f3s, franciscanos?\u00a0<\/span><\/i><\/p>\n<div id=\"attachment_213855\" style=\"width: 460px\" class=\"wp-caption alignright\"><img aria-describedby=\"caption-attachment-213855\" loading=\"lazy\" class=\"wp-image-213855 size-medium\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_8-450x338.jpeg\" alt=\"\" width=\"450\" height=\"338\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_8-450x338.jpeg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_8-768x576.jpeg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_8-1024x768.jpeg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_8-150x113.jpeg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_8-600x450.jpeg 600w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_8-1200x900.jpeg 1200w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_8.jpeg 1280w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><p id=\"caption-attachment-213855\" class=\"wp-caption-text\"><em>Dom Evaristo Spengler, Bispo da Prelazia do Maraj\u00f3, e Moema Miranda<\/em><\/p><\/div>\n<p><b>Moema Miranda: <\/b><span style=\"font-weight: 400;\">\u00c9 um S\u00ednodo fundamental porque busca novos caminhos para a Igreja e para a ecologia integral. A quest\u00e3o ecol\u00f3gica exponencia os limites do sistema que n\u00f3s estamos vivendo, que no documento final do S\u00ednodo \u00e9 reconhecido como um caminho indel\u00e9vel de morte se n\u00e3o for detido. A urg\u00eancia da crise ambiental est\u00e1 no centro das preocupa\u00e7\u00f5es de todo Pontificado do Papa Francisco. J\u00e1 com a Enc\u00edclica <\/span><i><span style=\"font-weight: 400;\">Laudato Si\u2019<\/span><\/i><span style=\"font-weight: 400;\"> ele anteviu a necessidade de\u00a0 transformar as perspectivas que constam na enc\u00edclica em algo muito mais concreto. N\u00f3s, franciscanos, temos essa experi\u00eancia e sabemos como a passagem da intui\u00e7\u00e3o para a institui\u00e7\u00e3o, muitas vezes, desidrata o sentido forte do carisma e da primeira paix\u00e3o. Ent\u00e3o, voltar para esse ponto de origem, como nos dizia Santa Clara, \u00e9 importante o todo tempo. O Papa Francisco, quando reconheceu a urg\u00eancia das quest\u00f5es clim\u00e1ticas e lan\u00e7ou a Enc\u00edclica <\/span><i><span style=\"font-weight: 400;\">Laudato Si\u2019,<\/span><\/i><span style=\"font-weight: 400;\"> afirmou que a Amaz\u00f4nia seria um teste para a Enc\u00edclica. Se na Amaz\u00f4nia a Igreja conseguir consolidar a ideia de uma ecologia integral, a partir de uma longa hist\u00f3ria de luzes e sombras, mas com uma Igreja que \u00e9 martirial, presente e forte, ent\u00e3o n\u00f3s passaremos neste teste que a Enc\u00edclica requer, fortalecendo a Igreja com um novo ar. Durante o encontro em Roma, na segunda semana de trabalhos, um bispo falou que ele sentia o S\u00ednodo como um grande encontro do<\/span><span style=\"font-weight: 400;\"> Rio Amazonas com o Tigre. <\/span><span style=\"font-weight: 400;\">Quer dizer, o rio da tradi\u00e7\u00e3o encontrando com outro grande rio vivo que \u00e9 o Amazonas. E esses encontros foram produtivos e proveitosos. Deixa para todos n\u00f3s a sensa\u00e7\u00e3o de que agora estamos come\u00e7ando de novo. Neste sentido, os jovens t\u00eam um papel essencial neste processo. N\u00f3s sabemos que em todo planeta os jovens v\u00eam desenvolvendo uma maior consci\u00eancia da urg\u00eancia da quest\u00e3o ambiental. E todos os movimentos da Europa, como o da Greta Ernman Thunberg e outros, mas tamb\u00e9m na Amaz\u00f4nia, temos uma for\u00e7a da juventude muito grande. Ent\u00e3o, nutrimos uma grande expectativa de que essa comunh\u00e3o se fa\u00e7a, mais ainda porque as quest\u00f5es ligadas ao consumismo, ao desperd\u00edcio e \u00e0 desigualdade entre a juventude, s\u00e3o muito brutais. N\u00f3s, que moramos aqui no Rio de Janeiro, sabemos como o assassinato de jovens negros \u00e9 crescente. Ent\u00e3o, acredito que o S\u00ednodo abre espa\u00e7o para essa comunh\u00e3o da juventude. N\u00e3o \u00e9 poss\u00edvel que os jovens frades, os jovens universit\u00e1rios, os jovens da cidade n\u00e3o se responsabilizem, n\u00e3o se\u00a0 corresponsabilizem por estes jovens que est\u00e3o sendo assassinados ali, muitas vezes nas periferias onde eles tamb\u00e9m moram. E o S\u00ednodo abre essa grande possibilidade: a Amaz\u00f4nia \u00e9 logo aqui. O que acontece na Amaz\u00f4nia, afeta n\u00f3s aqui. N\u00e3o foi \u00e0 toa, dias antes do S\u00ednodo, que o c\u00e9u ficou negro em S\u00e3o Paulo por conta das queimadas na Amaz\u00f4nia, como para dizer: <\/span><i><span style=\"font-weight: 400;\">gente, o Papa tinha toda raz\u00e3o!<\/span><\/i><span style=\"font-weight: 400;\"> Isso deu ao S\u00ednodo mais visibilidade. Por isso, toda a nossa juventude tem um papel fundamental, porque, s\u00e3o voc\u00eas que v\u00e3o levar adiante esse grande projeto de uma Igreja comprometida com a terra e com a salva\u00e7\u00e3o do mundo.<\/span><\/p>\n<p><b>Site Franciscanos: <\/b><i><span style=\"font-weight: 400;\">Qual \u00e9 a import\u00e2ncia do Pacto das Catacumbas? Voc\u00ea tamb\u00e9m assinou? Como descreve este momento \u00edmpar para toda Igreja?<\/span><\/i><\/p>\n<p><b>Moema Miranda: <\/b><span style=\"font-weight: 400;\">O Pacto das Catacumbas remonta ao Conc\u00edlio Vaticano II. No processo de prepara\u00e7\u00e3o do S\u00ednodo, vimos do Pacto das Catacumbas no Conc\u00edlio Vaticano II foi essencial para o que depois a Igreja desdobrou do Conc\u00edlio aqui na Am\u00e9rica Latina. Ent\u00e3o, aqueles bispos que fizeram o Pacto das Catacumbas em Santa Domitilla voltaram para o Brasil com um compromisso de mudar\u00a0 a Igreja e fazer esse percurso. Venderam os pal\u00e1cios episcopais, foram para as comunidades do interior, criaram Comunidades Eclesiais de Base (CEBS), ou seja, ali foi a origem de um processo popular de luta por democracia em nosso pa\u00eds, de luta com e pelos pobres, de compreender que durante mil\u00eanios n\u00f3s nos preocupamos com a salva\u00e7\u00e3o das almas, no entanto, hoje n\u00f3s continuamos a nos preocupar, mas sabemos que alma e corpo s\u00e3o integrados. N\u00e3o \u00e9 poss\u00edvel voc\u00ea esperar a salva\u00e7\u00e3o da alma na cidade de Deus, se na cidade dos homens se vive com tanta desigualdade, onde n\u00f3s pecamos por omiss\u00e3o ou coniv\u00eancia. Esse compromisso com os direitos humanos, com uma vida digna para os pobres, j\u00e1 foi assumido fortemente a partir do Conc\u00edlio Vaticano II. Mas agora \u00e9 um passo a mais: n\u00f3s precisamos salvar a matriz de toda a vida, as condi\u00e7\u00f5es de possibilidade de toda vida, pois \u00e9 a pr\u00f3pria terra que est\u00e1 amea\u00e7ada, essa terra que tamb\u00e9m \u00e9 viva e vivente. O Pacto das Catacumbas tentou ser esse momento forte de um compromisso pessoal com os temas que estavam sendo discutidos ali. Importante destacar que n\u00e3o foram somente os padres sinodais &#8211; \u00e9 claro que eles tinham\u00a0 preced\u00eancia -, mas todo povo de Deus esteve presente e p\u00f4de se comprometer com essa causa nobre. O que a gente espera \u00e9 que o pacto se desdobre em mais compromissos fortes com essa etapa fundamental em que a Igreja se torna, talvez, a institui\u00e7\u00e3o mais importante na defesa da Casa Comum. Por isso, faz todo sentido ter assinado o pacto dentro do S\u00ednodo para a Amaz\u00f4nia, que a gente tenha voltado \u00e0s Catacumbas de Santa Domitilla \u00e0s sete da manh\u00e3, que a Missa tenha sido celebrada por Dom Cl\u00e1udio Hummes, um franciscano que foi o relator do S\u00ednodo e pediu para o Cardeal Bergoglio, ao assumir o nome de Francisco, para n\u00e3o esquecer dos pobres, esse Dom Cl\u00e1udio que hoje \u00e9 uma figura prof\u00e9tica em nossa Igreja, comprometido e pr\u00f3ximo ao carisma franciscano. Outro elemento muito bonito \u00e9 que Dom Cl\u00e1udio usou durante a Celebra\u00e7\u00e3o Eucar\u00edstica nas Catacumbas a estola de Dom Helder C\u00e2mara. Depois, no final da missa, ele chamou Dom Erwin Kr\u00e4utler, entre tantos padres sinodais, e entregou a ele a estola, dizendo que a merecia. Por isso, foi muito bonito o encontro dessa Igreja que se reconhece no caminho da Igreja comprometida com os pobres e com a terra, no longo caminho da Igreja na Amaz\u00f4nia.<\/span><\/p>\n<div id=\"attachment_213844\" style=\"width: 900px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-213844\" loading=\"lazy\" class=\"wp-image-213844 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_1.jpg\" alt=\"\" width=\"890\" height=\"500\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_1.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_1-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_1-768x431.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_1-150x84.jpg 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><p id=\"caption-attachment-213844\" class=\"wp-caption-text\"><em>Assinatura do Pacto das Catacumbas, em Santa Domitila. Pe. D\u00e1rio Bossi e Ir Anttonnita ao lado esquerdo.<\/em><\/p><\/div>\n<p><b>Site Franciscanos:<\/b> <i><span style=\"font-weight: 400;\">O que significa a Amaz\u00f4nia para os povos ind\u00edgenas?<\/span><\/i><\/p>\n<p><b>Moema Miranda: <\/b><span style=\"font-weight: 400;\">O documento final possui uma express\u00e3o muito bonita onde fala que na Amaz\u00f4nia tudo est\u00e1 entrela\u00e7ado, a floresta, os rios, os povos. Este entrela\u00e7amento da vida, nas suas m\u00faltiplas formas, numa imensa floresta como \u00e9 a Amaz\u00f4nia, \u00e9 um elemento essencial. Para os povos ind\u00edgenas, o territ\u00f3rio \u00e9 a condi\u00e7\u00e3o de vida deles. A Irm\u00e3 Dorothy repetia uma frase famosa de um ind\u00edgena que diz: \u2018A morte da floresta \u00e9 o fim das nossas vidas\u2019. Na verdade, territ\u00f3rio e identidade, territ\u00f3rio e vida est\u00e3o absolutamente interligados. Para os povos dali, a floresta \u00e9 a fonte e a matriz da vida; \u00e9 a vida mesmo que se faz e se refaz. Eles est\u00e3o integrados e entrela\u00e7ados com esse grande bioma, em espa\u00e7o, tempo, biosfera, fauna e flora. Essa conex\u00e3o intensa \u00e9 que a gente percebe. O territ\u00f3rio \u00e9 fonte de vida e de identidade. Ao mesmo tempo, eles cuidam, enriquecem, ampliam as possibilidades de vida na Amaz\u00f4nia, como j\u00e1 fazem h\u00e1 milhares de anos. Essa conex\u00e3o \u00e9 um exemplo para todos n\u00f3s de aprendizado, de outra forma de ser e estar no mundo. Por isso, no documento final fica muito claro que eles s\u00e3o os protagonistas na defesa do seu territ\u00f3rio e n\u00f3s, como Igreja, devemos ser seus aliados, caminhando juntos. Na Carta que eles escreveram para o Papa, tendo em vista que na sala sinodal havia 22 ind\u00edgenas participando do S\u00ednodo &#8211; alguns convidados e outros s\u00e3o padres e irm\u00e3s &#8211; fazem defesa do territ\u00f3rio, dos direitos \u00e0 terra, como tamb\u00e9m da cultura, de um modo de ser e estar. Ou seja, a Igreja precisa ser uma aliada dos povos no seu direito de autodetermina\u00e7\u00e3o.\u00a0<\/span><\/p>\n<div id=\"attachment_213848\" style=\"width: 507px\" class=\"wp-caption alignleft\"><img aria-describedby=\"caption-attachment-213848\" loading=\"lazy\" class=\"wp-image-213848 \" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_5.jpeg\" alt=\"\" width=\"497\" height=\"373\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_5.jpeg 1032w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_5-450x338.jpeg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_5-768x576.jpeg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_5-1024x768.jpeg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_5-150x113.jpeg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_5-600x450.jpeg 600w\" sizes=\"(max-width: 497px) 100vw, 497px\" \/><p id=\"caption-attachment-213848\" class=\"wp-caption-text\"><em>Da esquerda para a direita: D\u00f3ris da OFS e a Irm\u00e3 Francine, Catequista Franciscana. No fundo aparece um &#8220;pano&#8221; trazido da Prelazia do Xingu e nele constam assinaturas de pessoas de v\u00e1rias comunidades onde foram realizadas consultas em prepara\u00e7\u00e3o ao S\u00ednodo para a Amaz\u00f4nia.<\/em><\/p><\/div>\n<p><b>Site Franciscanos: <\/b><i><span style=\"font-weight: 400;\">Fale sobre as novidades do S\u00ednodo? Como era a rotina dos trabalhos? Superou suas expectativas?<\/span><\/i><\/p>\n<p><b>Moema Miranda: <\/b><span style=\"font-weight: 400;\">Ah, com certeza, sim! Esse S\u00ednodo tem quatro elementos fundamentais. O primeiro \u00e9 um processo de escuta anterior realmente feito com muita gente. Cada um de n\u00f3s que esteve l\u00e1, trazia uma voz que nos transcendia. N\u00f3s sab\u00edamos que \u00e9ramos respons\u00e1veis por dar voz a muitas outras pessoas. Al\u00e9m disso, durante todo processo sinodal foram organizadas ora\u00e7\u00f5es, celebra\u00e7\u00f5es, ritos dos m\u00e1rtires na tenda da Casa Comum da Amaz\u00f4nia, em que durante todo esse processo houve a permeabilidade entre o que a gente pode chamar de fora e de dentro. Em todo o Brasil foram organizados momentos de celebra\u00e7\u00f5es e tr\u00edduos, e tudo isso chegou de uma Igreja que esteve em comunh\u00e3o, como se estivesse l\u00e1 na sala sinodal. Podemos dizer que as ora\u00e7\u00f5es chegaram ao S\u00ednodo. E isso nos deu uma grande responsabilidade na volta, porque sabemos que o S\u00ednodo foi um ponto de chegada, mas tamb\u00e9m \u00e9 um ponto de partida. O segundo, a presen\u00e7a dos povos ind\u00edgenas e uma mudan\u00e7a radical no reconhecimento do lugar deles. Depois que voltei de Roma, estava lendo sobre o trabalho realizado na Confer\u00eancia de Santo Domingo, em que o tema da incultura\u00e7\u00e3o e interculturalidade foram tratados, e tamb\u00e9m sobre todas as disputas que ali ocorreram entres os bispos e a C\u00faria Romana. Sobre essa discuss\u00e3o, Dom Erwin dizia que eles escreveram em um documento que a evangeliza\u00e7\u00e3o deve ser feita a partir das culturas. Ou seja, n\u00f3s queremos levar uma Boa Nova e uma evangeliza\u00e7\u00e3o que achata, nega e desconhece as culturas? Ou partimos das culturas? Elas j\u00e1 t\u00eam as sementes do verbo e a presen\u00e7a viva do Cristo. A partir da\u00ed n\u00f3s encontramos comunh\u00e3o, e assim a Igreja se fortalece e se torna mais cat\u00f3lica, pois ela se enriquece com todo esse processo que sempre foi assim desde o come\u00e7o. Isso n\u00e3o \u00e9 uma novidade da Amaz\u00f4nia. Se Paulo n\u00e3o tivesse ido conversar com os gregos e n\u00e3o tivesse traduzido do aramaico para o grego, e do grego para o latim, hoje a gente seria uma seita do meio Oriente. N\u00e3o existiria o cristianismo. Ent\u00e3o, esse processo de di\u00e1logo, onde a cultura que recebe a Boa-Nova \u00e9 o sujeito da incultura\u00e7\u00e3o, faz da Igreja Cat\u00f3lica uma Igreja Cat\u00f3lica! Desde o <\/span><i><span style=\"font-weight: 400;\">Instrumentum Laboris,<\/span><\/i><span style=\"font-weight: 400;\"> os povos ind\u00edgenas j\u00e1 eram reconhecidos como protagonistas, e no documento final essa realidade foi concretizada. Ent\u00e3o, a crise ambiental revela com mais for\u00e7a a relev\u00e2ncia dos povos ind\u00edgenas, porque eles sabem cuidar. \u00c9 um gesto de reconhecimento, de pedido de desculpa e de alian\u00e7a, mas uma alian\u00e7a que se faz com eles, os protagonistas. A presen\u00e7a dos povos ind\u00edgenas na sala sinodal foi marcante! Um l\u00edder da coordena\u00e7\u00e3o das entidades ind\u00edgenas, que estava como convidado especial, disse ao Papa que eles estavam <\/span><i><span style=\"font-weight: 400;\">\u201cempumados\u201d<\/span><\/i><span style=\"font-weight: 400;\"> (com penas) dentro do Vaticano. E o Papa com uma sensibilidade incr\u00edvel, disse que ao ouvir coment\u00e1rios negativos sobre alguns ind\u00edgenas que estavam usando as suas penas, ficou muito triste. \u2018Que diferen\u00e7a tem isso e o chap\u00e9u que a guarda su\u00ed\u00e7a usa?\u2019, perguntou o Papa. Ele \u00e9 uma pessoa fundamental nessa atitude do reconhecimento do protagonismo dos ind\u00edgenas e de colocar a Igreja como aliada. O terceiro aspecto \u00e9 a presen\u00e7a das mulheres, com sua relev\u00e2ncia, voz e for\u00e7a nas quest\u00f5es que foram tratadas. \u00c9 claro que o diaconato para as mulheres era uma reivindica\u00e7\u00e3o importante, que parte de um reconhecimento e de uma realidade a partir do que as mulheres j\u00e1 fazem na Amaz\u00f4nia. N\u00e3o teve ningu\u00e9m que trabalha na Amaz\u00f4nia que n\u00e3o tivesse falado sobre essa presen\u00e7a constante das mulheres. Embora esse ponto tenha ficado como indica\u00e7\u00e3o da retomada da comiss\u00e3o, a presen\u00e7a das mulheres na sala sinodal foi extremamente importante. E, por fim, destaco a possibilidade de um di\u00e1logo enriquecedor para todos entre a C\u00faria Romana, a tradi\u00e7\u00e3o e esses povos m\u00faltiplos que chegaram com suas vozes a partir de seus territ\u00f3rios, incluindo seus bispos. Sabemos que nem sempre esse encontro \u00e9 f\u00e1cil, sem atrito e sem tens\u00e3o. Mas o importante \u00e9 que se tenha a presen\u00e7a do Esp\u00edrito Santo, harmonizando essa voz para o bem maior da Igreja. E acho que isso n\u00f3s vivemos como uma experi\u00eancia sinodal da m\u00e1xima import\u00e2ncia.\u00a0<\/span><\/p>\n<p><b>Site Franciscanos: <\/b><i><span style=\"font-weight: 400;\">Quais s\u00e3o as tr\u00eas primeiras palavras que lhe v\u00eam \u00e0 mente quando voc\u00ea lembra do S\u00ednodo?\u00a0<\/span><\/i><\/p>\n<p><b>Moema Miranda: <\/b><span style=\"font-weight: 400;\">Em primeiro lugar, gratid\u00e3o por essa possibilidade de estar trilhando esse caminho. Em segundo lugar, resist\u00eancia e exist\u00eancia. Temos dito para os povos ind\u00edgenas que existir e resistir e \u00e9 <\/span><i><span style=\"font-weight: 400;\">reexistir<\/span><\/i><span style=\"font-weight: 400;\"> com \u201cx\u201d. Essa for\u00e7a que a morte n\u00e3o ter\u00e1 a \u00faltima palavra. Experi\u00eancia que n\u00f3s, mulheres, j\u00e1 fizemos aos p\u00e9s da cruz e que toda Igreja fez quando encontrou no Ressuscitado seu caminho, sua verdade e sua vida. E a terceira, talvez seja a alegria dessa possibilidade de, em um mundo dif\u00edcil, ter a alegria da for\u00e7a que vem da f\u00e9, da confian\u00e7a da presen\u00e7a de Deus, de saber que a gente n\u00e3o est\u00e1 sozinha. \u00c9 essa for\u00e7a da alegria que transforma e empurra o mundo para frente.\u00a0<\/span><\/p>\n<p><b>Site Franciscanos: <\/b><i><span style=\"font-weight: 400;\">Como \u00e9\u00a0 trabalho de uma auditora do S\u00ednodo?<\/span><\/i><\/p>\n<p><b>Moema Miranda: <\/b><span style=\"font-weight: 400;\">Todos que falavam na sala sinodal precisavam fazer previamente a inscri\u00e7\u00e3o de seus textos. Cada um s\u00f3 fala uma vez por quatro minutos. Eu, como auditora, ou um cardeal, ou um bispo, tem a palavra por uma vez durante quatro minutos. Ent\u00e3o, durante o debate na sala sinodal voc\u00ea n\u00e3o sabe quem vai falar antes de voc\u00ea nem depois. E a\u00ed, ap\u00f3s os quatro minutos de sua exorta\u00e7\u00e3o, faz-se quatro minutos de sil\u00eancio para que o pr\u00f3prio Esp\u00edrito Santo permita que aquelas falas sejam absorvidas e que a gente entre em um di\u00e1logo mais profundo. \u00c9 um di\u00e1logo n\u00e3o s\u00f3 entre n\u00f3s, mas tamb\u00e9m de cada um consigo mesmo. J\u00e1 nos c\u00edrculos (grupos) menores \u00e9 onde os di\u00e1logos s\u00e3o intensificados. Eram 12 c\u00edrculos organizados por l\u00ednguas onde tamb\u00e9m os auditores, peritos e os convidados especiais tiveram a oportunidade de interagir com os padres sinodais, embora s\u00f3 eles votassem. E puderam amadurecer a reflex\u00e3o neste processo de comunh\u00e3o. Partindo de uma din\u00e2mica que n\u00e3o foi confrontacional, mas sim acreditando que \u00e9 um momento \u00fanico com a presen\u00e7a do Esp\u00edrito Santo e que \u00e9 diferente de todas as outras experi\u00eancias de di\u00e1logo que a gente tem nos movimentos sociais, na sala de aula, no parlamento, ali tivemos a presen\u00e7a de uma for\u00e7a espiritual que vem da promessa de Cristo que disse a Madalena depois de ressuscitado: \u2018Vai e diga aos meus irm\u00e3os que me encontrem na Galileia\u201d. Isso mostra uma Igreja que busca caminhos e que tem a humildade de se colocar como aliada da terra, dos povos. Fomos aben\u00e7oados por termos participado de um momento t\u00e3o forte.<\/span><\/p>\n<div id=\"attachment_213849\" style=\"width: 460px\" class=\"wp-caption alignright\"><img aria-describedby=\"caption-attachment-213849\" loading=\"lazy\" class=\"wp-image-213849 size-medium\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_6-450x253.jpeg\" alt=\"\" width=\"450\" height=\"253\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_6-450x253.jpeg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_6-768x432.jpeg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_6-1024x576.jpeg 1024w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_6-150x84.jpeg 150w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_6.jpeg 1280w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><p id=\"caption-attachment-213849\" class=\"wp-caption-text\"><em>Papa Francisco concede sua b\u00ean\u00e7\u00e3o a Moema, durante o S\u00ednodo<\/em><\/p><\/div>\n<p><b>Site Franciscanos: <\/b><i><span style=\"font-weight: 400;\">Sobre o Papa Francisco, como foi estar pertinho dele? O que voc\u00ea acha dele?<\/span><\/i><\/p>\n<p><b>Moema Miranda: <\/b><span style=\"font-weight: 400;\">\u00c9 uma pessoa iluminada pelo Esp\u00edrito Santo! \u00c9 um homem com uma lucidez e uma for\u00e7a impressionante. Ao mesmo tempo uma consci\u00eancia sensacional ao mostrar que a comunica\u00e7\u00e3o n\u00e3o se faz do circuito do pensamento e da palavra, mas sim de toda a sua presen\u00e7a, de todo o seu corpo. Ele tem poesia, suavidade. O Papa Francisco recebe e acolhe todo mundo. Todos que quiseram tirar fotos, ele aceitou e, ao mesmo tempo, mostrou um compromisso com o todo o processo sinodal. Em todo tempo esteve presente, acompanhando, escutando, pensando e participando ativamente do processo de constru\u00e7\u00e3o, mostrando-se com uma simplicidade e uma consci\u00eancia de que ele \u00e9 um instrumento nas m\u00e3os de Deus. \u00c9 realmente comovente! Para n\u00f3s que estivemos pertinho dele, acho que a sa\u00edmos mais fortalecidos na f\u00e9. Esse \u00e9 o transbordamento da mensagem\u00a0 maravilhosa que pudemos ter. Pela sua humildade, ele se faz um com o Pai.<\/span><\/p>\n<p><b>Site Franciscanos: <\/b><i><span style=\"font-weight: 400;\">E sobre o protagonismo da mulher na Igreja, o que voc\u00ea teria a nos falar tendo em vista que foi uma das 35 mulheres que participaram do S\u00ednodo?<\/span><\/i><\/p>\n<p><b>Moema Miranda: <\/b><span style=\"font-weight: 400;\">O par\u00e1grafo 22 do documento final, fala da Igreja samaritana e apresenta a ideia de que n\u00f3s devemos ser uma Igreja Madalena e uma Igreja mariana. Uma igreja Madalena que foi acolhida e amada e a partir da\u00ed pode anunciar Jesus, morto e ressuscitado. Existe um longo percurso em que n\u00f3s mulheres seguimos e servimos desde a Galileia. Jesus foi um com as mulheres. Ele acolheu, escutou, e muito do que Ele veio a ser depois, aprendeu com as mulheres. Mulheres que ajudaram que o pr\u00f3prio mist\u00e9rio fosse se revelando para Ele. Que foram parteiras &#8211; a parteira n\u00e3o \u00e9 quem faz o filho &#8211; mas \u00e9 quem ajuda o filho a se fazer na luz. Acredito que as mulheres na Igreja, em um contexto muito machista, como continua sendo, em um contexto patriarcal e particularmente depois da modernidade em que o patriarcado \u00e9 uma das formas de explora\u00e7\u00e3o e de domina\u00e7\u00e3o funcionais, \u00e9 muito comovente que na Igreja se promova esse espa\u00e7o de abertura, reconquistado e conquistado a cada passo. N\u00e3o \u00e9 f\u00e1cil, n\u00e3o \u00e9 simples, ainda \u00e9 uma Igreja atrasada, isso \u00e9 indiscut\u00edvel, mas n\u00f3s precisamos assumir esse lado de sombra se queremos ir para a luz. As mulheres n\u00e3o foram chamadas para servir a Igreja e sim a Jesus. \u00c9 a Ele que n\u00f3s seguimos, e \u00e9 com Ele que n\u00f3s estamos comprometidas e sempre estivemos desde que sa\u00edmos da Galileia. Nesse momento, em que o feminic\u00eddio aumenta, ver a presen\u00e7a das mulheres lutando pela defesa da terra e da Casa Comum \u00e9 muito importante. Isso vai fazer da Igreja uma Igreja melhor. Isso precisa ser feito com cuidado e com carinho, porque eu sinto e vejo que esse \u00e9 um di\u00e1logo muito delicado inclusive para as mulheres na Igreja. Por outro lado, todo novo come\u00e7o tem certo medo. Dom Cl\u00e1udio afirmou que precisamos de novos caminhos e Jesus \u00e9 sempre o mesmo. Ele \u00e9 o novo. Ent\u00e3o, quando tivermos medo do novo pe\u00e7amos a Jesus que nos ajude a enfrentar esse medo para encontrar os novos caminhos necess\u00e1rios. A for\u00e7a das mulheres est\u00e1 sendo de imensa sabedoria, de afirma\u00e7\u00e3o e reconhecimento de trabalho em comunh\u00e3o.\u00a0<\/span><\/p>\n<div id=\"attachment_213847\" style=\"width: 900px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-213847\" loading=\"lazy\" class=\"wp-image-213847 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_4.jpg\" alt=\"\" width=\"890\" height=\"500\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_4.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_4-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_4-768x431.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_4-150x84.jpg 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><p id=\"caption-attachment-213847\" class=\"wp-caption-text\"><em>Papa Francisco e a presen\u00e7a das mulheres no S\u00ednodo<\/em><\/p><\/div>\n<p><b>Site Franciscanos: <\/b><i><span style=\"font-weight: 400;\">Que esperan\u00e7a tem ap\u00f3s o S\u00ednodo para a Amaz\u00f4nia? Quais os principais resultados?<\/span><\/i><\/p>\n<p><b>Moema Miranda: <\/b><span style=\"font-weight: 400;\">Essa \u00e9 uma quest\u00e3o fundamental. N\u00f3s estamos vivendo um momento muito s\u00e9rio em termos de risco para toda biosfera. Todo o debate no S\u00ednodo j\u00e1 come\u00e7ou com este sentido de urg\u00eancia. Na exorta\u00e7\u00e3o inicial de Dom Cl\u00e1udio Hummes, ele relembra que na Confer\u00eancia das Na\u00e7\u00f5es Unidas (COP 25),\u00a0 na Fran\u00e7a, um ministro disse que \u2018mais tarde pode ser tarde demais\u2019 se n\u00e3o nos preocuparmos com as quest\u00f5es ambientais e clim\u00e1ticas. Este sentido de urg\u00eancia, o Papa Francisco j\u00e1 tinha dito na Enc\u00edclica <\/span><i><span style=\"font-weight: 400;\">Laudato Si\u2019<\/span><\/i><span style=\"font-weight: 400;\">, que foi retomado na convoca\u00e7\u00e3o do S\u00ednodo para a Amaz\u00f4nia. Ent\u00e3o, Francisco numa de suas falas, afirmou que a raz\u00e3o da convoca\u00e7\u00e3o do S\u00ednodo foi uma intui\u00e7\u00e3o profunda que a Enc\u00edclica Laudato Si\u2019 precisava ter como um espa\u00e7o de teste, de comprova\u00e7\u00e3o do seu sentido mais profundo. A Amaz\u00f4nia \u00e9 este lugar. O sentido de urg\u00eancia muito claro em todo o debate e na prepara\u00e7\u00e3o do S\u00ednodo est\u00e1 plasmado logo na introdu\u00e7\u00e3o do documento final onde se apresenta a ideia de que n\u00f3s n\u00e3o estamos vivendo em um tempo comum, mas sim em um tempo muito especial. Nesse tempo, uma das quest\u00f5es fundamentais \u00e9 justamente a esperan\u00e7a e o futuro. Que esperan\u00e7a ter? E como\u00a0 n\u00e3o ter uma esperan\u00e7a que nos iluda de que se n\u00f3s ficarmos parados, deixando que tudo aconte\u00e7a, como sempre aconteceu, as coisas ter\u00e3o um resultado diferente? Essas s\u00e3o esperan\u00e7as que n\u00f3s, crist\u00e3os, n\u00e3o podemos ter, pois s\u00e3o muito perigosas. E por isso, \u00e9 preciso qualificar a esperan\u00e7a que n\u00f3s temos, e transform\u00e1-la em um compromisso em defesa da vida, da floresta, dos povos, tudo ao mesmo tempo, juntos e conectados. Defender os povos e as florestas para defender a nossa pr\u00f3pria vida. No documento tamb\u00e9m, por indica\u00e7\u00e3o dos cientistas presentes no S\u00ednodo, aparece a ideia da Amaz\u00f4nia como um \u00f3rg\u00e3o vital para todo o Planeta. Um dos cientistas disse: \u2018N\u00e3o pensem que a destrui\u00e7\u00e3o da floresta Amaz\u00f4nica tem import\u00e2ncia apenas para os povos amaz\u00f4nicos que vivem l\u00e1\u2019. Hoje n\u00f3s sabemos, pela ci\u00eancia do clima, que a destrui\u00e7\u00e3o de uma floresta como a Amaz\u00f4nica representa um desequil\u00edbrio para todo o Planeta. A esperan\u00e7a com que n\u00f3s sa\u00edmos do S\u00ednodo \u00e9 a esperan\u00e7a do compromisso, da alian\u00e7a e da convers\u00e3o. Convers\u00e3o \u00e9 a palavra central em todo documento. Se n\u00f3s reconhecemos o erro, o pecado ecol\u00f3gico, n\u00f3s temos a possibilidade de alterar o futuro e de nos comprometer\u00a0 com um futuro diferente que estamos construindo agora. Hoje, o cuidado com a Amaz\u00f4nia \u00e9 o cuidado com a vida no Planeta. Esse compromisso com o futuro da vida \u00e9 a maior esperan\u00e7a que tivemos ao sairmos do S\u00ednodo.\u00a0<\/span><\/p>\n<p><b>Site Franciscanos: <\/b><i><span style=\"font-weight: 400;\">Para finalizar, deixe uma mensagem!<\/span><\/i><\/p>\n<p><b>Moema Miranda: <\/b><span style=\"font-weight: 400;\">Por primeiro, agrade\u00e7o a voc\u00eas por essa entrevista. Gratid\u00e3o tamb\u00e9m pelas iniciativas que est\u00e3o sendo tomadas na divulga\u00e7\u00e3o do S\u00ednodo, pela conex\u00e3o e ora\u00e7\u00e3o. Mas a minha palavra final seria a seguinte: retomemos a nossa alian\u00e7a franciscana, retomemos o nosso compromisso e sejamos n\u00f3s, a partir de nosso carisma t\u00e3o importante nesse momento, atores, atrizes, irm\u00e3os e irm\u00e3s neste grande pacto pela Amaz\u00f4nia e pela vida. \u00c9 muito importante que n\u00f3s, franciscanos e franciscanas, assumamos a nossa responsabilidade neste momento. Particularmente, parabenizo voc\u00eas da Prov\u00edncia da Imaculada que s\u00e3o uma institui\u00e7\u00e3o muito importante em nosso pa\u00eds, com o protagonismo no compromisso, na convers\u00e3o e na alian\u00e7a com a Amaz\u00f4nia. Espero que n\u00f3s avancemos em muitas outras iniciativas de compromisso com o S\u00ednodo para a Amaz\u00f4nia com seus resultados e com seus desdobramentos. Paz e Bem!<\/span><\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-213846 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_3.jpg\" alt=\"\" width=\"890\" height=\"500\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_3.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_3-450x253.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_3-768x431.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_3-150x84.jpg 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevista Moema Miranda<\/p>\n","protected":false},"author":5,"featured_media":213850,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[758,1],"tags":[189,864,190,1535],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201c\u00c9 importante que n\u00f3s, franciscanos,\u00a0assumamos a nossa responsabilidade neste momento\u201d\u00a0 - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201c\u00c9 importante que n\u00f3s, franciscanos,\u00a0assumamos a nossa responsabilidade neste momento\u201d\u00a0 - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Entrevista Moema Miranda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-11T17:18:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-20T01:38:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"freiaugusto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"freiaugusto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"24 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_7.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_7.jpg\",\"width\":273,\"height\":181},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html\",\"name\":\"\u201c\u00c9 importante que n\u00f3s, franciscanos,\u00a0assumamos a nossa responsabilidade neste momento\u201d\u00a0 - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html#primaryimage\"},\"datePublished\":\"2019-11-11T17:18:34+00:00\",\"dateModified\":\"2021-04-20T01:38:47+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/37f88f0d111cd5358b12a6556a99eb91\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201c\u00c9 importante que n\u00f3s, franciscanos,\u00a0assumamos a nossa responsabilidade neste momento\u201d\u00a0\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/37f88f0d111cd5358b12a6556a99eb91\",\"name\":\"freiaugusto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9840b940e621801b24f3e6b059efb4b7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9840b940e621801b24f3e6b059efb4b7?s=96&d=mm&r=g\",\"caption\":\"freiaugusto\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/freiaugusto\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201c\u00c9 importante que n\u00f3s, franciscanos,\u00a0assumamos a nossa responsabilidade neste momento\u201d\u00a0 - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html","og_locale":"pt_BR","og_type":"article","og_title":"\u201c\u00c9 importante que n\u00f3s, franciscanos,\u00a0assumamos a nossa responsabilidade neste momento\u201d\u00a0 - Not\u00edcias - Franciscanos","og_description":"Entrevista Moema Miranda","og_url":"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2019-11-11T17:18:34+00:00","article_modified_time":"2021-04-20T01:38:47+00:00","og_image":[{"width":273,"height":181,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_7.jpg","type":"image\/jpeg"}],"author":"freiaugusto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"freiaugusto","Est. tempo de leitura":"24 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_7.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/11\/moema_111119_7.jpg","width":273,"height":181},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html","name":"\u201c\u00c9 importante que n\u00f3s, franciscanos,\u00a0assumamos a nossa responsabilidade neste momento\u201d\u00a0 - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html#primaryimage"},"datePublished":"2019-11-11T17:18:34+00:00","dateModified":"2021-04-20T01:38:47+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/37f88f0d111cd5358b12a6556a99eb91"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/e-muito-importante-que-nos-franciscanos-e-franciscanas-assumamos-a-nossa-responsabilidade-neste-momento.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"\u201c\u00c9 importante que n\u00f3s, franciscanos,\u00a0assumamos a nossa responsabilidade neste momento\u201d\u00a0"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/37f88f0d111cd5358b12a6556a99eb91","name":"freiaugusto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9840b940e621801b24f3e6b059efb4b7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9840b940e621801b24f3e6b059efb4b7?s=96&d=mm&r=g","caption":"freiaugusto"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/freiaugusto"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/213842"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=213842"}],"version-history":[{"count":2,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/213842\/revisions"}],"predecessor-version":[{"id":227228,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/213842\/revisions\/227228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/213850"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=213842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=213842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=213842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}