{"id":212684,"date":"2019-10-22T11:24:25","date_gmt":"2019-10-22T14:24:25","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=212684"},"modified":"2020-06-05T19:08:04","modified_gmt":"2020-06-05T22:08:04","slug":"sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html","title":{"rendered":"Intoler\u00e2ncia e viol\u00eancia: Est\u00e1tuas ind\u00edgenas s\u00e3o jogadas no Rio Tibre"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-224350\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/10\/pachamama.png\" alt=\"\" width=\"890\" height=\"502\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/10\/pachamama.png 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/10\/pachamama-450x254.png 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/10\/pachamama-768x433.png 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/10\/pachamama-150x85.png 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/p>\n<p>Dois homens, durante a madrugada, roubaram de Santa Maria em Traspontina, a par\u00f3quia romana mais pr\u00f3xima da Bas\u00edlica de S\u00e3o Pedro, na Via della Conciliazione, tr\u00eas est\u00e1tuas de madeira pertencentes \u00e0 exposi\u00e7\u00e3o dedicada ao S\u00ednodo sobre a Amaz\u00f4nia para depois jog\u00e1-las na rio Tibre.<\/p>\n<p>A raz\u00e3o para o gesto &#8211; documentado por um v\u00eddeo no YouTube gravado pelos pr\u00f3prios autores, intitulado &#8220;Pachamama idols thrown into the Tiber river!&#8221; &#8211; \u00e9 uma &#8220;repara\u00e7\u00e3o&#8221; para os supostos danos causados \u200b\u200ba Jesus e \u00e0 Igreja pelas tr\u00eas est\u00e1tuas que retratam uma mulher nua e gr\u00e1vida, de tra\u00e7os ind\u00edgenas, de joelhos, com a barriga vermelha para simbolizar a vida que carrega no colo.<\/p>\n<p>Um dos homens, de camisa azul listrada, enquanto o outro gravava com seu smartphone o v\u00eddeo que se tornou viral, entrou nos altares laterais da par\u00f3quia &#8211; onde estavam colocados outros s\u00edmbolos da \u201ccuenca amaz\u00f4nica\u201d, como remos, panos, fotografias miniaturas de canoas e papagaios &#8211; e, furtivamente, levou para fora as tr\u00eas esculturas segurando-as firmemente contra o peito. Em alguns segundos, chegou \u00e0 famosa ponte de Castel Sant&#8217;Angelo, de onde jogou as est\u00e1tuas no rio com um gesto seco e arrogante.<\/p>\n<p>Como se isso n\u00e3o bastasse, por volta das 10h30, dois outros homens (provavelmente os mesmos do v\u00eddeo) retornaram a Traspontina para concluir a obra, roubando a est\u00e1tua maior e afogando-a no Tibre para assim &#8220;salvar&#8221; a Igreja e o mundo. Os dois foram prontamente parados e denunciados \u00e0 pol\u00edcia pelo padre Antonio Soffiantini, respons\u00e1vel pela exibi\u00e7\u00e3o da associa\u00e7\u00e3o &#8220;Casa Comum&#8221;, que permanecer\u00e1 aberta at\u00e9 a conclus\u00e3o dos trabalhos sinodais. &#8220;Ficamos sabendo do roubo desta manh\u00e3 atrav\u00e9s das m\u00eddias sociais, ficamos atentos e notamos imediatamente que outros dois sujeitos estavam tentando roubar a est\u00e1tua maior. Alertamos a pol\u00edcia e eu pr\u00f3prio os denunciei&#8221;, explica o padre ao Vatican Insider.<\/p>\n<p>A associa\u00e7\u00e3o &#8220;Casa Comum&#8221;, ligada \u00e0 Repam, a rede pan-amaz\u00f4nica de bispos, religiosos e leigos que contribuiu para a organiza\u00e7\u00e3o do S\u00ednodo, agora pede ajuda \u00e0 Pol\u00edcia para vigiar os \u00faltimos dias da reuni\u00e3o e impedir que outros imitem o gesto.<\/p>\n<p>A criar quase uma psicose contra essa escultura que parece retratar a &#8220;Pachamama&#8221;, a m\u00e3e terra, cuja sacralidade est\u00e1 enraizada nas culturas amaz\u00f4nicas, ou uma Nossa Senhora de tra\u00e7os ind\u00edgenas, foram sites e blogs de vi\u00e9s conservador. Desde o in\u00edcio da assembleia no Vaticano, esses canais &#8220;denunciaram&#8221; a conota\u00e7\u00e3o (em sua opini\u00e3o) blasfema da imagem de madeira que, em 4 de outubro passado, havia sido levada aos Jardins do Vaticano para a cerim\u00f4nia presidida pelo Papa com um grupo de ind\u00edgenas \u00e0s v\u00e9speras da abertura do S\u00ednodo.<\/p>\n<p>Os mesmos locais tamb\u00e9m espalharam informa\u00e7\u00f5es tendenciosas sobre celebra\u00e7\u00f5es id\u00f3latras na par\u00f3quia de Traspontina, durante as quais os \u00edndios teriam se prostrado diante da ef\u00edgie, embora essas fossem autorizados e sempre presenciadas pelo p\u00e1roco.<\/p>\n<p><iframe loading=\"lazy\" title=\"Pachamama idols thrown into the Tiber river!\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/xoB_gjuZgf8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Nessas mesmas p\u00e1ginas, agora se podem encontrar t\u00edtulos alegres (&#8220;Justi\u00e7a \u00e9 feita&#8221;) que elogiam o gesto dos dois &#8220;cat\u00f3licos corajosos&#8221;. Tamb\u00e9m \u00e9 relan\u00e7ado o v\u00eddeo do que foi um roubo, conforme definido pelo Prefeito do Dicast\u00e9rio da Comunica\u00e7\u00e3o, Paolo Ruffini, que durante o briefing di\u00e1rio na Sala de Imprensa sobre o trabalho do S\u00ednodo &#8211; perguntado a respeito &#8211; disse: \u201c\u00c9 um roubo que fala por si\u201d. &#8220;Acredito que roubar algo de um lugar e jog\u00e1-lo fora \u00e9 uma bravata. J\u00e1 repetimos v\u00e1rias vezes que aquelas est\u00e1tuas representavam a vida, a terra, a fertilidade. O gesto contradiz o esp\u00edrito de di\u00e1logo que deveria animar todos&#8221;.<\/p>\n<p>J\u00e1 nos briefings anteriores, Ruffini havia se expressado sobre a quest\u00e3o da est\u00e1tua, respondendo \u00e0s perguntas insistentes de um site estadunidense &#8211; que no ano passado se destacara pelos cont\u00ednuos ataques ao Papa Francisco -, que promoveu a cruzada contra as esculturas \u201cde significado misterioso&#8221;, chegando a pedir &#8220;uma interven\u00e7\u00e3o com autoridade&#8221; por parte da Santa S\u00e9. Em particular, se solicitava um esclarecimento sobre o fato de que seria uma representa\u00e7\u00e3o pag\u00e3 ou uma representa\u00e7\u00e3o inapropriada de Nossa Senhora.<\/p>\n<p>&#8220;Sabemos que algumas coisas na hist\u00f3ria podem ter diferentes interpreta\u00e7\u00f5es &#8211; disse Ruffini -, mesmo nas igrejas voc\u00ea pode encontrar coisas que v\u00eam do passado, mas acredito que a est\u00e1tua representasse banalmente a vida, e pronto, enquanto procurar s\u00edmbolos de paganismo \u00e9 ver o mal onde n\u00e3o mal n\u00e3o existe\u201d.<\/p>\n<p>Palavras que Ruffini reafirmou mesmo nos dias seguintes, mas que parecem n\u00e3o ter sido suficientes para a blogosfera conservadora que levou adiante a sua campanha. Muito menos para os dois autores daquela que foi muito mais que uma &#8220;travessura&#8221;. Al\u00e9m disso, realizada na Igreja.<\/p>\n<p>A reportagem \u00e9 de Salvatore Cernuzio, publicada por La Stampa, 21-10-2019. A tradu\u00e7\u00e3o \u00e9 de Luisa Rabolini (http:\/\/www.ihu.unisinos.br).<\/p>\n<h3><strong>S\u00e3o Jo\u00e3o Newman e as est\u00e1tuas jogadas no rio Tibre<\/strong><\/h3>\n<p>Andrea Tornielli, do Vatican News, lembra que o roubo e o ato de jogar no rio Tibre as tr\u00eas est\u00e1tuas de madeira que representavam mulheres ind\u00edgenas gr\u00e1vidas, constituem um triste epis\u00f3dio, que fala por si s\u00f3. Impressiona algumas das rea\u00e7\u00f5es a este gesto violento e intolerante: \u201cfoi feita justi\u00e7a\u201d, foi a manchete entusiasmada de um site italiano, depois que as imagens do roubo gravadas pelos autores foram publicadas nas redes sociais. Em nome da tradi\u00e7\u00e3o e da doutrina jogou-se fora, com desprezo, uma ef\u00edgie da maternidade e da sacralidade da vida. Um s\u00edmbolo tradicional para os povos ind\u00edgenas que representa a liga\u00e7\u00e3o com a nossa \u201cm\u00e3e terra\u201d, assim definida por S\u00e3o Francisco de Assis no seu C\u00e2ntico das Criaturas.<\/p>\n<p>Ou\u00e7a e compartilhe!<br \/>\nAos novos iconoclastas, passados do \u00f3dio lan\u00e7ado nas redes sociais \u00e0 a\u00e7\u00e3o, poderia ser \u00fatil reler o que afirmou um dos novos santos canonizados poucos dias atr\u00e1s, o cardeal Jo\u00e3o Newman. Na sua obra Essay on the Development of Christian Doctrine, publicada em 1878, a prop\u00f3sito da ado\u00e7\u00e3o por parte da Igreja de elementos pag\u00e3os, o santo escrevia: \u201cO emprego de templos, e estes dedicados a certos santos, e enfeitados em ocasi\u00f5es com ramos de \u00e1rvores; incenso, l\u00e2mpadas e velas; promessas para cura de doen\u00e7as; \u00e1gua benta; asilos; dias santos e esta\u00e7\u00f5es, uso de calend\u00e1rios, prociss\u00f5es, b\u00ean\u00e7\u00e3os dos campos, vestimentas sacerdotais, a tonsura, o anel nos casamentos, o virar-se para o Oriente, imagens numa data ulterior, talvez o cantoch\u00e3o e o Kyrie Eleison, s\u00e3o todos de origem pag\u00e3 e santificados pela sua ado\u00e7\u00e3o na Igreja\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00ednodo para a Amaz\u00f4nia<\/p>\n","protected":false},"author":3,"featured_media":224351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[1535],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Intoler\u00e2ncia e viol\u00eancia: Est\u00e1tuas ind\u00edgenas s\u00e3o jogadas no Rio Tibre - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intoler\u00e2ncia e viol\u00eancia: Est\u00e1tuas ind\u00edgenas s\u00e3o jogadas no Rio Tibre - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"S\u00ednodo para a Amaz\u00f4nia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-22T14:24:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-05T22:08:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/10\/pachamama_p.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/10\/pachamama_p.png\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/10\/pachamama_p.png\",\"width\":800,\"height\":599},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html\",\"name\":\"Intoler\u00e2ncia e viol\u00eancia: Est\u00e1tuas ind\u00edgenas s\u00e3o jogadas no Rio Tibre - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html#primaryimage\"},\"datePublished\":\"2019-10-22T14:24:25+00:00\",\"dateModified\":\"2020-06-05T22:08:04+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intoler\u00e2ncia e viol\u00eancia: Est\u00e1tuas ind\u00edgenas s\u00e3o jogadas no Rio Tibre\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intoler\u00e2ncia e viol\u00eancia: Est\u00e1tuas ind\u00edgenas s\u00e3o jogadas no Rio Tibre - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html","og_locale":"pt_BR","og_type":"article","og_title":"Intoler\u00e2ncia e viol\u00eancia: Est\u00e1tuas ind\u00edgenas s\u00e3o jogadas no Rio Tibre - Not\u00edcias - Franciscanos","og_description":"S\u00ednodo para a Amaz\u00f4nia","og_url":"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2019-10-22T14:24:25+00:00","article_modified_time":"2020-06-05T22:08:04+00:00","og_image":[{"width":800,"height":599,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/10\/pachamama_p.png","type":"image\/png"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/10\/pachamama_p.png","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/10\/pachamama_p.png","width":800,"height":599},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html","name":"Intoler\u00e2ncia e viol\u00eancia: Est\u00e1tuas ind\u00edgenas s\u00e3o jogadas no Rio Tibre - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html#primaryimage"},"datePublished":"2019-10-22T14:24:25+00:00","dateModified":"2020-06-05T22:08:04+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/sinodo-intolerancia-e-violencia-com-estatuas-indigenas-no-rio-tibre.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Intoler\u00e2ncia e viol\u00eancia: Est\u00e1tuas ind\u00edgenas s\u00e3o jogadas no Rio Tibre"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/212684"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=212684"}],"version-history":[{"count":2,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/212684\/revisions"}],"predecessor-version":[{"id":224353,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/212684\/revisions\/224353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/224351"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=212684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=212684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=212684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}