{"id":204047,"date":"2019-04-28T14:25:48","date_gmt":"2019-04-28T17:25:48","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=204047"},"modified":"2019-04-29T14:16:13","modified_gmt":"2019-04-29T17:16:13","slug":"romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html","title":{"rendered":"Romaria da Diocese de Colatina lembra trag\u00e9dia de Brumadinho"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone wp-image-204048 size-full\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904.jpg\" alt=\"\" width=\"890\" height=\"593\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904-450x300.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904-768x512.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904-150x100.jpg 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/p>\n<p><strong>Moacir Beggo<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Vila Velha (ES)<\/strong> &#8211; A Diocese de Colatina foi a \u00faltima do Estado a subir o Morro da Penha neste domingo, 28 de abril, para prestar sua homenagem \u00e0 Padroeira do Estado do Esp\u00edrito Santo, Nossa Senhora da Penha. Cerca de 30 \u00f4nibus, com devotos de todas as 31 par\u00f3quias, vieram do Norte do Estado com o bispo diocesano Dom Joaquim Wladimir Lopes Dias. \u00c0s 7 horas, os romeiros subiram cantando e rezando o Morro da Penha e, \u00e0s 8 horas, D. Joaquim presidiu a Celebra\u00e7\u00e3o Eucar\u00edstica. Entre as 31 Par\u00f3quias, est\u00e1 a de Santa Clara, que \u00e9 assistida pelos frades da Prov\u00edncia da Imaculada: Frei Roberto Aparecido Pereira, Frei Jeferson Broca, Frei Jo\u00e3o Lopes da Silva e Frei Danilo.<\/p>\n<p>Dom Joaquim lembrou a todos que a Diocese de Colatina est\u00e1 na 29\u00aa Romaria Diocesana ao Convento da Penha e &#8220;vem com o cora\u00e7\u00e3o cheio de esperan\u00e7a e alegria participar do Oitav\u00e1rio em prepara\u00e7\u00e3o para Festa da Padroeira do nosso Estado&#8221;.<\/p>\n<p>Ele recordou que a Diocese est\u00e1 celebrando o Ano Mission\u00e1rio Diocesano. &#8220;Que possamos sair daqui mais mission\u00e1rios&#8221;, pediu.\u00a0A Diocese de Colatina prestou uma homenagem \u00e0s v\u00edtimas das trag\u00e9dias de Mariana e Brumadinho, ocorridas em novembro de 2015 e janeiro de 2019, respectivamente. Os bombeiros capixabas e todos que auxiliaram e trabalharam nos resgates e salvamentos de Brumadinho, tamb\u00e9m foram homenageados.<\/p>\n<p>Para lembrar as v\u00edtimas, um hino que relata os motivos e consequ\u00eancias das duas trag\u00e9dias foi cantado, enquanto eram levados ao altar uma faixa lembrando que todos fomos atingidos, um barco, que representou os pescadores que viviam da pesca no Rio Doce, e um cora\u00e7\u00e3o na cor marrom, mesma cor da lama que fez centenas de v\u00edtimas. Rosas vermelhas e brancas foram colocadas no cora\u00e7\u00e3o, oferecido a Nossa Senhora da Penha.<\/p>\n<p>&#8220;Sa\u00fado os militares do Corpo de Bombeiros do Estado do Esp\u00edrito Santo aqui presentes, dentre os quais alguns que atuaram com valentia em Brumadinho. E aqui, hoje, nossa Diocese presta uma homenagem de reconhecimento e gratid\u00e3o&#8221;, disse. A trag\u00e9dia de Brumadinho fez 179 mortos e, ao menos, 131 pessoas seguem desaparecidas.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-204049\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904_fra.jpg\" alt=\"\" width=\"890\" height=\"395\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904_fra.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904_fra-450x200.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904_fra-768x341.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904_fra-150x67.jpg 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/p>\n<p>Na sua homilia, destacou que este 2\u00ba Domingo de P\u00e1scoa \u00e9 tamb\u00e9m denominado como o &#8220;Domingo da Divina Miseric\u00f3rdia&#8221;. &#8220;Como \u00e9 bonita essa realidade de f\u00e9 para a nossa vida! Como \u00e9 grande e profundo o amor de Deus por n\u00f3s! \u00c9 um amor que n\u00e3o falha. Que sempre segura as nossas m\u00e3os, nos sustenta, levanta e guia. \u00c9 a m\u00e3o de Deus. No evangelho de hoje, Tom\u00e9 experimenta precisamente a miseric\u00f3rdia de Deus, que tem o rosto concreto em Jesus. O rosto de Jesus Ressuscitado. Tom\u00e9 n\u00e3o confia nos demais ap\u00f3stolos quando lhe dizem: &#8216;vimos o Senhor&#8217;. Para ele, n\u00e3o foi suficiente a promessa de Jesus, que anunciara: ao terceiro dia ressuscitarei. Tom\u00e9 quer ver, tocar as suas m\u00e3os, no sinal dos cravos e no peito. E qual \u00e9 a rea\u00e7\u00e3o de Jesus? A paci\u00eancia&#8221;, explicou Dom Joaquim.<\/p>\n<p>Segundo o bispo, Deus n\u00e3o abandona Tom\u00e9 relutante na sua incredulidade. &#8220;D\u00e1-lhe uma semana de tempo, n\u00e3o fecha a porta e espera. E Tom\u00e9 acaba por reconhecer a sua pr\u00f3pria pobreza e sua pouca f\u00e9, diz: &#8216;Meu Senhor e Meu Deus!&#8217; Com essa invoca\u00e7\u00e3o simples, mas carregada de f\u00e9, responde \u00e0 paci\u00eancia de Deus. Deixa-se envolver pela miseric\u00f3rdia divina, v\u00ea as feridas das m\u00e3os e dos p\u00e9s, do peito aberto, e readquire a confian\u00e7a. \u00c9 um homem novo e n\u00e3o mais incr\u00e9dulo&#8221;, acrescentou.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-204050\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_4.jpg\" alt=\"\" width=\"890\" height=\"593\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_4.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_4-450x300.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_4-768x512.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_4-150x100.jpg 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/p>\n<p>&#8220;Irm\u00e3os e irm\u00e3s, n\u00e3o percamos a confian\u00e7a na paciente miseric\u00f3rdia de Deus. Este \u00e9 o estilo de Deus. N\u00e3o \u00e9 impaciente como n\u00f3s, que muitas vezes queremos tudo e rapidamente. Mesmo quando se trata de pessoas. Deus \u00e9 paciente conosco porque nos ama. E quem ama compreende, d\u00e1 confian\u00e7a, n\u00e3o abandona, n\u00e3o constr\u00f3i muros, mas sabe perdoar, sabe esperar. Na nossa vida de disc\u00edpulos batizados, Deus sempre espera por n\u00f3s, mesmo quando nos afastamos. Ele sempre est\u00e1 pronto para nos acolher e abra\u00e7ar. Jesus mostra essa paci\u00eancia misericordiosa de Deus, para sempre reencontrarmos paci\u00eancia e confian\u00e7a Nele. Deus responde \u00e0 nossa fraqueza, ao nosso des\u00e2nimo com a paci\u00eancia. Esse \u00e9 o motivo da nossa esperan\u00e7a e alegria no Senhor. A paci\u00eancia de Deus deve encontrar em n\u00f3s a coragem de regressar ele, qualquer que seja o erro, o pecado da nossa vida&#8221;, completou.<\/p>\n<p>Atualmente, a Diocese de Colatina abrange 17 munic\u00edpios do norte capixaba: Aracruz, Baixo Guandu, Colatina, Governador Lindenberg, Ibira\u00e7u, Itagua\u00e7u, Itarana, Jo\u00e3o Neiva, Laranja da Terra, Linhares, Maril\u00e2ndia, Pancas, Rio Bananal, Santa Teresa, S\u00e3o Domingos do Norte, S\u00e3o Roque do Cana\u00e3 e Sooretama. As 31 par\u00f3quias est\u00e3o divididas em cinco \u00e1reas pastorais: de Colatina, do Caf\u00e9, BR-101 Norte, BR-101 Sul e Linha Ita.<\/p>\n<hr \/>\n<h2><img loading=\"lazy\" class=\"alignnone size-full wp-image-204051\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419.jpg\" alt=\"\" width=\"890\" height=\"668\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419-450x338.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419-768x576.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419-150x113.jpg 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/h2>\n<h2>Romaria dos Motociclistas: prece pela prote\u00e7\u00e3o no tr\u00e2nsito<\/h2>\n<p>Cerca de 7 mil motociclistas participaram da Romaria dos Motociclistas na manh\u00e3 deste domingo (28), segundo a organiza\u00e7\u00e3o da Festa da Penha. A romaria come\u00e7ou por volta das \u00a09h30, na Pra\u00e7a Costa Pereira, Centro de Vit\u00f3ria, e seguiu para o Parque da Prainha, em Vila Velha, quando foram recebidos, \u00e0s 10 horas, pelos freis Pedro Oliveira, Danilo Santos Oliveira e Felipe Carretta.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-204052\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_1.jpg\" alt=\"\" width=\"890\" height=\"561\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_1.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_1-450x284.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_1-768x484.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_1-150x95.jpg 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/p>\n<p>Em forma de ora\u00e7\u00e3o, Frei Pedro conseguiu silenciar a Prainha para fazerem uma ora\u00e7\u00e3o com ele, pedindo prote\u00e7\u00e3o no tr\u00e2nsito. O frade pediu que os motociclistas tirassem as chaves da igni\u00e7\u00e3o e levantassem bem alto em dire\u00e7\u00e3o \u00e0 imagem de Nossa Senhora para rezarem: &#8220;M\u00e3e, erguendo essas chaves, eu confio a ti a minha vida. Confio a ti, meu ve\u00edculo. Pe\u00e7o que me conduza onde eu estiver. Pe\u00e7o M\u00e3e, que, com teu olhar terno e doce, me conduza, me acompanhe, me proteja n\u00e3o s\u00f3 a mim, mas a todos que comigo estiverem, de todo e qualquer acidente, de todos os inimigos do tr\u00e2nsito. M\u00e3e, Virgem da Penha, M\u00e3e das Alegrias, te pe\u00e7o, n\u00e3o me abandoneis. Me acompanhe e me proteja!&#8221;, rezou, pedindo que rezassem em sil\u00eancio por alguns segundos: &#8220;O que voc\u00eas gostariam de pedir \u00e0 M\u00e3e?&#8221;. E Frei Pedro conseguiu o &#8220;milagre&#8221; de deixar a Prainha em sil\u00eancio.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-204053\" src=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_3.jpg\" alt=\"\" width=\"890\" height=\"593\" srcset=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_3.jpg 890w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_3-450x300.jpg 450w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_3-768x512.jpg 768w, https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/motos_290419_3-150x100.jpg 150w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/p>\n<p>Depois, os motociclistas foram convidados a homenagearam Nossa Senhora com buzina\u00e7o. Com os capacetes e chaves erguidos, receberam a \u00e1gua benta aspergida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Festa da Penha 2019<\/p>\n","protected":false},"author":3,"featured_media":204054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[245],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Romaria da Diocese de Colatina lembra trag\u00e9dia de Brumadinho - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Romaria da Diocese de Colatina lembra trag\u00e9dia de Brumadinho - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Festa da Penha 2019\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-28T17:25:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-29T17:16:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904d.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904d.jpg\",\"width\":273,\"height\":182},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html\",\"name\":\"Romaria da Diocese de Colatina lembra trag\u00e9dia de Brumadinho - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html#primaryimage\"},\"datePublished\":\"2019-04-28T17:25:48+00:00\",\"dateModified\":\"2019-04-29T17:16:13+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Romaria da Diocese de Colatina lembra trag\u00e9dia de Brumadinho\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Romaria da Diocese de Colatina lembra trag\u00e9dia de Brumadinho - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html","og_locale":"pt_BR","og_type":"article","og_title":"Romaria da Diocese de Colatina lembra trag\u00e9dia de Brumadinho - Not\u00edcias - Franciscanos","og_description":"Festa da Penha 2019","og_url":"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2019-04-28T17:25:48+00:00","article_modified_time":"2019-04-29T17:16:13+00:00","og_image":[{"width":273,"height":182,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904d.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904d.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/04\/colatina_2904d.jpg","width":273,"height":182},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html","name":"Romaria da Diocese de Colatina lembra trag\u00e9dia de Brumadinho - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html#primaryimage"},"datePublished":"2019-04-28T17:25:48+00:00","dateModified":"2019-04-29T17:16:13+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/romaria-da-diocese-de-colatina-lembra-tragedia-de-brumadinho.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Romaria da Diocese de Colatina lembra trag\u00e9dia de Brumadinho"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/204047"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=204047"}],"version-history":[{"count":0,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/204047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/204054"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=204047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=204047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=204047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}