{"id":195566,"date":"2019-01-20T15:30:02","date_gmt":"2019-01-20T17:30:02","guid":{"rendered":"https:\/\/franciscanos.org.br\/noticias\/?p=195566"},"modified":"2019-01-22T15:35:47","modified_gmt":"2019-01-22T17:35:47","slug":"carta-da-ofs-sobre-o-desarmamento","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html","title":{"rendered":"Carta da OFS sobre o desarmamento"},"content":{"rendered":"<p style=\"text-align: right;\"><em>Como portadores de PAZ e lembrando-se de que ela deve ser constru\u00edda incessantemente, procurem os caminhos da unidade e dos entendimentos fraternos mediante o di\u00e1logo, confiantes na presen\u00e7a do germe divino que existe no homem e na for\u00e7a transformadora do amor e do perd\u00e3o. (<strong>Regra19<\/strong>)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-177337\" src=\"https:\/\/vidacrista.franciscanos.org.br\/wp-content\/uploads\/2019\/01\/sultao_francisco_200119.jpg\" alt=\"\" width=\"890\" height=\"482\" \/><\/p>\n<p><strong>Rio de Janeiro, 19 de janeiro de 2019<\/strong><\/p>\n<p>Vivemos tempos confusos, nos quais o nosso posicionamento de f\u00e9 precisa ser bem claro e prof\u00e9tico; e nada melhor que ir \u00e0s fontes de nosso carisma para saborear a viv\u00eancia dos que nos antecederam e, assim, encontrar fertilidade nos momentos de deserto.<\/p>\n<p>Revisitamos, portanto, a nossa primeira Regra da Ordem Franciscana Secular<em>, Memoriale Propositi<\/em>, de 1221, na qual somos conclamados a <strong><em>n\u00e3o receber e nem levarmos conosco armas mortais contra quem quer que seja.<\/em><\/strong> Contemplamos, assim, um dos nossos maiores tesouros pelos s\u00e9culos de franciscanismo: uma postura de Paz e contra o armamento, claramente inspirada em Francisco de Assis.<\/p>\n<p>Em mem\u00f3ria bem mais recente, ouvimos ecoar as palavras do nosso ent\u00e3o ministro nacional, Jos\u00e9 Carlos Andrade, que nos exortava a respeito da cultura da Paz por ocasi\u00e3o do referendo sobre desarmamento da popula\u00e7\u00e3o por meio da circular 11, do dia 27 de agosto de 2005. Assim nos disse: <strong><em>&#8220;Devemos criar cada vez mais uma cultura de paz. Todos os franciscanos t\u00eam um des\u00edgnio de paz para o mundo. A paz faz parte da identidade dos franciscanos, que usam a Paz e o Bem como forma de sauda\u00e7\u00e3o. Devemos em todo o tempo defender firmemente a paz. A ORDEM FRANCISCANA SECULAR deve defender, propagar e buscar sempre o caminho da paz, da unidade e dos entendimentos fraternos mediante o di\u00e1logo.&#8221;<\/em><\/strong><\/p>\n<p>Como base para sua circular, usou a Campanha da Fraternidade Ecum\u00eanica de 2005, com o tema <strong>\u201cSolidariedade e Paz\u201d,<\/strong> que incentivou as Igrejas no Brasil a se unirem na ora\u00e7\u00e3o e na promo\u00e7\u00e3o da cultura de paz, e a <strong>NOTA e<\/strong>mitida pela 43\u00aa Assembleia Geral da CNBB, realizada em Itaici\u2013 SP, de 9 a 17 de agosto de 2005, a respeito do <strong><em>Referendo sobre a proibi\u00e7\u00e3o do com\u00e9rcio de armas de fogo e muni\u00e7\u00e3o<\/em><\/strong>, que aconteceu no dia 23 de outubro daquele ano, quando na ocasi\u00e3o o povo foi convocado a se pronunciar sobre o aludido desarmamento. Os Bispos reunidos nesta Assembleia se posicionaram <strong><em>a favor da proibi\u00e7\u00e3o do com\u00e9rcio de armas de fogo e muni\u00e7\u00e3o<\/em><\/strong> em todo o territ\u00f3rio nacional. E conclamaram os crist\u00e3os e todas as pessoas de boa vontade a votar <strong>SIM<\/strong> neste Referendo.<\/p>\n<p>Da mesma forma, ao final da circular, nosso irm\u00e3o Jos\u00e9 Carlos exortou a todos os irm\u00e3os e irm\u00e3s da Ordem Franciscana Secular do Brasil, em uni\u00e3o com toda a Igreja, a se posicionar em favor da proibi\u00e7\u00e3o do com\u00e9rcio de armas de fogo e muni\u00e7\u00e3o. E, da mesma forma, nos <strong>CONCLAMOU<\/strong> a votarmos <strong>SIM<\/strong> pelo desarmamento.<\/p>\n<p>Novamente estamos sendo desafiados a darmos uma resposta firme em favor da Paz. Nosso lema e sauda\u00e7\u00e3o nos impulsiona a dizermos <strong>SIM<\/strong> \u00e0 vida e <strong>N\u00c3O <\/strong>\u00e0s armas e, por for\u00e7a de nosso carisma, n\u00e3o cabe qualquer outra interpreta\u00e7\u00e3o diferente desta.<\/p>\n<p>Nos preparativos para a celebra\u00e7\u00e3o dos 800 anos do encontro entre Francisco de Assis e o Sult\u00e3o Malek Al-Kamil recordemos a for\u00e7a do encontro e do di\u00e1logo do Pobrezinho de Assis que marcou para sempre a hist\u00f3ria da humanidade com seu cora\u00e7\u00e3o livre e suas m\u00e3os desarmadas.<\/p>\n<p>Fraternalmente e, \u00e0 exemplo do Ser\u00e1fico Pai, <em>&#8220;comecemos, irm\u00e3os, a servir ao Senhor nosso Deus, porque at\u00e9 agora pouco resultado obtivemos&#8221; (<\/em>LM XIV 1,3)<\/p>\n<p><strong>Maria Jos\u00e9 Coelho<\/strong>, Ministra Nacional<\/p>\n<p><strong>H\u00e9lio Gouv\u00eaa<\/strong>, coordenador JPIC<\/p>\n<h6><strong> <img loading=\"lazy\" class=\"alignleft wp-image-177339 size-full\" src=\"https:\/\/vidacrista.franciscanos.org.br\/wp-content\/uploads\/2019\/01\/download.jpg\" alt=\"\" width=\"334\" height=\"134\" \/><\/strong><\/h6>\n<h6><\/h6>\n<h6><strong>Ordem Franciscana Secular do Brasil<br \/>\n<\/strong>Rua Adro de S\u00e3o Francisco, s\/n, Sa\u00fade. Zona Portu\u00e1ria, Rio de Janeiro &#8211; RJ. CEP 20081-290<br \/>\nFone: +55 (21) 2240-4565. Email: ofsbr@terra.com.br \/ comunicacaoofsbr@gmail.com<br \/>\nSite: www.ofs.org.br<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Como portadores de PAZ e lembrando-se de que ela deve ser constru\u00edda incessantemente, procurem os caminhos da unidade e dos entendimentos fraternos mediante o di\u00e1logo, confiantes na presen\u00e7a do germe divino que existe no homem e na for\u00e7a transformadora do amor e do perd\u00e3o. (Regra19) &nbsp; Rio de Janeiro, 19 de janeiro de 2019 Vivemos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":195572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[1273],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta da OFS sobre o desarmamento - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta da OFS sobre o desarmamento - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Como portadores de PAZ e lembrando-se de que ela deve ser constru\u00edda incessantemente, procurem os caminhos da unidade e dos entendimentos fraternos mediante o di\u00e1logo, confiantes na presen\u00e7a do germe divino que existe no homem e na for\u00e7a transformadora do amor e do perd\u00e3o. (Regra19) &nbsp; Rio de Janeiro, 19 de janeiro de 2019 Vivemos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-20T17:30:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-22T17:35:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/01\/sultao_francisco_200119.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moacir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"moacir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/01\/sultao_francisco_200119.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/01\/sultao_francisco_200119.jpg\",\"width\":273,\"height\":181},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html\",\"name\":\"Carta da OFS sobre o desarmamento - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html#primaryimage\"},\"datePublished\":\"2019-01-20T17:30:02+00:00\",\"dateModified\":\"2019-01-22T17:35:47+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta da OFS sobre o desarmamento\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4\",\"name\":\"moacir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g\",\"caption\":\"moacir\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/moacir\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta da OFS sobre o desarmamento - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html","og_locale":"pt_BR","og_type":"article","og_title":"Carta da OFS sobre o desarmamento - Not\u00edcias - Franciscanos","og_description":"Como portadores de PAZ e lembrando-se de que ela deve ser constru\u00edda incessantemente, procurem os caminhos da unidade e dos entendimentos fraternos mediante o di\u00e1logo, confiantes na presen\u00e7a do germe divino que existe no homem e na for\u00e7a transformadora do amor e do perd\u00e3o. (Regra19) &nbsp; Rio de Janeiro, 19 de janeiro de 2019 Vivemos [&hellip;]","og_url":"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2019-01-20T17:30:02+00:00","article_modified_time":"2019-01-22T17:35:47+00:00","og_image":[{"width":273,"height":181,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/01\/sultao_francisco_200119.jpg","type":"image\/jpeg"}],"author":"moacir","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"moacir","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/01\/sultao_francisco_200119.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2019\/01\/sultao_francisco_200119.jpg","width":273,"height":181},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html","name":"Carta da OFS sobre o desarmamento - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html#primaryimage"},"datePublished":"2019-01-20T17:30:02+00:00","dateModified":"2019-01-22T17:35:47+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/carta-da-ofs-sobre-o-desarmamento.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Carta da OFS sobre o desarmamento"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b5c8cba458c330ccff548b056e95a5d4","name":"moacir","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d08aa2ce4c8dd416d4479aa8536fcf64?s=96&d=mm&r=g","caption":"moacir"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/moacir"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/195566"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=195566"}],"version-history":[{"count":0,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/195566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/195572"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=195566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=195566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=195566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}