{"id":169787,"date":"2018-08-24T12:51:54","date_gmt":"2018-08-24T15:51:54","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=169787"},"modified":"2020-02-11T13:35:05","modified_gmt":"2020-02-11T16:35:05","slug":"unesco-e-colegio-ajudam-alunos-de-escola-publica","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html","title":{"rendered":"Unesco e Col\u00e9gio ajudam alunos de escola p\u00fablica"},"content":{"rendered":"<p><strong><img loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2018\/08\/bomjesus_240818.jpg\" alt=\"bomjesus_240818\" width=\"830\" height=\"467\" \/><\/strong><\/p>\n<h2><em>A\u00e7\u00e3o conjunta beneficia mais de 50 alunos de col\u00e9gio estadual em Curitiba<\/em><\/h2>\n<p>Alunos do 8.\u00ba e do 9.\u00ba ano do Ensino Fundamental do Col\u00e9gio Estadual Gua\u00edra, em Curitiba (PR), recebem refor\u00e7o nos estudos de L\u00edngua Portuguesa e de Matem\u00e1tica. Um grupo de volunt\u00e1rios formado por estudantes do Ensino M\u00e9dio do Col\u00e9gio Bom Jesus se re\u00fane semanalmente na escola p\u00fablica para retomar conte\u00fados, tirar d\u00favidas e ajudar os alunos atendidos pelo projeto a descobrir novas formas de estudar.<\/p>\n<p>A iniciativa surgiu pela equipe da Unidade Bom Jesus Centro, que assumiu essa grande miss\u00e3o, intitulada \u201cProjeto Monitoria: Integra\u00e7\u00e3o que Transforma\u201d. Vale destacar que essa a\u00e7\u00e3o est\u00e1 correlacionada ao <strong>PEA-Unesco<\/strong> (Programa de Escolas Associadas \u00e0 Unesco) pois, desde 2008, o Grupo Educacional Bom Jesus faz parte desse programa por desenvolver a\u00e7\u00f5es que contribuem para a forma\u00e7\u00e3o humana de seus alunos, com reflexos diretos na comunidade.<\/p>\n<p>De acordo com o gestor da Unidade, <strong>Marcelo Bianchini Favaro<\/strong>, o principal objetivo do projeto \u00e9 contribuir para uma sociedade mais justa e feliz por meio da integra\u00e7\u00e3o de jovens de diferentes realidades. \u201cA a\u00e7\u00e3o volunt\u00e1ria vai al\u00e9m do aspecto pedag\u00f3gico, permitindo uma rica troca de experi\u00eancias de vida. O resultado dessa conviv\u00eancia, para n\u00f3s, \u00e9 o mais importante\u201d, explica Marcelo.<\/p>\n<p>Segundo a diretora-geral do Col\u00e9gio Gua\u00edra, <strong>Ana Cristina Ross Dybax<\/strong>, a din\u00e2mica entre os adolescentes de ambas as escolas tem evolu\u00eddo a cada encontro. \u201cA rela\u00e7\u00e3o entre os alunos \u00e9 facilitada pela linguagem e pelos interesses comuns, facilitando as atividades e melhorando continuamente a postura comportamental e o desempenho escolar dos nossos estudantes\u201d, conta Ana.<strong>\u00a0 \u00a0 \u00a0 <\/strong><\/p>\n<p><strong><img loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2018\/08\/bomjesus_240818_2.jpg\" alt=\"bomjesus_240818_2\" width=\"830\" height=\"526\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/strong><\/p>\n<p><strong>Depoimento de alunos do Col\u00e9gio Estadual Gua\u00edra<\/strong>:<\/p>\n<p><em>\u201cMeu nome \u00e9 Nathaly, tenho 13 anos e sou aluna do 8.\u00ba ano B do Col\u00e9gio Gua\u00edra. Todas as segundas-feiras n\u00f3s temos refor\u00e7o com os alunos do Col\u00e9gio Bom Jesus e \u00e9 muito bom. Temos pessoas que nos ajudam naquilo que temos dificuldade. Meu desenvolvimento na sala de aula melhorou muito depois que eu comecei a fazer as aulas de refor\u00e7o. Todas as vezes que eu tenho alguma d\u00favida, eles me ajudam e eu gosto muito. Por\u00e9m, poderia ser em mais dias da semana e voltar a ser na 3.\u00aa aula. Tirando isso, estou aprendendo muito com esse novo aux\u00edlio.\u201d<\/em><\/p>\n<p><em>\u201cO Projeto Volunt\u00e1rio Bom Jesus est\u00e1 bem executado e estou melhorando o aprendizado. O \u00fanico problema \u00e9 a frequ\u00eancia, pois uma vez por semana \u00e9 muito pouco. Duas vezes por semana seria \u00f3timo! Agrade\u00e7o a equipe pela oportunidade. Atenciosamente, Bruno Henrique O. C.\u201d<\/em><\/p>\n<p><strong><img loading=\"lazy\" class=\"alignleft wp-image-169790 \" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2018\/08\/bomjesus_240818_3.jpg\" alt=\"bomjesus_240818_3\" width=\"331\" height=\"414\" \/>O projeto<\/strong><\/p>\n<p>Em n\u00fameros gerais, o projeto impacta, direta e indiretamente, mais de 500 pessoas, entre alunos e professores das duas institui\u00e7\u00f5es de ensino. Os primeiros encontros tiveram in\u00edcio em maio de 2017, e as atividades continuar\u00e3o neste ano, com previs\u00e3o de continuidade em 2019.<strong>\u00a0<\/strong><\/p>\n<p><strong>Voluntariado<\/strong><\/p>\n<p>No m\u00eas em que \u00e9 comemorado o Dia Nacional do Voluntariado, o Col\u00e9gio Bom Jesus promoveu uma a\u00e7\u00e3o solid\u00e1ria no Col\u00e9gio Estadual Gua\u00edra. As atividades ocorreram durante a tarde do dia 21 de agosto. No mesmo dia, outras nove escolas do Paran\u00e1, associadas ao PEA-Unesco, promoveram iniciativas semelhantes em suas institui\u00e7\u00f5es atendidas.<\/p>\n<p><strong>Miss\u00e3o franciscana<\/strong><\/p>\n<p>O Col\u00e9gio Bom Jesus atua h\u00e1 mais de 120 anos com inspira\u00e7\u00e3o no exemplo de fraternidade e de amor de S\u00e3o Francisco de Assis a todos os seres e \u00e0 natureza. Por meio do ensino, a Institui\u00e7\u00e3o promove a ajuda ao pr\u00f3ximo e a preserva\u00e7\u00e3o do meio ambiente, concretizando suas a\u00e7\u00f5es humanit\u00e1rias com o programa\u00a0Bom Jesus Social,\u00a0presente em cinco estados e conduzido nas mais de 30 unidades do Col\u00e9gio. Mais informa\u00e7\u00f5es e novidades a respeito dessas atividades est\u00e3o dispon\u00edveis\u00a0<strong><a href=\"http:\/\/bomjesus.br\/sobre\/social.vm\">aqui<\/a>\u00a0<\/strong>e no perfil do programa no\u00a0<strong><a href=\"https:\/\/www.facebook.com\/BomJesusSocial\/\">Facebook<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bom Jesus<\/p>\n","protected":false},"author":1,"featured_media":219383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Unesco e Col\u00e9gio ajudam alunos de escola p\u00fablica - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unesco e Col\u00e9gio ajudam alunos de escola p\u00fablica - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Bom Jesus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-24T15:51:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-11T16:35:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/bomjesus_240818.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/bomjesus_240818.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/bomjesus_240818.jpg\",\"width\":273,\"height\":181},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html\",\"name\":\"Unesco e Col\u00e9gio ajudam alunos de escola p\u00fablica - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html#primaryimage\"},\"datePublished\":\"2018-08-24T15:51:54+00:00\",\"dateModified\":\"2020-02-11T16:35:05+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unesco e Col\u00e9gio ajudam alunos de escola p\u00fablica\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unesco e Col\u00e9gio ajudam alunos de escola p\u00fablica - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html","og_locale":"pt_BR","og_type":"article","og_title":"Unesco e Col\u00e9gio ajudam alunos de escola p\u00fablica - Not\u00edcias - Franciscanos","og_description":"Bom Jesus","og_url":"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2018-08-24T15:51:54+00:00","article_modified_time":"2020-02-11T16:35:05+00:00","og_image":[{"width":273,"height":181,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/bomjesus_240818.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/bomjesus_240818.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/bomjesus_240818.jpg","width":273,"height":181},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html","name":"Unesco e Col\u00e9gio ajudam alunos de escola p\u00fablica - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html#primaryimage"},"datePublished":"2018-08-24T15:51:54+00:00","dateModified":"2020-02-11T16:35:05+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/unesco-e-colegio-ajudam-alunos-de-escola-publica.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Unesco e Col\u00e9gio ajudam alunos de escola p\u00fablica"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/169787"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=169787"}],"version-history":[{"count":0,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/169787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/219383"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=169787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=169787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=169787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}