{"id":169523,"date":"2018-08-22T12:05:13","date_gmt":"2018-08-22T15:05:13","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=169523"},"modified":"2019-01-02T13:11:58","modified_gmt":"2019-01-02T15:11:58","slug":"semana-missionaria-da-familia-em-santo-amaro","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html","title":{"rendered":"Semana Mission\u00e1ria da Fam\u00edlia em Santo Amaro"},"content":{"rendered":"<p><img loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2018\/08\/familia_220818.jpg\" alt=\"familia_220818\" width=\"830\" height=\"400\" \/><br \/>\n<strong>Frei Nilton Decker e Frei Daniel Dellandrea<\/strong><\/p>\n<p><strong>Santo Amaro da Imperatriz (SC) &#8211;<\/strong> Entre os dias 12 a 19 de agosto, a Par\u00f3quia de Santo Amaro, em Santo Amaro da Imperatriz (SC), vivenciou uma semana intensa de a\u00e7\u00e3o mission\u00e1ria, experimentando a alegria de uma Igreja em sa\u00edda, vivenciando a cultura da proximidade e do encontro. O objetivo era fortalecer o esp\u00edrito mission\u00e1rio e despertar novamente em cada um o amor ao Evangelho e pela Igreja-Comunidade Povo de Deus. Muitos volunt\u00e1rios colocaram-se a caminho ao longo da semana, seja na parte da manh\u00e3, como na parte da tarde. \u00c0 noite, al\u00e9m do momento celebrativo, houve evangeliza\u00e7\u00e3o para as crian\u00e7as.<\/p>\n<p>Para auxiliar na organiza\u00e7\u00e3o e na prepara\u00e7\u00e3o dessa semana, os organizadores seguiram as orienta\u00e7\u00f5es do subs\u00eddio da CNBB, Semana Mission\u00e1ria \u2013 Igreja em sa\u00edda (2\u00aa edi\u00e7\u00e3o, 2018). Tornou-se importante a integra\u00e7\u00e3o e o empenho do p\u00e1roco, do vig\u00e1rio paroquial, das lideran\u00e7as pastorais, dos colaboradores e de v\u00e1rios paroquianos volunt\u00e1rios. Realizaram-se antecipadamente v\u00e1rios encontros de motiva\u00e7\u00e3o e de capacita\u00e7\u00e3o dos agentes mission\u00e1rios. As atividades foram planejadas, com divis\u00e3o de grupos e uso de estrat\u00e9gias que auxiliaram a viv\u00eancia do tema proposto para cada dia com sua respectiva a\u00e7\u00e3o.<\/p>\n<p>Os temas contidos no subs\u00eddio da CNBB inspiram os crist\u00e3os leigos e leigas a serem \u201csal da terra e luz do mundo\u201d, assumindo um protagonismo mission\u00e1rio junto \u00e0 evangeliza\u00e7\u00e3o na cidade. A proposta foi adaptada tamb\u00e9m para as celebra\u00e7\u00f5es na Semana Nacional da Fam\u00edlia.<\/p>\n<p>Na segunda-feira, 13, o tema foi a Fam\u00edlia e o mundo do trabalho. Foram realizadas visitas aos estabelecimentos comerciais, ind\u00fastrias e casas de acolhida de idosos. Na ter\u00e7a-feira, 14, com o tema Fam\u00edlia e o mundo da pol\u00edtica, os paroquianos visitaram a C\u00e2mara de Vereadores, como tamb\u00e9m uma miss\u00e3o de visita\u00e7\u00e3o em um dos bairros da cidade, onde residem algumas fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade social e outras fragilizadas e necessitadas de um renovado ardor no seguimento a Jesus Cristo. Foi muito elogiada esta iniciativa. Na quarta-feira, 15, o tema foi a Fam\u00edlia e o mundo da comunica\u00e7\u00e3o e da educa\u00e7\u00e3o. Houve neste dia visitas a escolas, creches, APAE, catequese e prosseguimento de visitas ao com\u00e9rcio da cidade. A Fam\u00edlia e a cultura e a casa comum foi o tema da quinta-feira. Al\u00e9m dos estabelecimentos comerciais, houve visitas em algumas empresas, aos enfermos e colaboradores do Hospital S\u00e3o Francisco. Na sexta-feira, 17, com o tema a Fam\u00edlia e a supera\u00e7\u00e3o da viol\u00eancia e a busca da cultura da paz, realizaram-se visitas \u00e0 Pol\u00edcia Militar e Civil, Corpo de Bombeiros, e outras institui\u00e7\u00f5es que no seu dia a dia, promovem a cultura da paz e lutam por um mundo mais fraterno e igual. \u00c0 noite, junto \u00e0 celebra\u00e7\u00e3o da comunidade, estas institui\u00e7\u00f5es receberam uma lembran\u00e7a da Par\u00f3quia pela relevante miss\u00e3o na valoriza\u00e7\u00e3o da vida. O \u00faltimo tema foi a Fam\u00edlia, um olhar pelas crian\u00e7as. Al\u00e9m da evangeliza\u00e7\u00e3o direcionada \u00e0s crian\u00e7as que acontecia cada noite durante as celebra\u00e7\u00f5es da missa, uma celebra\u00e7\u00e3o com as crian\u00e7as foi realizada no s\u00e1bado, \u00e0s 15h, com cantos, din\u00e2micas e o evangelho encenado pelas pr\u00f3prias crian\u00e7as.<\/p>\n<p>Cada dia, os mission\u00e1rios se reuniam na Igreja, diante do Sacr\u00e1rio, para um momento de ora\u00e7\u00e3o e envio. Isto ajudou a perceber que \u00e9ramos chamados por Jesus para a miss\u00e3o e de que, estar \u00fanicos a Ele, seria a garantia da efic\u00e1cia de nossa a\u00e7\u00e3o evangelizadora. Primeiro permanecer com Ele, para depois, ir anunciar a alegria do Evangelho, a servi\u00e7o do Reino, em uma Igreja decididamente em sa\u00edda, mission\u00e1ria, solid\u00e1ria e misericordiosa.<\/p>\n<p>O grande encerramento da Semana aconteceu no domingo, 19, \u00e0s 19h no sal\u00e3o da Igreja Matriz. Muitas pessoas estiveram reunidas para rezarem a devo\u00e7\u00e3o do ter\u00e7o pelas fam\u00edlias, a Igreja dom\u00e9stica. A cada mist\u00e9rio da dezena, foram apresentas as seguintes reflex\u00f5es: O valor da voca\u00e7\u00e3o materna e o sim \u00e0 vida; a import\u00e2ncia hoje da miss\u00e3o do pai em assumir a condu\u00e7\u00e3o da fam\u00edlia e a educa\u00e7\u00e3o de seus filhos; a recorda\u00e7\u00e3o aos jovens de que constituir fam\u00edlia hoje \u00e9 a preven\u00e7\u00e3o da solid\u00e3o no futuro; o cuidado e cultivo do amor pelos idosos e enfermos na fam\u00edlia e na \u00faltima dezena, por ter sido o dia da voca\u00e7\u00e3o religiosa, a fam\u00edlia como ber\u00e7o vocacional. A ora\u00e7\u00e3o do ter\u00e7o era intercalada com m\u00fasicas do grande coral formado com 150 integrantes, que cantaram m\u00fasicas conhecidas para que todos os presentes pudessem tamb\u00e9m entoar suas vozes. Foi uma noite linda de louvor e ora\u00e7\u00e3o pelas fam\u00edlias. O grande momento foi a coroa\u00e7\u00e3o de Nossa Senhora e a consagra\u00e7\u00e3o das fam\u00edlias \u00e0 M\u00e3e Rainha da Gl\u00f3ria. E por fim, encerrando a noite, n\u00e3o poderia ter ficado de fora o canto da Ora\u00e7\u00e3o da Fam\u00edlia, pendido a Deus: \u201cAben\u00e7oa, Senhor, as fam\u00edlias! Am\u00e9m\u201d!<\/p>\n<p>Temos a certeza de que a Semana Mission\u00e1ria da Fam\u00edlia alcan\u00e7ou o seu objetivo de animar o esp\u00edrito mission\u00e1rio e de estreitar la\u00e7os de muitas pessoas com Jesus Cristo e sua comunidade, a Igreja. Muitos j\u00e1 se perguntam: \u201cEsta miss\u00e3o n\u00e3o poderia continuar?\u201d. Com certeza sim. A miss\u00e3o se torna necess\u00e1ria e permanente. Parab\u00e9ns aos leigos e leigas que percebem cada vez mais, de que s\u00e3o agentes, protagonistas de uma Igreja mission\u00e1ria e misericordiosa, a exemplo de Cristo.<\/p>\n<p>Testemunho da jovem Luana Martins Theisges: \u201cQuando aceitei participar, eu imaginava que ia ser bom! Hoje o meu sentimento \u00e9 de que foi uma Ben\u00e7\u00e3o de Deus, algo maravilhoso e promissor, momentos que nos fizeram refletir, evoluir, compreender&#8230; Um misto de Amor, Doa\u00e7\u00e3o, Miss\u00e3o, Ensinamentos! Miss\u00f5es que nos levaram de Mission\u00e1rios a aprendizes, que nos tocaram profundamente. Deus \u00e9 Maravilhoso e nos apresenta pessoas especiais para caminharem conosco, juntos vivemos a Alegria de levar a F\u00e9 a muito lugares, a muitas Fam\u00edlias que nos mostraram de uma maneira linda que a humildade est\u00e1 no ser, est\u00e1 nas atitudes e no modo de vida! Agradecimentos a todos que participaram e a todos que nos acolheram&#8230; Voc\u00eas s\u00e3o b\u00ean\u00e7\u00e3os de Deus!\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santa Catarina<\/p>\n","protected":false},"author":1,"featured_media":193466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[704],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Semana Mission\u00e1ria da Fam\u00edlia em Santo Amaro - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semana Mission\u00e1ria da Fam\u00edlia em Santo Amaro - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Santa Catarina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-22T15:05:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-02T15:11:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/familia_220818d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/familia_220818d.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/familia_220818d.jpg\",\"width\":273,\"height\":181},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html\",\"name\":\"Semana Mission\u00e1ria da Fam\u00edlia em Santo Amaro - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html#primaryimage\"},\"datePublished\":\"2018-08-22T15:05:13+00:00\",\"dateModified\":\"2019-01-02T15:11:58+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semana Mission\u00e1ria da Fam\u00edlia em Santo Amaro\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semana Mission\u00e1ria da Fam\u00edlia em Santo Amaro - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html","og_locale":"pt_BR","og_type":"article","og_title":"Semana Mission\u00e1ria da Fam\u00edlia em Santo Amaro - Not\u00edcias - Franciscanos","og_description":"Santa Catarina","og_url":"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2018-08-22T15:05:13+00:00","article_modified_time":"2019-01-02T15:11:58+00:00","og_image":[{"width":273,"height":181,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/familia_220818d.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/familia_220818d.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/08\/familia_220818d.jpg","width":273,"height":181},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html","name":"Semana Mission\u00e1ria da Fam\u00edlia em Santo Amaro - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html#primaryimage"},"datePublished":"2018-08-22T15:05:13+00:00","dateModified":"2019-01-02T15:11:58+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/semana-missionaria-da-familia-em-santo-amaro.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Semana Mission\u00e1ria da Fam\u00edlia em Santo Amaro"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/169523"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=169523"}],"version-history":[{"count":0,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/169523\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/193466"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=169523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=169523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=169523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}