{"id":165736,"date":"2018-07-01T08:29:24","date_gmt":"2018-07-01T11:29:24","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=165736"},"modified":"2019-06-28T07:43:20","modified_gmt":"2019-06-28T10:43:20","slug":"familia-a-pedra-que-edifica-a-igreja","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html","title":{"rendered":"\u201cFam\u00edlia, a pedra que edifica a Igreja\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2018\/07\/pedro_010718.jpg\" alt=\"pedro_010718\" width=\"830\" height=\"553\" \/><\/p>\n<p><strong>Frei Jo\u00e3o Manoel Zechinatto<\/strong><\/p>\n<p><strong>Gaspar (SC)<\/strong> &#8211; Na tarde deste s\u00e1bado, a Igreja Matriz S\u00e3o Pedro Ap\u00f3stolo de Gaspar lotou nesse \u00faltimo dia do Tr\u00edduo em prepara\u00e7\u00e3o para a festa de seu Padroeiro. S\u00e3o 168 anos de devo\u00e7\u00e3o do povo gasparense \u00e0quele que \u00e9 uma das colunas da Igreja. A celebra\u00e7\u00e3o contou com a presen\u00e7a de toda a catequese da Par\u00f3quia e tamb\u00e9m dos coroinhas, tanto da Matriz como tamb\u00e9m das comunidades.<\/p>\n<p>O p\u00e1roco, Frei Paulijacson de Moura, acolheu, antes do in\u00edcio da celebra\u00e7\u00e3o, \u00a0com muita alegria, todas as crian\u00e7as, catequistas, pais e familiares que vieram celebrar juntos em mais este dia de festa. A celebra\u00e7\u00e3o foi presidida pelo pregador do tr\u00edduo, Dom Jaime Spengler, que falou sobre \u201cPedro, testemunha do Ressuscitado, pedra da Igreja\u201d!<\/p>\n<p>O coral das crian\u00e7as da catequese cantou \u201cSeja Bem-Vindo, Paz e Bem\u201d, como canto de acolhida. Irm\u00e3 Vanessa, da Congrega\u00e7\u00e3o das Irm\u00e3s Franciscanas da Imaculada Concei\u00e7\u00e3o, que reside em Gaspar, ficou respons\u00e1vel por neste ano iniciar um coral com as crian\u00e7as. Os catequizandos estavam todos de branco na escadaria do presbit\u00e9rio e cantavam, enquanto a prociss\u00e3o de entrada vinha pelo corredor central da Igreja Matriz.<\/p>\n<p><img loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2018\/07\/pedro_010718_2.jpg\" alt=\"pedro_010718_2\" width=\"830\" height=\"475\" \/><\/p>\n<p>Em sua homilia, Dom Jaime dirigiu-se, primeiramente, aos pais e familiares ali presentes: \u201cMaternidade e Paternidade n\u00e3o pode ser um acidente ou um imprevisto. Ser pai e m\u00e3e deve ser um desejo e um sonho de participar da obra de cria\u00e7\u00e3o do Criador, ser participante de uma profunda responsabilidade\u201d. O bispo ressaltou o quanto \u00e9 triste ver pais que n\u00e3o se importam com seus filhos e os deixam ao l\u00e9u. Os filhos, disse ele, s\u00e3o o bem mais precioso que podemos ter, eles s\u00e3o o sustent\u00e1culo da esperan\u00e7a de um bom futuro. \u201cQuem n\u00e3o cuida do seu bem, um dia chorar\u00e1 por v\u00ea-lo se perder\u201d. Dom Jaime insistiu para que os pais sejam verdadeira presen\u00e7a amiga na vida de seus filhos.<\/p>\n<p>Depois, dirigindo-se \u00e0s crian\u00e7as, Dom Jaime lembrou da profiss\u00e3o de f\u00e9 de S\u00e3o Pedro no Evangelho do dia: \u201cTu \u00e9s o Messias, o Filho do Deus vivo\u201d (Mt 16,16). Disse que cada fam\u00edlia \u00e9 pedra viva que promove e edifica a Igreja, ressaltou tamb\u00e9m, que como crist\u00e3os n\u00e3o somos \u201cadeptos\u201d desta f\u00e9 ou daquela cren\u00e7a, mas disc\u00edpulos do Senhor. \u201cVossos pais quando vos transmitirem a f\u00e9 devem ensin\u00e1-los a serem disc\u00edpulos do Filho do Deus vivo\u201d. Por fim, pediu \u00e0s crian\u00e7as que sigam, com fidelidade, a Jesus; fazendo sempre o bem em todas as coisas.<\/p>\n<p>No final da celebra\u00e7\u00e3o, Frei Paulijacson agradeceu Dom Jaime pela presen\u00e7a fraterna e acolhedora em mais este dia de prepara\u00e7\u00e3o \u00e0 Solenidade de S\u00e3o Pedro e S\u00e3o Paulo. Agradeceu tamb\u00e9m a toda e Equipe da Catequese da Par\u00f3quia pela bel\u00edssima celebra\u00e7\u00e3o. O coral da catequese foi a frente novamente e cantou com toda a comunidade o hino do padroeiro S\u00e3o Pedro, logo ap\u00f3s, Dom Jaime encerrou a celebra\u00e7\u00e3o com a b\u00ean\u00e7\u00e3o final.<\/p>\n<p><img loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2018\/07\/pedro_010718_3.jpg\" alt=\"pedro_010718_3\" width=\"830\" height=\"445\" \/><\/p>\n<p><strong>Ofertar nosso melhor!<\/strong><\/p>\n<p>O tradicional leil\u00e3o da Festa de S\u00e3o Pedro Ap\u00f3stolo \u00e9 um dos grandes destaques de toda a festa. Prova concreta da generosidade do povo de Gaspar que oferece parte de seu gado e rebanho como forma de agradecer a Deus pelas b\u00ean\u00e7\u00e3os no campo.<\/p>\n<p>Nas semanas que antecedem a festa, Frei Lindolfo Jasper ao lado do Sr. Beto Tonholi andam por toda Gaspar arrecadando doa\u00e7\u00f5es dos agricultores, empresas e benfeitores. Porcos, ovelhas, galinhas, cavalos e mais de 30 cabe\u00e7as de gado foram doados para o leil\u00e3o.<\/p>\n<p>Devido ao grande n\u00famero de prendas, o leil\u00e3o, neste ano, n\u00e3o ocorrer\u00e1 apenas no domingo (01\/07), como \u00e9 o costume, mas tamb\u00e9m j\u00e1 no s\u00e1bado. Assim, como Deus se alegrou com a boa oferta de Abel, tamb\u00e9m hoje, o Senhor se alegra com a generosa oferta do povo de Gaspar! Que este seja mais um ano aben\u00e7oado a todos os nossos agricultores e que nos anos vindouros, possamos sempre contar com a generosa oferta de quem oferece o seu melhor ao pr\u00f3prio Deus!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Festa de S\u00e3o Pedro Ap\u00f3stolo na Par\u00f3quia de Gaspar<\/p>\n","protected":false},"author":1,"featured_media":206574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[298,292],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cFam\u00edlia, a pedra que edifica a Igreja\u201d - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cFam\u00edlia, a pedra que edifica a Igreja\u201d - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Festa de S\u00e3o Pedro Ap\u00f3stolo na Par\u00f3quia de Gaspar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-01T11:29:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-28T10:43:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/07\/pedro_010718_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/07\/pedro_010718_1.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/07\/pedro_010718_1.jpg\",\"width\":273,\"height\":181},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html\",\"name\":\"\u201cFam\u00edlia, a pedra que edifica a Igreja\u201d - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html#primaryimage\"},\"datePublished\":\"2018-07-01T11:29:24+00:00\",\"dateModified\":\"2019-06-28T10:43:20+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cFam\u00edlia, a pedra que edifica a Igreja\u201d\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cFam\u00edlia, a pedra que edifica a Igreja\u201d - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html","og_locale":"pt_BR","og_type":"article","og_title":"\u201cFam\u00edlia, a pedra que edifica a Igreja\u201d - Not\u00edcias - Franciscanos","og_description":"Festa de S\u00e3o Pedro Ap\u00f3stolo na Par\u00f3quia de Gaspar","og_url":"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2018-07-01T11:29:24+00:00","article_modified_time":"2019-06-28T10:43:20+00:00","og_image":[{"width":273,"height":181,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/07\/pedro_010718_1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/07\/pedro_010718_1.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2018\/07\/pedro_010718_1.jpg","width":273,"height":181},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html","name":"\u201cFam\u00edlia, a pedra que edifica a Igreja\u201d - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html#primaryimage"},"datePublished":"2018-07-01T11:29:24+00:00","dateModified":"2019-06-28T10:43:20+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/familia-a-pedra-que-edifica-a-igreja.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"\u201cFam\u00edlia, a pedra que edifica a Igreja\u201d"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/165736"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=165736"}],"version-history":[{"count":0,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/165736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/206574"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=165736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=165736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=165736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}