{"id":143280,"date":"2017-10-05T08:55:51","date_gmt":"2017-10-05T11:55:51","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=143280"},"modified":"2020-06-08T16:56:34","modified_gmt":"2020-06-08T19:56:34","slug":"um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html","title":{"rendered":"&#8220;Um povo sem ra\u00edzes \u00e9 um povo doente\u201d, diz o Papa Francisco"},"content":{"rendered":"<p><img loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2017\/10\/papa_051017.jpg\" alt=\"papa_051017\" width=\"820\" height=\"470\" \/><\/p>\n<p><strong>Cidade do Vaticano<\/strong> &#8211; \u201cQuem reencontra as pr\u00f3prias ra\u00edzes \u00e9 uma pessoa da alegria. O autoex\u00edlio psicol\u00f3gico da comunidade e da sociedade faz muito mal\u201d, disse o Papa Francisco na homilia da Missa matutina celebrada nesta quinta-feira (05\/10), na capela da Casa Santa Marta.<\/p>\n<p>O Papa exortou a encontrar novamente a pr\u00f3pria perten\u00e7a, partindo da Primeira Leitura do dia, extra\u00edda do Livro de Neemias, que descreve \u201cuma grande assembleia lit\u00fargica\u201d: \u00e9 o povo que se reuniu na pra\u00e7a que fica defronte da porta das \u00c1guas, em Jerusal\u00e9m. Era o final de uma hist\u00f3ria que durou mais de 70 anos, a hist\u00f3ria da deporta\u00e7\u00e3o para a Babil\u00f4nia, uma hist\u00f3ria de pranto para o povo de Deus. Depois da queda do imp\u00e9rio da Babil\u00f4nia causada pelos persas, o rei persa Artaxerxes, vendo triste Neemias, seu copeiro, enquanto lhe servia o vinho, come\u00e7ou a dialogar com ele. Neemias manifestou o desejo de voltar a Jerusal\u00e9m e \u201cchorava\u201d: tinha \u201csaudade de sua cidade\u201d.<\/p>\n<p>Francisco lembrou ent\u00e3o ao Salmo que diz: \u201cAo longo dos rios da Babil\u00f4nia se sentavam e choravam\u201d. N\u00e3o podiam cantar, suas liras estavam penduradas nos salgueiros, mas n\u00e3o queriam esquecer. Nesse momento, o Papa pensou tamb\u00e9m na \u201csaudade dos migrantes\u201d, aqueles que \u201cest\u00e3o distantes da P\u00e1tria e querem voltar\u201d. Francisco recordou tamb\u00e9m o gesto do coral, em G\u00eanova, no final da missa que cantou uma m\u00fasica recordando todos os migrantes que gostariam de estar ali, na missa com o Papa, mas estavam distantes.<\/p>\n<p>Neemias se prepara para voltar e levar novamente o povo a Jerusal\u00e9m. Uma viagem \u201cpara reencontrar a cidade, uma viagem dif\u00edcil\u201d, ressaltou o Papa, pois \u201cdeveria convencer muita gente\u201d e levar as coisas para reconstruir a cidade, os muros e o Templo, \u201cmas sobretudo era uma viagem para reencontrar as ra\u00edzes do povo\u201d. Depois de muitos anos, as ra\u00edzes \u201ctinham se enfraquecido\u201d, mas n\u00e3o foram perdidas. Retomar as ra\u00edzes \u201csignifica retomar a perten\u00e7a a um povo\u201d, explicou o Papa. \u201cSem as ra\u00edzes n\u00e3o \u00e9 poss\u00edvel viver: um povo sem ra\u00edzes ou que deixa perder as ra\u00edzes, \u00e9 um povo doente\u201d. Disse o Papa que acrescentou: \u201cUma pessoa sem ra\u00edzes, que esqueceu as pr\u00f3prias ra\u00edzes, \u00e9 doente. Reencontrar, redescobrir as pr\u00f3prias ra\u00edzes e tomar a for\u00e7a para ir adiante, a for\u00e7a para frutificar, e como disse o profeta, \u2018a for\u00e7a para florescer, pois o que floresce na \u00e1rvore vem do subterr\u00e2neo. Aquela rela\u00e7\u00e3o entre a raiz e o bem que n\u00f3s podemos fazer.\u201d<\/p>\n<p>Neste caminho existem \u201cmuitas resist\u00eancias: n\u00e3o \u00e9 poss\u00edvel, existem dificuldades\u201d: \u201cAs resist\u00eancias s\u00e3o daqueles que preferem o ex\u00edlio, e quando n\u00e3o h\u00e1 o ex\u00edlio f\u00edsico, h\u00e1 o ex\u00edlio psicol\u00f3gico: o autoex\u00edlio da comunidade, da sociedade, aqueles que preferem ser povo desarraigado, sem ra\u00edzes. Devemos pensar na doen\u00e7a do autoex\u00edlio psicol\u00f3gico que faz muito mal, nos tira as ra\u00edzes, nos tira a perten\u00e7a.\u201d<\/p>\n<p>O povo, por\u00e9m, vai adiante e chega o dia da reconstru\u00e7\u00e3o. O povo se re\u00fane para \u201crestabelecer as ra\u00edzes\u201d, ou seja, para ouvir a Palavra de Deus que o escriba Esdras lia e o povo chorava. Mas desta vez n\u00e3o era o pranto da Babil\u00f4nia: \u201cera o choro da alegria, do encontro com as pr\u00f3prias ra\u00edzes, o encontro com, a pr\u00f3pria perten\u00e7a\u201d. Terminada a leitura, Neemias convida o povo a festejar. Trata-se da alegria de quem encontrou as pr\u00f3prias ra\u00edzes: \u201cO homem e a mulher que reencontram as pr\u00f3prias ra\u00edzes, que s\u00e3o fi\u00e9is \u00e0 pr\u00f3pria perten\u00e7a, s\u00e3o um homem e uma mulher na alegria, de alegria e esta alegria \u00e9 a sua for\u00e7a. Do choro de tristeza ao choro de alegria, do choro de fraqueza por estar distante das ra\u00edzes, distante de seu povo, ao choro da perten\u00e7a: estou em casa, estou em casa\u201d.<\/p>\n<p>O Papa convidou os fi\u00e9is presentes na missa a lerem o cap\u00edtulo oitavo de Neemias, primeira leitura da liturgia de hoje, e a se perguntarem se deixaram se perder a lembran\u00e7a do Senhor, se devem come\u00e7ar um caminho para reencontrar as pr\u00f3prias ra\u00edzes ou se preferem o autoex\u00edlio psicol\u00f3gico, fechados em si mesmos.<\/p>\n<p>O Papa disse ainda que quem tem medo de chorar, ter\u00e1 medo de sorrir, pois quando se chora de tristeza, depois se chora de alegria. \u00c9 preciso pedir a gra\u00e7a do \u201cchoro arrependido\u201d, triste pelos nossos pecados, mas tamb\u00e9m a gra\u00e7a do choro de alegria, pois o Senhor \u201cnos perdoou e fez em nossa vida o que fez com o seu povo. Enfim, pedir a gra\u00e7a de se colocar a caminho para se encontrar com as pr\u00f3prias ra\u00edzes.<\/p>\n<hr \/>\n<p><em>Fonte: Vatican News<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Missa em Santa Marta<\/p>\n","protected":false},"author":1,"featured_media":203376,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[1586],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Um povo sem ra\u00edzes \u00e9 um povo doente\u201d, diz o Papa Francisco - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Um povo sem ra\u00edzes \u00e9 um povo doente\u201d, diz o Papa Francisco - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Missa em Santa Marta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-05T11:55:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-08T19:56:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/10\/papa_051017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/10\/papa_051017.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/10\/papa_051017.jpg\",\"width\":273,\"height\":181},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html\",\"name\":\"\\\"Um povo sem ra\u00edzes \u00e9 um povo doente\u201d, diz o Papa Francisco - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html#primaryimage\"},\"datePublished\":\"2017-10-05T11:55:51+00:00\",\"dateModified\":\"2020-06-08T19:56:34+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Um povo sem ra\u00edzes \u00e9 um povo doente\u201d, diz o Papa Francisco\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Um povo sem ra\u00edzes \u00e9 um povo doente\u201d, diz o Papa Francisco - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html","og_locale":"pt_BR","og_type":"article","og_title":"\"Um povo sem ra\u00edzes \u00e9 um povo doente\u201d, diz o Papa Francisco - Not\u00edcias - Franciscanos","og_description":"Missa em Santa Marta","og_url":"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2017-10-05T11:55:51+00:00","article_modified_time":"2020-06-08T19:56:34+00:00","og_image":[{"width":273,"height":181,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/10\/papa_051017.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/10\/papa_051017.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/10\/papa_051017.jpg","width":273,"height":181},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html","name":"\"Um povo sem ra\u00edzes \u00e9 um povo doente\u201d, diz o Papa Francisco - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html#primaryimage"},"datePublished":"2017-10-05T11:55:51+00:00","dateModified":"2020-06-08T19:56:34+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/um-povo-sem-raizes-e-um-povo-doente-diz-o-papa-francisco.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"&#8220;Um povo sem ra\u00edzes \u00e9 um povo doente\u201d, diz o Papa Francisco"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/143280"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=143280"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/143280\/revisions"}],"predecessor-version":[{"id":225227,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/143280\/revisions\/225227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/203376"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=143280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=143280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=143280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}