{"id":124931,"date":"2017-01-23T00:34:35","date_gmt":"2017-01-23T02:34:35","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=124931"},"modified":"2020-06-09T11:06:12","modified_gmt":"2020-06-09T14:06:12","slug":"papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html","title":{"rendered":"Papa aos dominicanos: Ai de uma Igreja que perde o sabor!"},"content":{"rendered":"<p><strong><img loading=\"lazy\" class=\"alignleft size-full wp-image-124932\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2017\/01\/dominicanos_230117.jpg\" alt=\"dominicanos_230117\" width=\"391\" height=\"792\" \/>Cidade do Vaticano<\/strong> \u2013 O Papa Francisco presidiu na tarde deste s\u00e1bado, 21 de janeiro, na Bas\u00edlica S\u00e3o Jo\u00e3o de Latr\u00e3o, a Solene Celebra\u00e7\u00e3o Eucar\u00edstica de conclus\u00e3o do Jubileu dos 800 anos de funda\u00e7\u00e3o da Ordem dos Pregadores (dominicanos). De fato, em 21 de janeiro de 1217, S\u00e3o Domingos de Gusm\u00e3o recebeu do Papa Hon\u00f3rio III a Bula Gratiarum Largitori Omnium, na qual, pela primeira vez, se fala de \u201cOrdem dos Pregadores\u201d. Precisamente o anivers\u00e1rio deste documento papal foi escolhido como data para a conclus\u00e3o do Jubileu Dominicano.<\/p>\n<p>Na sua homilia, o Papa Francisco recordou a Evangelho do dia no qual a Palavra de Deus apresenta dois cen\u00e1rios humanos opostos: \u201cDe um lado o &#8220;carnaval&#8221; da curiosidade mundana, do outro a glorifica\u00e7\u00e3o do Pai atrav\u00e9s das boas obras\u201d. A nossa vida \u2013 disse o Santo Padre &#8211; se move sempre entre esses dois cen\u00e1rios.<\/p>\n<p>\u00c9 interessante ver como, j\u00e1 ent\u00e3o, dois mil anos atr\u00e1s, os ap\u00f3stolos do Evangelho se encontrassem diante deste cen\u00e1rio, que nos dias de hoje se desenvolveu e globalizou por causa da sedu\u00e7\u00e3o do relativismo subjetivista.<\/p>\n<p><strong>Sociedade l\u00edquida<\/strong><br \/>\n\u201cA tend\u00eancia \u00e0 busca de novidade, pr\u00f3pria do ser humano encontra o ambiente perfeito na sociedade do aparecer, no consumo, na qual muitas vezes se reciclam coisas velhas, mas o importante \u00e9 faz\u00ea-las aparecer como novas, atraentes, cativantes. Tamb\u00e9m a verdade \u00e9 manipulada, disse Francisco acrescentando: \u201cN\u00f3s nos movemos na chamada &#8216;sociedade l\u00edquida&#8217;, sem pontos fixos, desequilibrada, sem refer\u00eancias s\u00f3lidas e est\u00e1veis; na cultura do ef\u00eamero, do usa e joga fora\u201d.<\/p>\n<p><strong>&#8220;Carnaval&#8221; mundano<\/strong><br \/>\nDiante deste &#8220;carnaval&#8221; mundano destaca-se nitidamente o cen\u00e1rio oposto, que encontramos nas palavras de Jesus que acabamos de ouvir: &#8220;Glorifiquem a vosso Pai que est\u00e1 nos c\u00e9us&#8221;. E como ocorre essa passagem da superficialidade pseudo-festiva \u00e0 glorifica\u00e7\u00e3o?, pergunta-se o Papa. \u201cOcorre gra\u00e7as \u00e0s boas obras daqueles que, tornando-se disc\u00edpulos de Jesus, tornaram-se &#8220;sal&#8221; e &#8220;luz&#8221;.<\/p>\n<p>Francisco afirmou em seguida que em meio ao &#8220;carnaval&#8221; de ontem e de hoje, esta \u00e9 a resposta de Jesus e da Igreja, este \u00e9 o apoio s\u00f3lido em meio ao ambiente &#8220;l\u00edquido&#8221;: as boas obras que podemos realizar gra\u00e7as a Cristo e ao seu Santo Esp\u00edrito, e que fazem nascer no cora\u00e7\u00e3o a a\u00e7\u00e3o de gra\u00e7as a Deus Pai, o louvor. E a pergunta: &#8220;por qu\u00ea?&#8221;, &#8220;por que aquela pessoa se comporta dessa maneira?&#8221;: a inquietude do mundo diante do testemunho do Evangelho.<\/p>\n<p><strong>\u00c9 preciso que o sal n\u00e3o perca o sabor<\/strong><br \/>\nMas para que ocorra este &#8220;abalo&#8221; \u00e9 preciso que o sal n\u00e3o perca o sabor e a luz n\u00e3o se esconda. Jesus diz muito claramente: se o sal perde o seu sabor n\u00e3o serve para mais nada. Ai do sal que perde o seu sabor! Ai de uma Igreja que perde o sabor! Ai de um padre, de um consagrado, de uma congrega\u00e7\u00e3o que perde o sabor!<\/p>\n<p>Francisco concluiu: \u201cHoje damos gl\u00f3ria ao Pai pela obra que S\u00e3o Domingos, cheio da luz e sal de Cristo, realizou oitocentos anos atr\u00e1s; uma obra a servi\u00e7o do Evangelho, pregado com a palavra e com a vida; uma obra que, com a gra\u00e7a do Esp\u00edrito Santo, fez com que muitos homens e mulheres fossem ajudados a n\u00e3o se perderem no meio do &#8220;carnaval&#8221; da curiosidade mundana, mas, ao inv\u00e9s sentissem o sabor da s\u00e3 doutrina, o sabor do Evangelho, e se tornassem, por sua vez, luz e sal, artes\u00e3os de boas obras &#8230; e verdadeiros irm\u00e3os e irm\u00e3s que glorificam a Deus e ensinam a glorificar a Deus com as boas obras da vida\u201d.<\/p>\n<hr \/>\n<p><em>Fonte: R\u00e1dio Vaticano<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jubileu 800 anos<\/p>\n","protected":false},"author":1,"featured_media":195486,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[1272],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Papa aos dominicanos: Ai de uma Igreja que perde o sabor! - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa aos dominicanos: Ai de uma Igreja que perde o sabor! - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Jubileu 800 anos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-23T02:34:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-09T14:06:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa-dominicanosp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa-dominicanosp.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa-dominicanosp.jpg\",\"width\":273,\"height\":181},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html\",\"name\":\"Papa aos dominicanos: Ai de uma Igreja que perde o sabor! - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html#primaryimage\"},\"datePublished\":\"2017-01-23T02:34:35+00:00\",\"dateModified\":\"2020-06-09T14:06:12+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa aos dominicanos: Ai de uma Igreja que perde o sabor!\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa aos dominicanos: Ai de uma Igreja que perde o sabor! - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html","og_locale":"pt_BR","og_type":"article","og_title":"Papa aos dominicanos: Ai de uma Igreja que perde o sabor! - Not\u00edcias - Franciscanos","og_description":"Jubileu 800 anos","og_url":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2017-01-23T02:34:35+00:00","article_modified_time":"2020-06-09T14:06:12+00:00","og_image":[{"width":273,"height":181,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa-dominicanosp.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa-dominicanosp.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa-dominicanosp.jpg","width":273,"height":181},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html","name":"Papa aos dominicanos: Ai de uma Igreja que perde o sabor! - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html#primaryimage"},"datePublished":"2017-01-23T02:34:35+00:00","dateModified":"2020-06-09T14:06:12+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/papa-aos-dominicanos-ai-de-uma-igreja-que-perde-o-sabor.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Papa aos dominicanos: Ai de uma Igreja que perde o sabor!"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/124931"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=124931"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/124931\/revisions"}],"predecessor-version":[{"id":225476,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/124931\/revisions\/225476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/195486"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=124931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=124931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=124931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}