{"id":124144,"date":"2017-01-18T08:31:49","date_gmt":"2017-01-18T10:31:49","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=124144"},"modified":"2020-06-09T11:10:10","modified_gmt":"2020-06-09T14:10:10","slug":"diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html","title":{"rendered":"&#8220;Diante da morte, a esperan\u00e7a da vida eterna&#8221;, diz o Papa"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignleft\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2017\/01\/papa_180117.jpg\" alt=\"papa_180117\" width=\"820\" height=\"383\" \/><\/p>\n<p><strong>Cidade do Vaticano<\/strong> \u2013 \u201cJonas, a esperan\u00e7a e a ora\u00e7\u00e3o\u201d: este foi o tema da catequese feita pelo Papa aos fi\u00e9is em seu encontro nesta quarta-feira (18\/01), para a audi\u00eancia geral. Francisco se concentrou de modo mais concreto na nossa decis\u00e3o de nos colocarmos em ora\u00e7\u00e3o movidos pela esperan\u00e7a no perd\u00e3o de Deus e mencionou a par\u00e1bola do Profeta Jonas, em cuja vida esta rela\u00e7\u00e3o ficou bem clara.<\/p>\n<p>Jonas \u00e9 um profeta \u2018em sa\u00edda\u2019, \u2018em fuga\u2019, disse o Papa, um profeta que Deus enviou \u2018\u00e0 periferia\u2019, em N\u00ednive, para converter os moradores daquela grande cidade&#8230; Mas o profeta n\u00e3o quis ir: N\u00ednive fez demasiado mal ao seu povo, para Jonas conseguir desejar-lhe a salva\u00e7\u00e3o. Ent\u00e3o, o profeta toma uma nave, com o prop\u00f3sito de seguir na dire\u00e7\u00e3o oposta de N\u00ednive.<\/p>\n<p>\u201cDurante sua fuga, o profeta entra em contato com os pag\u00e3os, os marinheiros do navio, para se afastar de Deus e de sua miss\u00e3o. E \u00e9 justamente o comportamento destes homens que nos faz hoje refletir sobre a esperan\u00e7a que, diante do perigo e da morte, se expressa em ora\u00e7\u00e3o\u201d.<\/p>\n<p>Uma grande tempestade amea\u00e7a afundar a nave; sobre ela, desesperados, todos come\u00e7am a rezar cada um ao seu pr\u00f3prio deus para que os salve. Todos n\u00e3o! Jonas dorme no por\u00e3o. O comandante o acorda dizendo-lhe: \u201cInvoca o teu Deus, a ver se por acaso se lembra de n\u00f3s e nos livra da morte\u201d.<\/p>\n<p>Nestas palavras \u2013 explicou o Pont\u00edfice \u2013 transparece toda a esperan\u00e7a do ser humano na sua impot\u00eancia face a um perigo mortal. \u00c9 a esperan\u00e7a que se faz ora\u00e7\u00e3o, uma s\u00faplica cheia de ang\u00fastia que sobe dos l\u00e1bios humanos em perigo iminente de morte.<\/p>\n<p>O fato destas palavras sa\u00edrem da boca de \u201cpag\u00e3os\u201d, como era o comandante da nave, s\u00f3 confirma como a necessidade de o fazer seja intuitiva e generalizada na alma humana. O pavor instintivo de morrer revela a necessidade de esperar no Deus da vida. \u201cMuitas vezes, facilmente, n\u00f3s n\u00e3o nos dirigimos a Deus no momento da necessidade por considerarmos uma ora\u00e7\u00e3o interesseira e imperfeita. Deus, no entanto, conhece as nossas fraquezas, sabe que n\u00f3s nos recordamos Dele para pedir ajuda, e com o sorriso indulgente de um pai, responde positivamente\u201d.<\/p>\n<p>\u201cQuando Jonas, reconhecendo as pr\u00f3prias responsabilidades, se joga no mar para salvar seus companheiros de travessia, a tempestade se acalma. Aceitando sacrificar-se por eles, Jonas agora conduz os sobreviventes ao reconhecimento do verdadeiro Senhor\u201d.<\/p>\n<p>E a ora\u00e7\u00e3o ditada pela esperan\u00e7a surtiu efeito, Deus realizou quanto esperavam e pediam: a nave foi salva, o profeta aprendeu a obedecer e Deus perdoou \u00e0 cidade arrependida.<\/p>\n<p>O Papa concluiu a reflex\u00e3o afirmando que sob a miseric\u00f3rdia divina, e ainda mais, \u00e0 luz do mist\u00e9rio pascal, a morte pode se tornar, como o foi para S\u00e3o Francisco de Assis, \u201cnossa irm\u00e3 morte\u201d e representar, para cada homem e para cada um de n\u00f3s, a surpreendente ocasi\u00e3o para conhecer a esperan\u00e7a e encontrar o Senhor.<\/p>\n<hr \/>\n<p><em>Fonte: R\u00e1dio Vaticano<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Audi\u00eancia Geral<\/p>\n","protected":false},"author":1,"featured_media":195588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1428],"tags":[487],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Diante da morte, a esperan\u00e7a da vida eterna&quot;, diz o Papa - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Diante da morte, a esperan\u00e7a da vida eterna&quot;, diz o Papa - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Audi\u00eancia Geral\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-18T10:31:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-09T14:10:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa_180117.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa_180117.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa_180117.jpg\",\"width\":273,\"height\":181},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html\",\"name\":\"\\\"Diante da morte, a esperan\u00e7a da vida eterna\\\", diz o Papa - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html#primaryimage\"},\"datePublished\":\"2017-01-18T10:31:49+00:00\",\"dateModified\":\"2020-06-09T14:10:10+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Diante da morte, a esperan\u00e7a da vida eterna&#8221;, diz o Papa\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Diante da morte, a esperan\u00e7a da vida eterna\", diz o Papa - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html","og_locale":"pt_BR","og_type":"article","og_title":"\"Diante da morte, a esperan\u00e7a da vida eterna\", diz o Papa - Not\u00edcias - Franciscanos","og_description":"Audi\u00eancia Geral","og_url":"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2017-01-18T10:31:49+00:00","article_modified_time":"2020-06-09T14:10:10+00:00","og_image":[{"width":273,"height":181,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa_180117.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa_180117.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2017\/01\/papa_180117.jpg","width":273,"height":181},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html","name":"\"Diante da morte, a esperan\u00e7a da vida eterna\", diz o Papa - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html#primaryimage"},"datePublished":"2017-01-18T10:31:49+00:00","dateModified":"2020-06-09T14:10:10+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/diante-da-morte-a-esperanca-da-vida-eterna-diz-o-papa-aos-fieis.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"&#8220;Diante da morte, a esperan\u00e7a da vida eterna&#8221;, diz o Papa"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/124144"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=124144"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/124144\/revisions"}],"predecessor-version":[{"id":225481,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/124144\/revisions\/225481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/195588"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=124144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=124144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=124144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}